﻿{"id":15818,"date":"2014-03-17T22:06:56","date_gmt":"2014-03-17T20:06:56","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=15818"},"modified":"2016-08-24T14:38:37","modified_gmt":"2016-08-24T12:38:37","slug":"victoire-pour-chenois-et-joye-contre-ugs","status":"publish","type":"post","link":"http:\/\/www.proxifoot.ch\/geneve\/2014\/03\/victoire-pour-chenois-et-joye-contre-ugs\/","title":{"rendered":"Victoire pour Ch\u00eanois et Joye contre UGS"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Victoire importante du CS Ch\u00eanois de David Joye pour son retour \u00e0 Frontenex, dans ce derby qui n&#8217;aura pas donn\u00e9 au public beaucoup d&#8217;occasions de fr\u00e9mir\u00a0tant les situations chaudes auront \u00e9t\u00e9 rares de part et d&#8217;autre.<!--more--><\/strong><\/p>\n<p style=\"text-align: justify;\">Ch\u00eanois se d\u00e9pla\u00e7ait \u00e0 Frontenex fort de son bon point obtenu la semaine derni\u00e8re face aux M-21 serventtiens alors que du c\u00f4t\u00e9 d&#8217;UGS, on d\u00e9sirait surtout inscrire les premiers points de l&#8217;ann\u00e9e apr\u00e8s une d\u00e9faite frustrante contre Vevey lors de leur premi\u00e8re sortie.<\/p>\n<p style=\"text-align: justify;\">En d\u00e9but de match, les deux formations, align\u00e9es en 4-2-3-1, cherchent \u00e0 s&#8217;installer chez l&#8217;adversaire sans r\u00e9elle r\u00e9ussite et, si chacune aura une situation int\u00e9ressante dans les vingt premi\u00e8res minutes, aucune d&#8217;entre elles ne donnera lieu \u00e0 un v\u00e9ritable danger pour les deux gardiens.<\/p>\n<p style=\"text-align: justify;\"><strong>Six minutes plus int\u00e9ressantes<\/strong><\/p>\n<p style=\"text-align: justify;\">La premi\u00e8re vraie banderille sera ch\u00eanoise, quand un coup franc d&#8217;H\u00e9lin trouve la t\u00eate d&#8217;Ellegaard qui ne cadre pas, mais marque une l\u00e9g\u00e8re prise en main du jeu des visiteurs qui va vite \u00eatre concr\u00e9tis\u00e9e.\u00a0A la 27\u00e8me minute, Gaio, intenable sur son c\u00f4t\u00e9 gauche, entre dans la surface et provoque la faute de Pacella pour obtenir un penalty. Le capitaine H\u00e9lin prend ses responsabilit\u00e9s et transforme la sentence pour ouvrir la marque.<\/p>\n<div id=\"attachment_15890\" style=\"width: 589px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-15890\" loading=\"lazy\" class=\"wp-image-15890\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/03\/UGS-Chenois1314-1.jpg\" width=\"579\" height=\"446\" srcset=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/03\/UGS-Chenois1314-1.jpg 965w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/03\/UGS-Chenois1314-1-300x231.jpg 300w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/03\/UGS-Chenois1314-1-660x508.jpg 660w\" sizes=\"(max-width: 579px) 100vw, 579px\" \/><p id=\"caption-attachment-15890\" class=\"wp-caption-text\">Gaio crochet\u00e9 par Pacella<\/p><\/div>\n<p style=\"text-align: justify;\">UGS va tr\u00e8s vite r\u00e9agir \u00e0 cette ouverture du score, mais malheureusement pour les Violets, la belle frappe d&#8217;Errasti se heurte \u00e0 la transversale de Pietrini.<\/p>\n<p style=\"text-align: justify;\">Plus rien ne sera \u00e0 noter dans cette premi\u00e8re mi-temps entre UGS qui peine a installer son jeu et amener le danger dans la d\u00e9fense adverse et Ch\u00eanois qui g\u00e8re son avantage jusqu&#8217;\u00e0 la pause.<\/p>\n<p style=\"text-align: justify;\">La seconde p\u00e9riode commence avec un remplacement du c\u00f4t\u00e9 des Violets avec l&#8217;entr\u00e9e en jeu de Yameogo pour Carnazzi, tr\u00e8s rapidement suivi de la sortie de Dupont pour l&#8217;entr\u00e9e en jeu de Fofana. Ce double changement ug\u00e9iste va avoir pour effet de permettre un positionnement plus haut dans le terrain, mais sans que cela n&#8217;ait de r\u00e9elle cons\u00e9quence en termes de chances de but, seule la belle reprise d&#8217;Errasti sur un superbe centre de Jimenez est \u00e0 noter (50&#8242;).<\/p>\n<p style=\"text-align: justify;\"><strong>UGS peine \u00e0 r\u00e9agir, Ch\u00eanois recule<\/strong><\/p>\n<p style=\"text-align: justify;\">La derni\u00e8re demi heure se d\u00e9roulera ainsi principalement dans le camp ch\u00eanois mais sans que Petrini ne soit inqui\u00e9t\u00e9. Une situation frustrante pour les locaux qui vont, comme difficult\u00e9 suppl\u00e9mentaire, se voir r\u00e9duits \u00e0 10, puis \u00e0 9, suite aux expulsions de Martinez (70&#8242;) et Araujo (92&#8242;), tout deux prenant leur deuxi\u00e8me avertissement pour r\u00e9clamations envers le corps arbitral. Et c&#8217;est sur un dernier essai non cadr\u00e9 de Rashani dans les arr\u00eats de jeu que se termine ce derby.<\/p>\n<p style=\"text-align: justify;\">C&#8217;est donc une victoire des visiteurs qui vient sanctionner ce derby, une victoire un peu plus sp\u00e9ciale pour son entra\u00eeneur, David Joye, qui a longtemps offici\u00e9 \u00e0 la t\u00eate de ses h\u00f4tes du jour. Mais ce sont surtout trois points capitaux pour une \u00e9quipe de Ch\u00eanois qui repasse du bon c\u00f4t\u00e9 de la barre gr\u00e2ce \u00e0 ses quatre unit\u00e9s en deux sorties 2014, comme nous le confirme le principal concern\u00e9 : <em>&#8220;Ce sont trois points importants au terme d&#8217;un match qui, s&#8217;il n&#8217;a pas atteint des sommets de qualit\u00e9, nous permet de passer au dessus de la barre. Mon \u00e9quipe a su \u00eatre bien organis\u00e9e et on a conc\u00e9d\u00e9 tr\u00e8s peu d&#8217;occasions \u00e0 UGS. A nous de continuer sur cette lanc\u00e9e, avec cette \u00e9quipe qui se construit semaine apr\u00e8s semaine et qui est saine, sans toutefois s&#8217;enflammer!&#8221;<\/em><\/p>\n<div id=\"attachment_15891\" style=\"width: 589px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/oneclick-photo.ch\/category\/40934.html\" target=\"_blank\"><img aria-describedby=\"caption-attachment-15891\" loading=\"lazy\" class=\" wp-image-15891\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/03\/UGS-Chenois1314-2.jpg\" alt=\"UGS vs CS Ch\u00eanois 0-1\" width=\"579\" height=\"331\" srcset=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/03\/UGS-Chenois1314-2.jpg 965w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/03\/UGS-Chenois1314-2-300x171.jpg 300w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/03\/UGS-Chenois1314-2-768x439.jpg 768w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/03\/UGS-Chenois1314-2-660x376.jpg 660w\" sizes=\"(max-width: 579px) 100vw, 579px\" \/><\/a><p id=\"caption-attachment-15891\" class=\"wp-caption-text\">L&#8217;unique buteur, H\u00e9lin, au milieu de trois Ug\u00e9istes<\/p><\/div>\n<p style=\"text-align: justify;\">Du c\u00f4t\u00e9 d&#8217;UGS, cette deuxi\u00e8me d\u00e9faite cons\u00e9cutive est surtout le fruit d&#8217;une difficult\u00e9 \u00e0 r\u00e9agir apr\u00e8s l&#8217;ouverture du score adverse. Avant le but, on se disait que le match pouvait basculer sur un petit rien tant les deux formations semblaient proches,. Malheureusement pour les hommes d&#8217;Herv\u00e9 Musqu\u00e8re, les choses n&#8217;ont pas tourn\u00e9 en leur faveur.<\/p>\n<p>&nbsp;<\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><strong>FC UGS &#8211; CS CH\u00caNOIS \u00a00-1 (0-1)<\/strong><br \/>\nStade de Frontenex<\/p>\n<p style=\"text-align: justify;\"><strong>But<\/strong> : 27&#8242; H\u00e9lin (P) 0-1<\/p>\n<p style=\"text-align: justify;\"><strong>UGS<\/strong> (4-2-3-1) : Revilloud &#8211; Rashani, Pacella, Cavaglia \u00a9, Jimenez &#8211; Carnazzi (46&#8242; Yameogo), Vanzo &#8211; Araujo, Martinez, Dupont (52&#8242; Fofana) &#8211; Errasti.<br \/>\nEntra\u00eeneur : Herv\u00e9 Musqu\u00e8re<\/p>\n<p style=\"text-align: justify;\"><strong>Ch\u00eanois<\/strong> (4-2-3-1) : Pietrini &#8211; Andr\u00e9, Nguendjio, Martello, Ouchard &#8211; Remy, Ughetto &#8211; Ellegaard (61&#8242; Gille), H\u00e9lin \u00a9, Gaio (85&#8242; Herman) &#8211; Tanga.<br \/>\nEntra\u00eeneur : David Joye<\/p>\n<p style=\"text-align: justify;\"><strong>Avertissements<\/strong> : Errasti, Yameogo, Martinez et Araujo (UGS) ; Gille (Ch\u00eanois)<br \/>\n<strong>Expulsions<\/strong> : 70&#8242; Martinez et 92&#8242; Araujo (UGS)<\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><em>Photos : <\/em><a href=\"http:\/\/oneclick-photo.ch\/\" target=\"_blank\"><em><u><span style=\"color: #0066cc;\">OneClick-Photo<\/span><\/u><\/em><\/a><\/p>\n<p><script src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\" async=\"\"><\/script><!-- superieur --> <ins class=\"adsbygoogle\" style=\"display: inline-block; width: 728px; height: 90px;\" data-ad-slot=\"1875735477\" data-ad-client=\"ca-pub-1317159203547503\"><\/ins><script>\/\/ <![CDATA[\n(adsbygoogle = window.adsbygoogle || []).push({});\n\/\/ ]]><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Victoire importante du CS Ch\u00eanois de David Joye pour son retour \u00e0 Frontenex, dans ce derby qui n&#8217;aura pas donn\u00e9 au public beaucoup d&#8217;occasions de fr\u00e9mir\u00a0tant les situations chaudes auront \u00e9t\u00e9 rares de part et d&#8217;autre.<\/p>\n","protected":false},"author":34,"featured_media":15848,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[26],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.proxifoot.ch\/geneve\/2014\/03\/victoire-pour-chenois-et-joye-contre-ugs\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Victoire pour Ch\u00eanois et Joye contre UGS - Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"og:description\" content=\"Victoire importante du CS Ch\u00eanois de David Joye pour son retour \u00e0 Frontenex, dans ce derby qui n&#8217;aura pas donn\u00e9 au public beaucoup d&#8217;occasions de fr\u00e9mir\u00a0tant les situations chaudes auront \u00e9t\u00e9 rares de part et d&#8217;autre.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.proxifoot.ch\/geneve\/2014\/03\/victoire-pour-chenois-et-joye-contre-ugs\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2014-03-17T20:06:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-08-24T12:38:37+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/03\/UGS-Chenois1314.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1378\" \/>\n\t<meta property=\"og:image:height\" content=\"772\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2014\/03\/victoire-pour-chenois-et-joye-contre-ugs\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/03\/UGS-Chenois1314.jpg\",\"width\":1378,\"height\":772},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2014\/03\/victoire-pour-chenois-et-joye-contre-ugs\/#webpage\",\"url\":\"http:\/\/www.proxifoot.ch\/geneve\/2014\/03\/victoire-pour-chenois-et-joye-contre-ugs\/\",\"name\":\"Victoire pour Ch\\u00eanois et Joye contre UGS - Proxifoot, le m\\u00e9dia du football genevois\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2014\/03\/victoire-pour-chenois-et-joye-contre-ugs\/#primaryimage\"},\"datePublished\":\"2014-03-17T20:06:56+00:00\",\"dateModified\":\"2016-08-24T12:38:37+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/85c9e873354a0bdc93a855141f775b3d\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.proxifoot.ch\/geneve\/2014\/03\/victoire-pour-chenois-et-joye-contre-ugs\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/85c9e873354a0bdc93a855141f775b3d\",\"name\":\"Greg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/15818"}],"collection":[{"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=15818"}],"version-history":[{"count":0,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/15818\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/15848"}],"wp:attachment":[{"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=15818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=15818"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=15818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}