﻿{"id":25672,"date":"2009-05-25T15:03:20","date_gmt":"2009-05-25T13:03:20","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=25672"},"modified":"2016-06-30T15:34:43","modified_gmt":"2016-06-30T13:34:43","slug":"choulex-nabdique-pas","status":"publish","type":"post","link":"http:\/\/www.proxifoot.ch\/geneve\/2009\/05\/choulex-nabdique-pas\/","title":{"rendered":"Choulex n&#8217;abdique pas"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Les prot\u00e9g\u00e9s de Jos\u00e9 Brea cueillent un succ\u00e8s capital face \u00e0 un adversaire direct dans la course au maintien, Athl\u00e9tique Regina. Cette victoire leur permet de se retrouver pour la premi\u00e8re fois au-dessus de la barre\u2026<\/strong><!--more--><\/p>\n<p align=\"justify\">Match \u00e0 enjeu direct en cette belle matin\u00e9e printani\u00e8re o\u00f9 la chaleur sera un \u00e9l\u00e9ment important du match, tout comme la qualit\u00e9 de la pelouse qui n\u2019avantagera pas le beau jeu.<\/p>\n<p align=\"justify\"><strong>Jeu long<\/strong><\/p>\n<p align=\"justify\">D\u00e8s le d\u00e9but de la rencontre, on peut s\u2019apercevoir que les deux \u00e9quipes ne prennent aucun risque et multiplient les longs ballons en avant, souvent sans r\u00e9ussite et parfois avec l\u2019unique intention de se retrouver vite dans le camp adverse. Il est vrai que le terrain de Varemb\u00e9 ne se pr\u00eate pas \u00e0 un jeu \u00e9labor\u00e9 depuis derri\u00e8re tant il serait facile de se faire surprendre par un mauvais rebond.<\/p>\n<p align=\"justify\">Choulex est un peu plus dangereux que son adversaire du jour, la pr\u00e9cision des balles longues de Barea permet aux visiteurs de se montrer mena\u00e7ants \u00e0 deux reprises en ce d\u00e9but de match, mais sans pour autant tromper la vigilance du portier Frutiger.<\/p>\n<p align=\"justify\"><img loading=\"lazy\" src=\"http:\/\/www.proxifoot.ch\/home\/images\/Photos\/vernier_choulex.jpg\" alt=\" \" width=\"327\" height=\"448\" \/><\/p>\n<p align=\"justify\">Cette premi\u00e8re p\u00e9riode, sans r\u00e9elles opportunit\u00e9s, refl\u00e8te l\u2019enjeu de cette partie. En effet, gare au perdant qui se verrait dans une situation d\u00e9savantageuse en vue du maintien \u00e0 seulement une journ\u00e9e de la fin du championnat. On sent les acteurs quelque peu crisp\u00e9s par l\u2019enjeu, peu de risques sont \u00e0 signaler et l\u2019organisation d\u00e9fensive des deux \u00e9quipes ne laisse entrevoir que tr\u00e8s peu de failles que l\u2019adversaire peine \u00e0 exploiter.<\/p>\n<p align=\"justify\">C\u2019est \u00e0 cinq minutes de la mi-temps que les d\u00e9bats vont s\u2019animer, tout d\u2019abord avec une t\u00eate du capitaine Lenga qui avait le poids d\u2019un but (40\u2019). Ensuite par le choc entre Mioch et Nogues qui verra ce dernier \u00eatre \u00e9vacu\u00e9 par la civi\u00e8re suite \u00e0 une mauvaise r\u00e9ception d\u2019un duel a\u00e9rien. Il faudra quelques minutes \u00e0 M. Belarbi pour calmer les esprits et finalement renvoyer tout le monde aux vestiaires.<\/p>\n<p align=\"justify\"><strong>L\u2019entr\u00e9e en jeu d\u2019Albanese<\/strong><\/p>\n<p align=\"justify\">D\u00e8s le d\u00e9but de la seconde p\u00e9riode, on sent Choulex un peu plus entreprenant. L\u2019entr\u00e9e en jeu d\u2019Albanese va permettre aux choul\u00e9siens de poser un peu plus le jeu et de gentiment s\u2019installer dans le camp adverse. Le duo de r\u00e9cup\u00e9rateurs Alonso-Camara joue dix m\u00e8tres plus haut et la qualit\u00e9 technique de Khir et Albanese laisse entrevoir de belles opportunit\u00e9s, surtout que la chaleur commence \u00e0 se faire sentir.<\/p>\n<p align=\"justify\">Le travail de labeur d\u2019Errasti fait souffrir la d\u00e9fense locale, ce joueur r\u00e9cemment transf\u00e9r\u00e9 d\u2019UGS, p\u00e8se sur cette d\u00e9fense et fait preuve d\u2019une g\u00e9n\u00e9rosit\u00e9 exemplaire dans l\u2019effort.<\/p>\n<p align=\"justify\">Les hommes de Bruno Aguilar peinent \u00e0 se montrer dangereux devant la cage du portier Basile, \u00e0 l\u2019exception de cette occasion de Gil qui rate son tir \u00e0 seulement quelques m\u00e8tres du but (57\u2019). La vitesse de Martinez n\u2019est pas exploit\u00e9e et l\u2019arri\u00e8re garde des visiteurs ne laisse quasiment aucun espace, le placement de la paire Barea El Edrissi \u00e9tant remarquable.<\/p>\n<p align=\"justify\"><strong>Le but d\u2019Errasti<\/strong><\/p>\n<p align=\"justify\">C\u2019est \u00e0 la 63\u00e8me minute que le match va basculer. Errasti profite d\u2019une erreur d\u00e9fensive pour aller ajuster Frutiger d\u2019un lob parfaitement dos\u00e9, c\u2019est l\u2019ouverture du score pour les visiteurs (0-1).<\/p>\n<p align=\"justify\">Malgr\u00e9 les encouragements du banc et du portier Frutiger, les pensionnaires de Varemb\u00e9 semblent sonn\u00e9s par ce but et on se demandent comment ils vont trouver l\u2019\u00e9nergie pour revenir dans le match. Deux changements de l\u2019entra\u00eeneur local et un repositionnement tactique (trois d\u00e9fenseurs) redonnent un peu d\u2019allant offensif aux locaux qui vont se montrer dangereux sur un centre tir de Martinez (82\u2019).<\/p>\n<p align=\"justify\">Mais cela ne suffira pas, Choulex aurait pu doubler la mise en contre mais on en restera l\u00e0 dans ce match de la peur. Les visiteurs empochent trois nouveaux points fort pr\u00e9cieux dans la course au maintien et continuent sur leur bonne dynamique du deuxi\u00e8me tour, alors qu\u2019Athl\u00e9tique Regina n\u2019y arrive pas et se trouve en situation p\u00e9rilleuse.<\/p>\n<p align=\"justify\">Choulex recevra Ch\u00eanois II dimanche prochain avec l\u2019obligation de faire \u00e0 nouveau des points, mais avec cette fois-ci son sort entre les mains. En effet, les Choul\u00e9siens aborderont ce match avec confiance et avec la certitude d\u2019\u00e9voluer la saison prochaine en deuxi\u00e8me ligue, s\u2019ils remportent les trois points de la victoire.<\/p>\n<p align=\"justify\">Regina recevra la plus mauvaise \u00e9quipe du deuxi\u00e8me tour, Veyrier, dans un match capital en vue du maintien. Ils devront imp\u00e9rativement obtenir une victoire en esp\u00e9rant que Choulex et Vernier ne gagnent pas.<\/p>\n<p>&nbsp;<\/p>\n<p align=\"justify\"><strong>ATHLETIQUE-REGINA FC \u2013 FC CHOULEX \u00a00-1 (0-0)<br \/>\n<\/strong>Stade de Varemb\u00e9, environ 100 spectateurs<\/p>\n<p align=\"justify\"><strong>Arbitre<\/strong> : M.Belarbi<\/p>\n<p align=\"justify\"><strong>But<\/strong>: 63\u2019 Errasti 0-1<\/p>\n<p style=\"text-align: justify;\" align=\"justify\"><strong>R\u00e9gina<\/strong> : Frutiger ; Maouche, Matri, Fouda, Cattin ; Nugues (41\u2019 M\u2019Bia), Lenga \u00a9,\u00a0Sahiti (68\u2019 Shabani), Cohen (77\u2019 Gomes) ; Gil, Martinez.<br \/>\nEntra\u00eeneur : Bruno Aguilar<\/p>\n<p style=\"text-align: justify;\" align=\"justify\"><strong>Choulex<\/strong> : Basile \u00a9; Camara, Barea, El Edrissi, Mioch (74\u2019 Jacquet) ; Alonso, Camara, Paturaux (52\u2019 Albanese), Rodriguez (64\u2019 Lachi) ; Khir ; Errasti.<br \/>\nEntra\u00eeneur : Jos\u00e9 Brea<\/p>\n<p><script src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\" async=\"\"><\/script><!-- superieur --> <ins class=\"adsbygoogle\" style=\"display: inline-block; width: 728px; height: 90px;\" data-ad-slot=\"1875735477\" data-ad-client=\"ca-pub-1317159203547503\"><\/ins><script>\/\/ <![CDATA[\n(adsbygoogle = window.adsbygoogle || []).push({});\n\/\/ ]]><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les prot\u00e9g\u00e9s de Jos\u00e9 Brea cueillent un succ\u00e8s capital face \u00e0 un adversaire direct dans la course au maintien, Athl\u00e9tique Regina. Cette victoire leur permet de se retrouver pour la premi\u00e8re fois au-dessus de la barre\u2026<\/p>\n","protected":false},"author":36,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[5],"tags":[157,88],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.proxifoot.ch\/geneve\/2009\/05\/choulex-nabdique-pas\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Choulex n&#039;abdique pas - Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"og:description\" content=\"Les prot\u00e9g\u00e9s de Jos\u00e9 Brea cueillent un succ\u00e8s capital face \u00e0 un adversaire direct dans la course au maintien, Athl\u00e9tique Regina. Cette victoire leur permet de se retrouver pour la premi\u00e8re fois au-dessus de la barre\u2026\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.proxifoot.ch\/geneve\/2009\/05\/choulex-nabdique-pas\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2009-05-25T13:03:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-06-30T13:34:43+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.proxifoot.ch\/home\/images\/Photos\/vernier_choulex.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2009\/05\/choulex-nabdique-pas\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"http:\/\/www.proxifoot.ch\/home\/images\/Photos\/vernier_choulex.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2009\/05\/choulex-nabdique-pas\/#webpage\",\"url\":\"http:\/\/www.proxifoot.ch\/geneve\/2009\/05\/choulex-nabdique-pas\/\",\"name\":\"Choulex n'abdique pas - Proxifoot, le m\\u00e9dia du football genevois\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2009\/05\/choulex-nabdique-pas\/#primaryimage\"},\"datePublished\":\"2009-05-25T13:03:20+00:00\",\"dateModified\":\"2016-06-30T13:34:43+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/eb4f1c13980294151e2ebeeb63aca7fb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.proxifoot.ch\/geneve\/2009\/05\/choulex-nabdique-pas\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/eb4f1c13980294151e2ebeeb63aca7fb\",\"name\":\"Daniel\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/25672"}],"collection":[{"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=25672"}],"version-history":[{"count":0,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/25672\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=25672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=25672"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=25672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}