﻿{"id":27557,"date":"2009-08-31T09:37:46","date_gmt":"2009-08-31T07:37:46","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=27557"},"modified":"2016-10-20T16:49:52","modified_gmt":"2016-10-20T14:49:52","slug":"regina-la-echappe-belle","status":"publish","type":"post","link":"http:\/\/www.proxifoot.ch\/geneve\/2009\/08\/regina-la-echappe-belle\/","title":{"rendered":"Regina l&#8217;a \u00e9chapp\u00e9 belle"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Regina remporte les trois points face \u00e0 Rapid Jonction dans un match engag\u00e9. Apr\u00e8s avoir \u00e9t\u00e9 men\u00e9s 3 \u00e0 0, les Bosniaques ont r\u00e9agi avec d\u00e9termination, mais pas assez pour renverser la tendance.<\/strong><!--more--><\/p>\n<p align=\"justify\">C\u2019est un dimanche matin ensoleill\u00e9 \u00e0 Varemb\u00e9 et les conditions sont id\u00e9ales pour d\u00e9marrer la saison. Le FC Athl\u00e9tique-Regina (fraichement rel\u00e9gu\u00e9 de 2\u00e8me ligue) a pour but de ne pas faire long feu en 3e ligue et Bruno Aguilar est bien plac\u00e9 aujourd\u2019hui pour y contribuer vu sa titularisation. Le FC Rapid Jonction Bosna, dirig\u00e9 par Nihad Omeragic, vise le maintien. Les objectifs sont diff\u00e9rents mais l\u2019envie de bien d\u00e9buter ce championnat reste la m\u00eame dans les deux camps.<\/p>\n<p align=\"justify\"><strong>Pas de round d\u2019observation<\/strong><\/p>\n<p align=\"justify\">En effet, d\u00e8s la deuxi\u00e8me minute de jeu, sur un centre-tir de Nugues repouss\u00e9 par Adnan Letic, M.Ciss\u00e9 marque d\u2019un joli plat du pied. La nouvelle recrue venue de Perly n\u2019a pas attendu longtemps pour prouver son talent.<\/p>\n<p align=\"justify\">Rapid Jonction ne se fait pas prier et cinq minutes plus tard, Maric place une frappe qui semble imparable mais le nouveau rempla\u00e7ant de Frutiger, Cassiano, est \u00e0 la parade.<\/p>\n<p align=\"justify\">La lourde d\u00e9fense du Rapid Jonction prend l\u2019eau. Elle a devant elle Nugues et M. Ciss\u00e9 qui combinent parfaitement et cr\u00e9ent le danger constamment.<\/p>\n<p align=\"justify\"><strong>Regina prend confiance<\/strong><\/p>\n<p align=\"justify\">Apr\u00e8s vingt minutes de jeu, Regina profite de la lenteur des axiaux bosniaques et \u00e0 la suite d\u2019une belle action collective, Nasri s\u2019\u00e9croule dans la surface. P\u00e9nalty! Rahali rate le 2\u00e00 face \u00e0 Adnan Letic qui se d\u00e9tend somptueusement.<\/p>\n<div><img loading=\"lazy\" src=\"http:\/\/www.proxifoot.ch\/home\/images\/regina\/dsc_0438.jpg\" alt=\" \" width=\"640\" height=\"428\" \/><\/div>\n<p style=\"text-align: justify;\" align=\"justify\">Regina poursuit ses assauts et Nugues se lance dans une course solitaire ou il enrhume cinq joueurs adverses pour ensuite servir parfaitement M. Ciss\u00e9 qui n\u2019a plus qu\u2019\u00e0 pousser le ballon au fond des filets.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\">Le Bosniaques subissent le jeu et font beaucoup de fautes, alors que les hommes de Aguilar joue au ballon et essaie de le faire tourner le plus possible en jouant beaucoup au sol.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\">Ils n\u2019ont pas beaucoup tard\u00e9 \u00e0 trouver la faille. Apr\u00e8s une demie-heure de jeu, une nouvelle action collective et M. Ciss\u00e9 trouve Nugues qui marque le 3 \u00e0 0 dans un but vide. Le duo d\u2019attaque de Varemb\u00e9, \u00e0 l\u2019origine des trois buts de Regina, semble plus que prometteur.<\/p>\n<div><img loading=\"lazy\" src=\"http:\/\/www.proxifoot.ch\/home\/images\/regina\/dsc_0451.jpg\" alt=\" \" width=\"640\" height=\"426\" \/><\/div>\n<p align=\"justify\"><strong>Rapid Jonction, r\u00e9action<\/strong><\/p>\n<p align=\"justify\">Nihad Omeragic op\u00e8re son premier changement peu apr\u00e8s la demie-heure de match pour renforcer son milieu de terrain et redynamiser la d\u00e9fense trop statique. Ce qui s\u2019av\u00e8re b\u00e9n\u00e9fique vu qu\u2019avant la fin de la premi\u00e8re mi-temps, Maric adresse un somptueux centre \u00e0 Modronja qui marque le 3 \u00e0 1 d\u2019une splendide vol\u00e9e. Rapid Jonction y croit encore! C\u2019est donc sur ce score que les deux \u00e9quipes se s\u00e9parent \u00e0 la mi-temps.<\/p>\n<p align=\"justify\"><strong>Regina suffisant, Rapid Jonction d\u00e9termin\u00e9<\/strong><\/p>\n<p align=\"justify\">Au retour des vestiaires,\u00a0 les pensionnaires du stade de Varemb\u00e9 continuent sur leur bonne lanc\u00e9e en multipliant les occasions de tuer le match. Mais c est sans compter sur les orgueilleux bosniaques qui gagnent de plus en plus de duels. La physionomie du match change totalement et devient une v\u00e9ritable bataille et Regina semble beaucoup plus timide qu\u2019en premi\u00e8re mi-temps. Ce qui profite \u00e0 Nedzad Omeragic qui, \u00e0 la 66e , perce la d\u00e9fense avec puissance et adresse une frappe imparable.<\/p>\n<div><img loading=\"lazy\" src=\"http:\/\/www.proxifoot.ch\/home\/images\/regina\/dsc_0464.jpg\" alt=\" \" width=\"337\" height=\"484\" \/><\/div>\n<p align=\"justify\">3 \u00e0 2 et Regina devient beaucoup plus f\u00e9brile. Rapid Jonction semble avoir les ressources pour \u00e9galiser mais c\u2019est sans compter sur un tr\u00e8s bon Cassiano qui multiplie les arr\u00eats de grande classe.<\/p>\n<p align=\"justify\">Les \u00e9quipes se quittent donc sur le score de 3 \u00e0 2.<\/p>\n<p align=\"justify\">Au terme de la rencontre, Bruno Aguilar livrait ses impressions: \u00ab La premi\u00e8re demie heure fut bien entam\u00e9e et nous avons bien jou\u00e9 collectivement. Le but encaiss\u00e9 avant la mi-temps n\u2019est pas survenu par hasard, car nous avions d\u00e9j\u00e0 commenc\u00e9 \u00e0 rel\u00e2cher. La deuxi\u00e8me p\u00e9riode fut diff\u00e9rente dans l\u2019esprit car chacun veut le ballon et jouer pour son compte. Le collectif s\u2019est perdu et vient le second but. Aujourd\u2019hui, j\u2019ai jou\u00e9 car il nous manque une dizaine de joueurs qui ne sont pas encore qualifi\u00e9s, notamment Yunes et Farid de Racing. Je suis content d\u2019avoir remport\u00e9 les trois points mais j\u2019aimerais quand m\u00eame que les jeunes jouent avec plus d\u2019envie! \u00bb<\/p>\n<p>&nbsp;<\/p>\n<blockquote>\n<p align=\"justify\"><strong>FC ATHL\u00c9TIQUE-REGINA &#8211; FC RAPID JONCTION BOSNA\u00a0 3-2 (3-1)<br \/>\n<\/strong>Stade\u00a0de Varemb\u00e9, 80 spectateurs.<\/p>\n<p align=\"justify\"><strong>Buts<\/strong>:\u00a0 2&#8242; Ciss\u00e9 1-0,\u00a024&#8242;\u00a0Ciss\u00e9 2-0, 36&#8242; Nugues 3-0, 45&#8242; Modronja 3-1, 66&#8242; Nedzad Omeragic 3-2<\/p>\n<p align=\"justify\"><strong>Regina<\/strong> (4-4-2): Cassiano; Saad\u00e9, Aguilar, Rahali, Maouche; Nasri (52&#8217;e Shabani), Frade (52&#8242; Gil), Sarbach (C), Boillat; M.Ciss\u00e9, Nugues (68&#8242; Kerkach).<br \/>\nEntra\u00eeneur : Bruno Aguilar<\/p>\n<p style=\"text-align: justify;\" align=\"justify\"><strong>Bosna<\/strong> (4-4-2): Adnan Letic; Sejmenovic, Nedzad Omeragic, Kospo, Almin Grdan; Genvra (57&#8242; Maleinovic), Ajdin Letic, Todorovsky (33&#8242; Eldin Grdan), Modronja; Mujezinovic (C), Maric (77&#8242; Delic).<br \/>\nEntra\u00eeneur\u00a0: Nihad Omeragic<\/p>\n<p style=\"text-align: justify;\" align=\"justify\"><strong>Avertissements<\/strong>: Sejmenovic, Rahali.<\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\" align=\"justify\"><em>Pour Proxifoot, clopes et angel<\/em><\/p>\n<p><script src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\" async=\"\"><\/script><!-- superieur --> <ins class=\"adsbygoogle\" style=\"display: inline-block; width: 728px; height: 90px;\" data-ad-slot=\"1875735477\" data-ad-client=\"ca-pub-1317159203547503\"><\/ins><script>\/\/ <![CDATA[ (adsbygoogle = window.adsbygoogle || []).push({}); \/\/ ]]><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Regina remporte les trois points face \u00e0 Rapid Jonction dans un match engag\u00e9. Apr\u00e8s avoir \u00e9t\u00e9 men\u00e9s 3 \u00e0 0, les Bosniaques ont r\u00e9agi avec d\u00e9termination, mais pas assez pour renverser la tendance.<\/p>\n","protected":false},"author":1,"featured_media":27558,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[6],"tags":[157,101],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.proxifoot.ch\/geneve\/2009\/08\/regina-la-echappe-belle\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Regina l&#039;a \u00e9chapp\u00e9 belle - Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"og:description\" content=\"Regina remporte les trois points face \u00e0 Rapid Jonction dans un match engag\u00e9. Apr\u00e8s avoir \u00e9t\u00e9 men\u00e9s 3 \u00e0 0, les Bosniaques ont r\u00e9agi avec d\u00e9termination, mais pas assez pour renverser la tendance.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.proxifoot.ch\/geneve\/2009\/08\/regina-la-echappe-belle\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2009-08-31T07:37:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-10-20T14:49:52+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/07\/Regina-Bosna-0910.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"414\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2009\/08\/regina-la-echappe-belle\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/07\/Regina-Bosna-0910.jpg\",\"width\":640,\"height\":414},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2009\/08\/regina-la-echappe-belle\/#webpage\",\"url\":\"http:\/\/www.proxifoot.ch\/geneve\/2009\/08\/regina-la-echappe-belle\/\",\"name\":\"Regina l'a \\u00e9chapp\\u00e9 belle - Proxifoot, le m\\u00e9dia du football genevois\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2009\/08\/regina-la-echappe-belle\/#primaryimage\"},\"datePublished\":\"2009-08-31T07:37:46+00:00\",\"dateModified\":\"2016-10-20T14:49:52+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.proxifoot.ch\/geneve\/2009\/08\/regina-la-echappe-belle\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\",\"name\":\"admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/27557"}],"collection":[{"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=27557"}],"version-history":[{"count":0,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/27557\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/27558"}],"wp:attachment":[{"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=27557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=27557"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=27557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}