﻿{"id":3323,"date":"2012-05-02T08:04:09","date_gmt":"2012-05-02T07:04:09","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=3323"},"modified":"2016-10-25T14:22:28","modified_gmt":"2016-10-25T12:22:28","slug":"vernier-aux-portes-de-la-2eme-ligue-inter","status":"publish","type":"post","link":"http:\/\/www.proxifoot.ch\/geneve\/2012\/05\/vernier-aux-portes-de-la-2eme-ligue-inter\/","title":{"rendered":"Vernier aux portes de la 2\u00e8me ligue inter"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Men\u00e9s 1-0 \u00e0 la mi-temps du match au sommet, les Verniolans finissent par l\u2019emporter et mettent d\u00e9j\u00e0 fin au suspense en championnat. Ils pourraient \u00eatre sacr\u00e9s champions dimanche prochain sur le terrain de Kosova.<!--more--><\/strong><\/p>\n<p style=\"text-align: justify;\">C\u2019est le genre de match qui d\u00e9cide une saison. Un match o\u00f9 le poursuivant se rend chez le leader pour lui rappeler qu\u2019il veut prendre sa place et lui faire vivre une fin de saison difficile. Cela a failli \u00eatre le cas, en tout cas durant les 45 premi\u00e8res minutes, jusqu\u2019\u00e0 ce que Vernier se rel\u00e8ve et dise\u00a0: \u00ab\u00a0Cette ann\u00e9e, c\u2019est moi le patron\u00a0\u00bb.<\/p>\n<p><strong>Carouge\u00a0: une mi-temps quasi-parfaite, puis\u2026<\/strong><\/p>\n<p style=\"text-align: justify;\">La tension qui r\u00e8gne dans ce type de rencontre peut se lire sur le visage des joueurs ainsi que lors des contacts tr\u00e8s engag\u00e9s, pas toujours ma\u00eetris\u00e9s. A titre d\u2019exemple, deux grosses fautes dans les toutes premi\u00e8res minutes des Carougeois Howard et Arifi, avertissement inclus pour ce dernier, viennent nous l\u2019illustrer. Le mot d\u2019ordre de l\u2019entra\u00eeneur Samuel Singarella semble \u00eatre assez clair\u00a0: \u00ab\u00a0agressivit\u00e9\u00a0\u00bb.<\/p>\n<p style=\"text-align: justify;\">La seconde garniture carougeoise \u00e9tait venue au Municipal de Vernier dans le but de contrer le potentiel offensif des Verniolans. La mission a \u00e9t\u00e9 remplie durant les 45 premi\u00e8res minutes. Les ailiers Bua et Fellah ne parviennent pas \u00e0 inqui\u00e9ter les lat\u00e9raux carougeois et la charni\u00e8re centrale Boschetti-Rinaldi est bien en place.<\/p>\n<p style=\"text-align: justify;\">L\u2019une des pi\u00e8ces de cette charni\u00e8re justement, Jos\u00e9 Boschetti, va m\u00eame faire trembler les filets adverses\u00a0: suite \u00e0 un corner jou\u00e9 \u00e0 deux, sur un centre-tir du tr\u00e8s technique Roch, le d\u00e9fenseur central pousse le ballon au fond des filets pour l\u2019ouverture du score (27\u2019, 0-1). Un avantage m\u00e9rit\u00e9 pour les Carougeois, plus entreprenants jusque-l\u00e0 et sup\u00e9rieurs au milieu de terrain.<\/p>\n<div id=\"attachment_3327\" style=\"width: 618px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/01.jpg\"><img aria-describedby=\"caption-attachment-3327\" loading=\"lazy\" class=\"size-large wp-image-3327 \" title=\"Vernier Fc vs Fc Etoile Carouge\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/01-1024x362.jpg\" alt=\"\" width=\"608\" height=\"215\" srcset=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/01-1024x362.jpg 1024w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/01-300x106.jpg 300w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/01-660x233.jpg 660w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/01.jpg 1843w\" sizes=\"(max-width: 608px) 100vw, 608px\" \/><\/a><p id=\"caption-attachment-3327\" class=\"wp-caption-text\">Ouverture du score sign\u00e9e Boschetti<\/p><\/div>\n<p style=\"text-align: justify;\">Entre temps, l\u2019ailier Baumgartner, tr\u00e8s actif, nous a donn\u00e9 une frayeur en perdant l\u2019\u00e9quilibre et en restant allong\u00e9 par terre durant de longues secondes. Heureusement, rien de grave n\u2019est \u00e0 signaler mais le Carougeois est remplac\u00e9 par pr\u00e9caution.<\/p>\n<p><strong>Un poison nomm\u00e9 Bua<\/strong><\/p>\n<p style=\"text-align: justify;\">Bien que le leader pousse en fin de mi-temps, notamment avec une t\u00eate \u00e0 bout portant manqu\u00e9e par Camara sur un centre de Bua, l\u2019heure du th\u00e9 arrive au bon moment pour les Carougeois.<\/p>\n<p style=\"text-align: justify;\">\u00ab\u00a0Une premi\u00e8re p\u00e9riode d\u00e9cevante mais compr\u00e9hensible. Nous nous sommes rassur\u00e9s \u00e0 la mi-temps, car nous savions qu\u2019en posant le jeu et augmentant la verticalit\u00e9 et largeur, nous pouvions les mettre en difficult\u00e9 \u00bb, nous avouera Claudio Morelli.<\/p>\n<p style=\"text-align: justify;\">Et il a vu juste. La seconde p\u00e9riode ne ressemble en rien \u00e0 la premi\u00e8re. Plus conqu\u00e9rants, les Verniolans parviennent cette fois-ci \u00e0 se montrer dangereux. Et \u00e0 ce jeu-l\u00e0, il y a \u00e0 Vernier un joueur qui est, comme on dit dans le jargon, \u00ab\u00a0en pleine bourre\u00a0\u00bb\u00a0: Kevin Bua.<\/p>\n<p style=\"text-align: justify;\">L\u2019attaquant des \u00ab\u00a0blancs\u00a0\u00bb, d\u00e9cal\u00e9 sur le c\u00f4t\u00e9 gauche, va nous livrer un spectacle de d\u00e9bordements dont le lat\u00e9ral carougeois Sordillo, pourtant solide en premi\u00e8re p\u00e9riode, va s\u2019en souvenir longtemps\u00a0: centre-tir sauv\u00e9 sur la ligne (48\u2019), centre pour Bebyack qui manque le cadre (53\u2019) et tir trop crois\u00e9 en position excentr\u00e9e (63\u2019). Inexplicablement, aucune des actions ne fera mouche.<\/p>\n<p style=\"text-align: justify;\">A force de pousser, les Verniolans vont parvenir \u00e0 \u00e9galiser au milieu de la seconde p\u00e9riode. Sur un long ballon de Camara, le lat\u00e9ral Hervo, mont\u00e9 aux avant-postes, se d\u00e9barrasse du gardien Giorgi avant d\u2019\u00e9galiser (65&#8242;, 1-1).<\/p>\n<div id=\"attachment_3328\" style=\"width: 563px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/02.jpg\"><img aria-describedby=\"caption-attachment-3328\" loading=\"lazy\" class=\"size-large wp-image-3328 \" title=\"Vernier Fc vs Fc Etoile Carouge\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/02-1024x525.jpg\" alt=\"\" width=\"553\" height=\"284\" srcset=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/02-1024x525.jpg 1024w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/02-300x153.jpg 300w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/02-660x338.jpg 660w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/02.jpg 1134w\" sizes=\"(max-width: 553px) 100vw, 553px\" \/><\/a><p id=\"caption-attachment-3328\" class=\"wp-caption-text\">Le lat\u00e9ral Hervo au moment de l&#8217;\u00e9galisation<\/p><\/div>\n<p style=\"text-align: justify;\">Malgr\u00e9 encore quelques montagnes rat\u00e9es par les attaquants locaux, notamment Bebyack et Stevanovic, Vernier continuera \u00e0 se ruer \u00e0 l&#8217;attaque. Puis enfin, \u00e0 10 minutes du terme, la cerise sur le g\u00e2teau. Omnipr\u00e9sent sur son flanc gauche, le jeune Kevin Bua se d\u00e9barrasse de deux d\u00e9fenseurs adverses avant d\u2019allumer le poteau. Le ballon revient dans les pieds du capitaine Pais \u2013 fr\u00e8re du joueur carougeois \u2013 qui, comme un symbole, se charge d\u2019offrir la victoire et 95% du titre \u00e0 son \u00e9quipe.<\/p>\n<div id=\"attachment_3329\" style=\"width: 563px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/03.jpg\"><img aria-describedby=\"caption-attachment-3329\" loading=\"lazy\" class=\"size-large wp-image-3329 \" title=\"Vernier Fc vs Fc Etoile Carouge\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/03-1024x717.jpg\" alt=\"\" width=\"553\" height=\"387\" srcset=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/03-1024x717.jpg 1024w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/03-300x210.jpg 300w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/03-660x462.jpg 660w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/03.jpg 1053w\" sizes=\"(max-width: 553px) 100vw, 553px\" \/><\/a><p id=\"caption-attachment-3329\" class=\"wp-caption-text\">Le capitaine Pais inscrit le but lib\u00e9rateur<\/p><\/div>\n<p style=\"text-align: justify;\"><strong>Morelli, des risques payants<\/strong><\/p>\n<p style=\"text-align: justify;\">Cette victoire verniolanne est aussi due, entre autres, au culot de l\u2019entra\u00eeneur Claudio Morelli. A 1-1, ce dernier ne se contentait pas du match nul et a fait rentrer son attaquant Cacaj \u00e0 la place de son d\u00e9fenseur Paul, afin de chercher la victoire et litt\u00e9ralement \u00ab\u00a0tuer\u00a0\u00bb le championnat.<\/p>\n<p style=\"text-align: justify;\">Chose qu\u2019il a atteinte avec brio, tant la sup\u00e9riorit\u00e9 de ses prot\u00e9g\u00e9s \u00e9tait \u00e9vidente lors de la seconde p\u00e9riode en particulier, et durant tout le championnat de mani\u00e8re plus globale.<\/p>\n<p style=\"text-align: justify;\">Le mentor du Municipal de Vernier \u00e9tait logiquement \u00ab\u00a0satisfait pour le r\u00e9sultat, ce sont trois points qui pourraient \u00eatre d\u00e9cisifs si nous abordons s\u00e9rieusement le prochain match. On a besoin d\u2019un point pour \u00e9crire une page historique pour notre \u00e9quipe et surtout notre club\u2026 On ne va pas se d\u00e9concentrer pour autant, alors au travail durant toute cette semaine qui s\u2019annonce, je le souhaite pour la famille verniolane, la plus belle de cette saison\u00a0! Pour la \u00e9ni\u00e8me fois je f\u00e9licite tout mon groupe (bless\u00e9s et ceux qui n\u2019ont malheureusement pas \u00e9t\u00e9 align\u00e9s aujourd\u2019hui). On a d\u00e9gag\u00e9 un caract\u00e8re et s\u00e9rieux qui furent \u00e9mouvants.\u00a0\u00bb<\/p>\n<div id=\"attachment_3330\" style=\"width: 563px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/04.jpg\"><img aria-describedby=\"caption-attachment-3330\" loading=\"lazy\" class=\"size-large wp-image-3330\" title=\"Vernier Fc vs Fc Etoile Carouge\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/04-1024x644.jpg\" alt=\"\" width=\"553\" height=\"347\" srcset=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/04-1024x644.jpg 1024w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/04-300x188.jpg 300w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/04-660x415.jpg 660w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/04.jpg 1134w\" sizes=\"(max-width: 553px) 100vw, 553px\" \/><\/a><p id=\"caption-attachment-3330\" class=\"wp-caption-text\">Gr\u00e2ce \u00e0 un contingent bien fourni, le titre n&#8217;\u00e9chappera pas aux Verniolans<\/p><\/div>\n<p style=\"text-align: justify;\">Avec le sacre haut la main en 3<span style=\"font-size: 11px;\">\u00e8me<\/span>\u00a0ligue la saison pass\u00e9e, Claudio Morelli et toute sa troupe sont donc sur le bon chemin pour un second titre d\u2019affil\u00e9e et ainsi rendre hommage \u00e0 leur cher pr\u00e9sident, M. Ozelley, disparu en novembre dernier. Ce sera peut-\u00eatre d\u00e9j\u00e0 le cas dimanche prochain aux alentours de midi au stade de Frontenex.<\/p>\n<p>&nbsp;<\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><strong>FC VERNIER \u2013 ETOILE CAROUGE FC II\u00a0 2-1 (0-1)<br \/>\n<\/strong>Stade municipal de Vernier, environ 150 spectateurs.<\/p>\n<p style=\"text-align: justify;\"><strong>Arbitre<\/strong> : M. D\u00e9truche<\/p>\n<p style=\"text-align: justify;\"><strong>Buts\u00a0:<\/strong> 27\u2019 Boschetti 0-1, 65\u2019 Hervo 1-1, 80\u2019 Pais 2-1<\/p>\n<p style=\"text-align: justify;\"><strong>Vernier<\/strong> (4-2-3-1)\u00a0: Marcon \u2013 Demba, Camara, Paul (74\u2019 Cacaj), Hervo \u2013 Zeneli, Pais \u2013 Fellah (44\u2019 Bebyack), Stevanovic (70\u2019 Tranchet), Bua \u2013 Delattre.<br \/>\nEntra\u00eeneur\u00a0: Claudio Morelli<\/p>\n<p style=\"text-align: justify;\"><strong>Carouge II<\/strong> (4-2-3-1)\u00a0: Giorgi \u2013 Sordillo, Boschetti, Rinaldi, Mikael Mendes \u2013 Arifi (46\u2019 Guijarrot), Roch \u2013 Baumgartner (34\u2019 Mike Mendes), Pais, Howard (70\u2019 Mutombo) \u2013 Vitkieviez.<br \/>\nEntra\u00eeneur\u00a0: Samuel Singarella<\/p>\n<p style=\"text-align: justify;\"><strong>Avertissements<\/strong>\u00a0: Zeneli et Bua (Vernier)\u00a0; Arifi (Carouge II)<\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<p><em>Photos\u00a0: <a href=\"http:\/\/www.oneclick-photo.ch\/category\/vernier-vs-carouge.html\" target=\"_blank\"><u><span style=\"color: #0066cc;\">OneClick-Photo<\/span><\/u><\/a><\/em><\/p>\n<p>&nbsp;<\/p>\n<p><u><\/u><br \/>\n<script src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\" async=\"\"><\/script><!-- superieur --> <ins class=\"adsbygoogle\" style=\"display: inline-block; width: 728px; height: 90px;\" data-ad-slot=\"1875735477\" data-ad-client=\"ca-pub-1317159203547503\"><\/ins><script>\/\/ <![CDATA[ (adsbygoogle = window.adsbygoogle || []).push({}); \/\/ ]]><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Men\u00e9s 1-0 \u00e0 la mi-temps du match au sommet, les Verniolans finissent par l\u2019emporter et mettent d\u00e9j\u00e0 fin au suspense en championnat. Ils pourraient \u00eatre sacr\u00e9s champions dimanche prochain sur le terrain de Kosova.<\/p>\n","protected":false},"author":30,"featured_media":3325,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[5],"tags":[59,81],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.proxifoot.ch\/geneve\/2012\/05\/vernier-aux-portes-de-la-2eme-ligue-inter\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vernier aux portes de la 2\u00e8me ligue inter - Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"og:description\" content=\"Men\u00e9s 1-0 \u00e0 la mi-temps du match au sommet, les Verniolans finissent par l\u2019emporter et mettent d\u00e9j\u00e0 fin au suspense en championnat. Ils pourraient \u00eatre sacr\u00e9s champions dimanche prochain sur le terrain de Kosova.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.proxifoot.ch\/geneve\/2012\/05\/vernier-aux-portes-de-la-2eme-ligue-inter\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2012-05-02T07:04:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-10-25T12:22:28+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/Vernier-Carouge2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1134\" \/>\n\t<meta property=\"og:image:height\" content=\"671\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@www.twitter.com\/maikel_f\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2012\/05\/vernier-aux-portes-de-la-2eme-ligue-inter\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/Vernier-Carouge2.jpg\",\"width\":1134,\"height\":671},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2012\/05\/vernier-aux-portes-de-la-2eme-ligue-inter\/#webpage\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/2012\/05\/vernier-aux-portes-de-la-2eme-ligue-inter\/\",\"name\":\"Vernier aux portes de la 2\\u00e8me ligue inter - Proxifoot, le m\\u00e9dia du football genevois\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2012\/05\/vernier-aux-portes-de-la-2eme-ligue-inter\/#primaryimage\"},\"datePublished\":\"2012-05-02T07:04:09+00:00\",\"dateModified\":\"2016-10-25T12:22:28+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/f8763ae73551193f68b47b57e2bdfb15\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.proxifoot.ch\/geneve\/2012\/05\/vernier-aux-portes-de-la-2eme-ligue-inter\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/f8763ae73551193f68b47b57e2bdfb15\",\"name\":\"Maikel\",\"sameAs\":[\"https:\/\/twitter.com\/www.twitter.com\/maikel_f\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/3323"}],"collection":[{"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=3323"}],"version-history":[{"count":0,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/3323\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/3325"}],"wp:attachment":[{"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=3323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=3323"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=3323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}