﻿{"id":63341,"date":"2024-07-23T16:30:12","date_gmt":"2024-07-23T14:30:12","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=63341"},"modified":"2024-07-23T16:30:12","modified_gmt":"2024-07-23T14:30:12","slug":"jai-hate-de-decouvrir-ce-monde","status":"publish","type":"post","link":"http:\/\/www.proxifoot.ch\/geneve\/2024\/07\/jai-hate-de-decouvrir-ce-monde\/","title":{"rendered":"\u00ab\u00a0J\u2019ai h\u00e2te de d\u00e9couvrir ce monde\u00a0\u00bb"},"content":{"rendered":"<p><strong>L&#8217;ancien footballeur professionnel Julian Esteban dirigera la Deux d&#8217;Etoile Carouge lors de la saison \u00e0 venir. Une premi\u00e8re aussi bien comme entra\u00eeneur principal que dans le foot r\u00e9gional.\u00a0<\/strong><\/p>\n<p><!--more--><\/p>\n<p class=\"p1\"><div class=\"g g-3\"><div class=\"g-dyn a-30 c-1\"><a class=\"gofollow\" data-track=\"MzAsMywxLDYw\" href=\"https:\/\/www.instagram.com\/mysols_sarl\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/08\/MySols-banner.jpg\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><div class=\"g-dyn a-26 c-2\"><a class=\"gofollow\" data-track=\"MjYsMywxLDYw\" href=\"https:\/\/hepta-sa.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/10\/HEPTA-Logo-2024.png\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><div class=\"g-dyn a-15 c-3\"><a class=\"gofollow\" data-track=\"MTUsMywxLDYw\" href=\"https:\/\/gabb-immo.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2022\/06\/Capture-de\u0301cran-202-06-21-a\u0300-15.32.jpg\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><div class=\"g-dyn a-16 c-4\"><a class=\"gofollow\" data-track=\"MTYsMywxLDYw\" href=\"https:\/\/pok-games.com\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2022\/06\/Capture-de\u0301cran-2022-06-21-a\u0300-15.32.19.png\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><div class=\"g-dyn a-12 c-5\"><a class=\"gofollow\" data-track=\"MTIsMywxLDYw\" href=\"http:\/\/arcus-fin.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2023\/01\/Arcus_Bannie\u0300re2.png\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><div class=\"g-dyn a-32 c-6\"><a class=\"gofollow\" data-track=\"MzIsMywxLDYw\" href=\"https:\/\/rentesgenevoises.ch\/l-annexe\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/08\/Annexe-Rentes-banner.jpg\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><div class=\"g-dyn a-33 c-7\"><a class=\"gofollow\" data-track=\"MzMsMywxLDYw\" href=\"https:\/\/www.genevoisefiduciaire.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/08\/Genevoise-Fiduciaire-banner.jpg\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><div class=\"g-dyn a-29 c-8\"><a class=\"gofollow\" data-track=\"MjksMywxLDYw\" href=\"https:\/\/www.infomaniak.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/10\/infomaniak-logo-banner.jpg\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><div class=\"g-dyn a-27 c-9\"><a class=\"gofollow\" data-track=\"MjcsMywxLDYw\" href=\"https:\/\/tsm-versoix.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/10\/TSM-CRP-logos-2024.png\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><div class=\"g-dyn a-28 c-10\"><a class=\"gofollow\" data-track=\"MjgsMywxLDYw\" href=\"https:\/\/www.rafaelstores.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/10\/Rafael-Stores-logo-2024.png\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><\/div>\n<p>Un constat quasi unanime revient avec r\u00e9currence depuis la fin de la saison 2023-24. Que ce soit pour les trois Genevois rel\u00e9gu\u00e9s de 2\u00e8me ligue inter ou la promotion de l&#8217;ambitieux Azzurri, un nivellement par le haut est attendu au plus haut \u00e9chelon r\u00e9gional. La saison de 2\u00e8me ligue \u00e0 venir promet du lourd, et l&#8217;arriv\u00e9e de nouveaux entra\u00eeneurs sur le circuit ne fait qu&#8217;amplifier l&#8217;enthousiasme. Julian Esteban est l&#8217;un d&#8217;entre eux. L&#8217;ex-attaquant de Servette et de Rennes \u00e0 la riche mais malheureusement trop courte carri\u00e8re se lance un nouveau d\u00e9fi, \u00e0 37 ans. Il est le nouvel entra\u00eeneur d&#8217;Etoile Carouge II.<\/p>\n<div id=\"attachment_63370\" style=\"width: 1210px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.proxifoot.ch\/geneve\/2024\/07\/jai-hate-de-decouvrir-ce-monde\/julian-esteban-2\/\" rel=\"attachment wp-att-63370\"><img aria-describedby=\"caption-attachment-63370\" loading=\"lazy\" class=\"size-full wp-image-63370\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/07\/julian-esteban.jpeg\" alt=\"\" width=\"1200\" height=\"1600\" srcset=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/07\/julian-esteban.jpeg 1200w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/07\/julian-esteban-225x300.jpeg 225w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/07\/julian-esteban-768x1024.jpeg 768w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/07\/julian-esteban-1152x1536.jpeg 1152w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a><p id=\"caption-attachment-63370\" class=\"wp-caption-text\">Julian Esteban succ\u00e8de \u00e0 Geoffrey Tr\u00e9and \u00e0 la t\u00eate de la Deux.<\/p><\/div>\n<p><strong>Une opportunit\u00e9 inattendue<\/strong><\/p>\n<p>Voir l&#8217;ancien international suisse M-21 arpenter les bancs du canton \u00e0 la t\u00eate de l&#8217;\u00e9quipe carougeoise fera sans doute un certain effet dans un premier temps, il faut bien l&#8217;avouer. Le principal int\u00e9ress\u00e9 est d&#8217;ailleurs le premier \u00e0 avoir \u00e9t\u00e9 surpris par cette opportunit\u00e9, lui qui exer\u00e7ait d\u00e9j\u00e0 au club en tant qu&#8217;assistant au sein du mouvement juniors : <em>&#8220;Ce n&#8217;\u00e9tait pas quelque chose de planifi\u00e9&#8221;, <\/em>explique Julian Esteban.\u00a0<em>&#8220;Lorsque Geoffrey\u00a0<\/em>(Tr\u00e9and, ex-entra\u00eeneur de la Deux, ndlr)\u00a0<em>a annonc\u00e9 son d\u00e9part, on m&#8217;a propos\u00e9 cela. J&#8217;\u00e9tais tr\u00e8s content qu&#8217;on ait pens\u00e9 \u00e0 moi et il ne m&#8217;a pas fallu beaucoup de temps pour me dire que j&#8217;allais me lancer. Il le faut bien un jour, de toute fa\u00e7on\u00a0<\/em>(rires)<em>&#8220;.<\/em><\/p>\n<p class=\"p1\"><b>Sous le signe de la d\u00e9couverte<\/b><\/p>\n<p>Ce r\u00f4le d&#8217;entra\u00eeneur d&#8217;Etoile Carouge II est une premi\u00e8re \u00e0 tous les niveaux pour celui dont le transfert du Servette FC au Stade Rennais avait tant fait parler \u00e0 l&#8217;hiver 2007. Une premi\u00e8re \u00e0 la fois comme coach principal, mais aussi plus largement dans le football r\u00e9gional : <em>&#8220;Je vais d\u00e9couvrir ce milieu et cette ligue que je n&#8217;ai pas eu l&#8217;occasion de conna\u00eetre \u00e0 l&#8217;\u00e9poque en tant que joueur&#8221;,<\/em> d\u00e9taille Esteban.\u00a0<em>&#8220;J&#8217;ai h\u00e2te de d\u00e9couvrir ce monde. Je suis aussi convaincu que le fait d&#8217;\u00eatre \u00e0 la t\u00eate d&#8217;un groupe de jeunes adultes va me permettre de d\u00e9couvrir des nouvelles facettes de moi-m\u00eame&#8221;.\u00a0<\/em><\/p>\n<div id=\"attachment_63371\" style=\"width: 207px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.proxifoot.ch\/geneve\/2024\/07\/jai-hate-de-decouvrir-ce-monde\/estebanjulian_399866\/\" rel=\"attachment wp-att-63371\"><img aria-describedby=\"caption-attachment-63371\" loading=\"lazy\" class=\"size-full wp-image-63371\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/07\/EstebanJulian_399866.jpg\" alt=\"\" width=\"197\" height=\"224\" \/><\/a><p id=\"caption-attachment-63371\" class=\"wp-caption-text\">Plus de six ans apr\u00e8s avoir stopp\u00e9 sa carri\u00e8re professionnelle, Julian Esteban avait rejoint Etoile Carouge \u00e0 l&#8217;\u00e9t\u00e9 2019. Il n&#8217;aura toutefois jamais jou\u00e9 avec les Stelliens pendant la saison du retour en Promotion League.<\/p><\/div>\n<p>Pour ses premiers pas dans un milieu nouveau pour lui, le nouvel homme fort de la r\u00e9serve stellienne pourra s&#8217;appuyer sur son bras droit G\u00e9d\u00e9on Roberto. D\u00e9j\u00e0 assistant de Geoffrey Tr\u00e9and, celui qui a \u00e9galement remport\u00e9 le doubl\u00e9 Coupe-championnat avec les Juniors B de Champel sera d&#8217;une grande aide pour l&#8217;ex-Servettien : <em>&#8220;J&#8217;ai demand\u00e9 \u00e0 G\u00e9d\u00e9on de prendre en charge l&#8217;\u00e9quipe au d\u00e9but de la pr\u00e9paration, pour que je puisse me concentrer sur l&#8217;observation et bien d\u00e9couvrir l&#8217;\u00e9quipe&#8221;. <\/em>L&#8217;effectif a d&#8217;ailleurs comme chaque ann\u00e9e connu un large turnover et un rajeunissement, avec \u00e9galement les arriv\u00e9es de joueurs confirm\u00e9s comme Iliy\u00e8s Maouche, Leonar Makolli ou Boris Mpon.<\/p>\n<p><strong>S&#8217;inspirer de la premi\u00e8re \u00e9quipe<\/strong><\/p>\n<p>La question des objectifs devient quant \u00e0 elle toujours plus fond\u00e9e, d&#8217;autant plus maintenant que la premi\u00e8re \u00e9quipe a \u00e9t\u00e9 promue en Challenge League et qu&#8217;Etoile Carouge II est devenue une r\u00e9serve de club professionnel. <em>&#8220;Rien que \u00e7a, je suis s\u00fbr que \u00e7a va nous permettre d&#8217;avoir une motivation sans faille tout au long de la saison&#8221;,<\/em> commente Esteban.\u00a0<em>&#8220;Le fait que les jeunes joueurs qui sont avec nous aient dans un coin de leur t\u00eate l&#8217;id\u00e9e qu&#8217;une possibilit\u00e9 d&#8217;int\u00e9grer la premi\u00e8re \u00e9quipe existe am\u00e8ne automatiquement une part de s\u00e9rieux en plus&#8221;.\u00a0<\/em><\/p>\n<div id=\"attachment_63372\" style=\"width: 1189px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.proxifoot.ch\/geneve\/2024\/07\/jai-hate-de-decouvrir-ce-monde\/nvendo\/\" rel=\"attachment wp-att-63372\"><img aria-describedby=\"caption-attachment-63372\" loading=\"lazy\" class=\"size-full wp-image-63372\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/07\/nvendo.jpeg\" alt=\"\" width=\"1179\" height=\"1343\" srcset=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/07\/nvendo.jpeg 1179w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/07\/nvendo-263x300.jpeg 263w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/07\/nvendo-899x1024.jpeg 899w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/07\/nvendo-768x875.jpeg 768w\" sizes=\"(max-width: 1179px) 100vw, 1179px\" \/><\/a><p id=\"caption-attachment-63372\" class=\"wp-caption-text\">Pass\u00e9 par la deuxi\u00e8me \u00e9quipe, Vincent Nvendo (2003) a d\u00e9marr\u00e9 la saison de Challenge League comme titulaire en \u00e9tant d\u00e9cisif avec un assist et un but. De quoi inspirer la rel\u00e8ve. (Photo : Etoile Carouge FC)<\/p><\/div>\n<p>La philosophie de jeu de la Une, instaur\u00e9e par l&#8217;entra\u00eeneur Adrian Ursea \u00e0 son arriv\u00e9e \u00e0 l&#8217;\u00e9t\u00e9 2023, sera par ailleurs int\u00e9gr\u00e9e au sein de la deuxi\u00e8me \u00e9quipe, comme cela avait \u00e9t\u00e9 amorc\u00e9 lors du deuxi\u00e8me tour de la pr\u00e9c\u00e9dente saison :\u00a0<em>&#8220;On va essayer de faire \u00e0 peu pr\u00e8s la m\u00eame chose que la premi\u00e8re \u00e9quipe tactiquement&#8221;, <\/em>confirme le nouvel entra\u00eeneur de Carouge II.\u00a0<em>&#8220;Cette mise en place d&#8217;un syst\u00e8me sera l&#8217;une des premi\u00e8res choses \u00e0 faire sur ce premier tour. Bien s\u00fbr, le fait de suivre ces instructions tactiques n&#8217;exclut pas le fait que je puisse ajouter ma touche personnelle&#8221;.\u00a0<\/em><\/p>\n<p>Un cocktail gagnant pour \u00eatre parmi les pr\u00e9tendants \u00e0 la promotion ? Avec la mont\u00e9e de la premi\u00e8re \u00e9quipe, r\u00e9duire l&#8217;\u00e9cart de quatre ligues entre la Une et la Deux ne serait sans doute pas de refus. Pour l&#8217;instant, cela n&#8217;est toutefois pas une priorit\u00e9.\u00a0<em>&#8220;Bien \u00e9videmment que pour le club \u00e7a serait top, mais ce n&#8217;est pas notre objectif principal&#8221;,\u00a0<\/em>explique Julian Esteban.\u00a0<em>&#8220;Notre priorit\u00e9 reste la progression individuelle des joueurs. On verra o\u00f9 on sera \u00e0 la fin du premier tour en termes de classement et c&#8217;est \u00e0 ce moment-l\u00e0 seulement que nous pourrons d\u00e9terminer si oui ou non nous pouvons viser quelque chose comme une promotion&#8221;.<\/em><\/p>\n<div id=\"attachment_63373\" style=\"width: 2224px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.proxifoot.ch\/geneve\/2024\/07\/jai-hate-de-decouvrir-ce-monde\/capture-decran-2024-07-23-a-16-29-28\/\" rel=\"attachment wp-att-63373\"><img aria-describedby=\"caption-attachment-63373\" loading=\"lazy\" class=\"size-full wp-image-63373\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/07\/Capture-de\u0301cran-2024-07-23-a\u0300-16.29.28.png\" alt=\"\" width=\"2214\" height=\"1210\" srcset=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/07\/Capture-de\u0301cran-2024-07-23-a\u0300-16.29.28.png 2214w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/07\/Capture-de\u0301cran-2024-07-23-a\u0300-16.29.28-300x164.png 300w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/07\/Capture-de\u0301cran-2024-07-23-a\u0300-16.29.28-1024x560.png 1024w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/07\/Capture-de\u0301cran-2024-07-23-a\u0300-16.29.28-768x420.png 768w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/07\/Capture-de\u0301cran-2024-07-23-a\u0300-16.29.28-1536x839.png 1536w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/07\/Capture-de\u0301cran-2024-07-23-a\u0300-16.29.28-2048x1119.png 2048w\" sizes=\"(max-width: 2214px) 100vw, 2214px\" \/><\/a><p id=\"caption-attachment-63373\" class=\"wp-caption-text\">Etoile Carouge II d\u00e9marrera sa saison avec la r\u00e9ception du CS Italien le dimanche 25 ao\u00fbt \u00e0 la Fontenette.<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;ancien footballeur professionnel Julian Esteban dirigera la Deux d&#8217;Etoile Carouge lors de la saison \u00e0 venir. Une premi\u00e8re aussi bien comme entra\u00eeneur principal que dans le foot r\u00e9gional.\u00a0<\/p>\n","protected":false},"author":51,"featured_media":63342,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[5,544],"tags":[59,740,931],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"description\" content=\"L&#039;ancien footballeur professionnel Julian Esteban dirigera la Deux d&#039;Etoile Carouge lors de la saison \u00e0 venir. Une premi\u00e8re aussi bien comme entra\u00eeneur principal que dans le foot r\u00e9gional.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.proxifoot.ch\/geneve\/2024\/07\/jai-hate-de-decouvrir-ce-monde\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00ab\u00a0J\u2019ai h\u00e2te de d\u00e9couvrir ce monde\u00a0\u00bb\" \/>\n<meta property=\"og:description\" content=\"L&#039;ancien footballeur professionnel Julian Esteban dirigera la Deux d&#039;Etoile Carouge lors de la saison \u00e0 venir. Une premi\u00e8re aussi bien comme entra\u00eeneur principal que dans le foot r\u00e9gional.\u00a0\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.proxifoot.ch\/geneve\/2024\/07\/jai-hate-de-decouvrir-ce-monde\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-23T14:30:12+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/07\/julian-esteban.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1404\" \/>\n\t<meta property=\"og:image:height\" content=\"672\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"\u00ab\u00a0J\u2019ai h\u00e2te de d\u00e9couvrir ce monde\u00a0\u00bb\" \/>\n<meta name=\"twitter:description\" content=\"L&#039;ancien footballeur professionnel Julian Esteban dirigera la Deux d&#039;Etoile Carouge lors de la saison \u00e0 venir. Une premi\u00e8re aussi bien comme entra\u00eeneur principal que dans le foot r\u00e9gional.\u00a0\" \/>\n<meta name=\"twitter:image\" content=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/07\/julian-esteban.png\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\">\n\t<meta name=\"twitter:data1\" content=\"5 minutes\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2024\/07\/jai-hate-de-decouvrir-ce-monde\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/07\/julian-esteban.png\",\"width\":1404,\"height\":672},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2024\/07\/jai-hate-de-decouvrir-ce-monde\/#webpage\",\"url\":\"http:\/\/www.proxifoot.ch\/geneve\/2024\/07\/jai-hate-de-decouvrir-ce-monde\/\",\"name\":\"\\u00ab\\u00a0J\\u2019ai h\\u00e2te de d\\u00e9couvrir ce monde\\u00a0\\u00bb\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2024\/07\/jai-hate-de-decouvrir-ce-monde\/#primaryimage\"},\"datePublished\":\"2024-07-23T14:30:12+00:00\",\"dateModified\":\"2024-07-23T14:30:12+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/cd8992ff5ae4e66d281c50a350f0c65a\"},\"description\":\"L'ancien footballeur professionnel Julian Esteban dirigera la Deux d'Etoile Carouge lors de la saison \\u00e0 venir. Une premi\\u00e8re aussi bien comme entra\\u00eeneur principal que dans le foot r\\u00e9gional.\\u00a0\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.proxifoot.ch\/geneve\/2024\/07\/jai-hate-de-decouvrir-ce-monde\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/cd8992ff5ae4e66d281c50a350f0c65a\",\"name\":\"Giacomo Notari\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/63341"}],"collection":[{"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/51"}],"replies":[{"embeddable":true,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=63341"}],"version-history":[{"count":7,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/63341\/revisions"}],"predecessor-version":[{"id":63375,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/63341\/revisions\/63375"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/63342"}],"wp:attachment":[{"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=63341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=63341"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=63341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}