﻿{"id":64100,"date":"2024-09-01T10:34:06","date_gmt":"2024-09-01T08:34:06","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=64100"},"modified":"2024-09-01T10:37:58","modified_gmt":"2024-09-01T08:37:58","slug":"plo-remporte-un-match-qui-a-tarde-a-offrir-des-emotions","status":"publish","type":"post","link":"http:\/\/www.proxifoot.ch\/geneve\/2024\/09\/plo-remporte-un-match-qui-a-tarde-a-offrir-des-emotions\/","title":{"rendered":"PLO remporte un match qui a tard\u00e9 \u00e0 offrir des \u00e9motions"},"content":{"rendered":"\r\n<p><strong>Apr\u00e8s avoir manqu\u00e9 plusieurs occasions tout au long de la partie, PLO a finalement conclu dans les derni\u00e8res secondes face \u00e0 Satigny (1-0).<\/strong><\/p>\r\n<p><!--more--><\/p>\r\n<p class=\"p1\"><!-- Erreur, Annonce n\u2019est pas disponible pour le moment en raison de restrictions de calendrier \/ g\u00e9olocalisation! -->\r\n<p>Tous deux vainqueurs en premi\u00e8re journ\u00e9e dans des matchs riches en buts, Plan-les-Ouates et Satigny semblaient \u00e0 m\u00eame de proposer une rencontre \u00e9lectrique aux Cherpines. Le fait que les impr\u00e9cisions aient conditionn\u00e9 l\u2019issue du match pendant tr\u00e8s longtemps est un bon indicateur de ce que cette rencontre n\u2019a pas \u00e9t\u00e9. <br \/><br \/><strong>Des locaux en manque de tranchant<\/strong><\/p>\r\n<p>Forts de leur d\u00e9monstration contre Onex (1-6), les hommes du <a href=\"https:\/\/www.proxifoot.ch\/geneve\/2024\/06\/plan-les-ouates-repartira-avec-helder-silva\/\" target=\"_blank\" rel=\"noopener noreferrer\">nouvel entra\u00eeneur Helder Silva<\/a> ont cherch\u00e9 \u00e0 prendre les initiatives dans le jeu, de mani\u00e8re plut\u00f4t brouillonne. Le match a en effet eu du mal \u00e0 s\u2019emballer en premi\u00e8re p\u00e9riode, mais les locaux \u00e9taient malgr\u00e9 tout les plus dangereux, manquant toutefois bien trop souvent le cadre sur leurs frappes. A l\u2019image de l\u2019immense opportunit\u00e9 d\u2019Arnaud Kiedi \u00e0 la demi-heure de jeu, non-cadr\u00e9e alors que le gardien satignote venait d\u2019\u00eatre \u00e9limin\u00e9 par une passe en retrait.<\/p>\r\n<div id=\"attachment_64115\" style=\"width: 1375px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.proxifoot.ch\/geneve\/2024\/09\/plo-remporte-un-match-qui-a-tarde-a-offrir-des-emotions\/coovi-plo\/\" rel=\"attachment wp-att-64115\"><img aria-describedby=\"caption-attachment-64115\" loading=\"lazy\" class=\"size-full wp-image-64115\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/09\/coovi-plo.jpeg\" alt=\"\" width=\"1365\" height=\"1024\" srcset=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/09\/coovi-plo.jpeg 1365w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/09\/coovi-plo-300x225.jpeg 300w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/09\/coovi-plo-1024x768.jpeg 1024w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/09\/coovi-plo-768x576.jpeg 768w\" sizes=\"(max-width: 1365px) 100vw, 1365px\" \/><\/a><p id=\"caption-attachment-64115\" class=\"wp-caption-text\">Cedric Coovi (\u00e0 dr.) fait partie des nombreuses recrues estivales plan-les-ouatiennes. <em><a href=\"https:\/\/www.instagram.com\/zuodarfoto\/\" target=\"_blank\" rel=\"noopener noreferrer\">@zuodarfoto<\/a><\/em><\/p><\/div>\r\n<p>Il a alors fallu attendre un peu avant l\u2019heure de jeu pour qu\u2019un frisson similaire ne parcoure \u00e0 nouveau le stade, gr\u00e2ce \u00e0 une superbe frappe enroul\u00e9e de Joao Oliveira \u00e0 l\u2019entr\u00e9e de surface repouss\u00e9e par l\u2019extension tout aussi impressionnante du portier Macchiarelli. Le match ne s\u2019est vraiment lib\u00e9r\u00e9 que dans le dernier quart d\u2019heure. Jusqu\u2019ici men\u00e9s aux points si l&#8217;on se r\u00e9f\u00e8re aux occasions franches, les Satignotes auraient pu r\u00e9aliser la bonne op\u00e9ration en fin de rencontre avec quelques bonnes opportunit\u00e9s cr\u00e9\u00e9es, dont un arr\u00eat important de Curtin sur Wristberg.<\/p>\r\n<div id=\"attachment_64110\" style=\"width: 1344px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.proxifoot.ch\/geneve\/2024\/09\/plo-remporte-un-match-qui-a-tarde-a-offrir-des-emotions\/helder-silva-remi-fusco\/\" rel=\"attachment wp-att-64110\"><img aria-describedby=\"caption-attachment-64110\" loading=\"lazy\" class=\"size-full wp-image-64110\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/09\/helder-silva-remi-fusco.jpeg\" alt=\"\" width=\"1334\" height=\"1001\" srcset=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/09\/helder-silva-remi-fusco.jpeg 1334w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/09\/helder-silva-remi-fusco-300x225.jpeg 300w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/09\/helder-silva-remi-fusco-1024x768.jpeg 1024w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/09\/helder-silva-remi-fusco-768x576.jpeg 768w\" sizes=\"(max-width: 1334px) 100vw, 1334px\" \/><\/a><p id=\"caption-attachment-64110\" class=\"wp-caption-text\">Helder Silva, entra\u00eeneur de PLO, de face, et R\u00e9mi Fusco, entra\u00eeneur de Satigny, de dos. <em><a href=\"https:\/\/www.instagram.com\/zuodarfoto\/\" target=\"_blank\" rel=\"noopener noreferrer\">@zuodarfoto<\/a><\/em><\/p><\/div>\r\n<p>Pass\u00e9 proche de tout perdre, le FC Plan-les-Ouates est finalement all\u00e9 arracher une victoire dans les ultimes instants sur un gros cafouillage remport\u00e9 par Anthony Cagol. PLO venait, quelques secondes auparavant, de voir sa tentative sauv\u00e9e sur la ligne. <em>&#8220;C\u2019\u00e9tait un match compliqu\u00e9 avec \u00e9norm\u00e9ment d\u2019actions qu\u2019on n\u2019a pas su concr\u00e9tiser. Notre \u00e9quipe a fait une bonne prestation et il ne manquait plus que le but&#8221;<\/em>, expliquait le buteur du soir.<\/p>\r\n<p><iframe title=\"FC Plan-les-Ouates - FC Satigny (1-0) : le but d&#039;Anthony Cagol\" width=\"702\" height=\"395\" src=\"https:\/\/www.youtube.com\/embed\/GxSVgiwwY5I?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\r\n<p>Un constat qui concorde avec celui du capitaine satignote Marvin Dos Santos : <em>&#8220;La premi\u00e8re mi-temps \u00e9tait difficile, on n&#8217;\u00e9tait pas tr\u00e8s bien en place et on a beaucoup subi lors des derni\u00e8res minutes. Les entr\u00e9es en deuxi\u00e8me mi-temps nous ont fait du bien et on a corrig\u00e9 le tir. On aurait pu marquer, mais sur l\u2019ensemble du match, ce n&#8217;est pas imm\u00e9rit\u00e9.&#8221;<\/em><\/p>\r\n<p>Six points sur six donc pour le rel\u00e9gu\u00e9 Plan-les-Ouates qui se rendra \u00e0 Meyrin dimanche prochain, alors que le FC Satigny poss\u00e8de trois unit\u00e9s avant d\u2019accueillir un Azzurri qui devrait repr\u00e9senter une nouvelle fois une grande adversit\u00e9 dans le jeu.<\/p>\r\n<p><iframe title=\"Anthony Cagol Apr\u00e8s Plan-les-Ouates - Satigny (1-0)\" width=\"702\" height=\"395\" src=\"https:\/\/www.youtube.com\/embed\/pQGRP0W_I3c?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\r\n<p><iframe title=\"Marvin Dos Santos apr\u00e8s Plan-les-Ouates - Satigny (1-0)\" width=\"702\" height=\"395\" src=\"https:\/\/www.youtube.com\/embed\/idHI054KjFg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\r\n<blockquote>\r\n<p><strong>FC PLAN-LES-OUATES &#8211; FC SATIGNY 1-0 (0-0)<br \/><\/strong>Stade des Cherpines, herbe<\/p>\r\n<p><strong>But :\u00a0<\/strong>90+5&#8242; Cagol.<\/p>\r\n<p><strong>PLO : <\/strong>Curtin &#8211; Coovi, Balde, Rasolondraibe, Meyer &#8211; Cagol, Oliveira, Ferrillo, Mangana \u00a9, Kiedi &#8211; Dionso.<br \/>Entr\u00e9s en jeu : 65&#8242; Cayazzo, Carucci ; 75&#8242; Robin, Gaud, Domingos.<br \/>Entra\u00eeneur : Helder Silva<\/p>\r\n<p><strong>Satigny :\u00a0<\/strong>Macchiarelli &#8211; De Sousa, Vilarino, Estupina, Pereira &#8211; Mi\u00e9ville, E. Wilkens, Wristberg, Dos Santos \u00a9 &#8211; Treleani, Greco.<br \/>Entr\u00e9s en jeu : 43&#8242; R. Dos Santos ; 57&#8242; M&#8217;Namdji, Tessaro ; 77&#8242; Albert.<br \/>Entra\u00eeneur : R\u00e9mi Fusco<\/p>\r\n<p><strong>Avertissements : <\/strong>43&#8242; Dionso, 53&#8242; Ferrillo (PLO) ; 78&#8242; E. Wilkens (Satigny)<\/p>\r\n<\/blockquote>\r\n<p><em>Photo de couverture : <a href=\"https:\/\/www.instagram.com\/zuodarfoto\/\" target=\"_blank\" rel=\"noopener noreferrer\">@zuodarfoto<\/a><\/em><\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s avoir manqu\u00e9 plusieurs occasions tout au long de la partie, PLO a finalement conclu dans les derni\u00e8res secondes face \u00e0 Satigny (1-0).<\/p>\n","protected":false},"author":187,"featured_media":64111,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[5],"tags":[696,747,80,104],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"description\" content=\"Apr\u00e8s avoir manqu\u00e9 plusieurs occasions tout au long de la partie, PLO a finalement conclu dans les derni\u00e8res secondes face \u00e0 Satigny (1-0).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.proxifoot.ch\/geneve\/2024\/09\/plo-remporte-un-match-qui-a-tarde-a-offrir-des-emotions\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PLO remporte un match qui a tard\u00e9 \u00e0 offrir des \u00e9motions\" \/>\n<meta property=\"og:description\" content=\"Apr\u00e8s avoir manqu\u00e9 plusieurs occasions tout au long de la partie, PLO a finalement conclu dans les derni\u00e8res secondes face \u00e0 Satigny (1-0).\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.proxifoot.ch\/geneve\/2024\/09\/plo-remporte-un-match-qui-a-tarde-a-offrir-des-emotions\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-01T08:34:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-01T08:37:58+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/09\/plo-fc-satigny-zuodarfoto-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1404\" \/>\n\t<meta property=\"og:image:height\" content=\"672\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"PLO remporte un match qui a tard\u00e9 \u00e0 offrir des \u00e9motions\" \/>\n<meta name=\"twitter:description\" content=\"Apr\u00e8s avoir manqu\u00e9 plusieurs occasions tout au long de la partie, PLO a finalement conclu dans les derni\u00e8res secondes face \u00e0 Satigny (1-0).\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\">\n\t<meta name=\"twitter:data1\" content=\"3 minutes\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"http:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"http:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2024\/09\/plo-remporte-un-match-qui-a-tarde-a-offrir-des-emotions\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/09\/plo-fc-satigny-zuodarfoto-.png\",\"width\":1404,\"height\":672},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2024\/09\/plo-remporte-un-match-qui-a-tarde-a-offrir-des-emotions\/#webpage\",\"url\":\"http:\/\/www.proxifoot.ch\/geneve\/2024\/09\/plo-remporte-un-match-qui-a-tarde-a-offrir-des-emotions\/\",\"name\":\"PLO remporte un match qui a tard\\u00e9 \\u00e0 offrir des \\u00e9motions\",\"isPartOf\":{\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2024\/09\/plo-remporte-un-match-qui-a-tarde-a-offrir-des-emotions\/#primaryimage\"},\"datePublished\":\"2024-09-01T08:34:06+00:00\",\"dateModified\":\"2024-09-01T08:37:58+00:00\",\"author\":{\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/7ceda2ce1400cf16de4f7999973a5b4f\"},\"description\":\"Apr\\u00e8s avoir manqu\\u00e9 plusieurs occasions tout au long de la partie, PLO a finalement conclu dans les derni\\u00e8res secondes face \\u00e0 Satigny (1-0).\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.proxifoot.ch\/geneve\/2024\/09\/plo-remporte-un-match-qui-a-tarde-a-offrir-des-emotions\/\"]}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/7ceda2ce1400cf16de4f7999973a5b4f\",\"name\":\"Mikael Merluzzo\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/64100"}],"collection":[{"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/187"}],"replies":[{"embeddable":true,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=64100"}],"version-history":[{"count":12,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/64100\/revisions"}],"predecessor-version":[{"id":64116,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/64100\/revisions\/64116"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/64111"}],"wp:attachment":[{"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=64100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=64100"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=64100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}