﻿{"id":8663,"date":"2012-11-20T17:51:42","date_gmt":"2012-11-20T16:51:42","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=8663"},"modified":"2012-11-21T12:07:51","modified_gmt":"2012-11-21T11:07:51","slug":"aux-tirs-au-but-onex-decroche-le-titre2","status":"publish","type":"post","link":"http:\/\/www.proxifoot.ch\/geneve\/2012\/11\/aux-tirs-au-but-onex-decroche-le-titre2\/","title":{"rendered":"Aux tirs au but, Onex d\u00e9croche le titre"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Juniors C \/ Men\u00e9s 2-0 \u00e0 la mi-temps, les Meyrinois parviennent \u00e0 \u00e9galiser en seconde p\u00e9riode mais doivent s&#8217;incliner lors de la loterie des tirs au but.<\/strong><!--more--><\/p>\n<p style=\"text-align: justify;\">Il fallait se lever t\u00f4t pour assister \u00e0 la premi\u00e8re des trois finales juniors qui avaient lieu samedi. A 10h \u00e0 Vaudagne, c\u2019est Meyrin et Onex qui avaient l\u2019honneur de lancer ce marathon footballistique qui mettait fin \u00e0 ce premier tour.<\/p>\n<p style=\"text-align: justify;\">Et les deux \u00e9quipes auront eu la particularit\u00e9 d\u2019avoir termin\u00e9 en t\u00eate du championnat \u00e0 \u00e9galit\u00e9 avec leurs dauphins mais avec une meilleure diff\u00e9rence de buts. Dans le groupe 1, Meyrin a profit\u00e9 de la d\u00e9faite de Champel \u00e0 Bernex pour s\u2019emparer de la premi\u00e8re place alors que les trois \u00e9quipes \u00e9taient \u00e0 \u00e9galit\u00e9 avec 19 points (+45 de goalaverage contre +31 et +15). Dans le groupe 2, Onex avait auparavant \u00e9t\u00e9 battu par Versoix, avant de profiter d\u2019une d\u00e9faite des Versoisiens contre Puplinge pour revenir \u00e0 \u00e9galit\u00e9. Au final, les On\u00e9siens terminent devant, comptant une meilleur diff\u00e9rence de buts (+47 contre +34), gr\u00e2ce notamment \u00e0 leur carton de d\u00e9but de saison contre Grand-Saconnex (victoire 25 \u00e0 2\u00a0!).<\/p>\n<p style=\"text-align: justify;\"><strong>Double avance pour Onex<\/strong><\/p>\n<p style=\"text-align: justify;\">Techniquement parlant, cette finale aura probablement \u00e9t\u00e9 la meilleure des trois de la journ\u00e9e. Aucune des deux \u00e9quipes n\u2019a eu recours aux longs ballons, et leur jeu au sol \u00e9tait beau \u00e0 voir.<\/p>\n<p style=\"text-align: justify;\">La premi\u00e8re p\u00e9riode est \u00e0 l\u2019avantage des On\u00e9siens, qui vont prendre l\u2019avantage par Monteleone, dont le tir bat le portier Aeby (19\u2019, 1-0). Dominateurs dans le jeu, gr\u00e2ce notamment \u00e0\u00a0l\u2019impressionnant\u00a0milieu de terrain Pessoa, Onex va doubler son avance juste avant la mi-temps par l\u2019interm\u00e9diaire de son rempla\u00e7ant Hoxhaj.<\/p>\n<div id=\"attachment_8668\" style=\"width: 449px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.footjuniors.ch\/Galerie\/thumbnails.php?album=1148\" target=\"_blank\"><img aria-describedby=\"caption-attachment-8668\" loading=\"lazy\" class=\"size-full wp-image-8668   \" title=\"Meyrin-Onex1\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/11\/Meyrin-Onex1.jpg\" alt=\"\" width=\"439\" height=\"369\" srcset=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/11\/Meyrin-Onex1.jpg 915w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/11\/Meyrin-Onex1-300x251.jpg 300w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/11\/Meyrin-Onex1-660x553.jpg 660w\" sizes=\"(max-width: 439px) 100vw, 439px\" \/><\/a><p id=\"caption-attachment-8668\" class=\"wp-caption-text\">Hoxhaj f\u00eate le 2\u00e8me but on\u00e9sien... au grand d\u00e9sespoir des Meyrinois<\/p><\/div>\n<p style=\"text-align: justify;\">Cette premi\u00e8re mi-temps a \u00e9t\u00e9 \u00e0 l&#8217;avantage des &#8220;Verts&#8221;, qui boivent le th\u00e9 sur une double avance de 2-0 \u00e0 la mi-temps. On se dit que les choses se dessinent bien pour les joueurs de Wilson Rafael et Emanuel Machado. Enfin, c\u2019est ce qu\u2019on croit\u2026<\/p>\n<p style=\"text-align: justify;\"><strong>Turrisi au secours de Meyrin<\/strong><\/p>\n<p style=\"text-align: justify;\">Les Meyrinois repartent plus conqu\u00e9rants apr\u00e8s le th\u00e9. La troupe d\u2019Eric Pasquettaz ne veut pas perdre \u00ab\u00a0sa\u00a0\u00bb finale \u00e0 domicile.<\/p>\n<p style=\"text-align: justify;\">Dans les premi\u00e8res minutes de la seconde p\u00e9riode, Meyrin va obtenir un penalty synonyme de regain d\u2019espoir. Turrisi ne tremble pas et relance la partie (55\u2019, 1-2).<\/p>\n<div id=\"attachment_8669\" style=\"width: 563px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.footjuniors.ch\/Galerie\/thumbnails.php?album=1148\" target=\"_blank\"><img aria-describedby=\"caption-attachment-8669\" loading=\"lazy\" class=\"size-full wp-image-8669 \" title=\"Meyrin-Onex2\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/11\/Meyrin-Onex2.jpg\" alt=\"\" width=\"553\" height=\"307\" srcset=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/11\/Meyrin-Onex2.jpg 1024w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/11\/Meyrin-Onex2-300x166.jpg 300w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/11\/Meyrin-Onex2-660x366.jpg 660w\" sizes=\"(max-width: 553px) 100vw, 553px\" \/><\/a><p id=\"caption-attachment-8669\" class=\"wp-caption-text\">Turrisi r\u00e9duit la marque sur penalty<\/p><\/div>\n<p style=\"text-align: justify;\">Les Meyrinois poussent pour obtenir l\u2019\u00e9galisation et vont y parvenir dans les minutes suivantes\u00a0: \u00e0 la r\u00e9ception d\u2019un centre d\u2019Oliveira, Turrisi ne se fait pas prier pour \u00e9galiser les buts vides (67\u2019, 2-2).<\/p>\n<p style=\"text-align: justify;\">Dans sa joie, le jeune attaquant meyrinois retire son maillot, ce qui lui vaut un avertissement, obligeant ses co\u00e9quipiers \u00e0 \u00e9voluer en inf\u00e9riorit\u00e9 num\u00e9rique pendant 10 minutes. Dommage, puisque Meyrin semblait en position favorable pour l\u2019emporter lors des derni\u00e8res minutes, si l\u2019\u00e9quipe \u00e9tait rest\u00e9e \u00e0 11.<\/p>\n<div id=\"attachment_8670\" style=\"width: 563px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.footjuniors.ch\/Galerie\/thumbnails.php?album=1148\" target=\"_blank\"><img aria-describedby=\"caption-attachment-8670\" loading=\"lazy\" class=\"size-full wp-image-8670 \" title=\"Meyrin-Onex3\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/11\/Meyrin-Onex3.jpg\" alt=\"\" width=\"553\" height=\"373\" srcset=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/11\/Meyrin-Onex3.jpg 1024w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/11\/Meyrin-Onex3-300x202.jpg 300w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/11\/Meyrin-Onex3-660x444.jpg 660w\" sizes=\"(max-width: 553px) 100vw, 553px\" \/><\/a><p id=\"caption-attachment-8670\" class=\"wp-caption-text\">La joie du double buteur Turrisi<\/p><\/div>\n<p style=\"text-align: justify;\">Plus rien ne sera marqu\u00e9 et c&#8217;est la loterie des tirs au but qui d\u00e9cidera du champion genevois de juniors C.<\/p>\n<p style=\"text-align: justify;\"><strong>Interminables tirs au but<\/strong><\/p>\n<p style=\"text-align: justify;\">Lors de la s\u00e9ance des tirs au but, les 22 acteurs sur le terrain ont \u00e9t\u00e9 mis \u00e0 contribution, surtout les gardiens qui ont pos\u00e9 leurs v\u00e9tos \u00e0 maintes reprises. Alors que les 10 joueurs de chaque champ ont proc\u00e9d\u00e9, avec plus ou moins de r\u00e9ussite, \u00e0 leur tentative, le score est de 5-5 et c\u2019est au tour des gardiens de se lancer. Et c\u2019est le portier on\u00e9sien Da Silva qui va se transformer en h\u00e9ros\u00a0: il d\u00e9tourne la tentative de son homologue meyrinois Aeby, avant d\u2019inscrire le sien, synonyme de victoire finale.<\/p>\n<div id=\"attachment_8671\" style=\"width: 563px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.footjuniors.ch\/Galerie\/thumbnails.php?album=1148\" target=\"_blank\"><img aria-describedby=\"caption-attachment-8671\" loading=\"lazy\" class=\"size-full wp-image-8671  \" title=\"Meyrin-Onex4\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/11\/Meyrin-Onex4.jpg\" alt=\"\" width=\"553\" height=\"369\" srcset=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/11\/Meyrin-Onex4.jpg 1024w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/11\/Meyrin-Onex4-300x200.jpg 300w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/11\/Meyrin-Onex4-660x440.jpg 660w\" sizes=\"(max-width: 553px) 100vw, 553px\" \/><\/a><p id=\"caption-attachment-8671\" class=\"wp-caption-text\">Da Silva inscrit le penalty victorieux<\/p><\/div>\n<p style=\"text-align: justify;\">Sc\u00e8nes de liesse et explosions de joie on\u00e9siennes contrastaient avec la d\u00e9ception des Meyrinois. S\u2019il est difficile de perdre une finale, \u00e7a l\u2019est encore plus aux tirs au but.<\/p>\n<p style=\"text-align: justify;\">L\u2019entra\u00eeneur meyrinois, Eric Pasquettaz, restait malgr\u00e9 tout fier de ses prot\u00e9g\u00e9s\u00a0: \u00ab\u00a0Etre men\u00e9s 2-0 \u00e0 la mi-temps par une tr\u00e8s bonne \u00e9quipe d\u2019Onex et revenir au score dans ces conditions et sur un terrain tr\u00e8s gras, on ne peut qu\u2019\u00eatre fier d\u2019avoir un groupe aussi fantastique. Ils ont eu la volont\u00e9 d\u2019y croire jusqu\u2019au bout\u2026 et les penaltys, on sait que c\u2019est une loterie. Je souhaite plein de r\u00e9ussite au FC Onex en C inter et surtout, je f\u00e9licite toute mon \u00e9quipe pour ce merveilleux premier tour.\u00a0\u00bb<\/p>\n<p style=\"text-align: justify;\">Du c\u00f4t\u00e9 des vainqueurs, Wilson Rafael tenait d\u2019abord \u00e0 signaler \u00ab\u00a0un gros fair-play entre entra\u00eeneurs, ce qui a rendu le match tr\u00e8s correct au niveau des joueurs. Je pense que chaque \u00e9quipe a eu ses moments positifs et n\u00e9gatifs. Un grand chapeau aux deux \u00e9quipes car durant la s\u00e9ance de tirs au but, seul un tir sur 22 n\u2019a pas \u00e9t\u00e9 cadr\u00e9.\u00a0\u00bb<\/p>\n<div id=\"attachment_8677\" style=\"width: 563px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.footjuniors.ch\/Galerie\/thumbnails.php?album=1148\" target=\"_blank\"><img aria-describedby=\"caption-attachment-8677\" loading=\"lazy\" class=\"size-full wp-image-8677  \" title=\"Meyrin-Onex5\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/11\/Meyrin-Onex5.jpg\" alt=\"\" width=\"553\" height=\"369\" srcset=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/11\/Meyrin-Onex5.jpg 1024w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/11\/Meyrin-Onex5-300x200.jpg 300w, http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/11\/Meyrin-Onex5-660x440.jpg 660w\" sizes=\"(max-width: 553px) 100vw, 553px\" \/><\/a><p id=\"caption-attachment-8677\" class=\"wp-caption-text\">Le capitaine Domingues re\u00e7oit la coupe de champion genevois<\/p><\/div>\n<p style=\"text-align: justify;\">L\u2019entra\u00eeneur des jeunes on\u00e9siens concluait\u00a0: \u00ab\u00a0Je pense que par le football propos\u00e9 par mes juniors, cette victoire est m\u00e9rit\u00e9e et confirme leur travail effectu\u00e9 pendant ce premier tour. Je f\u00e9licite le FC Meyrin pour avoir eu la force d\u2019y croire jusqu\u2019au bout.&#8221;<\/p>\n<p style=\"text-align: justify;\">C&#8217;est en cat\u00e9gorie interr\u00e9gionale que les On\u00e9siens \u00e9volueront au printemps prochain. Ils seront rejoints en fin de journ\u00e9e par leurs a\u00een\u00e9s des juniors A, \u00e9galement champions genevois, qui compl\u00e8tent ainsi le trio avec les juniors B qui figuraient d\u00e9j\u00e0 dans cette cat\u00e9gorie.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p style=\"text-align: justify;\">Pour Proxifoot, Klebs Pyra<br \/>\nPhotos: <a href=\"http:\/\/www.footjuniors.ch\/Galerie\/thumbnails.php?album=1148\" target=\"_blank\">Foot Juniors<\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong>FC MEYRIN \u2013 FC ONEX\u00a0 2-2 (tab 5-6)<br \/>\n<\/strong>Stade de Vaudagne<\/p>\n<p style=\"text-align: justify;\"><strong>Buts<\/strong>\u00a0: 19\u2019 Monteleone 0-1, 38\u2019 Hoxhaj 0-2, 55\u2019 Turrisi (P) 1-2, 67\u2019 Turrisi 2-2<\/p>\n<p style=\"text-align: justify;\"><strong>Meyrin<\/strong> : Aeby, Valentini, Doberjanca, Blazevic \u00a9, Makangila, Buil, Oliveira, Fortunato, Clarke, Mehmeti, \u00a0Turrisi.<br \/>\nRempla\u00e7ants : Villoz, Katchelewa, Ukbabe, Domingues, De Oliveira, Garcia.<br \/>\nEntra\u00eeneurs : Eric Pasquettaz et Anthony Resta<\/p>\n<p style=\"text-align: justify;\"><strong>Onex<\/strong> : Da Silva, Aljiji, Monteiro, Vair, Demiri, Pasche, Monteleone, Pessoa \u00a9, Andrade, Pires, Aubert.<br \/>\nRempla\u00e7ants\u00a0: Mathez, Domingues, Manzengo, Hoxhaj, Ferati.<br \/>\nEntra\u00eeneurs : Wilson Rafael et Emanuel Machado<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Juniors C \/ Men\u00e9s 2-0 \u00e0 la mi-temps, les Meyrinois parviennent \u00e0 \u00e9galiser en seconde p\u00e9riode mais doivent s&#8217;incliner lors de la loterie des tirs au but.<\/p>\n","protected":false},"author":1,"featured_media":8665,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[7],"tags":[64,75],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.proxifoot.ch\/geneve\/2012\/11\/aux-tirs-au-but-onex-decroche-le-titre2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aux tirs au but, Onex d\u00e9croche le titre - Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"og:description\" content=\"Juniors C \/ Men\u00e9s 2-0 \u00e0 la mi-temps, les Meyrinois parviennent \u00e0 \u00e9galiser en seconde p\u00e9riode mais doivent s&#8217;incliner lors de la loterie des tirs au but.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.proxifoot.ch\/geneve\/2012\/11\/aux-tirs-au-but-onex-decroche-le-titre2\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2012-11-20T16:51:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-11-21T11:07:51+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/11\/Meyrin-Onex.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"626\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2012\/11\/aux-tirs-au-but-onex-decroche-le-titre2\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/11\/Meyrin-Onex.jpg\",\"width\":1024,\"height\":626},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2012\/11\/aux-tirs-au-but-onex-decroche-le-titre2\/#webpage\",\"url\":\"http:\/\/www.proxifoot.ch\/geneve\/2012\/11\/aux-tirs-au-but-onex-decroche-le-titre2\/\",\"name\":\"Aux tirs au but, Onex d\\u00e9croche le titre - Proxifoot, le m\\u00e9dia du football genevois\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2012\/11\/aux-tirs-au-but-onex-decroche-le-titre2\/#primaryimage\"},\"datePublished\":\"2012-11-20T16:51:42+00:00\",\"dateModified\":\"2012-11-21T11:07:51+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.proxifoot.ch\/geneve\/2012\/11\/aux-tirs-au-but-onex-decroche-le-titre2\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\",\"name\":\"admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/8663"}],"collection":[{"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=8663"}],"version-history":[{"count":0,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/8663\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/8665"}],"wp:attachment":[{"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=8663"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=8663"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=8663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}