﻿{"id":63717,"date":"2024-03-12T14:09:47","date_gmt":"2024-03-12T12:09:47","guid":{"rendered":"http:\/\/www.proxifoot.ch\/vaud\/home\/?p=63717"},"modified":"2024-03-12T14:09:47","modified_gmt":"2024-03-12T12:09:47","slug":"kubilay-karaca-offre-le-derby-lausannois-a-malley","status":"publish","type":"post","link":"http:\/\/www.proxifoot.ch\/vaud\/2024\/03\/kubilay-karaca-offre-le-derby-lausannois-a-malley\/","title":{"rendered":"Kubilay Karaca offre le derby lausannois \u00e0 Malley"},"content":{"rendered":"<p><strong>Malley a id\u00e9alement lanc\u00e9 son deuxi\u00e8me tour en arrachant la victoire dans le temps additionnel face \u00e0 Renens (2-3).<\/strong><\/p>\r\n<p><!--more--><\/p>\r\n<p>Pour son second match officiel en 2024, le FC Renens recevait son voisin Malley avec l\u2019objectif de prendre sa revanche du match aller. Les Renanais restaient sur une excellente dynamique en championnat avec une seule d\u00e9faite lors de leurs 10 derniers matchs. De son c\u00f4t\u00e9, l\u2019\u00e9quipe visiteuse souhaitait effacer la mauvaise dynamique affich\u00e9e en fin d\u2019ann\u00e9e (5 points sur les 7 derniers matchs). Mission accomplie pour l\u2019\u00e9quipe de Malley entrain\u00e9e par Paulo Da Cruz.<\/p>\r\n<p>Entre deux formations ayant la volont\u00e9 de ne pas prendre trop de risques, la premi\u00e8re mi-temps a \u00e9t\u00e9 pauvre en occasions. Cependant, une mauvaise relance de la d\u00e9fense renanaise a permis au meilleur buteur de Malley, Dani Cosme, d\u2019ouvrir le score (15\u2019 0-1). \u00c0 noter que les visiteurs ont subi deux coups du sort avec deux sorties sur blessure avant la pause.<\/p>\r\n<p><iframe title=\"Renens - Malley (2-3) : le premier but de Dani Cosme\" width=\"702\" height=\"395\" src=\"https:\/\/www.youtube.com\/embed\/WLs3IvFmD48?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\r\n<p><strong>Deuxi\u00e8me mi-temps d\u00e9brid\u00e9e<\/strong><\/p>\r\n<p>Au retour des vestiaires, la physionomie de la rencontre a pris une toute autre tournure. D\u00e8s le coup d\u2019envoi, les visiteurs se sont offert une \u00e9norme occasion d\u2019alourdir le score qui s\u2019est \u00e9cras\u00e9e sur le poteau de Quillet. Dans une p\u00e9riode de large domination des visiteurs, contre le cours du jeu, les pensionnaires du stade de Censuy ont \u00e9galis\u00e9 d&#8217;un magnifique lob du milieu de terrain de leur artificier Dragan Jankovic (51\u2019 1-1).\u00a0<em>&#8220;Le gardien \u00e9tait aux seize m\u00e8tres, j&#8217;ai essay\u00e9 de viser le cadre et voil\u00e0. Ce n&#8217;\u00e9tait pas compliqu\u00e9&#8221;,\u00a0<\/em>a expliqu\u00e9 le buteur \u00e0 l&#8217;interview.<\/p>\r\n<p>Alors que les Renanais pensaient prendre le contr\u00f4le des d\u00e9bats \u00e0 la suite de cette r\u00e9ussite, les joueurs de Malley ont rapidement repris l\u2019avantage avec le deuxi\u00e8me but de Cosme (56\u2019 1-2), parfaitement plac\u00e9 pour pousser le ballon au fond des filets \u00e0 la suite d\u2019un arr\u00eat du gardien renanais sur un tir d\u2019Eren.<\/p>\r\n<p>Bien d\u00e9cid\u00e9s \u00e0 ne pas s\u2019incliner une seconde fois face \u00e0 leurs voisins, les Renanais ont multipli\u00e9 les offensives. Leurs efforts ont \u00e9t\u00e9 r\u00e9compens\u00e9s par une nouvelle \u00e9galisation sur un but contre son camp de Sllamniku, sur un cafouillage d\u00e9fensif des visiteurs (77\u2019 2-2). Dans une fin de match riche en actions, les joueurs de Malley ont r\u00e9ussi \u00e0 faire craquer une ultime fois leur voisin lausannois dans le temps additionnel par une frappe pleine de sang froid de Karaca (91\u2019 2-3).<\/p>\r\n<p><iframe title=\"Renens - Malley (2-3) : le but de la victoire de Kubilay Karaca\" width=\"702\" height=\"395\" src=\"https:\/\/www.youtube.com\/embed\/H3CDqzQW1xE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\r\n<p><strong>Renens ne perd pas espoir<\/strong><\/p>\r\n<p>Avec ce succ\u00e8s, les visiteurs devancent d\u00e9sormais leur adversaire du jour au classement. Cependant, l\u2019\u00e9quipe de Paulo Da Cruz ne souhaite pas s\u2019enflammer apr\u00e8s cette reprise r\u00e9ussie. <em>\u00ab\u00a0On ne va pas se prendre la t\u00eate, on joue match par match (\u2026) on va essayer de tout donner pour la coupe\u00a0\u00bb,<\/em> soulignait le double buteur du jour \u00e0 l\u2019interview. Avec ces 3 points suppl\u00e9mentaires, ES Malley s\u2019offre un matelas confortable de 8 points sur le premier rel\u00e9gable tout en restant \u00e0 distance des meilleures \u00e9quipes du groupe.<\/p>\r\n<div id=\"attachment_63836\" style=\"width: 712px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.proxifoot.ch\/vaud\/home\/2024\/03\/kubilay-karaca-offre-le-derby-lausannois-a-malley\/capture-decran-2024-03-12-a-13-03-02\/\" rel=\"attachment wp-att-63836\"><img aria-describedby=\"caption-attachment-63836\" loading=\"lazy\" class=\"size-large wp-image-63836\" src=\"http:\/\/www.proxifoot.ch\/vaud\/wp-content\/uploads\/2024\/03\/Capture-de\u0301cran-2024-03-12-a\u0300-13.03.02-1024x641.png\" alt=\"\" width=\"702\" height=\"439\" srcset=\"http:\/\/www.proxifoot.ch\/vaud\/wp-content\/uploads\/2024\/03\/Capture-de\u0301cran-2024-03-12-a\u0300-13.03.02-1024x641.png 1024w, http:\/\/www.proxifoot.ch\/vaud\/wp-content\/uploads\/2024\/03\/Capture-de\u0301cran-2024-03-12-a\u0300-13.03.02-300x188.png 300w, http:\/\/www.proxifoot.ch\/vaud\/wp-content\/uploads\/2024\/03\/Capture-de\u0301cran-2024-03-12-a\u0300-13.03.02-768x481.png 768w, http:\/\/www.proxifoot.ch\/vaud\/wp-content\/uploads\/2024\/03\/Capture-de\u0301cran-2024-03-12-a\u0300-13.03.02-343x215.png 343w, http:\/\/www.proxifoot.ch\/vaud\/wp-content\/uploads\/2024\/03\/Capture-de\u0301cran-2024-03-12-a\u0300-13.03.02-326x205.png 326w, http:\/\/www.proxifoot.ch\/vaud\/wp-content\/uploads\/2024\/03\/Capture-de\u0301cran-2024-03-12-a\u0300-13.03.02.png 1440w\" sizes=\"(max-width: 702px) 100vw, 702px\" \/><\/a><p id=\"caption-attachment-63836\" class=\"wp-caption-text\">Malley est pass\u00e9 devant Renens au classement.<\/p><\/div>\r\n<p>De son c\u00f4t\u00e9, Renens r\u00e9alise une bien mauvaise op\u00e9ration et se retrouve d\u00e9sormais \u00e0 neuf longueurs des deux premi\u00e8res places. Malgr\u00e9 cette d\u00e9faite, les pensionnaires du stade de Censuy croient encore en leurs chances. <em>\u00ab\u00a0On va essayer de faire les finales. Ce n\u2019est pas encore fini. On vient de commencer, il y a encore beaucoup de matchs \u00e0 jouer, il y a encore beaucoup de points en jeu\u00a0\u00bb, <\/em>d\u00e9clare le capitaine renanais Dragan Jankovic. Il faudra retrouver le chemin de la victoire dimanche contre le Racing Club Lausanne dans un nouveau derby lausannois (10h). De son c\u00f4t\u00e9, Malley accueillera Lutry samedi \u00e0 19h30 pour tenter d\u2019encha\u00eener.<\/p>\r\n<p><iframe title=\"R\u00e9action de Dani Cosme apr\u00e8s Renens - Malley (2-3)\" width=\"702\" height=\"395\" src=\"https:\/\/www.youtube.com\/embed\/F5aiSRJzKgA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\r\n<p><iframe title=\"R\u00e9action de Dragan Jankovic apr\u00e8s Renens - Malley (2-3)\" width=\"702\" height=\"395\" src=\"https:\/\/www.youtube.com\/embed\/vjZ_tJ3h8JU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\r\n<blockquote>\r\n<p><strong>FC RENENS \u2013 ES MALLEY 2-3 (0-1)<br \/><\/strong>Stade du Censuy<\/p>\r\n<p><strong>Buts<\/strong>\u00a0: 15\u2019 Cosme, 51\u2019 Jankovic, 56\u2019 Cosme, 77\u2019 Sllamniku, 91\u2019 Karaca<\/p>\r\n<p><strong>Renens<\/strong> (4-4-1-1) : Quillet, Salhi, Bekteshi, Simic (Nicomedio 86\u2019), Tavares (Campigotto 71\u2019), Dongmo, Chiza, Bojkaj, Brero (Brero 46\u2019), Bamba (Pereira 46\u2019), Jankovic \u00a9.<br \/>Entra\u00eeneur : Toumi Trabelsi<\/p>\r\n<p><strong>Malley<\/strong> (4-5-1) : Roulier, Sllamniku, Ciftci (Da Silva Roque 11\u2019), Bao Nguyen, Cabaco Baiao, Ebibi (Kilinc 30\u2019), Mizero, Karaca, Cosme, Eren (Fetahi 86\u2019), Allouchi (Moraga 74\u2019).<br \/>Entra\u00eeneur : Paulo Da Cruz<\/p>\r\n<p><strong>Avertissements<\/strong>\u00a0: Dongmo (Renens, 23\u2019)<\/p>\r\n<\/blockquote>\r\n","protected":false},"excerpt":{"rendered":"<p>Malley a id\u00e9alement lanc\u00e9 son deuxi\u00e8me tour en arrachant la victoire dans le temps additionnel face \u00e0 Renens (2-3).<\/p>\n","protected":false},"author":202,"featured_media":63824,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[5],"tags":[930,932,142,931],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.proxifoot.ch\/vaud\/2024\/03\/kubilay-karaca-offre-le-derby-lausannois-a-malley\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kubilay Karaca offre le derby lausannois \u00e0 Malley\" \/>\n<meta property=\"og:description\" content=\"Malley a id\u00e9alement lanc\u00e9 son deuxi\u00e8me tour en arrachant la victoire dans le temps additionnel face \u00e0 Renens (2-3).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.proxifoot.ch\/vaud\/2024\/03\/kubilay-karaca-offre-le-derby-lausannois-a-malley\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-12T12:09:47+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.proxifoot.ch\/vaud\/wp-content\/uploads\/2024\/03\/renens_malley.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1404\" \/>\n\t<meta property=\"og:image:height\" content=\"672\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\">\n\t<meta name=\"twitter:data1\" content=\"4 minutes\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/vaud\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/vaud\/\",\"name\":\"Proxifoot\",\"description\":\"L&#039;actualit\\u00e9 du football vaudois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/vaud\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.proxifoot.ch\/vaud\/2024\/03\/kubilay-karaca-offre-le-derby-lausannois-a-malley\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"http:\/\/www.proxifoot.ch\/vaud\/wp-content\/uploads\/2024\/03\/renens_malley.png\",\"width\":1404,\"height\":672},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.proxifoot.ch\/vaud\/2024\/03\/kubilay-karaca-offre-le-derby-lausannois-a-malley\/#webpage\",\"url\":\"https:\/\/www.proxifoot.ch\/vaud\/2024\/03\/kubilay-karaca-offre-le-derby-lausannois-a-malley\/\",\"name\":\"Kubilay Karaca offre le derby lausannois \\u00e0 Malley\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/vaud\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.proxifoot.ch\/vaud\/2024\/03\/kubilay-karaca-offre-le-derby-lausannois-a-malley\/#primaryimage\"},\"datePublished\":\"2024-03-12T12:09:47+00:00\",\"dateModified\":\"2024-03-12T12:09:47+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/vaud\/#\/schema\/person\/de40a7df9ca41bd3a8931f511e97a841\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.proxifoot.ch\/vaud\/2024\/03\/kubilay-karaca-offre-le-derby-lausannois-a-malley\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/vaud\/#\/schema\/person\/de40a7df9ca41bd3a8931f511e97a841\",\"name\":\"Alexian Roduit\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"http:\/\/www.proxifoot.ch\/vaud\/wp-json\/wp\/v2\/posts\/63717"}],"collection":[{"href":"http:\/\/www.proxifoot.ch\/vaud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.proxifoot.ch\/vaud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.proxifoot.ch\/vaud\/wp-json\/wp\/v2\/users\/202"}],"replies":[{"embeddable":true,"href":"http:\/\/www.proxifoot.ch\/vaud\/wp-json\/wp\/v2\/comments?post=63717"}],"version-history":[{"count":8,"href":"http:\/\/www.proxifoot.ch\/vaud\/wp-json\/wp\/v2\/posts\/63717\/revisions"}],"predecessor-version":[{"id":63839,"href":"http:\/\/www.proxifoot.ch\/vaud\/wp-json\/wp\/v2\/posts\/63717\/revisions\/63839"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.proxifoot.ch\/vaud\/wp-json\/wp\/v2\/media\/63824"}],"wp:attachment":[{"href":"http:\/\/www.proxifoot.ch\/vaud\/wp-json\/wp\/v2\/media?parent=63717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.proxifoot.ch\/vaud\/wp-json\/wp\/v2\/categories?post=63717"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.proxifoot.ch\/vaud\/wp-json\/wp\/v2\/tags?post=63717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}