﻿{"id":10582,"date":"2013-04-10T22:51:42","date_gmt":"2013-04-10T21:51:42","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=10582"},"modified":"2016-07-20T17:18:54","modified_gmt":"2016-07-20T15:18:54","slug":"3eme-ligue-groupe-1-interstar-recupere-son-trone","status":"publish","type":"post","link":"https:\/\/www.proxifoot.ch\/geneve\/2013\/04\/3eme-ligue-groupe-1-interstar-recupere-son-trone\/","title":{"rendered":"3\u00e8me ligue, groupe 1 : Interstar r\u00e9cup\u00e8re son tr\u00f4ne"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>En s&#8217;imposant nettement \u00e0 Donzelle en match en retard, Interstar repasse devant Meinier et reprend sa place de leader.<!--more--><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>FC Donzelle \u00a0 &#8211; \u00a0 CS Interstar \u00a0 1 &#8211; 4<br \/>\nButs\u00a0<\/strong>: 8&#8242; Simoes 0-1, 30&#8242; Fricker 0-2, 35&#8242; Fricker 0-3, 40&#8242; Costa 1-3, 60&#8242; Marques 1-4<\/p>\n<p style=\"text-align: justify;\">Ce match en retard entre Donzelle et Interstar \u00e9tait d\u2019une importance capitale pour les deux \u00e9quipes. Pour Interstar, il s\u2019agissait de r\u00e9cup\u00e9rer la premi\u00e8re place qui lui a \u00e9chapp\u00e9 il y a quelques semaines, tandis que pour Donzelle, le but \u00e9tait de se rapprocher de la t\u00eate et de r\u00e9cup\u00e9rer une place sur le podium.<\/p>\n<p style=\"text-align: justify;\">Et les choses vont id\u00e9alement commencer pour les visiteurs. Pouss\u00e9s par leurs fid\u00e8les ultras qui les accompagnent dans les quatre coins du canton, les joueurs d\u2019Interstar ouvrent la marque apr\u00e8s quelques minutes lorsque Bruno Mota sert parfaitement Simoes pour le 1-0.<\/p>\n<p style=\"text-align: justify;\">Mais la suite tournera au drame pour les joueurs d\u2019Interstar. Au quart d\u2019heure de jeu, ce m\u00eame Mota subit un tacle d\u2019un d\u00e9fenseur local. R\u00e9sultat\u00a0: fracture du tibia et du p\u00e9ron\u00e9 pour le milieu de terrain des visiteurs. Apr\u00e8s cet \u00e9v\u00e8nement tragique qui a choqu\u00e9 tous les acteurs, le match peut reprendre apr\u00e8s une demi-heure d\u2019arr\u00eat en attendant l\u2019ambulance.<\/p>\n<p style=\"text-align: justify;\">Malgr\u00e9 tout, les joueurs d\u2019Interstar vont se remobiliser et marquer deux buts coup sur coup par Fricker, qui profite de deux erreurs dans la d\u00e9fense adverse. Les Donzellois parviennent \u00e0 r\u00e9duire le score \u00e0 1-3 avant la pause gr\u00e2ce \u00e0 une frappe enroul\u00e9e de Costa.<\/p>\n<p style=\"text-align: justify;\">Les pensionnaires de Varemb\u00e9 ne vont pas faiblir en seconde p\u00e9riode, et vont m\u00eame ajouter un 4\u00e8me but au compteur, inscrit par Marques apr\u00e8s un tir de Fricker repouss\u00e9.<\/p>\n<p style=\"text-align: justify;\">Au final, Interstar obtient une victoire probante sur le terrain toujours difficile du Stade du Moulin. L\u2019\u00e9quipe de Tiago Da Silva reprend ainsi la premi\u00e8re place au classement, comptant d\u00e9sormais deux points de plus que Meinier avec un match en retard.<\/p>\n<p style=\"text-align: justify;\">L\u2019entra\u00eeneur d\u2019Interstar revenait sur la blessure de son meneur de jeu : \u00ab\u00a0C&#8217;est une grosse perte pour nous car Bruno est un de nos meilleurs joueurs. Au nom de toute l&#8217;\u00e9quipe, je tiens \u00e0 lui dire que nous le soutenons et que nous ferons tout pour qu&#8217;il vive au mieux cette situation difficile, car au CS Interstar avant d&#8217;\u00eatre ses simples co\u00e9quipiers, nous sommes ses amis.\u00a0\u00bb<\/p>\n<p style=\"text-align: justify;\">Pour l\u2019entra\u00eeneur de Donzelle, Christian Lamers, l\u2019heure est aux regrets\u00a0: Notre manque de r\u00e9alisme devant le but nous a une nouvelle fois co\u00fbt\u00e9 des points. J\u2019attends une r\u00e9action de mon \u00e9quipe d\u00e8s dimanche.\u00a0\u00bb<\/p>\n<p style=\"text-align: justify;\">\u00ab\u00a0Je tiens, au nom de mon \u00e9quipe et du FC Donzelle, souhaiter un bon r\u00e9tablissement \u00e0 Bruno Mota, on esp\u00e8re qu\u2019il pourra retrouver le chemin des terrains dans un avenir aussi proche que possible\u00a0\u00bb, concluait-il.<\/p>\n<p style=\"text-align: justify;\">Les Donzellois recevront Onex II dimanche prochain, tandis qu\u2019Interstar aura la visite d\u2019A\u00efre-le-Lignon, l\u2019\u00e9quipe qui leur a fait subir leur seule d\u00e9faite de la saison.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-10583\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2013\/04\/3ligue-13-bis.jpg\" alt=\"3ligue-13-bis\" width=\"662\" height=\"327\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2013\/04\/3ligue-13-bis.jpg 662w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2013\/04\/3ligue-13-bis-300x148.jpg 300w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2013\/04\/3ligue-13-bis-660x326.jpg 660w\" sizes=\"(max-width: 662px) 100vw, 662px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En s&#8217;imposant nettement \u00e0 Donzelle en match en retard, Interstar repasse devant Meinier et reprend sa place de leader.<\/p>\n","protected":false},"author":1,"featured_media":6247,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[6],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.proxifoot.ch\/geneve\/2013\/04\/3eme-ligue-groupe-1-interstar-recupere-son-trone\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3\u00e8me ligue, groupe 1 : Interstar r\u00e9cup\u00e8re son tr\u00f4ne - Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"og:description\" content=\"En s&#8217;imposant nettement \u00e0 Donzelle en match en retard, Interstar repasse devant Meinier et reprend sa place de leader.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.proxifoot.ch\/geneve\/2013\/04\/3eme-ligue-groupe-1-interstar-recupere-son-trone\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2013-04-10T21:51:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-20T15:18:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/09\/banniere-3\u00e8me-ligue1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"164\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2013\/04\/3eme-ligue-groupe-1-interstar-recupere-son-trone\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/09\/banniere-3\\u00e8me-ligue1.jpg\",\"width\":660,\"height\":164},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2013\/04\/3eme-ligue-groupe-1-interstar-recupere-son-trone\/#webpage\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/2013\/04\/3eme-ligue-groupe-1-interstar-recupere-son-trone\/\",\"name\":\"3\\u00e8me ligue, groupe 1 : Interstar r\\u00e9cup\\u00e8re son tr\\u00f4ne - Proxifoot, le m\\u00e9dia du football genevois\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2013\/04\/3eme-ligue-groupe-1-interstar-recupere-son-trone\/#primaryimage\"},\"datePublished\":\"2013-04-10T21:51:42+00:00\",\"dateModified\":\"2016-07-20T15:18:54+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.proxifoot.ch\/geneve\/2013\/04\/3eme-ligue-groupe-1-interstar-recupere-son-trone\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\",\"name\":\"admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/10582"}],"collection":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=10582"}],"version-history":[{"count":0,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/10582\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/6247"}],"wp:attachment":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=10582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=10582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=10582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}