﻿{"id":11109,"date":"2013-04-28T22:30:54","date_gmt":"2013-04-28T21:30:54","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=11109"},"modified":"2016-07-20T17:17:32","modified_gmt":"2016-07-20T15:17:32","slug":"3eme-ligue-groupe-2-trois-matchs-renvoye","status":"publish","type":"post","link":"https:\/\/www.proxifoot.ch\/geneve\/2013\/04\/3eme-ligue-groupe-2-trois-matchs-renvoye\/","title":{"rendered":"3\u00e8me ligue, groupe 2 : trois matchs renvoy\u00e9s"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>18\u00e8me journ\u00e9e \/ Seuls trois matchs ont eu lieu en raison de la pluie de samedi. Champel, qui aurait pu tuer le suspense dans ce championnat, est tenu en \u00e9chec par Puplinge, ce qui pourrait profiter \u00e0 R\u00e9gina.<!--more--><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>Signal FC Bernex-Confignon II\u00a0 \u00a0\u2013 \u00a0\u00a0FC Vernier II \u00a0 1 &#8211; 2<br \/>\nButs :<\/strong> Gobbi 1-0, Mota 1-1, Rochat 1-2<\/p>\n<p style=\"text-align: justify;\">Signal-Bernex II, qui restait sur trois d\u00e9faites d\u2019affil\u00e9e, recevait Vernier II dans l\u2019espoir de retrouver le chemin de la victoire.<\/p>\n<p style=\"text-align: justify;\">Les Bern\u00e9siens commencent id\u00e9alement la partie, puisqu\u2019ils parviennent \u00e0 prendre l\u2019avantage sur un coup-franc de Gobbi d\u00e8s le quart d\u2019heure de jeu. La suite de la p\u00e9riode est \u00e0 mettre au compte des locaux, qui se montrent plus dangereux que leurs adversaires sans r\u00e9ussir toutefois \u00e0 doubler la mise.<\/p>\n<p style=\"text-align: justify;\">Au retour des vestiaires, Vernier II montre un tout autre football. Sur un cafouillage sur un corner, Mota \u00e9galise d\u2019ailleurs pour les visiteurs. Quinze minutes plus tard, une t\u00eate de Rochat permet aux Verniolans de prendre une longueur d\u2019avance. Le match s\u2019emballe alors, les deux \u00e9quipes se procurant des occasions. Les Bern\u00e9siens sont tout proches de revenir au score \u00e0 dix minutes du terme de la partie, lorsqu\u2019ils b\u00e9n\u00e9ficient d\u2019un penalty. Mais le buteur Gobbi manque sa tentative.<\/p>\n<p style=\"text-align: justify;\">Vernier II repart donc avec les trois points. Jos\u00e9-Manuel Dinis soulignait la r\u00e9action des siens en deuxi\u00e8me p\u00e9riode : \u00ab Apr\u00e8s une premi\u00e8re mi-temps, o\u00f9 nous sommes pass\u00e9s compl\u00e8tement \u00e0 travers, nous avons bien corrig\u00e9 le tir et avons pris le contr\u00f4le du match en deuxi\u00e8me mi-temps. C&#8217;est une belle journ\u00e9e pour Vernier qui remporte les six points dans ses matches contre Bernex, la premi\u00e8re \u00e9quipe ayant gagn\u00e9 3-0 \u00bb.<\/p>\n<p style=\"text-align: justify;\">De son c\u00f4t\u00e9, Jos\u00e9 Monnerat confiait que son \u00e9quipe traverse \u00ab une mauvaise passe \u00bb. L\u2019entra\u00eeneur bern\u00e9sien ajoutait : \u00ab M\u00eame si je suis content du jeu produit, il n&#8217;en demeure pas moins qu&#8217;\u00e0 la sortie c&#8217;est une nouvelle d\u00e9faite qui est dure \u00e0 encaisser. On va se mobiliser et tout faire pour inverser la tendance actuelle. \u00bb<\/p>\n<p style=\"text-align: justify;\">Les Bern\u00e9siens essayeront de sortir de leur spirale n\u00e9gative face \u00e0 Puplinge dimanche prochain, tandis que Vernier II accueillera Saint-Paul.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>FC Champel\u00a0 \u00a0\u2013 \u00a0\u00a0FC Puplinge \u00a0 1 &#8211; 1<br \/>\nButs : <\/strong>Ghazraoui 0-1, Schwarb 1-1<\/p>\n<p style=\"text-align: justify;\">Dans sa lutte pour le maintien, Puplinge a r\u00e9ussi \u00e0 obtenir un bon point face \u00e0 Champel. D\u2019autant plus que les Champelois ont eu de multiples occasions pour remporter la victoire. Pascal P\u00eacheur avouait d\u2019ailleurs : \u00ab C\u2019est un match qui me laisse sur ma faim. \u00bb<\/p>\n<p style=\"text-align: justify;\">Les Champelois ont r\u00e9alis\u00e9 une bonne entame de match ponctu\u00e9e de plusieurs occasions, qui auraient pu leur permettre de prendre l\u2019avantage. Apr\u00e8s ce premier quart d\u2019heure champelois, les Puplingeois ont profit\u00e9 d\u2019une action de rupture pour ouvrir le score par Ghazraoui.<\/p>\n<p style=\"text-align: justify;\">\u00ab Ensuite, nous avons manqu\u00e9 de liant et de rythme \u00bb, expliquait Pascal P\u00eacheur. Malgr\u00e9 cela, Schwarb a permis \u00e0 son \u00e9quipe de revenir au score juste avant la pause.<\/p>\n<p style=\"text-align: justify;\">La seconde p\u00e9riode s&#8217;est r\u00e9sum\u00e9e \u00e0 une attaque-d\u00e9fense. Les Champelois se sont alors montr\u00e9s maladroits, voire malchanceux, comme le confirme leur entra\u00eeneur : \u00ab Le portier de Puplinge a livr\u00e9 une grande partie et &#8220;les poteaux \u00e9taient carr\u00e9s&#8221; pour nous, puisqu\u2019on les touche quatre fois. \u00bb<\/p>\n<p style=\"text-align: justify;\">A l\u2019approche du terme de la partie, Champel aurait pu tout perdre, puisqu\u2019un tir puissant de Ghazraoui a \u00e9t\u00e9 d\u00e9vi\u00e9 sur le poteau d\u2019Andreoli. Les deux \u00e9quipes se sont finalement quitt\u00e9es sur un match nul.<\/p>\n<p style=\"text-align: justify;\">Pascal P\u00eacheur nous livrait ses impressions : \u00ab Nous perdons deux points par notre faute. Nous allons travailler fort cette semaine \u00e0 l&#8217;entrainement afin de faire un grand match face \u00e0 City samedi. Nous savons que ce sera compliqu\u00e9 de s&#8217;imposer l\u00e0-bas mais nous serons pr\u00eats. \u00bb<\/p>\n<p style=\"text-align: justify;\">Quant aux Puplingeois, ils devront confirmer ce bon point dimanche face \u00e0 Signal-Bernex II.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>FC Rapid Jonction Bosna\u00a0 \u00a0\u2013 \u00a0\u00a0FC Meyrin II \u00a0 0 &#8211; 3\u00a0<\/strong><br \/>\n<strong>Buts :<\/strong> 50&#8242; Perrelet 0-1, 55&#8242; Da Silva 0-2, 75&#8242; Ferreira 0-3<\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s avoir remport\u00e9 ses deux derni\u00e8res rencontres, Meyrin II a r\u00e9ussi la passe de trois face \u00e0 Rapid Jonction Bosna. Pourtant, les Meyrinois ont d\u00fb attendre la deuxi\u00e8me mi-temps pour faire la diff\u00e9rence.<\/p>\n<p style=\"text-align: justify;\">En premi\u00e8re p\u00e9riode, les visiteurs n\u2019ont pas convaincu par le jeu, comme l\u2019explique Tiago Terrinha : \u00ab M\u00eame si trois occasions nettes sont \u00e0 comptabiliser, nous avons fait une mi-temps o\u00f9 la qualit\u00e9 de jeu n&#8217;y \u00e9tait pas \u00bb. De son c\u00f4t\u00e9, Senad Kospo estimait que son \u00e9quipe avait r\u00e9alis\u00e9 une bonne premi\u00e8re mi-temps : \u00ab Dans le jeu, on leur a tenu t\u00eate et on aurait pu \u00eatre devant au score, mais on a p\u00each\u00e9 \u00e0 la conclusion. \u00bb<\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s la pause, faisant valoir le jeu collectif, les Meyrinois ont rapidement ouvert le score gr\u00e2ce \u00e0 Perrelet. Cinq minutes plus tard, Da Silva a doubl\u00e9 la mise. Face \u00e0 ces deux buts, Rapid Jonction Bosna n\u2019a pas r\u00e9ussi \u00e0 r\u00e9agir. Meyrin II s\u2019est encore cr\u00e9\u00e9 quelques occasions et a fini logiquement par inscrire un troisi\u00e8me but.<\/p>\n<p style=\"text-align: justify;\">\u00ab Nous n\u2019avons pas eu beaucoup d\u2019id\u00e9es et surtout nous avons eu trop de d\u00e9chets techniques pour pouvoir esp\u00e9rer quelque chose dans ce match. La faute aussi \u00e0 notre adversaire, le FC Meyrin, qui nous n&#8217;a pas laiss\u00e9 d\u2019espace en faisant un match plein \u00bb, analysait Senad Kospo.<\/p>\n<p style=\"text-align: justify;\">\u00ab Il faut continuer \u00e0 travailler, il nous reste quatre matches et l\u2019objectif du maintien est encore loin d\u2019\u00eatre r\u00e9alis\u00e9 ! A nous de nous reprendre d\u00e8s dimanche prochain sur le terrain de Plan-les-Ouates ! \u00bb, concluait l\u2019entra\u00eeneur bosniaque.<\/p>\n<p style=\"text-align: justify;\">Tiago Terrinha nous livrait \u00e9galement ses impressions : \u00ab C&#8217;est une victoire m\u00e9rit\u00e9e pour l&#8217;\u00e9quipe, dommage qu&#8217;on ait d\u00fb attendre 45 minutes pour imposer notre jeu alors qu&#8217;on avait toutes les cartes en main. \u00bb<\/p>\n<p style=\"text-align: justify;\">Gr\u00e2ce \u00e0 ce succ\u00e8s, Meyrin II se relance dans la lutte pour le podium. Les Meyrinois tenteront d\u2019obtenir un quatri\u00e8me succ\u00e8s cons\u00e9cutif face \u00e0 Grand-Saconnex dimanche prochain.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>FC Saint-Paul\u00a0 \u00a0\u2013 \u00a0\u00a0Athl\u00e9tique-R\u00e9gina FC \u00a0<\/strong>\u00a0\u00a0\u00a0<em>Renvoy\u00e9<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>FC Grand-Saconnex\u00a0 \u00a0\u2013 \u00a0\u00a0FC City \u00a0<\/strong>\u00a0\u00a0\u00a0<em>Renvoy\u00e9<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>FC Satigny\u00a0 \u00a0\u2013 \u00a0\u00a0FC Plan-les-Ouates II \u00a0<\/strong>\u00a0\u00a0\u00a0<em>Renvoy\u00e9<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-11135\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2013\/04\/3ligue2-18.jpg\" alt=\"3ligue2-18\" width=\"641\" height=\"322\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2013\/04\/3ligue2-18.jpg 641w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2013\/04\/3ligue2-18-300x150.jpg 300w\" sizes=\"(max-width: 641px) 100vw, 641px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>18\u00e8me journ\u00e9e \/ Seuls trois matchs ont eu lieu en raison de la pluie de samedi. Champel, qui aurait pu tuer le suspense dans ce championnat, est tenu en \u00e9chec par Puplinge, ce qui pourrait profiter \u00e0 R\u00e9gina.<\/p>\n","protected":false},"author":1,"featured_media":6245,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[6],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.proxifoot.ch\/geneve\/2013\/04\/3eme-ligue-groupe-2-trois-matchs-renvoye\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3\u00e8me ligue, groupe 2 : trois matchs renvoy\u00e9s - Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"og:description\" content=\"18\u00e8me journ\u00e9e \/ Seuls trois matchs ont eu lieu en raison de la pluie de samedi. Champel, qui aurait pu tuer le suspense dans ce championnat, est tenu en \u00e9chec par Puplinge, ce qui pourrait profiter \u00e0 R\u00e9gina.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.proxifoot.ch\/geneve\/2013\/04\/3eme-ligue-groupe-2-trois-matchs-renvoye\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2013-04-28T21:30:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-20T15:17:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/09\/banniere-3\u00e8me-ligue2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"164\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2013\/04\/3eme-ligue-groupe-2-trois-matchs-renvoye\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/09\/banniere-3\\u00e8me-ligue2.jpg\",\"width\":660,\"height\":164},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2013\/04\/3eme-ligue-groupe-2-trois-matchs-renvoye\/#webpage\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/2013\/04\/3eme-ligue-groupe-2-trois-matchs-renvoye\/\",\"name\":\"3\\u00e8me ligue, groupe 2 : trois matchs renvoy\\u00e9s - Proxifoot, le m\\u00e9dia du football genevois\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2013\/04\/3eme-ligue-groupe-2-trois-matchs-renvoye\/#primaryimage\"},\"datePublished\":\"2013-04-28T21:30:54+00:00\",\"dateModified\":\"2016-07-20T15:17:32+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.proxifoot.ch\/geneve\/2013\/04\/3eme-ligue-groupe-2-trois-matchs-renvoye\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\",\"name\":\"admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/11109"}],"collection":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=11109"}],"version-history":[{"count":0,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/11109\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/6245"}],"wp:attachment":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=11109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=11109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=11109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}