﻿{"id":11412,"date":"2013-05-08T23:47:46","date_gmt":"2013-05-08T22:47:46","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=11412"},"modified":"2016-07-20T17:17:09","modified_gmt":"2016-07-20T15:17:09","slug":"3eme-ligue-groupe-2-le-grand-sac-proche-du-maintien","status":"publish","type":"post","link":"https:\/\/www.proxifoot.ch\/geneve\/2013\/05\/3eme-ligue-groupe-2-le-grand-sac-proche-du-maintien\/","title":{"rendered":"3\u00e8me ligue, groupe 2 : le Grand-Sac&#8217; proche du maintien"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Dans un match \u00e0 six points, Grand-Saconnex vient \u00e0 bout de City (2-0) et prend quatre longueurs d&#8217;avance sur la barre.<\/strong><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>FC Grand-Saconnex \u00a0 &#8211; \u00a0 FC City \u00a0 2 &#8211; 0<br \/>\n<\/strong><span style=\"font-size: 13px; line-height: 19px;\"><strong>Buts\u00a0<\/strong>: Righi 1-0, Silva 2-0<\/span><\/p>\n<p style=\"text-align: justify;\">A \u00e9galit\u00e9 avec 19 points au compteur, le gagnant de ce match en retard pouvait prendre quatre points d&#8217;avance sur la barre et envisager les trois derni\u00e8res journ\u00e9es avec un peu moins de pression.<\/p>\n<p style=\"text-align: justify;\">Sur la pelouse du Stade du Blanch\u00e9, la possession est pour les locaux qui sont plus d\u00e9termin\u00e9s \u00e0 chercher les trois points contre une \u00e9quipe de City plus timide qui cherchait \u00e0 exploiter les contres et les balles arr\u00eat\u00e9es.<\/p>\n<p style=\"text-align: justify;\">Le tournant du match arrive vers l&#8217;heure de jeu, lorsque l&#8217;entra\u00eeneur local Eugenio Rendeiro prend le risque de passer \u00e0 trois d\u00e9fenseurs. &#8220;Je voulais gagner le match et la prise de risque de notre part de passer \u00e0 trois d\u00e9fenseurs a \u00e9t\u00e9 tout de suite payante puisque 10 minutes plus tard, on ouvre le score&#8221;, nous d\u00e9clarait-il. C&#8217;est Righi, fraichement rentr\u00e9, qui va en effet marquer sur corner. Cinq minutes plus tard, les Saconn\u00e9siens doublent la mise par l&#8217;interm\u00e9diaire de Silva qui, bien servi par Nuredini, fusille le gardien des visiteurs.<\/p>\n<div id=\"attachment_11427\" style=\"width: 619px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-11427\" loading=\"lazy\" class=\" wp-image-11427\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2013\/05\/Grand-Sac-City.jpg\" alt=\"Grand Sac-City\" width=\"609\" height=\"407\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2013\/05\/Grand-Sac-City.jpg 870w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2013\/05\/Grand-Sac-City-300x200.jpg 300w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2013\/05\/Grand-Sac-City-660x440.jpg 660w\" sizes=\"(max-width: 609px) 100vw, 609px\" \/><p id=\"caption-attachment-11427\" class=\"wp-caption-text\">Les Saconn\u00e9siens prennent le dessus sur City (Photo: IV Sport)<\/p><\/div>\n<p style=\"text-align: justify;\">Pour Rendeiro, c&#8217;\u00e9tait &#8220;un match qui a mis du temps \u00e0 se d\u00e9cider mais qui a vu la meilleure \u00e9quipe gagner et surtout celle qui a tout fait pour prendre les trois points! Pour une fois, la logique a \u00e9t\u00e9 respect\u00e9e pour l&#8217;\u00e9quipe qui voulait gagner et une autre qui est venue chercher un point et peut-\u00eatre gagner le match en contre.&#8221;<\/p>\n<p style=\"text-align: justify;\">&#8220;Je veux f\u00e9liciter tout le monde y compris les bless\u00e9s, comit\u00e9, supporters qui \u00e9taient tous l\u00e0 pour supporter l&#8217;\u00e9quipe qui, je pense, a fait un pas vers le maintien, mais rien n&#8217;est encore fait alors il faut continuer \u00e0 travailler&#8230;&#8221; Les Saconn\u00e9siens affronteront le leader Champel dimanche &#8211; &#8220;p<span style=\"font-size: 13px; line-height: 19px;\">our une fois, ce n&#8217;est pas nous qui avons la pression!&#8221;, concluait Rendeiro &#8211; tandis<\/span><span style=\"font-size: 13px; line-height: 19px;\">\u00a0que City, qui reste menac\u00e9 par la barre, se rendra \u00e0 Bernex.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-11413\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2013\/05\/3ligue2-19bis.jpg\" alt=\"3ligue2-19bis\" width=\"582\" height=\"337\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2013\/05\/3ligue2-19bis.jpg 582w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2013\/05\/3ligue2-19bis-300x173.jpg 300w\" sizes=\"(max-width: 582px) 100vw, 582px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans un match \u00e0 six points, Grand-Saconnex vient \u00e0 bout de City (2-0) et prend quatre longueurs d&#8217;avance sur la barre.<\/p>\n","protected":false},"author":1,"featured_media":6245,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[6],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.proxifoot.ch\/geneve\/2013\/05\/3eme-ligue-groupe-2-le-grand-sac-proche-du-maintien\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3\u00e8me ligue, groupe 2 : le Grand-Sac&#039; proche du maintien - Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"og:description\" content=\"Dans un match \u00e0 six points, Grand-Saconnex vient \u00e0 bout de City (2-0) et prend quatre longueurs d&#8217;avance sur la barre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.proxifoot.ch\/geneve\/2013\/05\/3eme-ligue-groupe-2-le-grand-sac-proche-du-maintien\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2013-05-08T22:47:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-20T15:17:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/09\/banniere-3\u00e8me-ligue2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"164\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2013\/05\/3eme-ligue-groupe-2-le-grand-sac-proche-du-maintien\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/09\/banniere-3\\u00e8me-ligue2.jpg\",\"width\":660,\"height\":164},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2013\/05\/3eme-ligue-groupe-2-le-grand-sac-proche-du-maintien\/#webpage\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/2013\/05\/3eme-ligue-groupe-2-le-grand-sac-proche-du-maintien\/\",\"name\":\"3\\u00e8me ligue, groupe 2 : le Grand-Sac' proche du maintien - Proxifoot, le m\\u00e9dia du football genevois\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2013\/05\/3eme-ligue-groupe-2-le-grand-sac-proche-du-maintien\/#primaryimage\"},\"datePublished\":\"2013-05-08T22:47:46+00:00\",\"dateModified\":\"2016-07-20T15:17:09+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.proxifoot.ch\/geneve\/2013\/05\/3eme-ligue-groupe-2-le-grand-sac-proche-du-maintien\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\",\"name\":\"admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/11412"}],"collection":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=11412"}],"version-history":[{"count":0,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/11412\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/6245"}],"wp:attachment":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=11412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=11412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=11412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}