﻿{"id":12977,"date":"2013-08-28T10:10:05","date_gmt":"2013-08-28T09:10:05","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=12977"},"modified":"2013-08-28T10:11:36","modified_gmt":"2013-08-28T09:11:36","slug":"formation-darbitres-debutants-pour-le-championnat-de-juniors-c","status":"publish","type":"post","link":"https:\/\/www.proxifoot.ch\/geneve\/2013\/08\/formation-darbitres-debutants-pour-le-championnat-de-juniors-c\/","title":{"rendered":"Formation d&#8217;arbitres d\u00e9butants pour le championnat de juniors C"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Vous souhaitez d\u00e9buter dans le monde de l\u2019arbitrage ? N\u2019h\u00e9sitez plus et lancez-vous dans une nouvelle aventure.<!--more--><\/strong><\/p>\n<p style=\"text-align: justify;\">Chaque ann\u00e9e, l\u2019ASF propose des cours de base pour arbitres d\u00e9butants. Voici le programme des prochaines s\u00e9ances :<\/p>\n<p style=\"text-align: justify;\">&#8211; Le prochain cours de formation d\u2019arbitres d\u00e9butera le mardi 3 septembre 2013 \u00e0 18h30 par un\u00a0<strong>test physique<\/strong>\u00a0au stade du Bout-du-Monde (veuillez vous munir d\u2019une tenue de sport).<\/p>\n<p style=\"text-align: justify;\">&#8211; Le\u00a0<strong>cours th\u00e9orique<\/strong>\u00a0se tiendra du vendredi 13 septembre 2013 \u00e0 18h45 au dimanche 15 septembre 2012 \u00e0 18h au stade municipal de Bernex.<\/p>\n<p style=\"text-align: justify;\">Toutes les informations et le formulaire d\u2019inscription peuvent \u00eatre t\u00e9l\u00e9charg\u00e9s sur le site de l\u2019ACGF. Pour acc\u00e9der directement au formulaire d\u2019inscription,\u00a0<a href=\"http:\/\/www.acgf.ch\/Portaldata\/13\/Resources\/Dossier_Info___inscription_cours_d_butants_2-2013.pdf\" target=\"_blank\">cliquez\u00a0ici<\/a>.<\/p>\n<p>L&#8217;inscription doit inclure :<\/p>\n<p style=\"padding-left: 30px;\">&#8211; Le formulaire d\u00fbment compl\u00e9t\u00e9<br \/>\n&#8211; Deux photos<br \/>\n&#8211; Une copie de votre pi\u00e8ce d&#8217;identit\u00e9<\/p>\n<p>Votre inscription doit \u00eatre envoy\u00e9e\u00a0<span style=\"text-decoration: underline;\">avant le 30 ao\u00fbt<\/span> \u00e0 l&#8217;adresse suivante :<\/p>\n<p style=\"text-align: left; padding-left: 30px;\"><strong>Monsieur Malik Ezzrari<\/strong><br \/>\n<strong> 34, Avenue Ernest-Pictet<\/strong><br \/>\n<strong> 1203 Gen\u00e8ve\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Photo: OneClick-Photo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous souhaitez d\u00e9buter dans le monde de l\u2019arbitrage ? N\u2019h\u00e9sitez plus et lancez-vous dans une nouvelle aventure.<\/p>\n","protected":false},"author":1,"featured_media":12978,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.proxifoot.ch\/geneve\/2013\/08\/formation-darbitres-debutants-pour-le-championnat-de-juniors-c\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Formation d&#039;arbitres d\u00e9butants pour le championnat de juniors C - Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"og:description\" content=\"Vous souhaitez d\u00e9buter dans le monde de l\u2019arbitrage ? N\u2019h\u00e9sitez plus et lancez-vous dans une nouvelle aventure.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.proxifoot.ch\/geneve\/2013\/08\/formation-darbitres-debutants-pour-le-championnat-de-juniors-c\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2013-08-28T09:10:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-08-28T09:11:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2013\/08\/arbitres-2013.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1134\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2013\/08\/formation-darbitres-debutants-pour-le-championnat-de-juniors-c\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2013\/08\/arbitres-2013.jpg\",\"width\":1134,\"height\":683},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2013\/08\/formation-darbitres-debutants-pour-le-championnat-de-juniors-c\/#webpage\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/2013\/08\/formation-darbitres-debutants-pour-le-championnat-de-juniors-c\/\",\"name\":\"Formation d'arbitres d\\u00e9butants pour le championnat de juniors C - Proxifoot, le m\\u00e9dia du football genevois\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2013\/08\/formation-darbitres-debutants-pour-le-championnat-de-juniors-c\/#primaryimage\"},\"datePublished\":\"2013-08-28T09:10:05+00:00\",\"dateModified\":\"2013-08-28T09:11:36+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.proxifoot.ch\/geneve\/2013\/08\/formation-darbitres-debutants-pour-le-championnat-de-juniors-c\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\",\"name\":\"admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/12977"}],"collection":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=12977"}],"version-history":[{"count":0,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/12977\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/12978"}],"wp:attachment":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=12977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=12977"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=12977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}