﻿{"id":13311,"date":"2013-09-08T22:57:11","date_gmt":"2013-09-08T21:57:11","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=13311"},"modified":"2016-07-20T11:35:28","modified_gmt":"2016-07-20T09:35:28","slug":"2eme-ligue-inter-plan-les-ouates-sur-sa-lancee","status":"publish","type":"post","link":"https:\/\/www.proxifoot.ch\/geneve\/2013\/09\/2eme-ligue-inter-plan-les-ouates-sur-sa-lancee\/","title":{"rendered":"2\u00e8me ligue inter : Plan-les-Ouates sur sa lanc\u00e9e"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>5\u00e8me journ\u00e9e \/ Les huit \u00e9quipes genevoises se sont affront\u00e9es entre elles lors de cette journ\u00e9e de derbys, avec des victoires de Perly, Collex, Plan-les-Ouates et Bernex.<\/strong><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>FC Perly-Certoux\u00a0 \u00a0\u2013 \u00a0 \u00a0FC Vernier \u00a0 2 &#8211; 1<br \/>\nButs\u00a0<\/strong>: 4\u2019 Randrianantenaina 0-1, 63\u2019 Bouamri 0-2, 74\u2019 Fellah 1-2<\/p>\n<p style=\"text-align: justify;\">Le derby de vendredi entre Perly et Vernier a pench\u00e9 en faveur de l\u2019\u00e9quipe locale, mettant ainsi un terme \u00e0 la bonne s\u00e9rie de trois matches sans d\u00e9faite des Verniolans.<\/p>\n<p style=\"text-align: justify;\">Un match qui va vite tourner en faveur de Perly gr\u00e2ce \u00e0 un but tr\u00e8s rapide de Randrianantenaina apr\u00e8s quatre petites minutes de jeu. Par la suite, la premi\u00e8re mi-temps va globalement \u00eatre ma\u00eetris\u00e9e par les locaux alors que Vernier tente de r\u00e9agir, sans succ\u00e8s.<\/p>\n<p style=\"text-align: justify;\">A l\u2019heure de jeu, Perly va \u00e0 nouveau concr\u00e9tiser une action et ainsi prendre le break d\u00e9finitif par Bouamri. L\u2019expulsion de ce m\u00eame Bouamri et la r\u00e9duction du score de Fellah ne changeront rien au r\u00e9sultat final. Un r\u00e9sultat qui, paradoxalement, donne confiance aux perdants et laisse l\u2019entra\u00eeneur des vainqueurs insatisfait\u00a0: \u00ab\u00a0Les trois points sont le seul point positif de cette rencontre pour nous. Mes joueurs m\u2019ont d\u00e9\u00e7u en tombant trop dans la facilit\u00e9 apr\u00e8s chaque r\u00e9ussite. J\u2019attends mieux d\u2019eux et ils le savent\u00bb, constatait Mario Chedly.<\/p>\n<p style=\"text-align: justify;\">Pour Patrick Tami, l\u2019ouverture du score tr\u00e8s rapide n\u2019a rien arrang\u00e9, mais la confiance reste de mise\u00a0: \u00ab\u00a0On doit vite, trop vite courir apr\u00e8s le score, et contre une \u00e9quipe comme Perly, c\u2019est encore plus difficile. Mais nous avons, de nouveau, eu une belle r\u00e9action d\u2019orgueil qui me fait penser que ce groupe doit prendre confiance en ses qualit\u00e9s et ses capacit\u00e9s.\u00a0\u00bb<\/p>\n<p style=\"text-align: justify;\">\u00ab\u00a0Maintenant, on va profiter des dix jours de repos pour recharges les batteries et pr\u00e9parer le d\u00e9placement de Stade-Lausanne-Ouchy le 18 septembre prochain \u00bb, concluait-il.<\/p>\n<p style=\"text-align: justify;\">Pour Perly, qui f\u00eate son troisi\u00e8me succ\u00e8s cons\u00e9cutif, c\u2019est un derby face \u00e0 une autre \u00e9quipe en forme, Plan-les-Ouates, qui les attend vendredi prochain.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Servette FC M-21\u00a0 \u00a0\u2013 \u00a0 \u00a0FC Collex-Bossy \u00a0 0 &#8211; 5\u00a0<\/strong><br \/>\n<em><a title=\"Collex foudroie un Servette M-21 trop l\u00e9ger\" href=\"http:\/\/www.proxifoot.ch\/geneve\/2013\/09\/collex-foudroie-un-servette-m-21-trop-leger\/\"><strong>Lire l&#8217;article<\/strong><\/a><\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>FC UGS\u00a0 \u00a0\u2013 \u00a0 \u00a0FC Plan-les-Ouates \u00a0 0 &#8211; 2<br \/>\nButs<\/strong> : 11\u2019 Bajrami 0-1, 75\u2019 Bajrami 0-2<\/p>\n<p style=\"text-align: justify;\">Plan-les-Ouates continue sur sa lanc\u00e9e. Quatri\u00e8me victoire cons\u00e9cutive pour les hommes de Dominique Coelho qui sont venus \u00e0 bout ce week-end d\u2019UGS gr\u00e2ce \u00e0 un doubl\u00e9 de Behar Bajrami \u00e0 Frontenex. Dans l\u2019ensemble, chaque \u00e9quipe a eu une mi-temps, mais au final, les locaux vont payer cher l\u2019expulsion rapide de Ouattara (30\u2019) pour ne jamais r\u00e9ussir \u00e0 revenir dans la rencontre.<\/p>\n<p style=\"text-align: justify;\">Une victoire qui satisfait bien \u00e9videmment l\u2019entra\u00eeneur des n\u00e9o-promus\u00a0: \u00ab\u00a0On se r\u00e9jouit du r\u00e9sultat obtenu, on a marqu\u00e9 et r\u00e9alis\u00e9 un blanchissage. Tout bon pour notre confiance et l\u2019assurance. Si on nous avait dit qu\u2019on gagnerait ce match ainsi, on aurait sign\u00e9 tout de suite.\u00a0\u00bb<\/p>\n<p style=\"text-align: justify;\">Dans le camp d\u2019en face, du c\u00f4t\u00e9 des Violets de Frontenex, l\u2019entra\u00eeneur Herv\u00e9 Musqu\u00e8re reconna\u00eet le m\u00e9rite de son adversaire mais regrette l\u2019attitude de certains de ses cadres\u00a0: \u00ab\u00a0Nous sommes tout d\u2019abord tomb\u00e9s sur une bonne \u00e9quipe de PLO, et mon \u00e9quipe n&#8217;a pas \u00e9t\u00e9 \u00e0 la hauteur de mes esp\u00e9rances. J&#8217;ai d\u00e9plor\u00e9 le rendement de certains de mes cadres qui, dans ce genre de match, doivent nous amener beaucoup plus.\u00a0\u00bb<\/p>\n<p style=\"text-align: justify;\">\u00ab\u00a0Nous avons rat\u00e9 notre premi\u00e8re mi-temps, analysait le mentor ug\u00e9iste, perdu les duels et l\u2019ouverture du score de Plan-les-Ouates est logique alors que l\u2019expulsion de Ouattara nous a p\u00e9nalis\u00e9. En seconde p\u00e9riode, notre r\u00e9organisation tactique nous a permis de prendre la possession du ballon, mais nous avons manqu\u00e9 de r\u00e9ussite et on aurait pu obtenir un penalty qui aurait pu changer les choses, il faut l\u2019accepter et continuer \u00e0 travailler et savoir se surpasser dans certaines circonstances, le maintien passera par l\u00e0.\u00a0\u00bb<\/p>\n<p style=\"text-align: justify;\">Plan-les-Ouates esp\u00e8re continuer sa belle s\u00e9rie contre Perly samedi prochain tandis qu&#8217;UGS se rend vendredi sur le terrain de Collex.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Signal FC Bernex-Confignon\u00a0 \u00a0\u2013 \u00a0 \u00a0CS Ch\u00eanois \u00a0 3 &#8211; 1<br \/>\nButs\u00a0<\/strong>: 8\u2019 Shabani 1-0, 75\u2019 Boukhenoufa 2-0, 78\u2019 Manzolillo 3-0, 90\u2019 Cherkaoui 3-1<\/p>\n<p style=\"text-align: justify;\">D\u00e9j\u00e0 un derby de la peur entre les deux formations du canton ayant le moins bien r\u00e9ussi leur d\u00e9but de championnat. Au final, c\u2019est le Signal Bernex qui sort vainqueur, encha\u00eenant ainsi une seconde victoire cons\u00e9cutive et laissant son adversaire du jour toujours sans le moindre point.<\/p>\n<p style=\"text-align: justify;\">Mais s\u2019il est un c\u00f4t\u00e9 positif sur le plan comptable pour les hommes d\u2019Angel Bua, c\u2019est la premi\u00e8re r\u00e9ussite de la saison inscrite par Cherkaoui dans les arr\u00eats de jeu, une r\u00e9ussite tomb\u00e9e pour l\u2019honneur mais qui mettra sans doute un peu de baume au c\u0153ur ch\u00eanois.<\/p>\n<p style=\"text-align: justify;\">Du c\u00f4t\u00e9 bern\u00e9sien, la victoire ne fut pas facile \u00e0 se dessiner, mais les deux buts en trois minutes inscrits par Boukhenoufa et Manzolillo aux 75 et 78\u00e8me minute de jeu, permettant ainsi aux hommes de Farminio Isabella de creuser l\u2019\u00e9cart apr\u00e8s l\u2019ouverture du score rapide de Shabani.<\/p>\n<p style=\"text-align: justify;\">Une victoire qui fait du bien aux joueurs du coteau\u00a0: \u00ab\u00a0Match assez compliqu\u00e9 avec une premi\u00e8re mi-temps laborieuse m\u00eame si on a r\u00e9ussi \u00e0 marquer l\u2019ouverture du score. Heureusement, notre gardien nous a bien aid\u00e9s dans cette partie du match dans lequel on a passablement souffert. En deuxi\u00e8me mi-temps, on a \u00e9t\u00e9 plus agressifs et on a r\u00e9ussi \u00e0 creuser l\u2019\u00e9cart.\u00a0\u00bb<\/p>\n<p style=\"text-align: justify;\">\u00ab\u00a0Au final, concluait Farminio Isabella, l\u2019important \u00e9tait de gagner et nous l\u2019avons fait. Bravo \u00e0 mes joueurs, la mani\u00e8re va venir par la suite.\u00a0\u00bb<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>Autres r\u00e9sultats :<\/strong><\/em><\/p>\n<p><strong>FC Stade-Lausanne-Ouchy\u00a0 \u00a0\u2013 \u00a0 \u00a0FC Renens \u00a0 1 &#8211; 0\u00a0<\/strong><\/p>\n<p><strong>ES FC Malley LS\u00a0 \u00a0\u2013 \u00a0 \u00a0FC Dardania Lausanne \u00a0 0 &#8211; 5<\/strong><\/p>\n<p><strong>FC Sierre\u00a0\u00a0 \u00a0\u2013 \u00a0 \u00a0FC Vevey Sports 05 \u00a0 0 &#8211; 2\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-13316\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2013\/09\/2inter1314-5.jpg\" alt=\"2inter1314-5\" width=\"568\" height=\"335\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2013\/09\/2inter1314-5.jpg 568w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2013\/09\/2inter1314-5-300x176.jpg 300w\" sizes=\"(max-width: 568px) 100vw, 568px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>5\u00e8me journ\u00e9e \/ Les huit \u00e9quipes genevoises se sont affront\u00e9es entre elles lors de cette journ\u00e9e de derbys, avec des victoires de Perly, Collex, Plan-les-Ouates et Bernex.<\/p>\n","protected":false},"author":1,"featured_media":5722,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[26],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.proxifoot.ch\/geneve\/2013\/09\/2eme-ligue-inter-plan-les-ouates-sur-sa-lancee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2\u00e8me ligue inter : Plan-les-Ouates sur sa lanc\u00e9e - Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"og:description\" content=\"5\u00e8me journ\u00e9e \/ Les huit \u00e9quipes genevoises se sont affront\u00e9es entre elles lors de cette journ\u00e9e de derbys, avec des victoires de Perly, Collex, Plan-les-Ouates et Bernex.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.proxifoot.ch\/geneve\/2013\/09\/2eme-ligue-inter-plan-les-ouates-sur-sa-lancee\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2013-09-08T21:57:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-20T09:35:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/08\/banniere-2eme-inter.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"164\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2013\/09\/2eme-ligue-inter-plan-les-ouates-sur-sa-lancee\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/08\/banniere-2eme-inter.jpg\",\"width\":660,\"height\":164},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2013\/09\/2eme-ligue-inter-plan-les-ouates-sur-sa-lancee\/#webpage\",\"url\":\"http:\/\/www.proxifoot.ch\/geneve\/2013\/09\/2eme-ligue-inter-plan-les-ouates-sur-sa-lancee\/\",\"name\":\"2\\u00e8me ligue inter : Plan-les-Ouates sur sa lanc\\u00e9e - Proxifoot, le m\\u00e9dia du football genevois\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2013\/09\/2eme-ligue-inter-plan-les-ouates-sur-sa-lancee\/#primaryimage\"},\"datePublished\":\"2013-09-08T21:57:11+00:00\",\"dateModified\":\"2016-07-20T09:35:28+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.proxifoot.ch\/geneve\/2013\/09\/2eme-ligue-inter-plan-les-ouates-sur-sa-lancee\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\",\"name\":\"admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/13311"}],"collection":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=13311"}],"version-history":[{"count":0,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/13311\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/5722"}],"wp:attachment":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=13311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=13311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=13311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}