﻿{"id":1370,"date":"2011-09-26T12:13:25","date_gmt":"2011-09-26T11:13:25","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=1370"},"modified":"2016-09-21T17:24:04","modified_gmt":"2016-09-21T15:24:04","slug":"veyrier-au-mental","status":"publish","type":"post","link":"https:\/\/www.proxifoot.ch\/geneve\/2011\/09\/veyrier-au-mental\/","title":{"rendered":"Veyrier, au mental"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Veyrier l\u2019emporte, non sans mal, au terme d\u2019une fin de match riche en \u00e9motions et fait preuve d\u2019un mental \u00e0 toutes \u00e9preuves face \u00e0 une surprenante \u00e9quipe de Tordoya.<!--more--><\/strong><\/p>\n<p align=\"justify\">C\u2019est un match de haut de classement qui a lieu au stade de Veyrier-Village entre deux \u00e9quipes en confiance, d\u00fb \u00e0 leur tr\u00e8s bon d\u00e9but de saison. Le FC Tordoya, qui reste sur 3 victoires de rang toutes comp\u00e9titions confondues, d\u00e9fie l\u2019ogre veyrite, grand favori \u00e0 la mont\u00e9e et encore invaincu cette saison.<\/p>\n<p align=\"justify\"><strong>Une premi\u00e8re mi-temps engag\u00e9e et hach\u00e9e\u00a0<\/strong><\/p>\n<p align=\"justify\">On s\u2019attendait \u00e0 voir une \u00e9quipe de Veyrier entreprenante \u00e0 domicile et c\u2019est le cas puisqu\u2019 elle va se cr\u00e9er pas moins de trois occasions dans les cinq premi\u00e8res minutes du match. Tout d\u2019abord, c\u2019est Taddeo qui tente sa chance de loin sans vraiment inqui\u00e9ter le gardien visiteur Cruz. Puis c\u2019est Pereira qui par deux fois manque d\u2019ouvrir le score malgr\u00e9 un tr\u00e8s bon service de Taddeo notamment, tr\u00e8s en vue ce soir.<\/p>\n<p align=\"justify\">Les joueurs d\u2019Enrique Gago vont tout de m\u00eame sortir la t\u00eate de l\u2019eau et se cr\u00e9er leur premi\u00e8re occasion suite \u00e0 une magnifique vol\u00e9e de Da Silva bien capt\u00e9e par Batardon. Cela ne refroidit pas les h\u00f4tes qui repartent de l\u2019avant, Barbey se cr\u00e9e \u00e0 son tour deux occasions, mais ses deux frappes ne trouvent pas le cadre d\u2019un Cruz tr\u00e8s serein dans ses buts.<\/p>\n<p align=\"justify\">Malgr\u00e9 ces 20 premi\u00e8res minutes anim\u00e9es, Veyrier va peu \u00e0 peu arr\u00eater de jouer et tombe dans le faux rythme impos\u00e9 par Tordoya. Il s\u2019en suit un festival de longs ballons et de fautes \u00e0 mi-terrain. Il faut attendre la 40\u00e8me minute pour voir enfin une nouvelle occasion, le talentueux attaquant de Tordoya Nunes \u00e9limine trois d\u00e9fenseurs et sert Rossi sur un plateau mais ce dernier seul face \u00e0 Batardon, voit sa frappe s\u2019envoler au dessus du but. Cela aura au moins le m\u00e9rite de r\u00e9veiller l\u2019\u00e9quipe locale qui se cr\u00e9e la derni\u00e8re occasion d\u2019une triste premi\u00e8re p\u00e9riode, sur un tr\u00e8s bon centre du d\u00e9fenseur central Da Silva, Pereira esseul\u00e9 au cinq m\u00e8tres ne r\u00e9ussit pas \u00e0 cadrer sa t\u00eate.<\/p>\n<p align=\"justify\"><img loading=\"lazy\" src=\"http:\/\/www.proxifoot.ch\/home\/images\/veyrier_tordoya_2011_2012\/1.jpg\" alt=\" \" width=\"278\" height=\"321\" \/>\u00a0<img loading=\"lazy\" src=\"http:\/\/www.proxifoot.ch\/home\/images\/veyrier_tordoya_2011_2012\/2.jpg\" alt=\" \" width=\"285\" height=\"322\" \/><br \/>\n<em>Beaucoup de duels et d\u2019engagements au cours de cette premi\u00e8re p\u00e9riode<\/em><\/p>\n<p align=\"justify\">A l\u2019heure du th\u00e9, on constate que le 4-3-3 mis en place par Daniel Villa a eu beaucoup de difficult\u00e9 face au 4-5-1 concoct\u00e9 par Enrique Gago dans cette premi\u00e8re mi-temps, les trois milieux Veyrites ont eu de la peine \u00e0 combiner et \u00e0 se trouver, ce qui a notamment expliqu\u00e9 les nombreux longs ballons. Il faut aussi noter le tr\u00e8s bon travail d\u00e9fensif de Tordoya qui a su emp\u00eacher Veyrier de d\u00e9velopper son jeu et s\u2019est m\u00eame cr\u00e9e quelques occasions gr\u00e2ce notamment \u00e0 son avant-centre Nunes.<\/p>\n<p align=\"justify\"><strong>Au retour des vestiaires, le match s\u2019enflamme enfin<\/strong><\/p>\n<p align=\"justify\">Les 22 acteurs reviennent avec de biens meilleurs intentions apr\u00e8s le th\u00e9, Veyrier cherche \u00e0 dynamiser son attaque avec l\u2019entr\u00e9e d\u2019Abeyi \u00e0 la place de Pereira, mais c\u2019est bien les visiteurs qui vont rapidement ouvrir les hostilit\u00e9s apr\u00e8s seulement cinq minutes. Suite \u00e0 un long ballon, Nunes prend le dessus sur la d\u00e9fense adverse et se voit stopper irr\u00e9guli\u00e8rement aux abords de la surface par Lapaire, qui re\u00e7oit un carton jaune pour cette faute qui m\u00e9ritait peut \u00eatre plus. Rossi se charge du coup-franc et envoie le ballon avec classe dans la lucarne de Batardon, qui ne peut que contempler les d\u00e9g\u00e2ts.<\/p>\n<p align=\"justify\"><img loading=\"lazy\" src=\"http:\/\/www.proxifoot.ch\/home\/images\/veyrier_tordoya_2011_2012\/3.jpg\" alt=\" \" width=\"633\" height=\"251\" \/><br \/>\n<em>Ouverture du score suite \u00e0 ce tr\u00e8s beau coup-franc tir\u00e9 par Rossi<\/em><\/p>\n<p align=\"justify\">Apr\u00e8s ce coup sur la t\u00eate, Veyrier tente de r\u00e9agir et d\u2019\u00e9galiser au plus vite mais ni Baudin, ni Barbey, d\u2019un tr\u00e8s beau retourn\u00e9, ne trouvent le cadre. Les h\u00f4tes se font de plus en plus pressant en jouant notamment plus sur les c\u00f4t\u00e9s et cela paye rapidement puisque seulement quelques minutes apr\u00e8s l\u2019ouverture du score, Taddeo se fait crocheter dans la surface apr\u00e8s avoir \u00e9limin\u00e9 Pereira et l\u2019arbitre siffle p\u00e9nalty. Le nouvel entrant Abeyi ne se fait pas prier et \u00e9galise pour son \u00e9quipe en prenant Cruz \u00e0 contre-pied et permet ainsi \u00e0 son \u00e9quipe d\u2019\u00e9galiser et de ne pas douter.<\/p>\n<p align=\"justify\"><img loading=\"lazy\" src=\"http:\/\/www.proxifoot.ch\/home\/images\/veyrier_tordoya_2011_2012\/4.jpg\" alt=\" \" width=\"637\" height=\"191\" \/><br \/>\n<em>Transformation pleine de sang froid du nouvel entrant Abeyi<\/em><\/p>\n<p align=\"justify\">Les hommes de Daniel Villa tentent alors de profiter de leur temps fort en prenant l\u2019avantage mais Taddeo, sur une offrande du capitaine Allegra, \u00e9choue seul face au dernier rempart Cruz qui effectue une belle parade. Les joueurs de Tordoya vont alors avoir le m\u00e9rite de reprendre le dessus en restant solide et en r\u00e9ussissant \u00e0 r\u00e9\u00e9quilibrer les d\u00e9bats malgr\u00e9 la forte pression des locaux. Ces derniers n\u2019y arrivent plus, comme en premi\u00e8re p\u00e9riode, ils retombent dans leur travers. Ce sont alors les hommes d\u2019Enrique Gago qui tentent de faire la diff\u00e9rence mais la t\u00eate du nouvel entrant Ince et le coup franc de Da Silva n\u2019inqui\u00e8tent pas Batardon.<\/p>\n<p align=\"justify\">A dix minutes du terme, coup de tonnerre, le d\u00e9fenseur des &#8220;verts et noirs&#8221; Lapaire re\u00e7oit un deuxi\u00e8me carton jaune pour un tacle tr\u00e8s engag\u00e9 sur Ozbahar et laisse son \u00e9quipe terminer le match \u00e0 10. On pense alors que Veyrier va tenter de limiter les d\u00e9gats et se contenter de ce match nul, mais c\u2019est mal conna\u00eetre les ressources mentales de cette \u00e9quipe. Elle va arracher la victoire \u00e0 cinq minutes du terme, suite \u00e0 un corner bot\u00e9 par Gautier, Huguenin s\u2019impose dans les airs et place le ballon au fond des filets.<\/p>\n<p align=\"justify\"><em><img loading=\"lazy\" src=\"http:\/\/www.proxifoot.ch\/home\/images\/veyrier_tordoya_2011_2012\/5.jpg\" alt=\" \" width=\"638\" height=\"220\" \/><br \/>\n<\/em><em>Huguenin lib\u00e8re son \u00e9quipe sur le corner tir\u00e9 par Gautier.<\/em><\/p>\n<p align=\"justify\">Veyrier va alors g\u00e9rer sa fin de match et inscrire m\u00eame un troisi\u00e8me but dans les arr\u00eats de jeu. Briones, auteur d\u2019un magnifique solo assure les trois points, il \u00e9limine deux d\u00e9fenseurs et s\u2019en va battre le gardien. L\u2019arbitre renvoie tout le monde au vestiaire et les locaux peuvent lever les bras au terme d\u2019un vrai bras de fer o\u00f9 Tordoya n\u2019a pas d\u00e9m\u00e9rit\u00e9.<\/p>\n<p align=\"justify\"><strong>R\u00e9actions<\/strong><\/p>\n<p align=\"justify\">Au moment de l\u2019analyse, l\u2019entra\u00eeneur de la vaillante \u00e9quipe de Tordoya, Enrique Gago, nous confiait\u00a0: \u00ab\u00a0Honn\u00eatement, on \u00e9tait venu pour chercher le point mais c\u2019est nous qui nous cr\u00e9ons les deux actions les plus dangereuses m\u00eame s\u2019il est vrai que Veyrier m\u00e9ritait sa victoire dans le jeu. Au niveau de la domination il n\u2019y a rien \u00e0 redire, cependant les actions nettes notamment en premi\u00e8re mi-temps, c\u2019est nous qui nous les cr\u00e9ons. Je pense que le p\u00e9nalty est le tournant du match, c\u2019est ce qui a permis \u00e0 Veyrier de se relancer, sans cela, ils auraient vraiment commenc\u00e9 \u00e0 douter. Le score \u00e0 la fin est s\u00e9v\u00e8re, je pense que 2-1 aurait \u00e9t\u00e9 plus juste. Au niveau de l\u2019\u00e9quipe, on est entrain de d\u00e9montrer qu\u2019on peut faire de jolies choses et que l\u2019on peut \u00eatre la bonne surprise de ce championnat.\u00bb<\/p>\n<p align=\"justify\">De l\u2019autre c\u00f4t\u00e9, Daniel Villa \u00e9tait plut\u00f4t soulag\u00e9\u00a0: \u00ab\u00a0On a fait un bon d\u00e9but de match, ensuite on a un peu arr\u00eat\u00e9 de jouer et on est tomb\u00e9 sur une bonne \u00e9quipe de Tordoya, assez agressive. Sinon je pense que la logique est respect\u00e9e sur l\u2019ensemble du match, on a plus produit de jeu et on a \u00e9t\u00e9 plus dangereux qu\u2019eux. L\u2019expulsion \u00e0 un quart d\u2019heure de la fin n\u2019\u00e9tait pas pr\u00e9vue, mais gagner \u00e0 10 donne des grosses valeurs mentales et c\u2019est tr\u00e8s positif pour la suite. On va essayer de continuer comme \u00e7a.\u00bb<\/p>\n<p align=\"justify\">On constate que malgr\u00e9 la d\u00e9faite, les visiteurs sortent du match la t\u00eate haute en ayant pos\u00e9 bien des probl\u00e8mes \u00e0 la tr\u00e8s solide \u00e9quipe de Veyrier. Pour les locaux, c\u2019est une nouvelle victoire acquise dans les 10 derni\u00e8res minutes apr\u00e8s celle obtenue face \u00e0 Lancy II la semaine pass\u00e9e et ce sont surtout trois points qui leur permettent de prendre seul la t\u00eate du classement apr\u00e8s 4 journ\u00e9es.<\/p>\n<p>&nbsp;<\/p>\n<blockquote>\n<p style=\"text-align: justify;\" align=\"justify\"><strong>FC VEYRIER SPORTS \u2013 FC TORDOYA\u00a0 3-1 (0-0)<br \/>\n<\/strong>Stade de Veyrier-Village<\/p>\n<p style=\"text-align: justify;\" align=\"justify\"><strong>Buts\u00a0<\/strong>: 50&#8242; Rossi 0-1, 56&#8242; Abeyi (P) 1-1, 83&#8242; Huguenin 2-1, 92&#8242; Briones 3-1<\/p>\n<p style=\"text-align: justify;\" align=\"justify\"><strong>Veyrier\u00a0<\/strong>: Batardon \u2013 Lapaire, Fracheboud, Da Silva, Baudin \u2013 Allegra \u00a9 (64&#8242; Gautier), Briones, Huguenin \u2013 Barbey (70&#8242; Egli), Pereira (45&#8242; Abeyi), Taddeo.<br \/>\nEntra\u00eeneur\u00a0: Daniel Villa<\/p>\n<p style=\"text-align: justify;\" align=\"justify\"><strong>Tordoya\u00a0<\/strong>: Cruz \u00a9 \u2013 El Amiri, Iglesias (58&#8242; Perez), Ozbahar, Pereira (61&#8242; Ince) \u2013 Linares, Vieira, Guarin, Rossi (71&#8242; Querol), Da Silva \u2013 Nunes.<br \/>\nEntra\u00eeneur\u00a0: Enrique Gago<\/p>\n<p style=\"text-align: justify;\" align=\"justify\"><strong>Avertissements\u00a0<\/strong>: Abeyi et Lapaire (Veyrier)\u00a0; Rossi (Tordoya).<br \/>\n<strong>Expulsions\u00a0<\/strong>: Lapaire (Veyrier, deux avertissements)<\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<p><em>Photos\u00a0: D-click &amp;\u00a0Nels<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><script src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\" async=\"\"><\/script><!-- superieur --> <ins class=\"adsbygoogle\" style=\"display: inline-block; width: 728px; height: 90px;\" data-ad-slot=\"1875735477\" data-ad-client=\"ca-pub-1317159203547503\"><\/ins><script>\/\/ <![CDATA[ (adsbygoogle = window.adsbygoogle || []).push({}); \/\/ ]]><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Veyrier l\u2019emporte, non sans mal, au terme d\u2019une fin de match riche en \u00e9motions et fait preuve d\u2019un mental \u00e0 toutes \u00e9preuves face \u00e0 une surprenante \u00e9quipe de Tordoya.<\/p>\n","protected":false},"author":32,"featured_media":29752,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[6],"tags":[94,40],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.proxifoot.ch\/geneve\/2011\/09\/veyrier-au-mental\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Veyrier, au mental - Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"og:description\" content=\"Veyrier l\u2019emporte, non sans mal, au terme d\u2019une fin de match riche en \u00e9motions et fait preuve d\u2019un mental \u00e0 toutes \u00e9preuves face \u00e0 une surprenante \u00e9quipe de Tordoya.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.proxifoot.ch\/geneve\/2011\/09\/veyrier-au-mental\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2011-09-26T11:13:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-09-21T15:24:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2011\/09\/Veyrier-Tordoya-1112.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2089\" \/>\n\t<meta property=\"og:image:height\" content=\"2358\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2011\/09\/veyrier-au-mental\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2011\/09\/Veyrier-Tordoya-1112.jpg\",\"width\":2089,\"height\":2358},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2011\/09\/veyrier-au-mental\/#webpage\",\"url\":\"http:\/\/www.proxifoot.ch\/geneve\/2011\/09\/veyrier-au-mental\/\",\"name\":\"Veyrier, au mental - Proxifoot, le m\\u00e9dia du football genevois\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2011\/09\/veyrier-au-mental\/#primaryimage\"},\"datePublished\":\"2011-09-26T11:13:25+00:00\",\"dateModified\":\"2016-09-21T15:24:04+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e709cc61b3ec45e30de1699237497595\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.proxifoot.ch\/geneve\/2011\/09\/veyrier-au-mental\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e709cc61b3ec45e30de1699237497595\",\"name\":\"Thomas Arbes\\u00fa\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/1370"}],"collection":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=1370"}],"version-history":[{"count":0,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/1370\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/29752"}],"wp:attachment":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=1370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=1370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=1370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}