﻿{"id":14371,"date":"2013-10-27T19:08:27","date_gmt":"2013-10-27T17:08:27","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=14371"},"modified":"2016-07-19T15:36:27","modified_gmt":"2016-07-19T13:36:27","slug":"1ere-ligue-meyrin-encore-battu-2","status":"publish","type":"post","link":"https:\/\/www.proxifoot.ch\/geneve\/2013\/10\/1ere-ligue-meyrin-encore-battu-2\/","title":{"rendered":"1\u00e8re ligue : Meyrin encore battu"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>12\u00e8me journ\u00e9e \/ 3\u00e8me d\u00e9faite cons\u00e9cutive pour les Meyrinois qui s&#8217;inclinent face \u00e0 la lanterne rouge. De son c\u00f4t\u00e9, Lancy obtient une belle victoire qui l&#8217;\u00e9loigne de la barre.<!--more--><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>Lancy FC\u00a0 \u00a0\u2013 \u00a0\u00a0FC Monthey \u00a0 3 &#8211; 1<br \/>\nButs\u00a0<\/strong>: 35\u2019 Haliti (P) 1-0, 67\u2019 Aslan 1-1, 76\u2019 Dos Santos 2-1, 84\u2019 Meuris 3-1<\/p>\n<p style=\"text-align: justify;\">Lancy conclut sa semaine anglaise de superbe mani\u00e8re\u00a0! Apr\u00e8s avoir obtenu deux r\u00e9sultats nuls lors des deux premi\u00e8res sorties de la semaine, dont un contre le leader YB M-21, les joueurs de Marignac sont venus \u00e0 bout du FC Monthey, adversaire direct pour le maintien.<\/p>\n<p style=\"text-align: justify;\">La premi\u00e8re p\u00e9riode a propos\u00e9 une confrontation de styles entre un Lancy joueur et dominateur et des Valaisans au style de jeu beaucoup plus direct. Et c\u2019est logiquement que les locaux vont ouvrir la marque par Haliti sur penalty suite \u00e0 une faute sur Torres.<\/p>\n<p style=\"text-align: justify;\">En seconde mi-temps, le match va s\u2019\u00e9quilibrer et Lancy va se cr\u00e9er quelques grosses opportunit\u00e9s sur des contres, sans parvenir \u00e0 les concr\u00e9tiser, et comme souvent, les locaux vont \u00eatre punis par l\u2019\u00e9galisation du FC Monthey \u00e0 vingt-cinq minutes du terme. Vingt-cinq minutes durant lesquelles les joueurs de Bojan Dimic vont faire preuve d\u2019une belle r\u00e9action et Torres va inscrire le 2-1 sur une belle action d\u2019Ameti avant que le nouvel entrant, Meuris, ne scelle la victoire des siens \u00e0 la 84\u00e8me\u00a0minute en remportant son un contre un.<\/p>\n<p style=\"text-align: justify;\">Une victoire qui fait \u00e9videmment le bonheur de Bojan Dimic\u00a0: \u00ab\u00a0Nous avons \u00e9t\u00e9 r\u00e9compens\u00e9s de nos efforts\u00a0! L\u2019\u00e9quipe a \u00e9t\u00e9 s\u00e9rieuse et concentr\u00e9e m\u00eame lorsque notre adversaire a recoll\u00e9 au score. Une \u00e9galisation qui aurait pu nous faire tr\u00e8s mal, avec la fatigue accumul\u00e9e de notre troisi\u00e8me match de la semaine et du terrain difficile.\u00a0\u00bb<\/p>\n<p style=\"text-align: justify;\">Cinq points en trois matches, le bilan de la semaine lanc\u00e9enne est excellent, et l\u2019entra\u00eeneur de Marignac esp\u00e8re que cela va continuer ainsi\u00a0: \u00ab\u00a0Il faut maintenant que mes joueurs montrent, sur les trois derniers matches de l\u2019ann\u00e9e, la m\u00eame attitude. A eux de jouer et de prouver qu\u2019ils sont de grands comp\u00e9titeurs, car les trois prochains matches vont d\u00e9terminer l\u2019objectif de notre printemps\u00a0!\u00a0\u00bb<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Meyrin FC\u00a0 \u00a0\u2013 \u00a0\u00a0FC Bulle \u00a0 1 &#8211; 2<br \/>\nButs\u00a0<\/strong>: 45\u2019 Jaquet 0-1, 60\u2019 Chatagny (P) 0-2, 69\u2019 Besnard 1-2<\/p>\n<p style=\"text-align: justify;\">Contre-performance pour le FC Meyrin qui s\u2019incline \u00e0 domicile contre la lanterne rouge bulloise pour une troisi\u00e8me d\u00e9faite cons\u00e9cutive. Pourtant, Meyrin va essayer de prendre le match par le bon bout et faire valoir son statut de favori dans cette rencontre. Malheureusement, ce sont les Fribourgeois qui vont ouvrir la marque juste avant la pause par Jaquet.<\/p>\n<p style=\"text-align: justify;\">En seconde p\u00e9riode, c\u2019est encore Bulle qui va frapper le premier en inscrivant un penalty \u00e0 l\u2019heure de jeu par Chatagny. La r\u00e9duction du score de Benjamin Besnard \u00e0 25 minutes du terme n\u2019aura comme r\u00e9sultat que de donner espoirs pour la fin de match.<\/p>\n<p style=\"text-align: justify;\">Un match que Bruno Codeas, \u00a0l\u2019entra\u00eeneur meyrinois analyse simplement\u00a0: \u00ab\u00a0Bulle a \u00e9t\u00e9 plus r\u00e9aliste que nous. Les deux \u00e9quipes ont eu des occasions, les deux \u00e9quipes ont obtenu un penalty, mais l\u00e0 o\u00f9 nous on a manqu\u00e9 de r\u00e9alisme, ils ont mis leurs chances au fond. Dans le jeu, c\u2019\u00e9tait pas tr\u00e8s bon, et il faut qu\u2019on r\u00e9agisse vite.\u00a0\u00bb<\/p>\n<p style=\"text-align: justify;\">Une r\u00e9action attendue d\u00e8s jeudi soir sur le terrain de Terre-Sainte\u00a0: \u00ab\u00a0Jouer aussi rapidement ne peut nous faire que du bien, qui plus est un derby \u00bb, conclut Bruno Codeas.<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>Autres r\u00e9sultats :\u00a0<\/strong><\/em><\/p>\n<p><strong>FC Martigny-Sports\u00a0\u00a0 \u2013\u00a0\u00a0 FC Echallens R\u00e9gion \u00a0 4 &#8211; 2 \u00a0 \u00a0<\/strong><\/p>\n<p><strong>FC Azzurri 90 LS\u00a0\u00a0 \u2013\u00a0\u00a0 FC Oberwallis Naters \u00a0 1 &#8211; 1\u00a0<\/strong><\/p>\n<p><strong>FC Bavois\u00a0\u00a0 \u2013\u00a0\u00a0 SC D\u00fcdingen \u00a0 0 &#8211; 3\u00a0<\/strong><\/p>\n<p><strong>FC Fribourg\u00a0\u00a0 \u2013\u00a0\u00a0 US Terre Sainte \u00a0 3 &#8211; 0\u00a0<\/strong><\/p>\n<p><strong>BSC Young Boys II\u00a0\u00a0 \u2013\u00a0\u00a0 Yverdon-Sport FC \u00a0 1 &#8211; 3\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-14392\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2013\/10\/1ligue1314-12.jpg\" alt=\"1ligue1314-12\" width=\"579\" height=\"308\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2013\/10\/1ligue1314-12.jpg 579w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2013\/10\/1ligue1314-12-300x159.jpg 300w\" sizes=\"(max-width: 579px) 100vw, 579px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>12\u00e8me journ\u00e9e \/ 3\u00e8me d\u00e9faite cons\u00e9cutive pour les Meyrinois qui s&#8217;inclinent face \u00e0 la lanterne rouge. De son c\u00f4t\u00e9, Lancy obtient une belle victoire qui l&#8217;\u00e9loigne de la barre.<\/p>\n","protected":false},"author":1,"featured_media":5793,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[4],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.proxifoot.ch\/geneve\/2013\/10\/1ere-ligue-meyrin-encore-battu-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1\u00e8re ligue : Meyrin encore battu - Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"og:description\" content=\"12\u00e8me journ\u00e9e \/ 3\u00e8me d\u00e9faite cons\u00e9cutive pour les Meyrinois qui s&#8217;inclinent face \u00e0 la lanterne rouge. De son c\u00f4t\u00e9, Lancy obtient une belle victoire qui l&#8217;\u00e9loigne de la barre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.proxifoot.ch\/geneve\/2013\/10\/1ere-ligue-meyrin-encore-battu-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2013-10-27T17:08:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-19T13:36:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/08\/banniere-1\u00e8re-ligue.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"164\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2013\/10\/1ere-ligue-meyrin-encore-battu-2\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/08\/banniere-1\\u00e8re-ligue.jpg\",\"width\":660,\"height\":164},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2013\/10\/1ere-ligue-meyrin-encore-battu-2\/#webpage\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/2013\/10\/1ere-ligue-meyrin-encore-battu-2\/\",\"name\":\"1\\u00e8re ligue : Meyrin encore battu - Proxifoot, le m\\u00e9dia du football genevois\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2013\/10\/1ere-ligue-meyrin-encore-battu-2\/#primaryimage\"},\"datePublished\":\"2013-10-27T17:08:27+00:00\",\"dateModified\":\"2016-07-19T13:36:27+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.proxifoot.ch\/geneve\/2013\/10\/1ere-ligue-meyrin-encore-battu-2\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\",\"name\":\"admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/14371"}],"collection":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=14371"}],"version-history":[{"count":0,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/14371\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/5793"}],"wp:attachment":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=14371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=14371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=14371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}