﻿{"id":14500,"date":"2013-10-31T10:26:09","date_gmt":"2013-10-31T08:26:09","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=14500"},"modified":"2016-07-20T18:29:16","modified_gmt":"2016-07-20T16:29:16","slug":"les-matchs-en-retard-de-mercredi-30-10","status":"publish","type":"post","link":"https:\/\/www.proxifoot.ch\/geneve\/2013\/10\/les-matchs-en-retard-de-mercredi-30-10\/","title":{"rendered":"Les matchs en retard de mercredi 30.10"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Onex (2\u00e8me ligue) et Grand-Saconnex (3\u00e8me ligue) obtiennent deux victoires qui leur \u00e9taient obligatoires \u00e0 l&#8217;ext\u00e9rieur.<\/strong><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>2\u00c8ME LIGUE<\/strong><\/span><\/p>\n<p><strong>FC Compesi\u00e8res\u00a0\u00a0 \u2013\u00a0\u00a0 FC Onex\u00a0\u00a0 0 &#8211; 1 <\/strong><br \/>\n<strong>But :<\/strong>\u00a065&#8242; Arm. Selmani 0-1<\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s une seule victoire en 7 journ\u00e9es et 7 petits points compteur, Onex se devait de l&#8217;emporter sur le terrain de Compesi\u00e8res, qui comptait une unit\u00e9 en moins.<\/p>\n<p style=\"text-align: justify;\">Et gr\u00e2ce \u00e0 une r\u00e9ussite de leur meilleur buteur Armend Selmani &#8211; 6\u00e8me but en championnat &#8211; en milieu de seconde p\u00e9riode, les On\u00e9siens obtiennent une victoire importante. En effet, avec un moral retrouv\u00e9, la formation de Patrick Hochstrasser pourra se rendre sur le terrain du CS Italien dimanche avec l&#8217;intention de jouer les trouble-f\u00eates et, pourquoi pas, se relancer dans la course aux premi\u00e8res places.<\/p>\n<p style=\"text-align: justify;\">L&#8217;entra\u00eeneur on\u00e9sien, Patrick Hochstrasser, \u00e9tait ogiquemennt ravi de ce succ\u00e8s, qui doit en appeler d&#8217;autres : &#8220;Je suis content d&#8217;avoir gagn\u00e9 ce match car \u00e0 Compesi\u00e8res il est\u00a0toujours tr\u00e8s difficile de venir glaner des points !\u00a0Mais pour moi, nous avons gagn\u00e9 ce match parce que nous en avons eu la rage,\u00a0la volont\u00e9 et les occasions pour gagner ces trois points.\u00a0Maintenant, il faut vraiment faire une grosse s\u00e9rie si on veut \u00eatre mieux\u00a0plac\u00e9 au classement&#8230;&#8221;<\/p>\n<p style=\"text-align: justify;\">De son c\u00f4t\u00e9, et malgr\u00e9 un bon d\u00e9part dans ce match, Compesi\u00e8res encha\u00eene un 5\u00e8me match sans victoire. L&#8217;\u00e9quipe d&#8217;Alex Dentand esp\u00e8re s&#8217;\u00e9loigner de la barre ce week-end avec la r\u00e9ception de Champel.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-14504\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2013\/10\/2ligue1314-9bis.jpg\" alt=\"2ligue1314-9bis\" width=\"586\" height=\"279\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2013\/10\/2ligue1314-9bis.jpg 586w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2013\/10\/2ligue1314-9bis-300x142.jpg 300w\" sizes=\"(max-width: 586px) 100vw, 586px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>3\u00c8ME LIGUE<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><strong>FC Donzelle\u00a0\u00a0 \u2013\u00a0\u00a0 FC Grand-Saconnex\u00a0\u00a0 1 &#8211; 6<\/strong><br \/>\n<strong>Buts :<\/strong> 7&#8242; Rexhepi 1-0, 13&#8242; Vazquez 1-1, 29&#8242; Amide 1-2, \u00a035&#8242; Kabashi 1-3, 38&#8242; Cacaj 1-4,\u00a0 52&#8242; Amide 1-5, 62&#8242; De Almeida 1-6<\/p>\n<p style=\"text-align: justify;\">Dans le but de ne pas se retrouver largu\u00e9 dans la course \u00e0 la premi\u00e8re place, objectif avou\u00e9 de l&#8217;\u00e9quipe, Grand-Saconnex \u00e9tait oblig\u00e9 de gagner sur le terrain de Donzelle.<\/p>\n<p style=\"text-align: justify;\">Pourtant, tout avait mal commenc\u00e9 pour les Saconn\u00e9siens \u00e0 La Plaine avec un but rapide de Rexhepi pour les locaux. &#8220;Ce but\u00a0va nous r\u00e9veiller&#8221;, analysait Eugenio Rendeiro. En effet, son \u00e9quipe n&#8217;a pas fait dans la demi-mesure apr\u00e8s ce d\u00e9but de match rat\u00e9, et s&#8217;en va boire le th\u00e9 sur un score de 1-4 qui leur a permis d&#8217;envisager sereinement la seconde p\u00e9riode.<\/p>\n<p style=\"text-align: justify;\">Une avance qu&#8217;ils vont accentuer avec deux nouveaux buts apr\u00e8s le th\u00e9, pour un score final de 1-6.\u00a0Pour Rendeiro, &#8220;on a \u00e9t\u00e9 meilleur que notre adversaire pendant tout le match et on m\u00e9rite la victoire sans discussion. Un grand bravo \u00e0 toute l&#8217;\u00e9quipe pour ce tr\u00e8s bon match et le s\u00e9rieux durant les 90 minutes.&#8221;<\/p>\n<p style=\"text-align: justify;\">Ce succ\u00e8s permet au Grand-Sac&#8217; de revenir \u00e0 8 longueurs du leader. Un leader, A\u00efre, qui sera justement le prochain rival des Saconn\u00e9siens. &#8220;Maintenant, on va pr\u00e9parer la venue d&#8217;A\u00efre dimanche et voir si on n&#8217;est pas trop fatigu\u00e9 parce qu&#8217;on fait 4 matchs en 15 jours&#8221;, poursuivait Rendeiro.<\/p>\n<p style=\"text-align: justify;\">Et de conclure : &#8220;Bonne suite \u00e0 Lamers et toute son \u00e9quipe, et bravo \u00e0 l&#8217;arbitre qui, lui aussi, a fait un bon match.&#8221;<\/p>\n<p><a href=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2013\/10\/3ligue2-1314-9bis.jpg\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-14506\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2013\/10\/3ligue2-1314-9bis.jpg\" alt=\"3ligue2-1314-9bis\" width=\"577\" height=\"273\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2013\/10\/3ligue2-1314-9bis.jpg 577w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2013\/10\/3ligue2-1314-9bis-300x141.jpg 300w\" sizes=\"(max-width: 577px) 100vw, 577px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Onex (2\u00e8me ligue) et Grand-Saconnex (3\u00e8me ligue) obtiennent deux victoires qui leur \u00e9taient obligatoires \u00e0 l&#8217;ext\u00e9rieur.<\/p>\n","protected":false},"author":1,"featured_media":698,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[5,6],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.proxifoot.ch\/geneve\/2013\/10\/les-matchs-en-retard-de-mercredi-30-10\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les matchs en retard de mercredi 30.10 - Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"og:description\" content=\"Onex (2\u00e8me ligue) et Grand-Saconnex (3\u00e8me ligue) obtiennent deux victoires qui leur \u00e9taient obligatoires \u00e0 l&#8217;ext\u00e9rieur.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.proxifoot.ch\/geneve\/2013\/10\/les-matchs-en-retard-de-mercredi-30-10\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2013-10-31T08:26:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-20T16:29:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/01\/new_proxif1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"164\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2013\/10\/les-matchs-en-retard-de-mercredi-30-10\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/01\/new_proxif1.jpg\",\"width\":660,\"height\":164},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2013\/10\/les-matchs-en-retard-de-mercredi-30-10\/#webpage\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/2013\/10\/les-matchs-en-retard-de-mercredi-30-10\/\",\"name\":\"Les matchs en retard de mercredi 30.10 - Proxifoot, le m\\u00e9dia du football genevois\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2013\/10\/les-matchs-en-retard-de-mercredi-30-10\/#primaryimage\"},\"datePublished\":\"2013-10-31T08:26:09+00:00\",\"dateModified\":\"2016-07-20T16:29:16+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.proxifoot.ch\/geneve\/2013\/10\/les-matchs-en-retard-de-mercredi-30-10\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\",\"name\":\"admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/14500"}],"collection":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=14500"}],"version-history":[{"count":0,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/14500\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/698"}],"wp:attachment":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=14500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=14500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=14500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}