﻿{"id":15154,"date":"2013-12-02T11:53:27","date_gmt":"2013-12-02T09:53:27","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=15154"},"modified":"2016-07-20T17:11:20","modified_gmt":"2016-07-20T15:11:20","slug":"les-derniers-matchs-du-fc-choulex","status":"publish","type":"post","link":"https:\/\/www.proxifoot.ch\/geneve\/2013\/12\/les-derniers-matchs-du-fc-choulex\/","title":{"rendered":"Les derniers matchs du FC Choulex"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Le premier tour est enfin termin\u00e9 pour les Choul\u00e9siens, qui affrontaient Donzelle et Grand-Saconnex \u00e0 la Fontenette.<\/strong><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>FC Donzelle \u00a0 &#8211; \u00a0 FC Choulex \u00a0 3 &#8211; 1 \u00a0 \u00a0<\/strong><em>Jou\u00e9 jeudi 28.11<\/em><br \/>\n<strong>Buts<\/strong> : 7&#8242; M\u00e8che (P) 1-0, 57&#8242; Abb\u00e9 2-0, 71&#8242; Albacete 3-0, 74&#8242; Oliveira 3-1<\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s presque trois semaines d&#8217;inactivit\u00e9, il a fallu du courage aux Donzellois pour se motiver \u00e0 jouer leur dernier match du premier tour.<\/p>\n<p style=\"text-align: justify;\">Jou\u00e9e sur le synth\u00e9tique de la Fontenette, cette rencontre face \u00e0 Choulex a bien d\u00e9marr\u00e9 pour les joueurs de Lamers et Vidakovic puisque M\u00e8che ouvrait le score sur penalty \u00e0 la 7\u00e8me minute d\u00e9j\u00e0. Une avance creus\u00e9e en seconde p\u00e9riode gr\u00e2ce \u00e0 Abb\u00e9 et Albacete qui portent le score \u00e0 3-0.<\/p>\n<p style=\"text-align: justify;\">La r\u00e9action choul\u00e9sienne arrivera dans la foul\u00e9e gr\u00e2ce \u00e0 Caio Oliveira, mais comme face \u00e0 Perly lors du match pr\u00e9c\u00e9dent, elle sera trop tardive. Les hommes de Dario Basile s&#8217;inclinent finalement 3-1. Apr\u00e8s leur belle victoire contre Gen\u00e8ve-Poste, Choulex n&#8217;a donc pas confirm\u00e9 en encha\u00eenant deux d\u00e9faites.<\/p>\n<p style=\"text-align: justify;\">Un dernier match est encore pr\u00e9vu pour eux&#8230; le 4 d\u00e9cembre. Arr\u00eat\u00e9e \u00e0 la 70\u00e8me minute en raison de l&#8217;arriv\u00e9e de l&#8217;ambulance et de la grave blessure de Camara, la rencontre face \u00e0 Grand-Saconnex se rejouera dans son int\u00e9gralit\u00e9 mercredi soir \u00e0 nouveau sur le synth\u00e9tique de la Fontenette.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>FC Choulex \u00a0 &#8211; \u00a0 FC Grand-Saconnex \u00a0 2 &#8211; 4 \u00a0<\/strong>\u00a0\u00a0<em>Jou\u00e9 mercredi 04.12<\/em><br \/>\n<strong> Buts :\u00a0<\/strong>19&#8242; Celestini 1-0, 24&#8242; Cacaj 1-1, 49&#8242; Cacaj 1-2, 68&#8242; Monteiro 2-2, 89&#8242; Cacaj 2-3, 92&#8242; Cacaj 2-4<\/p>\n<p style=\"text-align: justify;\">Mercredi soir, sur le synth\u00e9tique de la Fontenette, Choulex et Grand-Saconnex rejouaient en entier le match arr\u00eat\u00e9 il y a quelques jours \u00e0 la 70\u00e8me minute. Et du courage, les 22 acteurs ont d\u00fb en trouver pour chausser les crampons un 4 d\u00e9cembre, soit presque un mois apr\u00e8s la fin officielle du championnat.<\/p>\n<p style=\"text-align: justify;\">\u00ab\u00a0C\u2019\u00e9tait un match avec des conditions difficiles car on avait d\u00e9j\u00e0 arr\u00eat\u00e9 les entra\u00eenements il y a 2 semaines et, surtout, j&#8217;avais 2 joueurs suspendus suite \u00e0 un 4\u00e8me carton lors du match arr\u00eat\u00e9, ainsi que des joueurs partis en vacances. J&#8217;ai fait appel \u00e0 des joueurs de la 2\u00e8me \u00e9quipe que je remercie et je f\u00e9licite du tr\u00e8s bon match\u00a0\u00bb, nous d\u00e9clarait l\u2019entra\u00eeneur saconn\u00e9sien Eugenio Rendeiro.<\/p>\n<p style=\"text-align: justify;\">Ce sont les Choul\u00e9siens qui vont ouvrir le score gr\u00e2ce \u00e0 un missile de Celestini depuis presque le milieu de terrain qui trompe Frutiger. Mais le buteur des visiteurs, Cacaj, ne va attendre que 5 minutes avant de remettre les pendules \u00e0 l\u2019heure.<\/p>\n<p style=\"text-align: justify;\">L\u2019attaquant saconn\u00e9sien, inutile de le pr\u00e9ciser, sera l\u2019homme de la soir\u00e9e. En d\u00e9but de seconde p\u00e9riode, il donne l\u2019avantage aux siens, avant que Roberto Monteiro n\u2019\u00e9galise \u00e0 nouveau \u00e0 2-2. Mais la d\u00e9livrance pour les \u00ab\u00a0visiteurs\u00a0\u00bb tombe en fin de match\u00a0: ce diable de Cacaj s\u2019offre deux nouveaux buts lors des toutes derni\u00e8res minutes et offre une victoire tr\u00e8s importante \u00e0 son \u00e9quipe gr\u00e2ce \u00e0 un quadrupl\u00e9.<\/p>\n<p style=\"text-align: justify;\">En effet, ces trois points permettent \u00e0 Grand-Saconnex de passer l\u2019hiver sur le podium et de rester dans la course aux premi\u00e8res places, comme nous le confirme Rendeiro : \u00ab\u00a0Sur l&#8217;ensemble du match, on m\u00e9rite largement la victoire m\u00eame si cela a \u00e9t\u00e9 difficile jusqu&#8217;au bout.\u00a0Si on avait perdu des points, cela aurait \u00e9t\u00e9 tr\u00e8s dur pour la suite. Cette victoire nous permet de finir \u00e0 la 3\u00e8me place et nous laisse un peu d&#8217;espoir pour le 2\u00e8me tour \u00bb. Les chances de promotion pour le Grand-Sac\u2019 passeront par un sans-faute au second tour, puisque le leader a\u00efrois compte 8 longueurs d\u2019avance.<\/p>\n<p style=\"text-align: justify;\">Le mentor saconn\u00e9sien concluait : \u00ab Un grand bravo \u00e0 toute l&#8217;\u00e9quipe pour cette belle victoire et l&#8217;\u00e9tat d&#8217;esprit qui r\u00e8gne depuis quelques temps qui est bon signe pour la suite. Bonne suite \u00e0 Choulex et bonnes f\u00eates \u00e0 tout le monde\u2026 car on est bien au mois de d\u00e9cembre\u00a0!\u00a0\u00bb<\/p>\n<p style=\"text-align: justify;\">Du c\u00f4t\u00e9 de Choulex, l&#8217;\u00e9quipe de Dario Basile termine l&#8217;ann\u00e9e sur trois d\u00e9faites cons\u00e9cutives. Ce premier tour s&#8217;est fait beaucoup trop long pour les joueurs et c&#8217;est compr\u00e9hensible. L&#8217;entra\u00eeneur choul\u00e9sien estimait que &#8220;la pause nous fera le plus grand bien. Bravo \u00e0 Saconnex qui poss\u00e8de un attaquant vraiment exceptionnel, Cacaj. Bonnes f\u00eates \u00e0 tous&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-15187\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2013\/12\/3ligue2-1ertour.jpg\" alt=\"3ligue2-1ertour\" width=\"608\" height=\"312\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2013\/12\/3ligue2-1ertour.jpg 608w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2013\/12\/3ligue2-1ertour-300x153.jpg 300w\" sizes=\"(max-width: 608px) 100vw, 608px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le premier tour est enfin termin\u00e9 pour les Choul\u00e9siens, qui affrontaient Donzelle et Grand-Saconnex \u00e0 la Fontenette.<\/p>\n","protected":false},"author":1,"featured_media":6245,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[6],"tags":[88],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.proxifoot.ch\/geneve\/2013\/12\/les-derniers-matchs-du-fc-choulex\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les derniers matchs du FC Choulex - Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"og:description\" content=\"Le premier tour est enfin termin\u00e9 pour les Choul\u00e9siens, qui affrontaient Donzelle et Grand-Saconnex \u00e0 la Fontenette.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.proxifoot.ch\/geneve\/2013\/12\/les-derniers-matchs-du-fc-choulex\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2013-12-02T09:53:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-20T15:11:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/09\/banniere-3\u00e8me-ligue2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"164\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2013\/12\/les-derniers-matchs-du-fc-choulex\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/09\/banniere-3\\u00e8me-ligue2.jpg\",\"width\":660,\"height\":164},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2013\/12\/les-derniers-matchs-du-fc-choulex\/#webpage\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/2013\/12\/les-derniers-matchs-du-fc-choulex\/\",\"name\":\"Les derniers matchs du FC Choulex - Proxifoot, le m\\u00e9dia du football genevois\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2013\/12\/les-derniers-matchs-du-fc-choulex\/#primaryimage\"},\"datePublished\":\"2013-12-02T09:53:27+00:00\",\"dateModified\":\"2016-07-20T15:11:20+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.proxifoot.ch\/geneve\/2013\/12\/les-derniers-matchs-du-fc-choulex\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\",\"name\":\"admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/15154"}],"collection":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=15154"}],"version-history":[{"count":0,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/15154\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/6245"}],"wp:attachment":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=15154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=15154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=15154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}