﻿{"id":15969,"date":"2014-03-23T20:11:52","date_gmt":"2014-03-23T18:11:52","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=15969"},"modified":"2016-07-20T17:10:50","modified_gmt":"2016-07-20T15:10:50","slug":"3eme-ligue-groupe-1-la-course-a-la-promotion-continue","status":"publish","type":"post","link":"https:\/\/www.proxifoot.ch\/geneve\/2014\/03\/3eme-ligue-groupe-1-la-course-a-la-promotion-continue\/","title":{"rendered":"3\u00e8me ligue, groupe 1 : la course \u00e0 la promotion continue"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>14\u00e8me journ\u00e9e \/ Plan-les-Ouates II et City se partagent la premi\u00e8re place, mais Signal Bernex II et CS Italien II veillent au grain. En bas de tableau, cela commence \u00e0 devenir tr\u00e8s compliqu\u00e9 pour Collex II et Famalic\u00e3o.<!--more--><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>US Carouge FC\u00a0 \u00a0\u2013 \u00a0\u00a0FC City \u00a0 1 &#8211; 4<br \/>\nButs:<\/strong> 15\u2019 Marques 0-1, 40\u2019 Berisha 0-2, 51\u2018 Guijarrot 1-2, 57\u2019Berisha 1-3, 87\u2018 Duarte 1-4<\/p>\n<p style=\"text-align: justify;\">Invaincu depuis la reprise, City a continu\u00e9 sur sa lanc\u00e9e en allant cueillir une troisi\u00e8me victoire de rang chez US Carouge. Des Carougeois qui vivent un d\u00e9but de second tour compliqu\u00e9, puisqu\u2019ils ont subi leur troisi\u00e8me d\u00e9faite en autant de matches.<\/p>\n<p style=\"text-align: justify;\">Gr\u00e2ce \u00e0 ce succ\u00e8s, City partage ainsi la premi\u00e8re place avec Plan-les-Ouates II. Leur coach Patrick Stfani nous livrait ses impressions sur leur prestation contre US Carouge : <em>\u00ab\u00a0Nous sommes satisfaits de cette victoire obtenue contre une \u00e9quipe de haut du classement, malgr\u00e9 un match tr\u00e8s moyen de notre part, surtout en deuxi\u00e8me mi-temps durant laquelle on n&#8217;a pas eu la ma\u00eetrise du jeu habituelle.\u00a0\u00bb<\/em><\/p>\n<p style=\"text-align: justify;\">L\u2019entra\u00eeneur de City a d\u00e9j\u00e0 les yeux riv\u00e9s sur le choc contre Plan-les-Ouates II, qui les attend le week-end prochain\u00a0: <em>\u00ab\u00a0Nous esp\u00e9rons r\u00e9cup\u00e9rer certains de nos joueurs bless\u00e9s et il faudra bien se pr\u00e9parer avant de recevoir le FC Plan-Les-Ouates, qui est d&#8217;apr\u00e8s tous les sp\u00e9cialistes, l&#8217;\u00e9quipe favorite de ce groupe et le candidat num\u00e9ro 1 \u00e0 la promotion.\u00a0\u00bb<\/em><\/p>\n<p style=\"text-align: justify;\">US Carouge, de son c\u00f4t\u00e9, tentera de renouer avec le succ\u00e8s lors de son d\u00e9placement chez la lanterne rouge Famalic\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>FC Plan-les-Ouates II\u00a0 \u00a0\u2013 \u00a0\u00a0FC UGS II \u00a0 4 &#8211; 3<br \/>\nButs\u00a0:<\/strong> 16\u2019 Kari 0-1, 25\u2019 Mbacke 1-1, 50\u2019 Emini 1-2, 59\u2018 Kari 1-3, 70\u2018 Gomes 2-3, 78\u2018 Thery 3-3, 80\u2018 Thery 4-3<\/p>\n<p style=\"text-align: justify;\">La r\u00e9ception d\u2019UGS II a \u00e9t\u00e9 l\u2019occasion pour Plan-les-Ouates II d\u2019\u00e9trenner son r\u00f4le de leader. Les Plan-les-Ouatiens ont obtenu les trois points, m\u00eame si rien n\u2019a \u00e9t\u00e9 facile.<\/p>\n<p style=\"text-align: justify;\">UGS II a tr\u00e8s vite pris les choses en main et s\u2019est cr\u00e9\u00e9 plusieurs occasions, dont un tir de Roland, qui est venu s\u2019\u00e9chouer sur le poteau. <em>\u00a0\u00ab\u00a0En premi\u00e8re mi-temps, nous avons trouv\u00e9 en face une \u00e9quipe solide bien en place. Nous avons eu beaucoup de mal \u00e0 poser notre jeu\u00a0\u00bb<\/em>, confiait Javier Martinez, le coach des locaux.\u00a0Au quart d\u2019heure de jeu, les \u00ab\u00a0Violets\u00a0\u00bb ont enfin vu leurs efforts \u00eatre r\u00e9compens\u00e9s, lorsque Kari a ouvert la marque.<\/p>\n<p style=\"text-align: justify;\"><em>\u00ab\u00a0Jovanovic nous a montr\u00e9 qu&#8217;il \u00e9tait comme \u00e0 son habitude dans un grand jour, mais sur un ballon mal d\u00e9gag\u00e9 Plan-les-Ouates a \u00e9galis\u00e9\u00a0\u00bb<\/em>, expliquait Lorice Giraud, coach des visiteurs.<\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s la pause, les Ug\u00e9istes ont repris leur marche en avant et ont r\u00e9ussi \u00e0 prendre deux longueurs d\u2019avance gr\u00e2ce \u00e0 des buts d\u2019Emini et de Kari.\u00a0Mais comme contre Avanchet il y a une semaine, UGS II a vu son adversaire revenir au score. <em>\u00ab\u00a0Plan-les-Ouates a eu l&#8217;orgueil et le courage de ne rien l\u00e2cher et a pu reprendre l&#8217;avantage. Il faut reconnaitre que le potentiel offensif de Plan-les-Ouates a de quoi faire des envieux chez les adversaires\u00a0\u00bb<\/em>, analysait Lorice Giraud.<\/p>\n<p style=\"text-align: justify;\">Malgr\u00e9 une ultime occasion de Wahid, les \u00ab\u00a0Violets\u00a0\u00bb ont donc d\u00fb s\u2019avouer vaincus. Leur entra\u00eeneur se montrait n\u00e9anmoins fier de leur prestation\u00a0: <em>\u00ab\u00a0Ce qui est s\u00fbr, c&#8217;est que mon \u00e9quipe est en tr\u00e8s gros progr\u00e8s et que je ne peux rien lui reprocher.\u00a0\u00bb<\/em><\/p>\n<p style=\"text-align: justify;\"><em>\u00ab\u00a0Sur ce match, le partage des points m&#8217;aurait amplement combl\u00e9, mais la qualit\u00e9 de l&#8217;adversaire n&#8217;en a pas voulu ainsi. Je souhaite \u00e0 PLO et son entra\u00eeneur tout de bon pour cette fin de championnat\u00a0\u00bb<\/em>, ajoutait Lorice Giraud.<\/p>\n<p style=\"text-align: justify;\">Et de conclure\u00a0:<em> \u00ab\u00a0Quant \u00e0 nous, apr\u00e8s avoir jou\u00e9 trois leaders du championnat \u00a0cons\u00e9cutifs et inscrit 12 buts, le meilleur reste \u00e0 venir. L&#8217;\u00e9tat d&#8217;esprit et la solidarit\u00e9 affich\u00e9s depuis la reprise nous permettent d&#8217;esp\u00e9rer de tr\u00e8s belles choses pour ces huit derniers matches. Encore un gros bravo \u00e0 mes joueurs.\u00a0\u00bb<\/em><\/p>\n<p style=\"text-align: justify;\">De son c\u00f4t\u00e9, Javier Martinez rendait hommage aux qualit\u00e9s d\u2019UGS II\u00a0: <em>\u00ab\u00a0J&#8217;ai trouv\u00e9 en face de nous une \u00e9quipe solide bien en place, qui nous a cr\u00e9\u00e9 beaucoup de probl\u00e8mes dans notre jeu d\u00e9fensif. Une \u00e9quipe avec beaucoup de qualit\u00e9s. Je souhaite un tr\u00e8s tr\u00e8s bon championnat \u00e0 UGS.\u00a0\u00bb<\/em><\/p>\n<p style=\"text-align: justify;\">Plan-les-Ouates II, qui n\u2019a plus perdu depuis le 25 octobre dernier, aura \u00e0 c\u0153ur de d\u00e9fendre sa premi\u00e8re place contre son poursuivant City. Un beau choc en perspective.\u00a0Apr\u00e8s le leader plan-les-ouatien, UGS II affrontera lui dimanche Signal-Bernex II, une autre formation du haut de classement.<\/p>\n<p style=\"text-align: justify;\"><em>\u00a0<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Avanchet-Sport FC\u00a0 \u00a0\u2013 \u00a0\u00a0FC Famalic\u00e3o \u00a0 8 &#8211; 1<br \/>\nButs\u00a0: <\/strong>5\u2019 Ibrahimi 1-0, 10\u2019 Paixao 1-1, 20\u2019 Debbah 2-1, 23\u2019 Rexhepi 3-1, 28\u2019 Rexhepi 4-1, 32\u2019 Ibrahimi 5-1, 52\u2019 Rexhepi 6-1, 80\u2019 Ibrahimi 7-1, 87\u2019 Rexhepi 8-1<\/p>\n<p style=\"text-align: justify;\">Les matches se suivent et se ressemblent pour la lanterne rouge Famalic\u00e3o. Les Lusitaniens ont subi une lourde d\u00e9faite contre Avanchet et n\u2019ont plus gagn\u00e9 depuis 10 matches d\u00e9sormais.<\/p>\n<p style=\"text-align: justify;\">Dans leur duel avec Famalic\u00e3o, Avanchet a notamment profit\u00e9 de la grande forme de Rexhepi, auteur d\u2019un quadrupl\u00e9. Les prot\u00e9g\u00e9s de Martino Papa cueillent ainsi leur premi\u00e8re victoire depuis la reprise. De quoi satisfaire leur coach\u00a0: <em>\u00ab\u00a0Un bon match de mon \u00e9quipe qui a \u00e9t\u00e9 sup\u00e9rieur du d\u00e9but \u00e0 la fin. Si notre finalisation avait \u00e9t\u00e9 meilleure, \u00a0le score aurait pu \u00eatre encore plus dilat\u00e9.\u00a0\u00bb<\/em><\/p>\n<p style=\"text-align: justify;\">Avanchet devra confirmer le week-end prochain contre Collex-Bossy II, <em>\u00ab\u00a0un match tr\u00e8s important pour la suite de notre championnat\u00a0<\/em>\u00bb, estimait Martino Papa. Le mentor d\u2019Avanchet souhaitait \u00e9galement \u00e0 adresser un message aux Lusitaniens ainsi qu\u2019\u00e0 son \u00e9quipe\u00a0: <em>\u00ab\u00a0J&#8217;aimerais souhaiter beaucoup de courage \u00e0 Famalic\u00e3o pour le maintien et f\u00e9liciter mon \u00e9quipe pour le bon \u00e9tat d&#8217;esprit et l&#8217;engagement lors de ce match.\u00a0\u00bb<\/em><\/p>\n<p style=\"text-align: justify;\">Si Avanchet peut encore regarder sur le haut de classement, les choses se compliquent pour Famalic\u00e3o. Les Lusitaniens comptent d\u00e9sormais huit points de retard sur la barre. A eux de sortir de leur spirale n\u00e9gative dimanche contre US Carouge.<em>\u00a0<\/em><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>CS Italien II\u00a0 \u00a0\u2013 \u00a0\u00a0FC Collex-Bossy II \u00a0 2 &#8211; 1<br \/>\nButs :\u00a0 <\/strong>10\u2019 Ribeiro 1-0, 47\u2019 Vidal 2-0, 86\u2019 Ould 2-1<\/p>\n<p style=\"text-align: justify;\">Un d\u00e9placement compliqu\u00e9 attendait Collex-Bossy II, qui se rendait au Bois-de-la-B\u00e2tie pour affronter CS Italien II. Et ce d\u00e9placement s\u2019est sold\u00e9 par une d\u00e9faite pour les Collesiens, battus pour la 8\u00e8me\u00a0fois de la saison.<\/p>\n<p style=\"text-align: justify;\">Les locaux ont pris l\u2019avantage rapidement gr\u00e2ce \u00e0 une belle t\u00eate de Ribeiro. Face \u00e0 une \u00e9quipe de Collex-Bossy bien en place, CS Italien II a ensuite doubl\u00e9 la mise par Vidal. Les visiteurs sont n\u00e9anmoins parvenus \u00e0 r\u00e9duire le score en fin de rencontre, alors que leurs adversaires \u00e9voluaient \u00e0 dix \u00e0 la suite d\u2019une blessure d\u2019un joueur et de leurs trois changements \u00e9puis\u00e9s.<\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s leur victoire contre Onex II, CS Italien II f\u00eate donc son deuxi\u00e8me succ\u00e8s depuis la reprise. Le duo Giuseppe Carluccio-Nihad Omeragic \u00e9mettait toutefois un petit regret, quant au manque d\u2019efficacit\u00e9 de ses joueurs\u00a0: <em>\u00ab\u00a0Nous regrettons de ne pas avoir suffisamment r\u00e9ussi \u00e0 concr\u00e9tiser les diverses actions cr\u00e9\u00e9es, ce qui nous aurait permis d\u2019\u00eatre plus tranquilles. Il nous faut chercher davantage l\u2019efficacit\u00e9, si nous souhaitons continuer sur cette lign\u00e9e. Bravo \u00e0 notre \u00e9quipe, mais \u00e9galement \u00e0 notre adversaire du jour.\u00a0\u00bb<\/em><\/p>\n<p style=\"text-align: justify;\">Les mentors du CS Italien tenaient enfin \u00e0 d\u00e9dier ce succ\u00e8s \u00e0 un entra\u00eeneur du club, Stefano Rocci\u00a0: <em>\u00ab\u00a0Toutes nos condol\u00e9ances \u00e0 la famille Rocci, entra\u00eeneur du club, ayant perdu ses parents au cours de ces 3 derniers mois.\u00a0\u00bb<\/em><\/p>\n<p style=\"text-align: justify;\">Gr\u00e2ce \u00e0 ce succ\u00e8s, CS Italien II recolle \u00e0 deux points du leader Plan-les-Ouates II. L\u2019\u00e9quipe s\u2019en ira d\u00e9fier Vernier II la semaine prochaine.\u00a0Pour sa part, Collex-Bossy, qui compte sept points de retard sur la barre, accueillera Avanchet.<\/p>\n<p style=\"text-align: justify;\"><i>\u00a0<\/i><\/p>\n<p style=\"text-align: justify;\"><strong>Signal FC Bernex-Confignon II\u00a0 \u00a0\u2013 \u00a0\u00a0FC Puplinge \u00a0 3 &#8211; 0<br \/>\nButs\u00a0:<\/strong> Arrigoni 1-0, Habel 2-0, Habel 3-0<\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s connu la d\u00e9faite contre Vernier II dimanche pass\u00e9, Signal-Bernex II a relev\u00e9 la t\u00eate contre Puplinge.<\/p>\n<p style=\"text-align: justify;\">Dans une partie \u00e9quilibr\u00e9e, les Bern\u00e9siens ont ouvert le score sur un magnifique tir lointain d\u2019Arrigoni. Des occasions de part et d\u2019autre ont ensuite rythm\u00e9 la deuxi\u00e8me p\u00e9riode, mais les locaux ont finalement assur\u00e9 leur victoire \u00e0 un quart d\u2019heure de la fin gr\u00e2ce \u00e0 deux buts d\u2019Habel.<\/p>\n<p style=\"text-align: justify;\"><em>\u00ab\u00a0On est tr\u00e8s contents d&#8217;avoir remport\u00e9 cette victoire qui a \u00e9t\u00e9 longue \u00e0 se dessiner<\/em> \u00bb, confiait Jos\u00e9 Monnerat \u00e0 l\u2019issue de la rencontre. <em>Notre solidarit\u00e9 et l&#8217;\u00e9tat d&#8217;esprit ont \u00e9t\u00e9 exemplaires et tout le groupe est \u00e0 f\u00e9liciter.\u00a0\u00bb<\/em><\/p>\n<p style=\"text-align: justify;\">Dimanche prochain, Signal-Bernex II, qui monte sur le podium \u00e0 deux points de la premi\u00e8re place, se d\u00e9placera \u00e0 Frontenex pour d\u00e9fier UGS II. Puplinge, pour sa part, disputera un match important pour le maintien contre Onex II.<\/p>\n<div id=\"attachment_16129\" style=\"width: 560px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.facebook.com\/johan.franzen.376\/media_set?set=a.358673107604435.1073741916.100003852454093&amp;type=1\" target=\"_blank\"><img aria-describedby=\"caption-attachment-16129\" loading=\"lazy\" class=\" wp-image-16129 \" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/03\/Bernex-Puplinge-1314.jpg\" alt=\"Bernex-Puplinge-1314\" width=\"550\" height=\"371\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/03\/Bernex-Puplinge-1314.jpg 2048w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/03\/Bernex-Puplinge-1314-300x202.jpg 300w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/03\/Bernex-Puplinge-1314-1024x690.jpg 1024w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/03\/Bernex-Puplinge-1314-660x444.jpg 660w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/><\/a><p id=\"caption-attachment-16129\" class=\"wp-caption-text\">Victoire ais\u00e9e des Bern\u00e9siens (Photo: J. Franzen)<\/p><\/div>\n<p>&nbsp;<\/p>\n<p><strong>FC Onex II\u00a0 \u00a0\u2013 \u00a0\u00a0FC Vernier II \u00a0 2 &#8211; 0\u00a0<\/strong><br \/>\n<strong><a title=\"Victoire importante d\u2019Onex II\" href=\"http:\/\/www.proxifoot.ch\/geneve\/2014\/03\/victoire-importante-donex-ii\/\"><em>Lire l&#8217;article<\/em><\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-16023\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/03\/3eligue1-1314-14.jpg\" alt=\"3eligue1-1314-14\" width=\"564\" height=\"309\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/03\/3eligue1-1314-14.jpg 564w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/03\/3eligue1-1314-14-300x164.jpg 300w\" sizes=\"(max-width: 564px) 100vw, 564px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>14\u00e8me journ\u00e9e \/ Plan-les-Ouates II et City se partagent la premi\u00e8re place, mais Signal Bernex II et CS Italien II veillent au grain. En bas de tableau, cela commence \u00e0 devenir tr\u00e8s compliqu\u00e9 pour Collex II et Famalic\u00e3o.<\/p>\n","protected":false},"author":1,"featured_media":6247,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[6],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.proxifoot.ch\/geneve\/2014\/03\/3eme-ligue-groupe-1-la-course-a-la-promotion-continue\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3\u00e8me ligue, groupe 1 : la course \u00e0 la promotion continue - Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"og:description\" content=\"14\u00e8me journ\u00e9e \/ Plan-les-Ouates II et City se partagent la premi\u00e8re place, mais Signal Bernex II et CS Italien II veillent au grain. En bas de tableau, cela commence \u00e0 devenir tr\u00e8s compliqu\u00e9 pour Collex II et Famalic\u00e3o.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.proxifoot.ch\/geneve\/2014\/03\/3eme-ligue-groupe-1-la-course-a-la-promotion-continue\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2014-03-23T18:11:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-20T15:10:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/09\/banniere-3\u00e8me-ligue1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"164\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2014\/03\/3eme-ligue-groupe-1-la-course-a-la-promotion-continue\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/09\/banniere-3\\u00e8me-ligue1.jpg\",\"width\":660,\"height\":164},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2014\/03\/3eme-ligue-groupe-1-la-course-a-la-promotion-continue\/#webpage\",\"url\":\"http:\/\/www.proxifoot.ch\/geneve\/2014\/03\/3eme-ligue-groupe-1-la-course-a-la-promotion-continue\/\",\"name\":\"3\\u00e8me ligue, groupe 1 : la course \\u00e0 la promotion continue - Proxifoot, le m\\u00e9dia du football genevois\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2014\/03\/3eme-ligue-groupe-1-la-course-a-la-promotion-continue\/#primaryimage\"},\"datePublished\":\"2014-03-23T18:11:52+00:00\",\"dateModified\":\"2016-07-20T15:10:50+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.proxifoot.ch\/geneve\/2014\/03\/3eme-ligue-groupe-1-la-course-a-la-promotion-continue\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\",\"name\":\"admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/15969"}],"collection":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=15969"}],"version-history":[{"count":0,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/15969\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/6247"}],"wp:attachment":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=15969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=15969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=15969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}