﻿{"id":1656,"date":"2012-03-11T19:02:01","date_gmt":"2012-03-11T18:02:01","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=1656"},"modified":"2016-07-19T16:17:50","modified_gmt":"2016-07-19T14:17:50","slug":"1ere-ligue-16eme-journee","status":"publish","type":"post","link":"https:\/\/www.proxifoot.ch\/geneve\/2012\/03\/1ere-ligue-16eme-journee\/","title":{"rendered":"1\u00e8re ligue : 16\u00e8me journ\u00e9e"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Belles victoires \u00e0 domicile pour UGS et Grand-Lancy, Meyrin, quant \u00e0 lui, est revenu d\u00e9fait du Valais.<!--more--><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>R\u00e9sultats des \u00e9quipes genevoises :<\/em><\/strong><\/p>\n<p><strong>FC UGS &#8211;\u00a0 FC Fribourg\u00a0\u00a0 2 &#8211; 0<\/strong><br \/>\n<em>Voir <a title=\"Bonne reprise pour UGS\" href=\"http:\/\/www.proxifoot.ch\/geneve\/?p=1654\" target=\"_blank\">article Proxifoot<\/a><\/em><\/p>\n<p><span style=\"color: #ffffff;\">\u00a0.<\/span><\/p>\n<p><strong>FC Grand-Lancy\u00a0\u00a0 &#8211;\u00a0 FC Martigny-Sports\u00a0\u00a0 3 &#8211; 2<br \/>\nButs\u00a0:<\/strong> Linares 1-0, 1-1,\u00a0Ouattara 2-1, 2-2,\u00a0Ferati (P) 3-2<\/p>\n<p style=\"text-align: justify;\">Belle performance du FC Grand-Lancy lors de cette journ\u00e9e de reprise avec une victoire sur Martigny, permettant aux joueurs de Marignac de rester au contact du milieu de tableau.<\/p>\n<p style=\"text-align: justify;\">Cependant, les &#8220;bleu et blanc&#8221; ont longtemps cru que leur mal\u00e9diction du premier tour ne les avait pas l\u00e2ch\u00e9s, un poteau d\u00e8s la 1\u00e8re minute, un penalty rat\u00e9 et un nombre de grosses occasions rat\u00e9es par maladresse ou par le talent du portier adverse.<\/p>\n<p style=\"text-align: justify;\">Heureusement pour eux, les joueurs de Bojan Dimic parviendront \u00e0 tenir le 3-2 et \u00e0 remporter les trois points dans un match qu&#8217;ils auraient d\u00fb remporter bien plus largement, comme le confirme leur entra\u00eeneur\u00a0: \u00ab\u00a0Un bon match de reprise de la part de mes joueurs. Le score est serr\u00e9 mais uniquement de par notre manque de r\u00e9ussite car on s\u2019est cr\u00e9\u00e9s 7-8 occasions nettes ! On aurait d\u00fb boucler le match bien avant ! Mais le spectre du premier tour a ressurgi : beaucoup d\u2019occasions mais on ne marque pas et on se fait avoir\u00a0! Enfin, je suis content car on a \u00e9t\u00e9 solide et nous n\u2019avons paniqu\u00e9 \u00e0 aucun moment.\u00a0\u00bb<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong>FC Monthey\u00a0\u00a0 &#8211;\u00a0 FC Meyrin\u00a0\u00a0 1 &#8211; 0<\/strong><br \/>\n<em><br \/>\n<\/em>D\u00e9placement difficile pour le FC Meyrin en terres valaisannes, d\u00e9faits par le FC Monthey, avant-derniers au classement avant cette journ\u00e9e. Cette contre-performance comptable enfonce un peu plus les espoirs des hommes d&#8217;Herv\u00e9 Musqu\u00e8re de remonter au classement, mais le championnat est encore long.<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>Autres r\u00e9sultats :<\/strong><\/em><\/p>\n<p><strong>FC Le Mont LS\u00a0 &#8211;\u00a0 FC Naters\u00a0 \u00a01 &#8211; 1\u00a0\u00a0\u00a0<\/strong><br \/>\n<strong>\u00a0<\/strong><br \/>\n<strong>FC Bulle\u00a0\u00a0 &#8211;\u00a0 FC Echallens\u00a0 \u00a00 &#8211; 1\u00a0\u00a0\u00a0<\/strong><br \/>\n<strong>\u00a0<\/strong><br \/>\n<strong>SC D\u00fcdingen\u00a0\u00a0 &#8211;\u00a0 Yverdon-Sport FC\u00a0\u00a0 0 &#8211; 2\u00a0\u00a0<\/strong><br \/>\n<strong>\u00a0<\/strong><br \/>\n<strong>FC Baulmes\u00a0\u00a0 &#8211;\u00a0 BSC Young Boys U-21 \u00a0 4 &#8211; 6\u00a0\u00a0\u00a0\u00a0<\/strong><br \/>\n<strong>\u00a0\u00a0<\/strong><br \/>\n<strong>FC Sion M-21\u00a0 &#8211;\u00a0 ES FC Malley LS \u00a0 3 &#8211; 1\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/03\/1eligue16.jpg\"><img loading=\"lazy\" class=\"size-full wp-image-1657 alignleft\" title=\"1eligue16\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/03\/1eligue16.jpg\" alt=\"\" width=\"517\" height=\"288\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/03\/1eligue16.jpg 517w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/03\/1eligue16-300x167.jpg 300w\" sizes=\"(max-width: 517px) 100vw, 517px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Belles victoires \u00e0 domicile pour UGS et Grand-Lancy, Meyrin, quant \u00e0 lui, est revenu d\u00e9fait du Valais.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[4],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.proxifoot.ch\/geneve\/2012\/03\/1ere-ligue-16eme-journee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1\u00e8re ligue : 16\u00e8me journ\u00e9e - Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"og:description\" content=\"Belles victoires \u00e0 domicile pour UGS et Grand-Lancy, Meyrin, quant \u00e0 lui, est revenu d\u00e9fait du Valais.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.proxifoot.ch\/geneve\/2012\/03\/1ere-ligue-16eme-journee\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2012-03-11T18:02:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-19T14:17:50+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.proxifoot.ch\/new\/wp-content\/uploads\/2012\/03\/1eligue16.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2012\/03\/1ere-ligue-16eme-journee\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/03\/1eligue16.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2012\/03\/1ere-ligue-16eme-journee\/#webpage\",\"url\":\"http:\/\/www.proxifoot.ch\/geneve\/2012\/03\/1ere-ligue-16eme-journee\/\",\"name\":\"1\\u00e8re ligue : 16\\u00e8me journ\\u00e9e - Proxifoot, le m\\u00e9dia du football genevois\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2012\/03\/1ere-ligue-16eme-journee\/#primaryimage\"},\"datePublished\":\"2012-03-11T18:02:01+00:00\",\"dateModified\":\"2016-07-19T14:17:50+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.proxifoot.ch\/geneve\/2012\/03\/1ere-ligue-16eme-journee\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\",\"name\":\"admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/1656"}],"collection":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=1656"}],"version-history":[{"count":0,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/1656\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=1656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=1656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=1656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}