﻿{"id":16596,"date":"2014-04-22T12:20:17","date_gmt":"2014-04-22T10:20:17","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=16596"},"modified":"2021-09-03T17:06:14","modified_gmt":"2021-09-03T15:06:14","slug":"ivan-de-pedro-donzellois-dame-et-de-coeur","status":"publish","type":"post","link":"https:\/\/www.proxifoot.ch\/geneve\/2014\/04\/ivan-de-pedro-donzellois-dame-et-de-coeur\/","title":{"rendered":"Ivan De Pedro, Donzellois d\u2019\u00e2me et de coeur"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Joueur embl\u00e9matique du FC Donzelle, Ivan De Pedro termine actuellement sa 16\u00e8me&nbsp;saison en Premi\u00e8re \u00e9quipe, sa 14\u00e8me&nbsp;cons\u00e9cutive. Rencontre avec le fid\u00e8le num\u00e9ro 11 du Stade du Moulin.<!--more--><\/strong><\/p>\n<p style=\"text-align: justify;\"><b>&nbsp;<\/b><\/p>\n<p style=\"text-align: justify;\"><strong>Ivan, peux-tu te pr\u00e9senter pour ceux qui ne te connaissent pas encore&nbsp;?<br \/>\n<\/strong>Je m\u2019appelle Ivan De Pedro Blanco, j\u2019ai 33 ans. Je suis n\u00e9 et ai v\u00e9cu les premi\u00e8res ann\u00e9es de ma vie en Espagne, \u00e0 Valladolid. A l\u2019\u00e2ge de 9 ans, j\u2019ai rejoint ma m\u00e8re en Suisse o\u00f9 j\u2019ai commenc\u00e9 le foot au FC Donzelle. J\u2019y ai fait toutes mes classes juniors jusqu\u2019en B. C\u2019est alors que j\u2019ai int\u00e9gr\u00e9 la Premi\u00e8re \u00e9quipe, en compagnie de Fabrice Gisler, \u00e0 l\u2019\u00e2ge de 16 ans. Six mois plus tard, nous f\u00eations une promotion en 2\u00e8me&nbsp;ligue.&nbsp;La saison suivante, nous connaissons une rel\u00e9gation douloureuse et c\u2019est alors que je d\u00e9cide d\u2019aller tenter ma chance \u00e0 Meyrin.<b>&nbsp;<\/b><\/p>\n<p style=\"text-align: justify;\"><strong>Justement, parle-nous de ta seule ann\u00e9e disput\u00e9e ailleurs qu\u2019\u00e0 La Plaine.<br \/>\n<\/strong>A l\u2019\u00e9poque, j\u2019avais 17 ans, je jouais en 2\u00e8me&nbsp;ligue et ainsi, j\u2019ai eu quelques propositions de clubs de 1\u00e8re&nbsp;ligue. Yves Pazmandy, qui est l\u2019entra\u00eeneur qui m\u2019a donn\u00e9 ma chance en 3\u00e8me&nbsp;ligue, prenait la t\u00eate du CS Ch\u00eanois et m\u2019a propos\u00e9 de venir, mais finalement, j\u2019ai accept\u00e9 l\u2019offre de Meyrin, pour des raisons logistiques. J\u2019y ai donc sign\u00e9 et ai \u00e9t\u00e9 incorpor\u00e9 au contingent de la premi\u00e8re \u00e9quipe. Malheureusement, une grosse blessure \u00e0 la fin de la pr\u00e9paration estivale me fait prendre du retard dans le rythme et je me retrouve en juniors A inter. Je reviens \u00e0 la tr\u00eave hivernale, mais lors d\u2019un stage en Tunisie, je me d\u00e9chire un muscle et perds toutes mes chances de gagner ma place en 1\u00e8re&nbsp;ligue. J\u2019ai tout de m\u00eame eu la chance d\u2019y jouer 15 minutes \u00e0 Martigny. Toutefois, cette saison restera positive pour moi, puisqu\u2019avec les A inter, nous avons remport\u00e9 le titre de champions suisses de la cat\u00e9gorie ainsi que la coupe genevoise des actifs dont la finale aux Charmilles restera comme l\u2019un de mes meilleurs souvenirs.<\/p>\n<div id=\"attachment_16611\" style=\"width: 592px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-16611\" loading=\"lazy\" class=\" wp-image-16611 \" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/04\/De-Pedro-Donzelle-2.jpg\" alt=\"De-Pedro-Donzelle-2\" width=\"582\" height=\"431\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/04\/De-Pedro-Donzelle-2.jpg 924w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/04\/De-Pedro-Donzelle-2-300x222.jpg 300w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/04\/De-Pedro-Donzelle-2-660x489.jpg 660w\" sizes=\"(max-width: 582px) 100vw, 582px\" \/><p id=\"caption-attachment-16611\" class=\"wp-caption-text\">Le num\u00e9ro 11 donzellois, lors d&#8217;un de ses nombreux matchs au Moulin<\/p><\/div>\n<p style=\"text-align: justify;\"><strong>Apr\u00e8s cette saison, tu reviens \u00e0 Donzelle.<br \/>\n<\/strong>Oui, au terme de la saison, l\u2019\u00e9quipe des A inter a explos\u00e9 et bien qu\u2019ayant re\u00e7u quelques offres int\u00e9ressantes, j\u2019ai accept\u00e9 de revenir \u00e0 Donzelle, mon club formateur, sous les ordres de Pascal P\u00eacheur (<em>ndlr: actuel entra\u00eeneur de Champel<\/em>), mon entra\u00eeneur en B qui reprenait les r\u00eanes de la premi\u00e8re avec un projet qui m\u2019a tent\u00e9. Nous avons d\u2019ailleurs \u00e9t\u00e9 champions genevois de 3\u00e8me&nbsp;ligue d\u00e8s cette saison. Et depuis cet \u00e9t\u00e9 2000, je n\u2019ai plus quitt\u00e9 l\u2019\u00e9quipe.<\/p>\n<p style=\"text-align: justify;\"><strong>Comment expliques-tu cette fid\u00e9lit\u00e9 \u00e0 ton club formateur&nbsp;?<br \/>\n<\/strong>Le foot, et le sport en g\u00e9n\u00e9ral, sont un vrai besoin pour moi. J\u2019ai besoin de jouer au foot pour mon \u00e9quilibre. Et le FC Donzelle est mon vrai club de c\u0153ur. J\u2019y ai fait toutes mes classes, ai jou\u00e9 mes premiers matchs actifs avec la deuxi\u00e8me \u00e9quipe alors que j\u2019avais \u00e0 peine 14 ans, int\u00e9gr\u00e9 l\u2019\u00e9quipe fanion deux ans plus tard. J\u2019y ai v\u00e9cu deux promotions, deux rel\u00e9gations et plein d\u2019\u00e9motions. J\u2019ai entra\u00een\u00e9 \u00e0 presque tous les niveaux des juniors et, le jour o\u00f9 j\u2019arr\u00eaterai, ou partirai, ce sera vraiment triste pour moi.<\/p>\n<p style=\"text-align: justify;\"><strong>En parlant des juniors, comme tu l\u2019as dit, tu as entra\u00een\u00e9 \u00e0 tous les niveaux de l\u2019Ecole de Foot aux juniors B et bon nombre de joueurs que tu as connu jouent aujourd\u2019hui avec toi en Premi\u00e8re. Cela doit \u00eatre une fiert\u00e9\u2026<br \/>\n<\/strong>Il est vrai que j\u2019ai eu certains joueurs \u00e0 l\u2019Ecole de Foot (Zumbach, Monnier), et d\u2019autres en D ou en B (Marques, Rexhepi, Tesfamichael, entre autres) et c\u2019est un plaisir de les voir arriver et de les accueillir comme co\u00e9quipiers. Mais la plus grande fiert\u00e9 est d\u2019avoir eu la chance de jouer avec un p\u00e8re et son fils. A mon arriv\u00e9e, Luco Grunder a \u00e9t\u00e9 tr\u00e8s pr\u00e9sent \u00e0 mes c\u00f4t\u00e9s pour m\u2019aider et je me rappellerai toujours le jour o\u00f9 il nous a annonc\u00e9 la naissance de son fils. Aujourd\u2019hui, Dimitri a int\u00e9gr\u00e9 l\u2019\u00e9quipe et cela me rend particuli\u00e8rement fier.<\/p>\n<div id=\"attachment_16606\" style=\"width: 176px\" class=\"wp-caption alignleft\"><img aria-describedby=\"caption-attachment-16606\" loading=\"lazy\" class=\" wp-image-16606 \" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/04\/De-Pedro-Lamers.jpg\" alt=\"De-Pedro-Lamers\" width=\"166\" height=\"275\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/04\/De-Pedro-Lamers.jpg 384w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/04\/De-Pedro-Lamers-181x300.jpg 181w\" sizes=\"(max-width: 166px) 100vw, 166px\" \/><p id=\"caption-attachment-16606\" class=\"wp-caption-text\">Avec Lamers, son entra\u00eeneur actuel<\/p><\/div>\n<p style=\"text-align: justify;\"><strong>Tu as connu trois g\u00e9n\u00e9rations de joueurs lors de ces 14 derni\u00e8res saisons en Premi\u00e8re, comment d\u00e9finirais-tu les diff\u00e9rences entre elles&nbsp;?<br \/>\n<\/strong>Quand on est arriv\u00e9s en Premi\u00e8re \u00e9quipe avec Fabrice Gisler, on a tout de suite \u00e9t\u00e9 entour\u00e9s et pris sous l\u2019aile de gars exp\u00e9riment\u00e9s comme Christian Lamers, Ugo De Stefano, Luco Grunder et les fr\u00e8res Cautillo, Michel et Armand. Par la suite est arriv\u00e9e une g\u00e9n\u00e9ration de joueurs d\u2019un \u00e2ge plus proche du mien, m\u00eame si les r\u00e9sultats n\u2019ont plus \u00e9t\u00e9 aussi bons (rel\u00e9gation lors de la saison 2005\/2006) et enfin la g\u00e9n\u00e9ration actuelle de joueurs bien plus jeunes o\u00f9 je fais d\u00e9sormais partie des \u00ab&nbsp;anciens&nbsp;\u00bb. Mais ce que je constate, c\u2019est que ce statut \u00ab&nbsp;d\u2019ancien&nbsp;\u00bb n\u2019est plus aussi respect\u00e9 qu\u2019avant. Les jeunes arrivent avec leurs certitudes et pensent tout savoir ne donnant que tr\u00e8s peu de cr\u00e9dit \u00e0 l\u2019exp\u00e9rience, chose qui \u00e9tait impensable quand je suis arriv\u00e9 en 3\u00e8me&nbsp;ligue. C\u2019est malheureux, mais on ne peut que faire avec. J\u2019ai aussi le sentiment que l\u2019\u00e9tat d\u2019esprit donzellois, cette mentalit\u00e9 qui \u00e9tait la n\u00f4tre, a tendance \u00e0 dispara\u00eetre avec les jeunes qui ont pourtant des qualit\u00e9s techniques ind\u00e9niables, mais sans cet \u00e9tat d\u2019esprit, il sera dur pour nous de faire mieux que ce qu\u2019on fait actuellement.<\/p>\n<p style=\"text-align: justify;\"><strong>Si tu devais sortir ton meilleur et ton pire souvenir donzellois&nbsp;?<br \/>\n<\/strong>Au niveau du meilleur, je dirais sans aucun doute les deux promotions en 2\u00e8me&nbsp;ligue, avec une pr\u00e9f\u00e9rence pour la premi\u00e8re&nbsp;v\u00e9cue alors que j\u2019avais \u00e0 peine 16 ans et que je venais d\u2019int\u00e9grer l\u2019\u00e9quipe fanion de mon club formateur.&nbsp;Sinon, je garde aussi un excellent souvenir de cette finale de coupe genevoise gagn\u00e9e avec Meyrin, mais plus pour le cadre, et cette rencontre gagn\u00e9e aux Charmilles en ouverture du Servette. En termes de mauvais souvenirs, il y a \u00e9videmment les rel\u00e9gations, mais avec l\u00e0 aussi une mention \u00e0 la premi\u00e8re, v\u00e9cue une ann\u00e9e apr\u00e8s la promotion et alors que j\u2019avais d\u00e9cid\u00e9 de quitter Donzelle pour Meyrin. Ce sentiment de trahir mon club a \u00e9t\u00e9 dur \u00e0 dig\u00e9rer.&nbsp;J\u2019ai aussi eu la tristesse de vivre le d\u00e9c\u00e8s de trois co\u00e9quipiers, Marc Todesco, Christophe \u00ab&nbsp;Popoph&nbsp;\u00bb Salvi et surtout Armand Cautillo, dont la perte a \u00e9t\u00e9 terrible pour le club.<\/p>\n<p style=\"text-align: justify;\"><strong>Tu as 33 ans, l\u2019heure de la retraite va-t-elle bient\u00f4t sonner&nbsp;?<br \/>\n<\/strong>Je n\u2019ai pas encore envie d\u2019aller en V\u00e9t\u00e9rans, m\u00eame si cela me ferait tr\u00e8s plaisir de retrouver certains anciens co\u00e9quipiers, mais je pense pouvoir encore amener quelque chose en 3\u00e8me&nbsp;ligue. Et surtout, j\u2019adorerais terminer sur une promotion. J\u2019esp\u00e9rais cela possible la saison derni\u00e8re ou cette saison, malheureusement, si ce n\u2019est pas pass\u00e9 loin l\u2019an dernier, cette ann\u00e9e a \u00e9t\u00e9 plus compliqu\u00e9e. Et \u00e0 mon avis, sans certains changements, je suis pessimiste pour la suite.<\/p>\n<p style=\"text-align: justify;\"><strong>Tu as eu l\u2019occasion de fr\u00e9quenter bon nombre de co\u00e9quipiers, y en a-t-il qui t\u2019ont davantage marqu\u00e9 que d\u2019autres ?<br \/>\n<\/strong>Sur le plan foot, je mentionnerais Laurent Goy, qui \u00e9tait venu de LNB pour jouer avec nous en 3\u00e8me&nbsp;ligue pendant deux saisons, un joueur tr\u00e8s tr\u00e8s fort. Sur le plan humain, toute l\u2019\u00e9quipe qui m\u2019a accueillie quand j\u2019avais 16 ans. Les personnes que j\u2019ai mentionn\u00e9es tout \u00e0 l\u2019heure avec mention particuli\u00e8re \u00e0 Armand Cautillo, qui restera \u00e0 jamais le capitaine embl\u00e9matique du FC Donzelle. Enfin, derni\u00e8rement, je citerais Farid Lamri, joueur et homme incroyable.<\/p>\n<p style=\"text-align: justify;\"><strong>Enfin, as-tu un mot \u00e0 ajouter&nbsp;?<br \/>\n<\/strong>Oui, j\u2019aimerais vous remercier de l\u2019attention que vous me portez, mais je n\u2019ai pas fait grand-chose hormis rester fid\u00e8le \u00e0 mon club de c\u0153ur.&nbsp;Par ailleurs, Donzelle f\u00eate ses 80 ans cette ann\u00e9e et je convie tout le monde \u00e0 assister aux diverses animations qui seront propos\u00e9es pour ce bel anniversaire.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>BIO EXPRESS<\/strong><\/p>\n<p><strong>Naissance&nbsp;<\/strong>: 12 avril 1981 \u00e0 Valladolid (Espagne)<\/p>\n<p><strong>Parcours<\/strong><br \/>\nJuniors au FC Donzelle<br \/>\n1997-1999&nbsp;: FC Donzelle<br \/>\n1999-2000 : FC Meyrin<br \/>\nDepuis 2000 : FC Donzelle<\/p>\n<p>&nbsp;<\/p>\n<p><em>Photos : IV Sport<\/em><br \/>\n<script src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\" async=\"\"><\/script><!-- superieur --> <ins class=\"adsbygoogle\" style=\"display: inline-block; width: 728px; height: 90px;\" data-ad-slot=\"1875735477\" data-ad-client=\"ca-pub-1317159203547503\"><\/ins><script>\/\/ <![CDATA[ (adsbygoogle = window.adsbygoogle || []).push({}); \/\/ ]]><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Joueur embl\u00e9matique du FC Donzelle, Ivan De Pedro termine actuellement sa 16\u00e8me&nbsp;saison en Premi\u00e8re \u00e9quipe, sa 14\u00e8me&nbsp;cons\u00e9cutive. Rencontre avec le fid\u00e8le num\u00e9ro 11 du Stade du Moulin.<\/p>\n","protected":false},"author":34,"featured_media":16605,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[6,544],"tags":[92,46,203],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.proxifoot.ch\/geneve\/2014\/04\/ivan-de-pedro-donzellois-dame-et-de-coeur\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ivan De Pedro, Donzellois d\u2019\u00e2me et de coeur - Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"og:description\" content=\"Joueur embl\u00e9matique du FC Donzelle, Ivan De Pedro termine actuellement sa 16\u00e8me&nbsp;saison en Premi\u00e8re \u00e9quipe, sa 14\u00e8me&nbsp;cons\u00e9cutive. Rencontre avec le fid\u00e8le num\u00e9ro 11 du Stade du Moulin.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.proxifoot.ch\/geneve\/2014\/04\/ivan-de-pedro-donzellois-dame-et-de-coeur\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2014-04-22T10:20:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-03T15:06:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/04\/De-Pedro-Donzelle.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2014\/04\/ivan-de-pedro-donzellois-dame-et-de-coeur\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/04\/De-Pedro-Donzelle.jpg\",\"width\":1024,\"height\":640},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2014\/04\/ivan-de-pedro-donzellois-dame-et-de-coeur\/#webpage\",\"url\":\"http:\/\/www.proxifoot.ch\/geneve\/2014\/04\/ivan-de-pedro-donzellois-dame-et-de-coeur\/\",\"name\":\"Ivan De Pedro, Donzellois d\\u2019\\u00e2me et de coeur - Proxifoot, le m\\u00e9dia du football genevois\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2014\/04\/ivan-de-pedro-donzellois-dame-et-de-coeur\/#primaryimage\"},\"datePublished\":\"2014-04-22T10:20:17+00:00\",\"dateModified\":\"2021-09-03T15:06:14+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/85c9e873354a0bdc93a855141f775b3d\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.proxifoot.ch\/geneve\/2014\/04\/ivan-de-pedro-donzellois-dame-et-de-coeur\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/85c9e873354a0bdc93a855141f775b3d\",\"name\":\"Greg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/16596"}],"collection":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=16596"}],"version-history":[{"count":2,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/16596\/revisions"}],"predecessor-version":[{"id":46044,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/16596\/revisions\/46044"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/16605"}],"wp:attachment":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=16596"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=16596"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=16596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}