﻿{"id":19464,"date":"2014-10-12T23:10:46","date_gmt":"2014-10-12T21:10:46","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=19464"},"modified":"2016-10-25T12:33:16","modified_gmt":"2016-10-25T10:33:16","slug":"le-cs-ny-arrive-pas-a-domicile","status":"publish","type":"post","link":"https:\/\/www.proxifoot.ch\/geneve\/2014\/10\/le-cs-ny-arrive-pas-a-domicile\/","title":{"rendered":"Le CS n\u2019y arrive pas \u00e0 domicile"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Un unique but d&#8217;Howard a permis \u00e0 A\u00efre de l&#8217;emporter sur le terrain du Bois-de-la-B\u00e2tie. Avec ce succ\u00e8s, les hommes d&#8217;Helder Silva restent au contact du leader.<!--more--><\/strong><\/p>\n<p style=\"text-align: justify;\">Quatre matchs \u00e0 domicile : Onex (2-3), Kosova (1-2), City (2-3) et&#8230; A\u00efre (0-1). M\u00eame si les scores sont serr\u00e9s, le constat est toujours le m\u00eame : le CS Italien n&#8217;arrive pas \u00e0 engranger le moindre point \u00e0 la maison. A\u00efre est donc la derni\u00e8re \u00e9quipe \u00e0 \u00eatre repartie du Bois-de-la-B\u00e2tie avec les trois points en poche, au terme d&#8217;un match que les hommes d&#8217;Helder Silva ont globalement m\u00e9rit\u00e9 de gagner.<\/p>\n<p style=\"text-align: justify;\"><strong>Les arr\u00eats de Yamane, les rat\u00e9s d&#8217;Howard<\/strong><\/p>\n<p style=\"text-align: justify;\">Belle surprise de ce d\u00e9but du championnat, le n\u00e9o-promu a\u00efrois a mis longtemps \u00e0 ouvrir la marque sur le terrain du CS. La faute notamment au manque de pr\u00e9cision dans le dernier geste de l&#8217;attaquant Junior Howard (4&#8242;, 23&#8242;, 26&#8242; et 29&#8242;), mais \u00e9galement \u00e0 la grande premi\u00e8re mi-temps du gardien du CS, Mehdi Yamane, auteur de quelques arr\u00eats d\u00e9cisifs. Oui, seulement grande premi\u00e8re mi-temps puisque le jeune portier n\u00e9 en 1996 a d\u00fb \u00eatre remplac\u00e9 \u00e0 la pause en raison d&#8217;une blessure au coude.<\/p>\n<p style=\"text-align: justify;\">Toujours est-il qu&#8217;au terme d&#8217;un premier act\u00e9 hach\u00e9 aux tr\u00e8s nombreux coups de sifflet de l&#8217;arbitre, le score \u00e9tait toujours nul et vierge \u00e0 la B\u00e2tie. Sup\u00e9rieurs \u00e0 mi-terrain, les &#8220;Oranges&#8221; se sont montr\u00e9s davantage dangereux alors qu&#8217;au contraire, les locaux ont eu des probl\u00e8mes \u00e0 la relance. Leur poisse est aussi \u00e0 souligner, puisqu&#8217;en plus de leur gardien, l&#8217;attaquant Matri a \u00e9galement d\u00fb \u00eatre remplac\u00e9 sur blessure \u00e0 la demi-heure.<\/p>\n<div id=\"attachment_19477\" style=\"width: 622px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-19477\" loading=\"lazy\" class=\" wp-image-19477 \" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/10\/CSitalien-Aire-1415-1.jpg\" alt=\"CSitalien-Aire-1415-1\" width=\"612\" height=\"410\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/10\/CSitalien-Aire-1415-1.jpg 1417w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/10\/CSitalien-Aire-1415-1-300x201.jpg 300w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/10\/CSitalien-Aire-1415-1-1024x686.jpg 1024w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/10\/CSitalien-Aire-1415-1-660x442.jpg 660w\" sizes=\"(max-width: 612px) 100vw, 612px\" \/><p id=\"caption-attachment-19477\" class=\"wp-caption-text\">Costa et Blanco en action<\/p><\/div>\n<p><strong>Howard, finalement<\/strong><\/p>\n<p style=\"text-align: justify;\">La seconde mi-temps est cependant plus \u00e9quilibr\u00e9e et il a fallu qu&#8217;un d\u00e9tail se charge du sort de la rencontre : sur une passe en profondeur de Barros, le malheureux d\u00e9fenseur Antonilli manque son interception et permet \u00e0 Howard de s&#8217;en aller battre, enfin, le v\u00e9t\u00e9ran gardien Alvarez (63&#8242;, 0-1), rentr\u00e9 \u00e0 la mi-temps pour des raisons d\u00e9j\u00e0 \u00e9voqu\u00e9es.<\/p>\n<p style=\"text-align: justify;\">Ceci restera le seul but de la rencontre, au grand dam des prot\u00e9g\u00e9s de Raffaele Del Rosso, qui ont pouss\u00e9 en fin de match mais qui se sont heurt\u00e9s \u00e0 une d\u00e9fense quasi-imp\u00e9n\u00e9trable des A\u00efrois, emmen\u00e9e par l&#8217;exp\u00e9riment\u00e9 gardien Van der Laan, arriv\u00e9 cet \u00e9t\u00e9 en provenance de Plan-les-Ouates.<\/p>\n<p style=\"text-align: justify;\">Arborant son ins\u00e9parable maillot des Pays-Bas, le d\u00e9j\u00e0 capitaine est ce qu&#8217;il y a de plus rassurant pour une \u00e9quipe, non seulement en raison de ses arr\u00eats mais aussi de sa communication sur le terrain. Ce dernier nous a livr\u00e9 ses impressions :<em>\u00a0<i>\u00ab\u00a0<\/i>Je pense que notre victoire est logique, on a quand m\u00eame 3-4 grosses occasions, leur gardien a fait de tr\u00e8s bons arr\u00eats en premi\u00e8re p\u00e9riode. Pour le moment, notre saison se passe bien, c&#8217;est plus facile quand on regarde en haut, c&#8217;est s\u00fbr. De mon c\u00f4t\u00e9, je me sens tr\u00e8s bien, je suis \u00e0 l&#8217;aise dans cette \u00e9quipe. On m&#8217;a donn\u00e9 le brassard d\u00e8s mon arriv\u00e9e, c&#8217;est une belle marque de confiance&#8221;.<\/em><\/p>\n<div id=\"attachment_19476\" style=\"width: 622px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-19476\" loading=\"lazy\" class=\" wp-image-19476 \" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/10\/CSitalien-Aire-1415-2.jpg\" alt=\"CSitalien-Aire-1415-2\" width=\"612\" height=\"410\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/10\/CSitalien-Aire-1415-2.jpg 1417w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/10\/CSitalien-Aire-1415-2-300x201.jpg 300w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/10\/CSitalien-Aire-1415-2-1024x686.jpg 1024w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/10\/CSitalien-Aire-1415-2-660x442.jpg 660w\" sizes=\"(max-width: 612px) 100vw, 612px\" \/><p id=\"caption-attachment-19476\" class=\"wp-caption-text\">Martinez et Racalbuto se disputent le ballon sous les yeux de Van der Laan<\/p><\/div>\n<p style=\"text-align: justify;\">Helder Silva et son \u00e9quipe r\u00e9ussissent donc leur entr\u00e9e en 2\u00e8me ligue. Apr\u00e8s sept journ\u00e9es, ils sont \u00e0 seulement deux points de la t\u00eate. A souligner la bonne ligne d\u00e9fensive &#8211; mention sp\u00e9ciale \u00e0 Miguel &#8211; mais \u00e9galement le tr\u00e8s gros travail \u00e0 mi-terrain de Monteiro et Barros, ainsi que du milieu de couloir Costa, g\u00e9n\u00e9reux dans l&#8217;effort et pr\u00e9cieux dans la conservation.<\/p>\n<p style=\"text-align: justify;\">Si ce d\u00e9but de saison sourit \u00e0 A\u00efre, c&#8217;est tout le contraire en revanche pour le CS Italien. L&#8217;ann\u00e9e avait bien commenc\u00e9 avec le match de coupe suisse contre B\u00e2le, mais la r\u00e9alit\u00e9 du championnat a rattrap\u00e9 la formation de Del Rosso qui aspirait \u00e0 jouer la premi\u00e8re moiti\u00e9 de tableau mais qui doit d\u00e9sormais revoir ses ambitions \u00e0 la baisse.<\/p>\n<p>&nbsp;<\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><strong>CS ITALIEN &#8211; FC A\u00cfRE-LE-LIGNON \u00a00-1 (0-0)<\/strong><br \/>\nStade du Bois-de-la-B\u00e2tie, environ 180 spectateurs.<\/p>\n<p style=\"text-align: justify;\"><strong>But<\/strong> : 63&#8242; Howard 0-1<\/p>\n<p style=\"text-align: justify;\"><strong>CS Italien<\/strong> (4-3-3) : Yamane (46&#8242; Alvarez) &#8211; Kisunda Visi, Idrizi\u00a0\u00a9, Antonilli, Huguenin &#8211; Makabi, Blanco, Da Rocha (70&#8242; Albuquerque) &#8211; Martinez, Matri (29&#8242; Lopes), Iseli.<br \/>\nEntra\u00eeneur : Raffaele Del Rosso<\/p>\n<p style=\"text-align: justify;\"><strong>A\u00efre<\/strong> (4-4-2) : Van der Laan\u00a0\u00a9 &#8211; Racalbuto, Rego, Miguel, Rodrigues &#8211; Costa, Monteiro (76&#8242; Anderegg), Barros, Lopes &#8211; Howard (66&#8242; Cacaj), Tanga (83&#8242; Machado).<br \/>\nEntra\u00eeneur : Helder Silva<\/p>\n<p style=\"text-align: justify;\"><strong>Avertissements<\/strong> : Kisunda Visi et Idrizi (CS Italien) ; Barros et Lopes (A\u00efre)<\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><script src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\" async=\"\"><\/script><!-- superieur --> <ins class=\"adsbygoogle\" style=\"display: inline-block; width: 728px; height: 90px;\" data-ad-client=\"ca-pub-1317159203547503\" data-ad-slot=\"1875735477\"><\/ins><script>\/\/ <![CDATA[ (adsbygoogle = window.adsbygoogle || []).push({}); \/\/ ]]><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un unique but d&#8217;Howard a permis \u00e0 A\u00efre de l&#8217;emporter sur le terrain du Bois-de-la-B\u00e2tie. Avec ce succ\u00e8s, les hommes d&#8217;Helder Silva restent au contact du leader.<\/p>\n","protected":false},"author":30,"featured_media":19475,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[5],"tags":[87,43],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.proxifoot.ch\/geneve\/2014\/10\/le-cs-ny-arrive-pas-a-domicile\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le CS n\u2019y arrive pas \u00e0 domicile - Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"og:description\" content=\"Un unique but d&#8217;Howard a permis \u00e0 A\u00efre de l&#8217;emporter sur le terrain du Bois-de-la-B\u00e2tie. Avec ce succ\u00e8s, les hommes d&#8217;Helder Silva restent au contact du leader.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.proxifoot.ch\/geneve\/2014\/10\/le-cs-ny-arrive-pas-a-domicile\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2014-10-12T21:10:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-10-25T10:33:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/10\/CSitalien-Aire-1415.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1417\" \/>\n\t<meta property=\"og:image:height\" content=\"950\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@www.twitter.com\/maikel_f\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2014\/10\/le-cs-ny-arrive-pas-a-domicile\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/10\/CSitalien-Aire-1415.jpg\",\"width\":1417,\"height\":950},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2014\/10\/le-cs-ny-arrive-pas-a-domicile\/#webpage\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/2014\/10\/le-cs-ny-arrive-pas-a-domicile\/\",\"name\":\"Le CS n\\u2019y arrive pas \\u00e0 domicile - Proxifoot, le m\\u00e9dia du football genevois\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2014\/10\/le-cs-ny-arrive-pas-a-domicile\/#primaryimage\"},\"datePublished\":\"2014-10-12T21:10:46+00:00\",\"dateModified\":\"2016-10-25T10:33:16+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/f8763ae73551193f68b47b57e2bdfb15\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.proxifoot.ch\/geneve\/2014\/10\/le-cs-ny-arrive-pas-a-domicile\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/f8763ae73551193f68b47b57e2bdfb15\",\"name\":\"Maikel\",\"sameAs\":[\"https:\/\/twitter.com\/www.twitter.com\/maikel_f\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/19464"}],"collection":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=19464"}],"version-history":[{"count":0,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/19464\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/19475"}],"wp:attachment":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=19464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=19464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=19464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}