﻿{"id":1989,"date":"2012-03-19T14:20:02","date_gmt":"2012-03-19T13:20:02","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=1989"},"modified":"2016-09-20T16:56:33","modified_gmt":"2016-09-20T14:56:33","slug":"lenjeu-tue-le-jeu-a-florimont","status":"publish","type":"post","link":"https:\/\/www.proxifoot.ch\/geneve\/2012\/03\/lenjeu-tue-le-jeu-a-florimont\/","title":{"rendered":"L&#8217;enjeu tue le jeu \u00e0 Florimont"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Match d\u00e9cevant et teint de crispation \u00e0 Lancy. Les deux formations devront faire plus si elles souhaitent rapidement assurer leur maintien. R\u00e9cit d&#8217;un voyage au bout de l&#8217;ennui.<!--more--><\/strong><\/p>\n<p>Le cadre est pos\u00e9. Ciel sombre, vent froid et tourbillonnant, le synth\u00e9tique de Florimont \u00e9voque en ce dimanche matin une vaste plaine o\u00f9 l&#8217;on s&#8217;attend alors \u00e0 voir deux \u00e9quipes combattre vaillamment pour s&#8217;\u00e9loigner d&#8217;une barre qui, elle aussi, se fait mena\u00e7ante. Il n&#8217;en sera rien.<\/p>\n<p style=\"text-align: justify;\">Certes, les h\u00f4tes entrent rapidement dans le match et ne semblent pas vouloir laisser s&#8217;installer le traditionnel round d&#8217;observation. \u00c0 la 5\u00e8me minute, Fertikh, bien lanc\u00e9 dans la profondeur, s&#8217;\u00e9croule au contact d&#8217;un d\u00e9fenseur. L&#8217;arbitre ne se laisse pas abuser et laisse le jeu se poursuivre au grand dam de l&#8217;attaquant lanc\u00e9en qui aura tout de m\u00eame le m\u00e9rite de ne pas baisser les bras. Intenable en ce d\u00e9but de match, il place quatre minutes plus tard une t\u00eate plongeante mal ajust\u00e9e sur un centre venu de la droite puis tente \u00e0 la 13\u00e8me minute d&#8217;intercepter un passe en retrait pas assez appuy\u00e9e de Ciardo pour son gardien, sans succ\u00e8s.<\/p>\n<div id=\"attachment_1997\" style=\"width: 563px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/03\/012.jpg\"><img aria-describedby=\"caption-attachment-1997\" loading=\"lazy\" class=\"size-large wp-image-1997 \" title=\"2\u00c3\u00a8me ligue Lancy vs Versoix\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/03\/012-1024x595.jpg\" alt=\"\" width=\"553\" height=\"321\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/03\/012-1024x595.jpg 1024w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/03\/012-300x174.jpg 300w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/03\/012-660x384.jpg 660w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/03\/012.jpg 1134w\" sizes=\"(max-width: 553px) 100vw, 553px\" \/><\/a><p id=\"caption-attachment-1997\" class=\"wp-caption-text\">La t\u00eate plongeante de Fertikh ne fera pas mouche<\/p><\/div>\n<p style=\"text-align: justify;\">On se dit alors que les visiteurs, qui jouent tr\u00e8s bas et peinent \u00e0 ressortir le ballon correctement, risquent de passer une bien mauvaise matin\u00e9e, tant les intentions sont jaunes et noires en ce d\u00e9but de match. Mais la crispation, d\u00e9j\u00e0 bien pr\u00e9sente dans les rangs versoisiens, fini par gagner \u00e9galement l&#8217;\u00e9quipe lanc\u00e9enne dont les difficult\u00e9s affich\u00e9es dans le dernier geste sont effrayantes.<\/p>\n<p><strong>Le premier quart d&#8217;heure\u2026 puis le n\u00e9ant!<\/strong><\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s quinze minutes int\u00e9ressantes, les d\u00e9bats s&#8217;\u00e9quilibrent \u00e0 mesure que les erreurs techniques s&#8217;accumulent, ne laissant que tr\u00e8s peu de place au jeu. Les d\u00e9fenses prennent le pas sur les attaques et la cinquantaine de spectateurs amass\u00e9s sous l&#8217;avant-toit de la buvette commence \u00e0 exprimer son m\u00e9contentement. Dans le vide abyssal de cette premi\u00e8re mi-temps, on retiendra tout de m\u00eame un coup franc lanc\u00e9en tir\u00e9 c\u00f4t\u00e9 droit par Da Rocha et repris par Carvalho, contr\u00e9 in extremis par la d\u00e9fense des bleus (45\u2019). Du cot\u00e9 de Versoix justement, hormis l&#8217;agacement de l&#8217;entra\u00eeneur Auro Duarte, gesticulant au bord de la touche, et les quelques mont\u00e9es rageuses du lat\u00e9ral Ciardo, rien ne semble \u00e9maner de cette formation qui voit arriver le th\u00e9 avec un soulagement \u00e9vident.<\/p>\n<div id=\"attachment_1999\" style=\"width: 501px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/03\/033.jpg\"><img aria-describedby=\"caption-attachment-1999\" loading=\"lazy\" class=\"size-large wp-image-1999 \" title=\"2\u00c3\u00a8me ligue Lancy vs Versoix\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/03\/033-1024x872.jpg\" alt=\"\" width=\"491\" height=\"418\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/03\/033-1024x872.jpg 1024w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/03\/033-300x255.jpg 300w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/03\/033-660x562.jpg 660w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/03\/033.jpg 1134w\" sizes=\"(max-width: 491px) 100vw, 491px\" \/><\/a><p id=\"caption-attachment-1999\" class=\"wp-caption-text\">Misini et El Tayar au duel<\/p><\/div>\n<p style=\"text-align: justify;\">Conscients des limites affich\u00e9es en premi\u00e8re p\u00e9riode et probablement r\u00e9veill\u00e9s par leur coach durant la pause, les Versoisiens attaquent la seconde mi-temps avec un peu plus d&#8217;allant et se cr\u00e9ent deux occasions coup sur coup \u00e0 la 47\u00e8meet \u00e0 la 50\u00e8me minute. La frappe d&#8217;El Tayar passe de peu \u00e0 cot\u00e9 du but d&#8217;Otero tandis que le centre de Menga, cons\u00e9cutif \u00e0 une belle remont\u00e9e de balle, ne peut \u00eatre repris par Formenti, trop court. Piqu\u00e9 au vif, Lancy r\u00e9agit d\u00e8s la minute suivante par Spicher qui d\u00e9borde sur le cot\u00e9 droit et frappe au premier poteau, oubliant du m\u00eame coup Ferthik, esseul\u00e9 au point de p\u00e9nalty.<\/p>\n<p style=\"text-align: justify;\">Mais la pauvret\u00e9 technique de ce match reprend encore une fois le dessus sur le jeu. Et ce n&#8217;est pas la sortie sur blessure de Da Rocha \u00e0 la 60\u00e8me minute qui arrangera les choses, tant le capitaine lanc\u00e9en \u00e9tait l&#8217;un des seuls \u00e0 essayer de faire vivre le ballon. De fait, Versoix reprend p\u00e9niblement le jeu \u00e0 son compte. \u00c0 la 67\u00e8me minute une perte de balle de Garcia, dans l&#8217;axe, permet \u00e0 Menga de se retrouver en position favorable aux abords des16 m\u00e8tres. Mais il tergiverse avant de servir Bianco dans de mauvaises conditions. Frayeur pour le jeune stoppeur lanc\u00e9en, qui a pourtant \u00e9t\u00e9 excellent dans son placement et pr\u00e9cieux dans le jeu a\u00e9rien tout au long du match.<\/p>\n<p><strong>Fin de match ferm\u00e9e <\/strong><\/p>\n<p style=\"text-align: justify;\">Les vingt derni\u00e8res minutes sont un supplice pour les spectateurs qui ne peuvent d\u00e9terminer qui de la pluie battante ou du spectacle propos\u00e9 par les joueurs est le plus d\u00e9sagr\u00e9able\u2026 La morosit\u00e9 ambiante est tout de m\u00eame att\u00e9nu\u00e9e pendant quelques secondes lorsque Rexhepi, esseul\u00e9 \u00e0 25 m\u00e8tres tente sa chance et voit sa frappe l\u00e9g\u00e8rement d\u00e9vi\u00e9e finir sur le poteau de Rocha, manifestement battu sur la belle inspiration du milieu lanc\u00e9en (75\u2019).<\/p>\n<p style=\"text-align: justify;\">Mais personne n&#8217;y croit plus et les quelques changements effectu\u00e9s par chacun des entra\u00eeneurs ne parviennent pas \u00e0 tirer la partie de sa torpeur. M\u00eame la main involontaire de Lombardi dans sa surface dans les arr\u00eats de jeu ne soul\u00e8ve qu&#8217;un l\u00e9ger \u00e9moi dans les rangs versoisiens. Les deux \u00e9quipes ont d\u00e9j\u00e0 fait le deuil de leurs ambitions offensives depuis belle lurette et le point engrang\u00e9 et valid\u00e9 par le coup de sifflet final semble les contenter.<\/p>\n<div id=\"attachment_1998\" style=\"width: 501px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/03\/023.jpg\"><img aria-describedby=\"caption-attachment-1998\" loading=\"lazy\" class=\"size-large wp-image-1998 \" title=\"2\u00c3\u00a8me ligue Lancy vs Versoix\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/03\/023-1024x867.jpg\" alt=\"\" width=\"491\" height=\"416\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/03\/023-1024x867.jpg 1024w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/03\/023-300x254.jpg 300w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/03\/023-660x559.jpg 660w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/03\/023.jpg 1134w\" sizes=\"(max-width: 491px) 100vw, 491px\" \/><\/a><p id=\"caption-attachment-1998\" class=\"wp-caption-text\">Shabani (Versoix) fait le pressing sur Lombardi<\/p><\/div>\n<p style=\"text-align: justify;\">Il faudra toutefois faire preuve de moins de suffisance la semaine prochaine pour Versoix qui re\u00e7oit la lanterne rouge, Saint-Paul, m\u00eame si les mouvements et la r\u00e9action timide aper\u00e7us en seconde mi-temps augurent des lendemains plus heureux. La situation de Lancy est plus compliqu\u00e9e puisque l&#8217;\u00e9quipe de<strong>\u00a0<\/strong>Jean-Yves Soilihi se d\u00e9place chez le leader Vernier et voit revenir Compesi\u00e8res, surprenant vainqueur de Kosova.<\/p>\n<p style=\"text-align: justify;\">L\u2019entra\u00eeneur lanc\u00e9en analysait : &#8220;J&#8217;ai trouv\u00e9 aujourd&#8217;hui une ossature et une solidarit\u00e9 plus importante qu&#8217;en d\u00e9but de saison. Je pense qu&#8217;au premier tour, dans un match de ce type nous aurions encaiss\u00e9 un but \u00e0 la 89\u00e8me minute. Il reste du travail, notamment dans les encha\u00eenements et les phases de jeu. Malgr\u00e9 le manque d&#8217;efficacit\u00e9 en premi\u00e8re mi temps, je suis assez satisfait de l&#8217;\u00e9tat d&#8217;esprit. Mon \u00e9quipe est jeune avec plus de 8 joueurs issus des Juniors A, et face \u00e0 l&#8217;exp\u00e9rience des joueurs de Versoix, notamment au milieu et devant, je suis satisfait du point pris aujourd&#8217;hui.&#8221;<\/p>\n<p style=\"text-align: justify;\">Du c\u00f4t\u00e9 des visiteurs, Auro Duarte\u00a0 d\u00e9clarait \u00e0 son tour : &#8220;On savait que ce serait un match important au niveau du classement. On ne joue plus le haut de tableau, il faut donc se consacrer \u00e0 la lutte contre la rel\u00e9gation. Dans ce match \u00e0 six points, les deux \u00e9quipes ont cherch\u00e9 la victoire mais n&#8217;ont pu l&#8217;obtenir. En ce qui nous concerne, nous avons corrig\u00e9 nos erreurs en deuxi\u00e8me mi-temps, en r\u00e9ussissant \u00e0 amener un peu plus de danger.&#8221;<\/p>\n<p>&nbsp;<\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><strong>FC LANCY-SPORTS \u2013 FC VERSOIX\u00a0 0-0<br \/>\n<\/strong>Stade de Lancy-Florimont, environ 50 spectateurs.<\/p>\n<p style=\"text-align: justify;\"><strong>Arbitre<\/strong> : Sadri Saieb<\/p>\n<p style=\"text-align: justify;\"><strong>Lancy<\/strong> (4-4-2) : Otero \u2013 Buci, Shaquiri, Garcia, Lombardi \u2013 Croce, Spicher (82&#8242; Ngefa), Da Rocha \u00a9, Rexhepi \u2013 Fertikh, Carvalho (90&#8242; Ramiqi).<br \/>\nEntra\u00eeneur\u00a0: Jean-Yves Soilihi<\/p>\n<p style=\"text-align: justify;\"><strong>Versoix<\/strong> (4-2-3-1) : Rocha \u00a9 \u2013 Neto (46&#8242; Dijkhuizen), Figueredo, Seramondi, Ciardo \u2013 El Tayar (90&#8242; Togni), Formenti \u2013 Shabani, Puleo, Bianco (74&#8242; Mottier) \u2013 Menga.<br \/>\nEntra\u00eeneur\u00a0: Auro Duarte<\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<p><em>Photos\u00a0: <a href=\"http:\/\/www.oneclick-photo.ch\/category\/lancy-vs-versoix.html\" target=\"_blank\"><u><span style=\"color: #0066cc;\">OneClick-Photo<\/span><\/u><\/a><\/em><\/p>\n<p><script src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\" async=\"\"><\/script><!-- superieur --> <ins class=\"adsbygoogle\" style=\"display: inline-block; width: 728px; height: 90px;\" data-ad-client=\"ca-pub-1317159203547503\" data-ad-slot=\"1875735477\"><\/ins><script>\/\/ <![CDATA[ (adsbygoogle = window.adsbygoogle || []).push({}); \/\/ ]]><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Match d\u00e9cevant et teint de crispation \u00e0 Lancy. Les deux formations devront faire plus si elles souhaitent rapidement assurer leur maintien. R\u00e9cit d&#8217;un voyage au bout de l&#8217;ennui.<\/p>\n","protected":false},"author":40,"featured_media":1996,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[5],"tags":[84,76],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.proxifoot.ch\/geneve\/2012\/03\/lenjeu-tue-le-jeu-a-florimont\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;enjeu tue le jeu \u00e0 Florimont - Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"og:description\" content=\"Match d\u00e9cevant et teint de crispation \u00e0 Lancy. Les deux formations devront faire plus si elles souhaitent rapidement assurer leur maintien. R\u00e9cit d&#8217;un voyage au bout de l&#8217;ennui.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.proxifoot.ch\/geneve\/2012\/03\/lenjeu-tue-le-jeu-a-florimont\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2012-03-19T13:20:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-09-20T14:56:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/03\/lancy-versoix.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"490\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2012\/03\/lenjeu-tue-le-jeu-a-florimont\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/03\/lancy-versoix.jpg\",\"width\":850,\"height\":490},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2012\/03\/lenjeu-tue-le-jeu-a-florimont\/#webpage\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/2012\/03\/lenjeu-tue-le-jeu-a-florimont\/\",\"name\":\"L'enjeu tue le jeu \\u00e0 Florimont - Proxifoot, le m\\u00e9dia du football genevois\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2012\/03\/lenjeu-tue-le-jeu-a-florimont\/#primaryimage\"},\"datePublished\":\"2012-03-19T13:20:02+00:00\",\"dateModified\":\"2016-09-20T14:56:33+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/f9e6cb94cac0d5b21be2ed4b5ee059b6\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.proxifoot.ch\/geneve\/2012\/03\/lenjeu-tue-le-jeu-a-florimont\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/f9e6cb94cac0d5b21be2ed4b5ee059b6\",\"name\":\"Anthony\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/1989"}],"collection":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=1989"}],"version-history":[{"count":0,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/1989\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/1996"}],"wp:attachment":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=1989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=1989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=1989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}