﻿{"id":21299,"date":"2015-04-12T18:31:20","date_gmt":"2015-04-12T16:31:20","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=21299"},"modified":"2016-07-20T18:11:39","modified_gmt":"2016-07-20T16:11:39","slug":"1ere-ligue-meyrin-file-sous-la-barre","status":"publish","type":"post","link":"https:\/\/www.proxifoot.ch\/geneve\/2015\/04\/1ere-ligue-meyrin-file-sous-la-barre\/","title":{"rendered":"1\u00e8re ligue : Meyrin file sous la barre"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>18\u00e8me journ\u00e9e \/ Lancy et Meyrin sont \u00e0 nouveau battus, avec plus de cons\u00e9quences pour les Meyrinois qui sont d\u00e9sormais rel\u00e9gables.<!--more--><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>FC Fribourg\u00a0 \u00a0\u2013\u00a0\u00a0\u00a0Meyrin FC \u00a0 3 &#8211; 1<br \/>\nButs<\/strong> : 24&#8242; Benhaddouche 0-1, 51&#8242; Bourquenoud 1-1, 53&#8242; Uka 2-1, 58&#8242; Ngalou 3-1<\/p>\n<p style=\"text-align: justify;\">Meyrin se remet en danger. Une troisi\u00e8me d\u00e9faite cons\u00e9cutive condamne les hommes de Carlos Alves \u00e0 retomber sous la barre de rel\u00e9gation \u00e0 sept journ\u00e9es de la fin.<\/p>\n<p style=\"text-align: justify;\">Pourtant, les Meyrinois ont r\u00e9ussi une bonne premi\u00e8re p\u00e9riode, buvant le th\u00e9 avec un avantage de un but gr\u00e2ce \u00e0 Benhaddouche \u00e0 la 24\u00e8me minute.\u00a0Malheureusement, Fribourg va revenir au score et prendre l\u2019avantage et le large en l\u2019espace de sept petites minutes sur trois coups de pieds arr\u00eat\u00e9s.<\/p>\n<p style=\"text-align: justify;\">Au final, Meyrin conc\u00e8de donc une troisi\u00e8me d\u00e9faite cons\u00e9cutive, la quatri\u00e8me sur les cinq derni\u00e8res sorties en championnat, et voit Martigny, vainqueur de Terre-Sainte dans le match crucial de cette journ\u00e9e, leur passer devant.<\/p>\n<p style=\"text-align: justify;\">A l\u2019heure de l\u2019analyse, Carlos Alves r\u00e9sumait la d\u00e9faite des siens en une phrase\u00a0: <em>\u00ab\u00a0On a souffert face aux gabarits imposants et au jeu direct de Fribourg. Les trois buts conc\u00e9d\u00e9s sur coup de pied arr\u00eat\u00e9 sont l\u00e0 pour le prouver. C\u2019est dommage, car malgr\u00e9 quatre absences importantes, mon \u00e9quipe avait bien d\u00e9but\u00e9 son match.\u00a0\u00bb<\/em><\/p>\n<p style=\"text-align: justify;\"><em>\u00ab\u00a0On repasse sous la barre, mais rien n\u2019est jou\u00e9 et je suis confiant\u00a0! J\u2019ai repris l\u2019\u00e9quipe avant un match contre Naters que l\u2019on avait gagn\u00e9 avec la mani\u00e8re, j\u2019esp\u00e8re que notre prochaine journ\u00e9e contre ce m\u00eame adversaire aura le m\u00eame r\u00e9sultat\u00a0!\u00a0\u00bb, <\/em>conclut le mentor meyrinois.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Lancy FC\u00a0 \u00a0\u2013\u00a0\u00a0\u00a0Team Vaud M-21 \u00a0 0 &#8211; 1<br \/>\nBut<\/strong> : 43&#8242; Makshana 0-1<\/p>\n<p style=\"text-align: justify;\">Lancy n&#8217;avance plus en 2015. Avec un effectif diminu\u00e9 par les blessures, la formation de Marignac a \u00e9t\u00e9 battue par les M21 du Team Vaud par le plus petit des scores et peut d\u00e9sormais dire adieu \u00e0 tout espoir de jouer les finales.<\/p>\n<p style=\"text-align: justify;\"><em>&#8220;Avec l\u2019h\u00e9catombe de bless\u00e9s avant ce match, nous n\u2019avons pas \u00e9t\u00e9 ridicules,<\/em> confiait Bojan Dimic. <em>Malheureusement, nous n\u2019avons pas pu concr\u00e9tiser nos occasions dans nos moments forts notamment par Mazamay et Maanane en toute fin de match qui avaient le poids de l\u2019\u00e9galisation.\u00a0Il faut reconna\u00eetre aussi que l\u2019on a rencontr\u00e9 certainement la meilleure \u00e9quipe vue \u00e0 Marignac cette saison. Notre adversaire poss\u00e8de de tr\u00e8s jeunes et tr\u00e8s prometteurs talents&#8221;.<\/em><\/p>\n<p style=\"text-align: justify;\">Les Lanc\u00e9ens n&#8217;ont obtenu qu&#8217;un seul point lors des 4 derni\u00e8res sorties et peuvent entrevoir une fin de saison sans r\u00e9el objectif \u00e0 aller chercher puisque la m\u00eame distance les s\u00e9pare les finales et de la rel\u00e9gation, \u00e0 savoir 10 points.<\/p>\n<p style=\"text-align: justify;\">Bojan Dimic reconnaissait : <em>&#8220;Nous sommes dans le dur, comme on dit, car avec les r\u00e9sultats n\u00e9gatifs et surtout le peu de joueurs \u00e0 disposition,\u00a0il est difficile de r\u00e9galer dans ce championnat relev\u00e9. Une \u00e9quipe comme la n\u00f4tre ne peut pas se passer de certains cadres bless\u00e9s et qui n\u2019ont toujours pas jou\u00e9 une seule minute dans ce deuxi\u00e8me\u00a0tour&#8221;.<\/em><\/p>\n<p style=\"text-align: justify;\">Et de conclure : <em>&#8220;Mais nous n\u2019avons pas le choix que celui de continuer \u00e0 travailler avec la base de joueurs restants et d\u2019essayer d\u2019arr\u00eater la dynamique n\u00e9gative dans laquelle nous sommes rentr\u00e9s depuis 3 matchs maintenant.\u00a0Et pour cela, il faudra sortir un tr\u00e8s gros match contre la meilleure \u00e9quipe de ce championnat selon moi qu\u2019est le FC Stade-Lausanne&#8221;.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>Autres r\u00e9sultats :\u00a0<\/strong><\/em><\/p>\n<p><strong>FC Oberwallis Naters<strong>\u00a0 \u00a0\u2013 \u00a0\u00a0<\/strong>SC D\u00fcdingen \u00a0 1 &#8211; 2\u00a0<\/strong><\/p>\n<p><strong>FC Martigny-Sports<strong>\u00a0 \u00a0\u2013 \u00a0\u00a0<\/strong>US Terre Sainte \u00a0 4 &#8211; 2\u00a0<\/strong><\/p>\n<p><strong>FC Azzurri 90 LS<strong>\u00a0 \u00a0\u2013 \u00a0\u00a0<\/strong>Yverdon-Sport FC \u00a0 1 &#8211; 1\u00a0<\/strong><\/p>\n<p><strong>FC Bavois<strong>\u00a0 \u00a0\u2013 \u00a0\u00a0<\/strong>FC Stade-Lausanne-Ouchy \u00a0 1 &#8211; 2\u00a0<\/strong><\/p>\n<p><strong>FC Echallens R\u00e9gion<strong>\u00a0 \u00a0\u2013 \u00a0\u00a0<\/strong>FC Monthey \u00a0 2 &#8211; 1\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-21386\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2015\/04\/1ligue1415-19.jpg\" alt=\"1ligue1415-19\" width=\"609\" height=\"338\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2015\/04\/1ligue1415-19.jpg 609w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2015\/04\/1ligue1415-19-300x167.jpg 300w\" sizes=\"(max-width: 609px) 100vw, 609px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>18\u00e8me journ\u00e9e \/ Lancy et Meyrin sont \u00e0 nouveau battus, avec plus de cons\u00e9quences pour les Meyrinois qui sont d\u00e9sormais rel\u00e9gables.<\/p>\n","protected":false},"author":1,"featured_media":5793,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[4],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.proxifoot.ch\/geneve\/2015\/04\/1ere-ligue-meyrin-file-sous-la-barre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1\u00e8re ligue : Meyrin file sous la barre - Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"og:description\" content=\"18\u00e8me journ\u00e9e \/ Lancy et Meyrin sont \u00e0 nouveau battus, avec plus de cons\u00e9quences pour les Meyrinois qui sont d\u00e9sormais rel\u00e9gables.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.proxifoot.ch\/geneve\/2015\/04\/1ere-ligue-meyrin-file-sous-la-barre\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-12T16:31:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-20T16:11:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/08\/banniere-1\u00e8re-ligue.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"164\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2015\/04\/1ere-ligue-meyrin-file-sous-la-barre\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/08\/banniere-1\\u00e8re-ligue.jpg\",\"width\":660,\"height\":164},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2015\/04\/1ere-ligue-meyrin-file-sous-la-barre\/#webpage\",\"url\":\"http:\/\/www.proxifoot.ch\/geneve\/2015\/04\/1ere-ligue-meyrin-file-sous-la-barre\/\",\"name\":\"1\\u00e8re ligue : Meyrin file sous la barre - Proxifoot, le m\\u00e9dia du football genevois\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2015\/04\/1ere-ligue-meyrin-file-sous-la-barre\/#primaryimage\"},\"datePublished\":\"2015-04-12T16:31:20+00:00\",\"dateModified\":\"2016-07-20T16:11:39+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.proxifoot.ch\/geneve\/2015\/04\/1ere-ligue-meyrin-file-sous-la-barre\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\",\"name\":\"admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/21299"}],"collection":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=21299"}],"version-history":[{"count":0,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/21299\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/5793"}],"wp:attachment":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=21299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=21299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=21299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}