﻿{"id":21301,"date":"2015-04-12T18:34:26","date_gmt":"2015-04-12T16:34:26","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=21301"},"modified":"2016-07-20T18:11:36","modified_gmt":"2016-07-20T16:11:36","slug":"2eme-ligue-inter-signal-bernex-nouveau-leader","status":"publish","type":"post","link":"https:\/\/www.proxifoot.ch\/geneve\/2015\/04\/2eme-ligue-inter-signal-bernex-nouveau-leader\/","title":{"rendered":"2\u00e8me ligue inter : Signal Bernex, nouveau leader"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>18\u00e8me journ\u00e9e \/ Au terme d&#8217;une journ\u00e9e qui n&#8217;a vu aucune d\u00e9faite genevoise, les Bern\u00e9siens prennent la t\u00eate pour la premi\u00e8re fois de la saison apr\u00e8s leur succ\u00e8s sur le terrain de Dardania. UGS et Collex compl\u00e8tent le podium qui reste serr\u00e9. En bas de tableau, Veyrier se rapproche de la barre.<!--more--><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>FC Perly-Certoux\u00a0 \u00a0\u2013\u00a0\u00a0\u00a0FC Montreux-Sports \u00a0 1 &#8211; 1<br \/>\nButs<\/strong> : 12&#8242; Rameau 0-1, 41&#8242; Barbosa 1-1<\/p>\n<p style=\"text-align: justify;\">Toujours pas de victoire depuis octobre dernier pour Perly, soit 9 journ\u00e9es de championnat. Face \u00e0 Montreux, une \u00e9quipe rel\u00e9gable, les Perlysiens avaient pourtant une belle opportunit\u00e9 de mettre fin \u00e0 cette mauvaise s\u00e9rie. Mais ils n&#8217;obtiendront pas mieux qu&#8217;un nul, obtenu gr\u00e2ce \u00e0 une \u00e9galisation de Barbosa apr\u00e8s l&#8217;ouverture du score de Rameau.<\/p>\n<p style=\"text-align: justify;\">Vendredi soir, c&#8217;est un difficile d\u00e9placement sur le terrain d&#8217;UGS qui attend la troupe de Mario Chedly, qui esp\u00e8re ne pas encha\u00eener un 10\u00e8me match de championnat sans succ\u00e8s.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>FC Vevey Sports 05\u00a0 \u00a0\u2013\u00a0\u00a0\u00a0FC Collex-Bossy \u00a0 0 &#8211; 1<br \/>\nBut<\/strong> : 89&#8242; Sanches 0-1<strong><br \/>\n<\/strong><\/p>\n<p style=\"text-align: justify;\">On joue les toutes derni\u00e8res minutes au Stade de Copet et le match entre Vevey et Collex se dirige vers un score nul et vierge&#8230; jusqu&#8217;\u00e0 ce corner direct de Fabrice Sanches qui se loge directement dans les filets veveysans.<\/p>\n<p style=\"text-align: justify;\">D\u00e9j\u00e0 buteur la semaine derni\u00e8re, le joker collesien est \u00e0 nouveau d\u00e9cisif et offre aux &#8220;Chevaliers&#8221; une victoire qui leur permet de r\u00eaver d&#8217;ici la fin du championnat. En effet, les voici d\u00e9sormais sur un podium 100% genevois \u00e0 trois longueurs du nouveau leader bern\u00e9sien. A confirmer ce week-end avec la r\u00e9ception de Saxon ?<\/p>\n<p>&nbsp;<\/p>\n<p><strong>FC Plan-les-Ouates\u00a0 \u00a0\u2013\u00a0\u00a0\u00a0FC UGS \u00a0 1 &#8211; 1<br \/>\nButs<\/strong> : 77\u2019 Dia 0-1, 78\u2019 Revilloud (CSC) 1-1<\/p>\n<p style=\"text-align: justify;\">Seul derby de cette journ\u00e9e de 2\u00e8me\u00a0ligue inter, la rencontre entre l\u2019\u00e9quipe en forme de ce deuxi\u00e8me tour, Plan-les-Ouates, et le leader UGS n\u2019a donn\u00e9 aucun vainqueur.<\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s une premi\u00e8re p\u00e9riode \u00e9quilibr\u00e9e, Plan-les-Ouates prend le dessus dans le jeu apr\u00e8s le th\u00e9, mais sans parvenir \u00e0 concr\u00e9tiser. Jusqu\u2019\u00e0 ces faits de jeu originaux qui vont amener les deux buts. Suite \u00e0 une blessure de Dia, Plan-les-Ouates sort le ballon pour permettre \u00e0 l\u2019attaquant adverse de se faire soigner. Sur la remise en jeu, ce m\u00eame Dia, d\u00e9sirant remettre le ballon au gardien Mendes, manque son affaire et lobe le portier adverse pour inscrire un but involontaire. Sportifs, les \u00ab\u00a0Violets\u00a0\u00bb permettront \u00e0 leurs h\u00f4tes du jour de recoller au score par Revilloud, mettant volontairement le ballon au fond de son but.<\/p>\n<p style=\"text-align: justify;\">Au final, ce match nul n\u2019arrange pas vraiment une ou l\u2019autre \u00e9quipe, UGS se faisant d\u00e9passer par Bernex alors que Plan-les-Ouates ne profite pas du revers de Sierre pour gagner une place au classement.<\/p>\n<p style=\"text-align: justify;\">A l\u2019heure de l\u2019analyse, le sentiment de frustration tend \u00e0 pr\u00e9valoir de chaque c\u00f4t\u00e9, mais pas pour les m\u00eames raisons. Du c\u00f4t\u00e9 plan-les-ouatien, c\u2019est une frustration due au r\u00e9sultat\u00a0: <em>\u00ab\u00a0Globalement,<\/em> confie Boris Mitrovic, <em>nous sommes d\u00e9\u00e7us du r\u00e9sultat. Apr\u00e8s une premi\u00e8re mi-temps \u00e9quilibr\u00e9e, on prend le dessus sur notre adversaire et pour moi on m\u00e9rite plus que le match nul.\u00a0Dans le jeu, on \u00e9tait bien en place tactiquement et dans l&#8217;agressivit\u00e9, mais dans les transitions et les offensives, on a sans doute fait notre moins bon match depuis la reprise&#8230;\u00a0\u00bb<\/em><\/p>\n<p style=\"text-align: justify;\">\u00ab\u00a0Concernant les buts, poursuit-il, je n&#8217;ai jamais vu \u00e7a de toute ma carri\u00e8re ! Mais je tiens \u00e0 saluer la sportivit\u00e9 de notre adversaire pour nous laisser revenir apr\u00e8s le but involontaire de leur attaquant&#8221;.\u00a0Et de conclure : <em>&#8220;P\u00e2ques a un peu coup\u00e9 notre dynamique, mais malgr\u00e9 tout on reste invaincu et on tient t\u00eate aux meilleures formations du groupe, c&#8217;est bien entendu positif !\u00a0Le maintien n\u2019est pas dans notre discours, on regarde vers l&#8217;avant match apr\u00e8s match et on fera les comptes \u00e0 la fin.\u00a0\u00a0\u00bb<\/em><\/p>\n<div id=\"attachment_21435\" style=\"width: 588px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-21435\" loading=\"lazy\" class=\" wp-image-21435 \" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2015\/04\/Plan-les-Ouates-UGS-1415.png\" alt=\"Plan-les-Ouates-UGS-1415\" width=\"578\" height=\"439\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2015\/04\/Plan-les-Ouates-UGS-1415.png 803w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2015\/04\/Plan-les-Ouates-UGS-1415-300x228.png 300w\" sizes=\"(max-width: 578px) 100vw, 578px\" \/><p id=\"caption-attachment-21435\" class=\"wp-caption-text\">Pas de vainqueur entre Jaunes et Violets (Photo: F. Pascal-Girod)<\/p><\/div>\n<p style=\"text-align: justify;\">Dans le camp des visiteurs, la frustration se situe dans la p\u00e9riode difficile travers\u00e9e par les \u00ab\u00a0Violet\u00a0\u00bb, comme nous l\u2019indique Herv\u00e9 Musqu\u00e8re\u00a0: <em>\u00ab\u00a0Nous ne sommes pas dans une bonne p\u00e9riode, notre jeu manque de liant, nous avons des difficult\u00e9s \u00e0 retrouver un \u00e9quilibre dans le jeu suite au d\u00e9part de\u00a0Florian Dupont \u00e0 Carouge et donc cela se ressent dans nos matchs depuis la reprise.\u00a0\u00bb<\/em><\/p>\n<p style=\"text-align: justify;\"><em>\u00ab\u00a0Face \u00e0 PLO,<\/em> encha\u00eene le mentor de Frontenex, <em>nous avons bien d\u00e9fendu mais nous n\u2019avons pas r\u00e9ussi \u00e0 ressortir le ballon proprement ce qui a donn\u00e9 un match m\u00e9diocre de notre part. Le r\u00e9sultat nul est logique. PLO voulait prendre des points, l&#8217;adversaire est rest\u00e9 bien en place sans prendre de risque et nous avons \u00e9t\u00e9 incapables d&#8217;imposer notre rythme pour leur poser des probl\u00e8mes.\u00a0\u00bb<\/em><\/p>\n<p style=\"text-align: justify;\">Et de conclure\u00a0: <em>\u00ab\u00a0J\u2019esp\u00e8re que ce n\u2019\u00e9tait qu\u2019un jour sans pour les miens, mais cela fait deux matches que nous ne sommes pas bons. Il faudra encore travailler d\u2019avantage si on veut rester au contact du peloton de t\u00eate et jouer les trouble-f\u00eates. Il reste huit matches et tout est ouvert, aussi bien pour la promotion que pour la rel\u00e9gation. Aucun match ne sera facile et nous en sommes conscients\u00a0!\u00a0\u00bb<\/em><\/p>\n<p style=\"text-align: justify;\">UGS perd ainsi la t\u00eate du classement et esp\u00e8rera la r\u00e9cup\u00e9rer d\u00e8s la semaine prochaine en recevant Perly.\u00a0De son c\u00f4t\u00e9, Plan-les-Ouates reste invaincu sous la houlette de Boris Mitrovic et voudra continuer sa s\u00e9rie sur la pelouse des M-21 servettiens.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>FC Sierre\u00a0 \u00a0\u2013\u00a0\u00a0\u00a0FC Veyrier Sports \u00a0 1 &#8211; 2<br \/>\nButs<\/strong> : 6\u2019 Amato 1-0, 40\u2019 Jeangros 1-1, 47\u2019 Huguenin 1-2<\/p>\n<p style=\"text-align: justify;\">Deux semaines apr\u00e8s leur belle performance face \u00e0 Dardania, Veyrier a confirm\u00e9 sa forme en encha\u00eenant une deuxi\u00e8me victoire cons\u00e9cutive et un troisi\u00e8me match sans d\u00e9faite.<\/p>\n<p style=\"text-align: justify;\">Samedi, c\u2019est \u00e0 Sierre que les joueurs de Daniel Villa ont r\u00e9ussi \u00e0 d\u00e9crocher les trois points apr\u00e8s avoir, pourtant, conc\u00e9d\u00e9 l\u2019ouverture du score en tout d\u00e9but de match. Deux r\u00e9ussites de Jeangros et Huguenin, juste avant et apr\u00e8s la pause, permettent aux n\u00e9o-promus de ramener la victoire du Valais et de revenir \u00e0 deux petites unit\u00e9s de Saxon dans la course au maintien.<\/p>\n<p style=\"text-align: justify;\">A l\u2019heure de l\u2019analyse, la satisfaction se fait bien s\u00fbr sentir dans les propos de l\u2019entra\u00eeneur Daniel Villa\u00a0: <em>\u00ab\u00a0Malgr\u00e9 une tr\u00e8s bonne entame de match, on perd un ballon \u00e9vitable et on se retrouve men\u00e9s au score. Malgr\u00e9 cela, on a su rester calmes et j\u2019ai senti une forte s\u00e9r\u00e9nit\u00e9 mais surtout une grande d\u00e9termination \u00e0 poursuivre notre envie d\u2019imposer notre jeu.\u00a0\u00bb<\/em><\/p>\n<p style=\"text-align: justify;\"><em>\u00ab\u00a0On est r\u00e9compens\u00e9 juste avant la pause gr\u00e2ce \u00e0 une belle action conclue par Jeangros,<\/em> analyse Villa. <em>Le retour des vestiaires est \u00e0 notre avantage et on profite de notre temps fort pour prendre l\u2019avantage. Par la suite, on a bien g\u00e9r\u00e9 notre avance en jouant les contre et en maintenant les assauts adverses.\u00a0\u00bb<\/em><\/p>\n<p style=\"text-align: justify;\"><em>\u00ab\u00a0Cette victoire nous fait un grand bien,<\/em> conclut l\u2019entra\u00eeneur veyrite, <em>elle confirme nos progr\u00e8s dans le jeu, la gestion g\u00e9n\u00e9rale du match et, surtout, dans notre approche mentale. Je suis fier de mes joueurs, mais on doit continuer \u00e0 travailler dur afin de r\u00e9\u00e9diter ce genre de performance qui nous am\u00e8nera, je l\u2019esp\u00e8re, l\u00e0 o\u00f9 on a envie d\u2019aller.\u00a0\u00bb<\/em><\/p>\n<p style=\"text-align: justify;\">La semaine prochaine, Veyrier re\u00e7oit Vevey pour esp\u00e9rer continuer sa s\u00e9rie victorieuse.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>FC Vernier\u00a0 \u00a0\u2013\u00a0\u00a0\u00a0FC Saxon Sports \u00a0 2 &#8211; 2<br \/>\nButs<\/strong> : 8&#8242; Rodrigues 0-1, 42&#8242; Rodrigues 0-2, 58&#8242; Arifi 1-2, 83&#8242; Mboli 2-2<strong><br \/>\n<\/strong><\/p>\n<p style=\"text-align: justify;\">Semaine anglaise sans d\u00e9faite pour Vernier mais sans satisfaction pour autant, l&#8217;\u00e9quipe stagnant \u00e0 cette derni\u00e8re place du classement. En effet, mercredi soir, Verniolans et Servettiens se quittaient sur un nul (1-1) qui \u00e9tait positif pour la formation de Patrick Tami. Mais face \u00e0 Saxon, \u00e9quipe situ\u00e9e juste au-dessus de la barre, la victoire \u00e9tait obligatoire pour le Genevois afin de pouvoir r\u00eaver de maintien.<\/p>\n<p style=\"text-align: justify;\">Mais ce ne sera pas le cas. L&#8217;\u00e9quipe de Tami devra se contenter d&#8217;un nouveau partage des points, bien que cela aurait pu \u00eatre pire puisque les Valaisans menaient 0-2 \u00e0 la pause.\u00a0<em>&#8220;C&#8217;\u00e9tait un bon match nul mercredi soir \u00e0 Balexert et un nul dimanche contre Saxon qui s&#8217;apparente \u00e0 une d\u00e9faite, malgr\u00e9 le fait que nous remontons un handicap de deux buts&#8221;.<\/em><\/p>\n<p style=\"text-align: justify;\">Des buts d&#8217;Arifi et Mboli ont permis de sauver un point qui ne fait pas vraiment les affaires de la lanterne rouge du championnat, qui reste \u00e0 8 points de la barre. Patrick Tami conserve malgr\u00e9 tout une lueur d&#8217;espoir : <em>&#8220;Le d\u00e9but de cette s\u00e9rie victorieuse obligatoire pour se sauver n&#8217;est donc pas encore arriv\u00e9e.\u00a0Il reste 24 points en jeu et nous sommes capables d&#8217;engranger les 18 points n\u00e9cessaires \u00e0 notre sauvetage mais la marge se r\u00e9duit \u00e0 chaque match!\u00a0Notre prochaine finale: dimanche 15h \u00e0 la Sarraz&#8221;.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>FC La Sarraz-Ecl\u00e9pens\u00a0 \u00a0\u2013\u00a0\u00a0\u00a0Servette FC M-21 \u00a0 1 &#8211; 1<br \/>\nButs<\/strong> : 29&#8242; Georgiev 1-0, 93&#8242; Caslei (P) 1-1<strong><br \/>\n<\/strong><\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s avoir obtenu un nul contre Vernier mercredi soir (1-1), Servette FC obtient le m\u00eame r\u00e9sultat en d\u00e9placement \u00e0 La Sarraz. Dans ce duel entre des \u00e9quipes qui ne luttent ni pour leur maintien ni pour la promotion, les Servettiens sont parvenus \u00e0 arracher un nul dans les arr\u00eats de jeu, gr\u00e2ce \u00e0 un penalty transform\u00e9 par Bruno Caslei.<\/p>\n<p style=\"text-align: justify;\">Ce week-end, les joueurs de William Niederhauser recevront une \u00e9quipe de Plan-les-Ouates toujours invaincue lors de ce second tour.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>FC Dardania Lausanne\u00a0 \u00a0\u2013\u00a0\u00a0\u00a0Signal FC Bernex-Confignon \u00a0 1 &#8211; 2<br \/>\nButs<\/strong> : 33&#8242; Calleja 0-1, 38&#8242; Hoxha 1-1, 48&#8242; Koum 1-2<strong><br \/>\n<\/strong><\/p>\n<p style=\"text-align: justify;\">Bernex est le nouveau leader du championnat ! Lors du match au sommet de la journ\u00e9e, les joueurs de Claudio Morelli ont frapp\u00e9 un grand coup en s&#8217;imposant sur le terrain de Dardania.<\/p>\n<p style=\"text-align: justify;\">Un but de Calleja apr\u00e8s la demi-heure de jeu et un autre de Koum d\u00e8s l&#8217;entame de la seconde p\u00e9riode ont suffi au bonheur des Bern\u00e9siens. Entre chaque but, Dardania avait \u00e9galis\u00e9 juste avant la pause. Les Lausannois auraient pu obtenir un match nul, mais les deux face \u00e0 face dans le dernier quart d&#8217;heure ont tourn\u00e9 en faveur du portier bern\u00e9sien, d\u00e9cisif sur l&#8217;un notamment.<\/p>\n<p style=\"text-align: justify;\"><em>&#8220;J\u2019ai beaucoup aim\u00e9 notre intensit\u00e9 et pr\u00e9sence physique jusqu\u2019\u00e0 la 75\u00e8me minute<\/em>, analysait l&#8217;entra\u00eeneur du nouveau leader. <em>Au niveau du jeu, l\u00e0 aussi une rencontre qui a laiss\u00e9 peu de place et de temps pour un jeu l\u00e9ch\u00e9. Le terrain plut\u00f4t \u00e9troit et les premi\u00e8res chaleurs ne nous n&#8217;ont pas favoris\u00e9, mais nous avons su nous adapter et imposer notre faim et volont\u00e9 d\u2019aller au bout pour prendre les trois points&#8221;.<\/em><\/p>\n<div id=\"attachment_21422\" style=\"width: 356px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-21422\" loading=\"lazy\" class=\" wp-image-21422 \" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2015\/04\/Dardania-Bernex-1415.jpg\" alt=\"Dardania-Bernex-1415\" width=\"346\" height=\"369\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2015\/04\/Dardania-Bernex-1415.jpg 902w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2015\/04\/Dardania-Bernex-1415-282x300.jpg 282w\" sizes=\"(max-width: 346px) 100vw, 346px\" \/><p id=\"caption-attachment-21422\" class=\"wp-caption-text\">Calleja, encore d\u00e9cisif pour Bernex (Photo : F. Pascal-Girod)<\/p><\/div>\n<p style=\"text-align: justify;\">Apr\u00e8s un mauvais d\u00e9but de saison &#8211; quatre points obtenus lors des six premi\u00e8res journ\u00e9es &#8211; les joueurs du coteau ont depuis encha\u00een\u00e9 une s\u00e9rie de r\u00e9sultats spectaculaires qui sont r\u00e9compens\u00e9s aujourd&#8217;hui avec cette premi\u00e8re place au classement : 11 victoires et un nul lors des 12 derni\u00e8res journ\u00e9es. <em>&#8220;L\u2019historique de nos r\u00e9sultats depuis mi-septembre 2014 doit \u00eatre un point de d\u00e9part qui nous permettra d\u2019aborder les huit derni\u00e8res rencontres avec la m\u00eame d\u00e9termination que nous avons mis dans tous nos entra\u00eenements et tous nos matches pass\u00e9s&#8221;<\/em>, nous confiait \u00e0 ce sujet Claudio Morelli.<\/p>\n<p style=\"text-align: justify;\"><em>&#8220;Aujourd&#8217;hui, on savoure notre nouvelle position au classement, <\/em>poursuit Morelli<em>. Une nouvelle page s\u2019ouvre \u00e0 nous : nous sommes dor\u00e9navant les seuls ma\u00eetres de notre destin, \u00e0 nous de rester sereins pour la suite de notre parcours et faire abstraction des autres \u00e9quipes que nous allons rencontrer d&#8217;ici la fin de ce championnat&#8221;.<\/em><\/p>\n<p style=\"text-align: justify;\">Et de conclure : <em>&#8220;J\u2019aimerais tirer un grand coup de chapeau pour la prestation de notre\u00a0senior\u00a0Mouelle Koum qui, depuis son retour \u00e0 Bernex en ao\u00fbt dernier, est un exemple pour toute notre \u00e9quipe et nos juniors. Je le f\u00e9licite. Je voudrais aussi d\u00e9dier notre victoire \u00e0 Laurent Dupraz, devenu papa de la petite Mila en fin de semaine derni\u00e8re. Nous souhaitons \u00e0 lui ainsi qu\u2019\u00e0 toute sa famille beaucoup de bonheur !&#8221;<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-21391\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2015\/04\/2einter1415-18.jpg\" alt=\"2einter1415-18\" width=\"606\" height=\"341\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2015\/04\/2einter1415-18.jpg 606w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2015\/04\/2einter1415-18-300x169.jpg 300w\" sizes=\"(max-width: 606px) 100vw, 606px\" \/><\/p>\n<p>&nbsp;<\/p>\n<table class=\" aligncenter\" border=\"0\" width=\"342\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td width=\"21\" height=\"20\"><\/td>\n<td width=\"257\"><strong>CLASSEMENT DES BUTEURS<\/strong><\/td>\n<td width=\"64\"><\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td height=\"20\">1.<\/td>\n<td>Florian DUPONT (UGS)<\/td>\n<td>19 buts<\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td height=\"20\">2.<\/td>\n<td>Valon HYSENAJ (La Sarraz\/Dardania)<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td>Jorge Filipe RODRIGUES (Saxon)<\/td>\n<td>13 buts<\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td height=\"20\">4.<\/td>\n<td>Gentian BUNJAKU (Dardania)<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td>Kevin EYER (Collex)<\/td>\n<td>9 buts<\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td height=\"20\">6.<\/td>\n<td>J\u00e9r\u00f4me THERY (Plan-les-Ouates)<\/td>\n<td>8 buts<\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td height=\"20\">7.<\/td>\n<td>Malik MUTOMBO (Bernex)<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td>Mario MACHADO (Bernex)<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td>Nicolas LHONEUX (Collex)<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td>Aboubacar DIA (UGS)<\/td>\n<td>7 buts<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>18\u00e8me journ\u00e9e \/ Au terme d&#8217;une journ\u00e9e qui n&#8217;a vu aucune d\u00e9faite genevoise, les Bern\u00e9siens prennent la t\u00eate pour la premi\u00e8re fois de la saison apr\u00e8s leur succ\u00e8s sur le terrain de Dardania. UGS et Collex compl\u00e8tent le podium qui reste serr\u00e9. En bas de tableau, Veyrier se rapproche de la barre.<\/p>\n","protected":false},"author":1,"featured_media":5722,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[26],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.proxifoot.ch\/geneve\/2015\/04\/2eme-ligue-inter-signal-bernex-nouveau-leader\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2\u00e8me ligue inter : Signal Bernex, nouveau leader - Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"og:description\" content=\"18\u00e8me journ\u00e9e \/ Au terme d&#8217;une journ\u00e9e qui n&#8217;a vu aucune d\u00e9faite genevoise, les Bern\u00e9siens prennent la t\u00eate pour la premi\u00e8re fois de la saison apr\u00e8s leur succ\u00e8s sur le terrain de Dardania. UGS et Collex compl\u00e8tent le podium qui reste serr\u00e9. En bas de tableau, Veyrier se rapproche de la barre.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.proxifoot.ch\/geneve\/2015\/04\/2eme-ligue-inter-signal-bernex-nouveau-leader\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-12T16:34:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-20T16:11:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/08\/banniere-2eme-inter.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"164\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2015\/04\/2eme-ligue-inter-signal-bernex-nouveau-leader\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/08\/banniere-2eme-inter.jpg\",\"width\":660,\"height\":164},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2015\/04\/2eme-ligue-inter-signal-bernex-nouveau-leader\/#webpage\",\"url\":\"http:\/\/www.proxifoot.ch\/geneve\/2015\/04\/2eme-ligue-inter-signal-bernex-nouveau-leader\/\",\"name\":\"2\\u00e8me ligue inter : Signal Bernex, nouveau leader - Proxifoot, le m\\u00e9dia du football genevois\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2015\/04\/2eme-ligue-inter-signal-bernex-nouveau-leader\/#primaryimage\"},\"datePublished\":\"2015-04-12T16:34:26+00:00\",\"dateModified\":\"2016-07-20T16:11:36+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.proxifoot.ch\/geneve\/2015\/04\/2eme-ligue-inter-signal-bernex-nouveau-leader\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\",\"name\":\"admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/21301"}],"collection":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=21301"}],"version-history":[{"count":0,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/21301\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/5722"}],"wp:attachment":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=21301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=21301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=21301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}