﻿{"id":21646,"date":"2015-04-26T18:31:33","date_gmt":"2015-04-26T16:31:33","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=21646"},"modified":"2016-07-20T18:10:11","modified_gmt":"2016-07-20T16:10:11","slug":"3eme-ligue-retour-sur-la-18eme-journee","status":"publish","type":"post","link":"https:\/\/www.proxifoot.ch\/geneve\/2015\/04\/3eme-ligue-retour-sur-la-18eme-journee\/","title":{"rendered":"3\u00e8me ligue : retour sur la 18\u00e8me journ\u00e9e"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Bien que tenu en \u00e9chec, Veyrier II conserve sa premi\u00e8re place dans le groupe 1. Dans le groupe 2, Interstar subit sa premi\u00e8re d\u00e9faite de la saison.<!--more--><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>GROUPE 1<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">Le suspense risque de durer un moment dans ce groupe 1 de 3\u00e8me ligue. Samedi, le leader Veyrier II a sauv\u00e9 le point du match nul \u00e0 la derni\u00e8re minute contre Gen\u00e8ve-Poste (3-3). Connaissant ce r\u00e9sultat, Avanchet pouvait prendre la t\u00eate dimanche mais les joueurs de Martino Papa ont \u00e9t\u00e9 \u00e9galement tenus en \u00e9chec sur le terrain de Bernex II (1-1).<\/p>\n<p style=\"text-align: justify;\"><em>Status quo<\/em> donc en t\u00eate du classement ? Pas tant que \u00e7a&#8230; Ces r\u00e9sultats ont profit\u00e9 \u00e0 Meyrin II qui est le grand b\u00e9n\u00e9ficiaire de cette journ\u00e9e. L&#8217;\u00e9quipe de Jean-Philippe Lebeau s&#8217;est largement impos\u00e9e sur le terrain d&#8217;Azzurri par 5 buts \u00e0 2.<em> &#8220;On est bien rentr\u00e9s dans le match, avec une grande application, ce qui nous a permis de nous mettre \u00e0 l&#8217;abri d\u00e8s la premi\u00e8re mi-temps, <\/em>analysait l&#8217;entra\u00eeneur meyrinois<em>. La deuxi\u00e8me p\u00e9riode a \u00e9t\u00e9 moins rythm\u00e9e et plus d\u00e9cousue, on aurait d\u00fb creuser d&#8217;avantage l&#8217;\u00e9cart. Mais l&#8217;essentiel est l\u00e0, c&#8217;est le principal&#8221;.<\/em><\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s une mauvaise s\u00e9rie de six matchs sans victoire (les trois derniers du premier tour et les trois premiers du second tour), les jeunes Meyrinois ont rectifi\u00e9 le tir en encha\u00eenant un troisi\u00e8me succ\u00e8s cons\u00e9cutif. Lebeau revenait sur cet \u00e9tat de forme : <em>&#8220;On a mal commenc\u00e9 le second tour, avec une \u00e9quipe diff\u00e9rente du premier tour.\u00a0Quelques joueurs de mon contingent sont d\u00e9sormais en premi\u00e8re, et ils jouent! Ils \u00e9taient des titulaires lors de la premi\u00e8re phase. Il a fallu s&#8217;adapter et que tout l&#8217;effectif travaille dur pour rester comp\u00e9titif. Et je leur en suis tr\u00e8s reconnaissant! On passe maintenant une meilleure p\u00e9riode qui, je l&#8217;esp\u00e8re, va continuer&#8221;.<\/em><\/p>\n<p style=\"text-align: justify;\">Revenu \u00e0 trois longueurs de Veyrier II et \u00e0 deux d&#8217;Avanchet, Meyrin II se relance ainsi dans la course \u00e0 la promotion. Mais pour Lebeau, la saison est d\u00e9j\u00e0 une r\u00e9ussite :\u00a0<em>&#8220;La qualit\u00e9 des joueurs et leur abn\u00e9gation dans le travail leur a permis de faire une tr\u00e8s belle saison quoi qu&#8217;il arrive.\u00a0On est toujours bien plac\u00e9, et on fera les comptes \u00e0 la fin mai&#8221;.<\/em><\/p>\n<p style=\"text-align: justify;\">Autre \u00e9quipe en forme, Vernier II, qui ne perd plus depuis 8 journ\u00e9es et qui vient de s&#8217;offrir une large victoire contre UGS II : 9-1, avec notamment un tripl\u00e9 de\u00a0Zlotykamien en un peu plus de 5 minutes ! Les Verniolans, d\u00e9sormais en milieu de tableau, auront \u00e0 c\u0153ur de terminer le second tour sans perdre un match.<\/p>\n<p style=\"text-align: justify;\">Dans la course au maintien, Onex II a r\u00e9alis\u00e9 une la bonne op\u00e9ration du jour. En s&#8217;imposant dans les derni\u00e8res minutes au terme d&#8217;un match fou contre Choulex (7-4), les On\u00e9siens reviennent ainsi \u00e0 deux points d&#8217;Azzurri. La mauvaise nouvelle pour eux est que les deux prochaines sorties sont contre Meyrin II et Avanchet. De son c\u00f4t\u00e9, Bosna a laiss\u00e9 \u00e9chapper la victoire contre Perly II dans les derni\u00e8res minutes. La lanterne rouge perd ainsi une belle opportunit\u00e9 de r\u00e9duire la distance avec la barre, qui est \u00e0 5 points.<\/p>\n<div id=\"attachment_21730\" style=\"width: 654px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-21730\" loading=\"lazy\" class=\" wp-image-21730 \" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2015\/04\/Bernex2-Avanchet-1415.jpg\" alt=\"Bernex2-Avanchet-1415\" width=\"644\" height=\"426\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2015\/04\/Bernex2-Avanchet-1415.jpg 1134w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2015\/04\/Bernex2-Avanchet-1415-300x199.jpg 300w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2015\/04\/Bernex2-Avanchet-1415-1024x678.jpg 1024w\" sizes=\"(max-width: 644px) 100vw, 644px\" \/><p id=\"caption-attachment-21730\" class=\"wp-caption-text\">Pas de vainqueur entre Bernex II et Avanchet (Photo: J. Franzen)<\/p><\/div>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>FC Veyrier Sports II\u00a0 \u00a0\u2013 \u00a0\u00a0US Gen\u00e8ve-Poste FC \u00a0 3 &#8211; 3<br \/>\n<\/strong><em><strong>Buts<\/strong> : 37&#8242; Palmen 1-0, 41&#8242; Pappalardo 1-1, 49&#8242; Pappalardo 1-2, 53&#8242; Audergon 2-2, 72&#8242; G. Prezioso (P) 2-3, 90&#8242; Carvalho 3-3<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>FC Vernier II\u00a0 \u00a0\u2013 \u00a0\u00a0FC UGS II \u00a0 9 &#8211; 1<br \/>\n<\/strong><em><strong>Buts<\/strong> : 9&#8242; Baptiste 1-0, 30&#8242; Knezevic 2-0, 39&#8242; Marques 3-0, 43&#8242; Zlotykamien 4-0, 46&#8242;\u00a0<em>Zlotykamien 5-0, 49&#8242;\u00a0<em>Zlotykamien 6-0, 62&#8242; Chaka 7-0, 85&#8242; Champod 8-0, 90&#8242; Tomasini 9-0, 92&#8242; N. Horvath 9-1<\/em><\/em><\/em><\/p>\n<p><strong>FC Rapid Jonction Bosna\u00a0 \u00a0\u2013 \u00a0\u00a0FC Perly-Certoux II \u00a0 1 &#8211; 1<br \/>\n<\/strong><em><strong>Buts<\/strong> : 42&#8242; Ni. Omeragic 1-0, 83&#8242; Geinoz 1-1<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>USI Azzurri\u00a0 \u00a0\u2013 \u00a0\u00a0Meyrin FC II \u00a0 2 &#8211; 5<br \/>\n<\/strong><em><strong>Buts<\/strong>\u00a0: 26&#8242; Leite 0-1, 36&#8242; Lounissi (P) 0-2, 50&#8242; Kinkembo 0-3, 53&#8242; Loureiro 0-4, 55&#8242; Beqiri 1-4, 60&#8242; Heritier 1-5, 83&#8242; Fehlmann 2-5<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>FC Onex II\u00a0 \u00a0\u2013 \u00a0\u00a0FC Choulex \u00a0 7 &#8211; 4<br \/>\n<\/strong><em><strong>Buts<\/strong> : 18&#8242; Berrut 1-0, 19&#8242; Moro 1-1, 55&#8242; Monteiro 1-2, 62&#8242; Negro 1-3, 62&#8242; Marchi 2-3, 64&#8242; Berrut 3-3, 67&#8242; Loup Beausoleil 4-3, 76&#8242; Prencipe 4-4, 79&#8242; Girard 5-4, 81&#8242; Mehadjri 6-4, 83&#8242; Pereira 7-4<\/em><\/p>\n<p><strong>Signal FC Bernex-Confignon II\u00a0 \u00a0\u2013 \u00a0\u00a0Avanchet-Sport FC \u00a0 1 &#8211; 1<br \/>\n<\/strong><em><strong>Buts<\/strong> : 59&#8242; Q. Van der Sch\u00fcren 1-0, 72&#8242; Rexhepi 1-1<\/em><\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-21681\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2015\/04\/3ligue1415-1-18.jpg\" alt=\"3ligue1415-1-18\" width=\"620\" height=\"325\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2015\/04\/3ligue1415-1-18.jpg 620w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2015\/04\/3ligue1415-1-18-300x157.jpg 300w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2015\/04\/3ligue1415-1-18-351x185.jpg 351w\" sizes=\"(max-width: 620px) 100vw, 620px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>GROUPE 2<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">Le leader est tomb\u00e9. D\u00e9j\u00e0 assur\u00e9 de la promotion en 2\u00e8me ligue, Interstar a subi sa premi\u00e8re d\u00e9faite de la saison contre Plan-les-Ouates II. Les joueurs de St\u00e9phane Formenti, qui ont rat\u00e9 un penalty dans les arr\u00eats de jeu, ont subi la loi de Bruno Rebelo, le v\u00e9loce ailier plan-les-ouatien auteur d&#8217;un tripl\u00e9 \u00e0 Varemb\u00e9 (2-3).<\/p>\n<p style=\"text-align: justify;\">Du c\u00f4t\u00e9 des poursuivants, Versoix a pris une option sur la seconde place gr\u00e2ce \u00e0 une nouvelle victoire, cette fois sur le terrain de Saint-Paul (0-3). Le podium est compl\u00e9t\u00e9 par l&#8217;US Carouge, victorieux \u00e0 Puplinge (1-2) et qui a \u00e9galement fait un grand pas pour terminer dans le top 3.<\/p>\n<p style=\"text-align: justify;\">Mais le suspense dans ce groupe 2 r\u00e9side dans la course au maintien. Et le match de samedi entre Ch\u00eanois II et Meinier avait des airs de finale avant l&#8217;heure pour le maintien en 3\u00e8me ligue, alors que c&#8217;\u00e9tait un match de 2\u00e8me ligue l&#8217;ann\u00e9e derni\u00e8re. Gr\u00e2ce \u00e0 une premi\u00e8re mi-temps de haut vol lors de laquelle il y avait d\u00e9j\u00e0 4-0, la seconde garniture ch\u00eanoise a pris le dessus sur Meinier. Score final : 5-2, avec un tripl\u00e9 de M&#8217;Baye et un doubl\u00e9 de Cerutti. Carlos Alonso, l&#8217;entra\u00eeneur des jeunes ch\u00eanois, soulignait la premi\u00e8re mi-temps de son \u00e9quipe : <em>&#8220;Nous avons r\u00e9alis\u00e9 une tr\u00e8s bonne premi\u00e8re mi-temps : discipline d\u00e9fensive, utilisation des intervalles, nos transmissions offensives \u00e9taient pr\u00e9cises et par cons\u00e9quent nous avons trouv\u00e9 nos attaquants qui ont \u00e9t\u00e9 lucides \u00e0 la finition. En seconde p\u00e9riode, nous avons contr\u00f4l\u00e9 le match malgr\u00e9 que Meinier ait jou\u00e9 plus haut et avec leur esprit de combat, ils nous ont pos\u00e9 plus probl\u00e8mes au milieu du terrain&#8221;.<\/em><\/p>\n<p style=\"text-align: justify;\">Ce succ\u00e8s fait un bien fou \u00e0 Ch\u00eanois II qui n&#8217;avait toujours pas gagn\u00e9 en 2015. Carlos Alonso concluait :<em> &#8220;C&#8217;est notre premi\u00e8re victoire en 2015, elle est importante pour notre confiance et dans l&#8217;optique du maintien. Toutes les \u00e9quipes font des points, ce qui rend cette fin de saison palpitante et ind\u00e9cise. Malgr\u00e9 cela, notre philosophie au CS Ch\u00eanois concernant la formation ne changera pas : contre Meinier, 7 joueurs titulaires sont n\u00e9s entre 1995 et 1997\u00a0<em>\u00bb<\/em><\/em>.<\/p>\n<p style=\"text-align: justify;\">La seconde \u00e9quipe du CS Italien a \u00e9galement fait la bonne op\u00e9ration dans la lutte pour le maintien en s&#8217;imposant 3-0 contre Champel II. Bien que situ\u00e9e au-dessus de la barre, il faudra se m\u00e9fier de cette 10\u00e8me place qui pourrait \u00eatre synonyme de barrage pour le maintien. Pour cela, il faudra attendre la fin de saison en 2\u00e8me ligue inter. Et dans ce groupe 2, beaucoup d&#8217;\u00e9quipes restent menac\u00e9es par ce barrage puisqu&#8217;il n&#8217;y a que trois points d&#8217;\u00e9cart entre Ch\u00eanois II, 10\u00e8me, et Plan-les-Ouates II, 6\u00e8me.<\/p>\n<div id=\"attachment_21693\" style=\"width: 584px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-21693\" loading=\"lazy\" class=\" wp-image-21693 \" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2015\/04\/Saint-Paul-Versoix-1415.jpg\" alt=\"Saint-Paul-Versoix-1415\" width=\"574\" height=\"382\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2015\/04\/Saint-Paul-Versoix-1415.jpg 1024w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2015\/04\/Saint-Paul-Versoix-1415-300x200.jpg 300w\" sizes=\"(max-width: 574px) 100vw, 574px\" \/><p id=\"caption-attachment-21693\" class=\"wp-caption-text\">Les Versoisiens, vainqueurs \u00e0 la Californie (Photo: IV Sport)<\/p><\/div>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>CS Ch\u00eanois II<strong>\u00a0 \u00a0\u2013 \u00a0\u00a0<\/strong>US Meinier \u00a0 5 &#8211; 2<br \/>\n<em>Buts<\/em><\/strong><em> : 10&#8242; Cerutti 1-0, 11&#8242; M&#8217;Baye 2-0, 24&#8242; M&#8217;Baye 3-0, 41&#8242; Cerutti 4-0, 55&#8242; Lazzarelli 4-1, 80&#8242; M&#8217;Baye 5-1, 85&#8242; Jimenez (P) 5-2<\/em><\/p>\n<p><strong>FC Saint-Paul<strong>\u00a0 \u00a0\u2013 \u00a0\u00a0<\/strong>FC Versoix \u00a0 0 &#8211; 3<br \/>\n<\/strong><em><strong>Buts<\/strong> : 24&#8242; Shabani 0-1, 91&#8242; Bebay 0-2, 93&#8242; Diagne 0-3<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>CS Interstar<strong>\u00a0 \u00a0\u2013 \u00a0\u00a0<\/strong>FC Plan-les-Ouates II \u00a0 2 &#8211; 3<br \/>\n<\/strong><em><strong>Buts<\/strong> : 16&#8242; Rebelo 0-1, 24&#8242; Rebelo 0-2, 26&#8242; Hanson 1-2, 35&#8242; Fricker (P) 2-2, 48&#8242; Rebelo 2-3<\/em><\/p>\n<p><strong>FC Puplinge<strong>\u00a0 \u00a0\u2013 \u00a0\u00a0<\/strong>US Carouge FC \u00a0 1 &#8211; 2<br \/>\n<\/strong><em><strong>Buts<\/strong> : 13&#8242; Loureiro 0-1, 57&#8242; Tartaglione (P) 1-1, 70&#8242; Torreira 1-2<\/em><\/p>\n<p><strong>FC Donzelle<strong>\u00a0 \u00a0\u2013 \u00a0\u00a0<\/strong>FC Satigny \u00a0 0 &#8211; 5<br \/>\n<a title=\"Satigny remporte largement le derby\" href=\"http:\/\/www.proxifoot.ch\/geneve\/2015\/04\/satigny-remporte-largement-le-derby\/\"><em>Lire l&#8217;article<\/em><\/a><\/strong><\/p>\n<p><strong>CS Italien II<strong>\u00a0 \u00a0\u2013 \u00a0\u00a0<\/strong>FC Champel II \u00a0 3 &#8211; 0<br \/>\n<\/strong><em><strong>Buts<\/strong> : 2&#8242; Looga 1-0, 15&#8242; Pereiras 2-0, 87&#8242; Puopolo 3-0<\/em><\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-21677\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2015\/04\/3ligue1415-2-18.jpg\" alt=\"3ligue1415-2-18\" width=\"618\" height=\"313\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2015\/04\/3ligue1415-2-18.jpg 618w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2015\/04\/3ligue1415-2-18-300x152.jpg 300w\" sizes=\"(max-width: 618px) 100vw, 618px\" \/><\/p>\n<p>&nbsp;<\/p>\n<table class=\" aligncenter\" border=\"0\" width=\"332\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"21\" \/>\n<col width=\"247\" \/>\n<col width=\"64\" \/> <\/colgroup>\n<tbody>\n<tr>\n<td width=\"21\" height=\"20\"><\/td>\n<td width=\"247\"><strong>CLASSEMENT DES BUTEURS<\/strong><\/td>\n<td width=\"64\"><\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td height=\"20\">1.<\/td>\n<td>Flamur SELMANI (Avanchet)<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td>Alagie CASSAMA (Donzelle)<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td>Gianluca PREZIOSO (Gen\u00e8ve-Poste)<\/td>\n<td>18 buts<\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td height=\"20\">4.<\/td>\n<td>Luis LOUREIRO (Meyrin II)<\/td>\n<td>17 buts<\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td height=\"20\">5.<\/td>\n<td>Ridvan IBRAHIMI (Avanchet)<\/td>\n<td>16 buts<\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td height=\"20\">6.<\/td>\n<td>Agron SHABANI (Versoix)<\/td>\n<td>14 buts<\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td height=\"20\">7.<\/td>\n<td>St\u00e9phane CESAREO (Veyrier II)<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td>Anthony GOBBI (Bernex II)<\/td>\n<td>13 buts<\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td height=\"20\">9.<\/td>\n<td>Taulant GASHI (Gen\u00e8ve-Poste)<\/td>\n<td>12 buts<\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td height=\"20\">10.<\/td>\n<td>Ugo TOGNI (Versoix)<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td>Elias GHAZRAOUI (Puplinge)<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td>Brandon KINKEMBO (Meyrin II)<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td height=\"20\"><\/td>\n<td>Anthony BERRUT (Onex II)<\/td>\n<td>11 buts<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bien que tenu en \u00e9chec, Veyrier II conserve sa premi\u00e8re place dans le groupe 1. Dans le groupe 2, Interstar subit sa premi\u00e8re d\u00e9faite de la saison.<\/p>\n","protected":false},"author":1,"featured_media":18707,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[6],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.proxifoot.ch\/geneve\/2015\/04\/3eme-ligue-retour-sur-la-18eme-journee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3\u00e8me ligue : retour sur la 18\u00e8me journ\u00e9e - Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"og:description\" content=\"Bien que tenu en \u00e9chec, Veyrier II conserve sa premi\u00e8re place dans le groupe 1. Dans le groupe 2, Interstar subit sa premi\u00e8re d\u00e9faite de la saison.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.proxifoot.ch\/geneve\/2015\/04\/3eme-ligue-retour-sur-la-18eme-journee\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-26T16:31:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-20T16:10:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/08\/banniere-3\u00e8me-ligue.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"164\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2015\/04\/3eme-ligue-retour-sur-la-18eme-journee\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2014\/08\/banniere-3\\u00e8me-ligue.jpg\",\"width\":660,\"height\":164},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2015\/04\/3eme-ligue-retour-sur-la-18eme-journee\/#webpage\",\"url\":\"http:\/\/www.proxifoot.ch\/geneve\/2015\/04\/3eme-ligue-retour-sur-la-18eme-journee\/\",\"name\":\"3\\u00e8me ligue : retour sur la 18\\u00e8me journ\\u00e9e - Proxifoot, le m\\u00e9dia du football genevois\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2015\/04\/3eme-ligue-retour-sur-la-18eme-journee\/#primaryimage\"},\"datePublished\":\"2015-04-26T16:31:33+00:00\",\"dateModified\":\"2016-07-20T16:10:11+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.proxifoot.ch\/geneve\/2015\/04\/3eme-ligue-retour-sur-la-18eme-journee\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\",\"name\":\"admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/21646"}],"collection":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=21646"}],"version-history":[{"count":0,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/21646\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/18707"}],"wp:attachment":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=21646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=21646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=21646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}