﻿{"id":22755,"date":"2015-06-18T11:38:52","date_gmt":"2015-06-18T09:38:52","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=22755"},"modified":"2015-06-18T11:38:52","modified_gmt":"2015-06-18T09:38:52","slug":"2eme-ligue-inter-lequipe-type-de-la-saison-2014-2015","status":"publish","type":"post","link":"https:\/\/www.proxifoot.ch\/geneve\/2015\/06\/2eme-ligue-inter-lequipe-type-de-la-saison-2014-2015\/","title":{"rendered":"2\u00e8me ligue inter : l\u2019\u00e9quipe-type de la saison 2014-2015"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>D\u00e9couvrez l\u2019\u00e9quipe-type du groupe 1 de 2\u00e8me ligue inter (Gen\u00e8ve, Vaud, Valais) d\u00e9cid\u00e9e par les votes des entra\u00eeneurs et des lecteurs.<\/strong><span id=\"more-22726\"><\/span><!--more--><\/p>\n<p style=\"text-align: justify;\">Les championnats respectifs d\u00e9sormais termin\u00e9s, il est temps de savoir qui ont \u00e9t\u00e9 les meilleurs de la saison\u2026\u00a0Apr\u00e8s six\u00a0ann\u00e9es o\u00f9 les \u00e9quipes-types\u00a0\u00e9taient d\u00e9cid\u00e9es uniquement par les votes des entra\u00eeneurs, nous avons offert cette ann\u00e9e la possibilit\u00e9 \u00e0 nos lecteurs de donner leur voix. La pond\u00e9ration du vote du public est bien entendu inf\u00e9rieure \u00e0 celle des entra\u00eeneurs : 0.25 par voix du public contre 1.0 pour les entra\u00eeneurs.<\/p>\n<p style=\"text-align: justify;\">L&#8217;autre nouveaut\u00e9\u00a0de la saison est la cr\u00e9ation d&#8217;une \u00e9quipe-type de 2\u00e8me ligue inter, \u00e9tant donn\u00e9 le nombre \u00e9lev\u00e9 de clubs genevois dans cette cat\u00e9gorie (8).\u00a0Les votes ont donc \u00e9t\u00e9 demand\u00e9s aux entra\u00eeneurs du groupe 1 de 2\u00e8me ligue interr\u00e9gionale (genevois, vaudois et valaisans).<\/p>\n<p style=\"text-align: justify;\">Cette \u00e9quipe-type de la saison a la particularit\u00e9 de contenir des joueurs n&#8217;ayant jou\u00e9\u00a0que le premier tour dans cette cat\u00e9gorie. On pense \u00e0 Dupont (UGS, parti \u00e0 Etoile Carouge) et\u00a0Morina (Dardania, parti \u00e0 K\u00f6niz), dont les votes du premier tour ont \u00e9t\u00e9 suffisamment nombreux\u00a0pour se maintenir dans l&#8217;\u00e9quipe.<\/p>\n<p style=\"text-align: justify;\">Les trois clubs\u00a0qui ont longtemps lutt\u00e9 pour le titre sont les plus repr\u00e9sent\u00e9s : Bernex, UGS et Collex comptent 4 joueurs dans l&#8217;\u00e9quipe, devant Dardania qui en compte 3. Sont \u00e9galement pr\u00e9sents\u00a0: Perly, Veyrier, La Sarraz, Vevey et Saxon avec un joueur, pour un total de 9 \u00e9quipes repr\u00e9sent\u00e9es sur 14.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" class=\"alignnone wp-image-22756\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2015\/06\/2\u00e8me-inter-2014-2015.png\" alt=\"2\u00e8me inter - 2014-2015\" width=\"700\" height=\"664\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2015\/06\/2\u00e8me-inter-2014-2015.png 827w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2015\/06\/2\u00e8me-inter-2014-2015-300x284.png 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez l\u2019\u00e9quipe-type du groupe 1 de 2\u00e8me ligue inter (Gen\u00e8ve, Vaud, Valais) d\u00e9cid\u00e9e par les votes des entra\u00eeneurs et des lecteurs.<\/p>\n","protected":false},"author":1,"featured_media":4593,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[26],"tags":[53],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.proxifoot.ch\/geneve\/2015\/06\/2eme-ligue-inter-lequipe-type-de-la-saison-2014-2015\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2\u00e8me ligue inter : l\u2019\u00e9quipe-type de la saison 2014-2015 - Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez l\u2019\u00e9quipe-type du groupe 1 de 2\u00e8me ligue inter (Gen\u00e8ve, Vaud, Valais) d\u00e9cid\u00e9e par les votes des entra\u00eeneurs et des lecteurs.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.proxifoot.ch\/geneve\/2015\/06\/2eme-ligue-inter-lequipe-type-de-la-saison-2014-2015\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-18T09:38:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/06\/banni\u00e8re-equipes-types.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"164\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2015\/06\/2eme-ligue-inter-lequipe-type-de-la-saison-2014-2015\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/06\/banni\\u00e8re-equipes-types.jpg\",\"width\":660,\"height\":164},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2015\/06\/2eme-ligue-inter-lequipe-type-de-la-saison-2014-2015\/#webpage\",\"url\":\"http:\/\/www.proxifoot.ch\/geneve\/2015\/06\/2eme-ligue-inter-lequipe-type-de-la-saison-2014-2015\/\",\"name\":\"2\\u00e8me ligue inter : l\\u2019\\u00e9quipe-type de la saison 2014-2015 - Proxifoot, le m\\u00e9dia du football genevois\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2015\/06\/2eme-ligue-inter-lequipe-type-de-la-saison-2014-2015\/#primaryimage\"},\"datePublished\":\"2015-06-18T09:38:52+00:00\",\"dateModified\":\"2015-06-18T09:38:52+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.proxifoot.ch\/geneve\/2015\/06\/2eme-ligue-inter-lequipe-type-de-la-saison-2014-2015\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\",\"name\":\"admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/22755"}],"collection":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=22755"}],"version-history":[{"count":0,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/22755\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/4593"}],"wp:attachment":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=22755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=22755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=22755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}