﻿{"id":23220,"date":"2015-08-24T21:39:40","date_gmt":"2015-08-24T19:39:40","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=23220"},"modified":"2016-08-24T14:30:53","modified_gmt":"2016-08-24T12:30:53","slug":"la-coupe-suisse-digeree-meyrin-se-place-co-leader","status":"publish","type":"post","link":"https:\/\/www.proxifoot.ch\/geneve\/2015\/08\/la-coupe-suisse-digeree-meyrin-se-place-co-leader\/","title":{"rendered":"La Coupe suisse dig\u00e9r\u00e9e, Meyrin se place co-leader"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Les Meyrinois ont assur\u00e9 leur semaine post-B\u00e2le\u00a0avec quatre points en deux journ\u00e9es. Ils se partagent d\u00e9sormais la t\u00eate avec trois autres \u00e9quipes.<\/strong><!--more--><\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s trois journ\u00e9es en 2\u00e8me ligue inter, aucune \u00e9quipe n&#8217;a obtenu la totalit\u00e9 des points. Meyrin a perdu ses premiers mardi contre Monthey, seulement trois jours apr\u00e8s avoir affront\u00e9 le FC B\u00e2le en Coupe suisse. <em>&#8220;Nous avons bien dig\u00e9r\u00e9 le match contre B\u00e2le,<\/em> nous confie l&#8217;entra\u00eeneur Jean-Philippe Lebeau. <em>Nous sommes contents du match, autant pour le club que pour les joueurs, \u00e7a leur fait une belle exp\u00e9rience. Et nous n&#8217;avons pas \u00e9t\u00e9 ridicules, nous aurions m\u00eame m\u00e9rit\u00e9 de marquer un but&#8221;.<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Semaine charg\u00e9e<\/strong><\/p>\n<p style=\"text-align: justify;\">Une belle exp\u00e9rience, certes, mais il fallait rapidement se remettre en mode championnat, puisque les Meyrinois recevaient Monthey trois jours plus tard. Un match au terme\u00a0duquel les pensionnaires des Arb\u00e8res ont conc\u00e9d\u00e9 le nul (1-1). <em>&#8220;Ce n&#8217;\u00e9tait pas facile,<\/em> poursuit Lebeau,<em> autant au niveau de la t\u00eate que des jambes. Mais il fallait s&#8217;y attendre, apr\u00e8s B\u00e2le<\/em><em>. Dans l&#8217;ensemble, je suis satisfait de ce match nul&#8221;.<\/em><\/p>\n<p style=\"text-align: justify;\">La semaine charg\u00e9e des Meyrinois s&#8217;est achev\u00e9e samedi\u00a0avec une nette victoire sur le terrain des M21 de Servette pour le premier derby de la saison pour les\u00a0Jaune et Noir. Un match que les visiteurs ont pris \u00e0 leur compte d\u00e8s la premi\u00e8re mi-temps et l&#8217;ouverture du score par Fitim Rugovaj, un des nombreux jeunes talentueux, qui b\u00e9n\u00e9ficie de temps de jeu en ce d\u00e9but de saison :\u00a0<em>&#8220;C&#8217;est un joueur int\u00e9ressant, un bon jeune, comme d&#8217;autres dans l&#8217;\u00e9quipe. Il a l&#8217;avantage de jouer \u00e0 un poste offensif, c&#8217;est donc plus facile pour lui d&#8217;avoir des minutes de jeu par rapport aux autres. Contre Servette, il a eu l&#8217;occasion de jouer d&#8217;entr\u00e9e et il a marqu\u00e9&#8221;.<\/em><\/p>\n<div id=\"attachment_23234\" style=\"width: 610px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.proxifoot.ch\/geneve\/2015\/08\/la-coupe-suisse-digeree-meyrin-se-place-co-leader\/rugovaj-meyrin-bale-1516\/\" rel=\"attachment wp-att-23234\"><img aria-describedby=\"caption-attachment-23234\" loading=\"lazy\" class=\"wp-image-23234\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2015\/08\/Rugovaj-Meyrin-Bale-1516.jpg\" alt=\"Rugovaj a eu droit \u00e0 une vingtaine de minutes contre le FC B\u00e2le de Walter Samuel\" width=\"600\" height=\"354\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2015\/08\/Rugovaj-Meyrin-Bale-1516.jpg 960w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2015\/08\/Rugovaj-Meyrin-Bale-1516-300x177.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><p id=\"caption-attachment-23234\" class=\"wp-caption-text\">Rugovaj a eu droit \u00e0 une vingtaine de minutes contre le FC B\u00e2le de Walter Samuel<\/p><\/div>\n<p style=\"text-align: justify;\">En seconde p\u00e9riode, Moukoko &#8211; auteur d&#8217;un bon d\u00e9but de saison &#8211; et Belladon ont permis \u00e0 la formation des Arb\u00e8res de prendre le large. La r\u00e9duction du score en fin de match a \u00e9t\u00e9 anecdotique et Meyrin a obtenu\u00a0un succ\u00e8s que Lebeau estimait juste : <em>&#8220;Nous \u00e9tions mentalement pr\u00eats. C&#8217;est une victoire m\u00e9rit\u00e9e, nous avons \u00e9t\u00e9 r\u00e9alistes. Ce n&#8217;est pas \u00e9vident tactiquement de demander une chose \u00e0 mes joueurs, puis le temps de quelques jours pr\u00e9parer une tactique d\u00e9fensive pour B\u00e2le, et \u00e0 nouveau repartir comme avant. Ce n&#8217;est pas encore \u00e7a, mais \u00e7a viendra&#8221;.<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Il faudra compter sur Meyrin<\/strong><\/p>\n<p style=\"text-align: justify;\">Toujours est-il que m\u00eame si c&#8217;est seulement la 3\u00e8me journ\u00e9e, Meyrin se place dans le peloton de t\u00eate, co-leader avec Vevey, Aigle et Collex. C&#8217;est anecdotique pour le moment mais il est important de se placer. Car Meyrin ne cache pas ses ambitions : en tant que rel\u00e9gu\u00e9 de 1\u00e8re ligue, le but\u00a0est de rebondir au plus vite. Lebeau confirme : <em>&#8220;On ne va pas se voiler la face, l&#8217;objectif est de remonter tout de suite. Mais cela ne va pas \u00eatre facile, la 2\u00e8me ligue inter est plus relev\u00e9e cette ann\u00e9e que les autres ann\u00e9es, il y a des grosses \u00e9quipes comme Vevey, UGS ou Ch\u00eanois. Mais il ne s&#8217;agira pas d&#8217;une confrontation mais d&#8217;une saison enti\u00e8re. La saison est longue, et surtout l&#8217;intersaison o\u00f9 les \u00e9quipes peuvent beaucoup changer. Il faudra travailler, c&#8217;est le plus important&#8221;.<\/em><\/p>\n<p style=\"text-align: justify;\">En attendant, Meyrin aura \u00e0 coeur de rester dans le peloton de t\u00eate d\u00e8s ce week-end, o\u00f9 un d\u00e9placement les attend \u00e0 Veyrier-Village.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p><strong>SERVETTE FC M-21 &#8211; MEYRIN FC \u00a01-3 (0-1)<\/strong><\/p>\n<p><strong>Buts<\/strong> : 30&#8242; Rugovaj 0-1, 49&#8242; Moukoko 0-2, 81&#8242; Belladon 0-3, 89&#8242; Negro 1-3<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p><em>Photos : <a href=\"http:\/\/www.oneclick-photo.ch\">OneClick-Photo<\/a> &amp; <a href=\"https:\/\/www.facebook.com\/carlos.m.trigo\" target=\"_blank\">C.M. Trigo<\/a>\u00a0<\/em><\/p>\n<p><script src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\" async=\"\"><\/script><!-- superieur --> <ins class=\"adsbygoogle\" style=\"display: inline-block; width: 728px; height: 90px;\" data-ad-slot=\"1875735477\" data-ad-client=\"ca-pub-1317159203547503\"><\/ins><script>\/\/ <![CDATA[\n(adsbygoogle = window.adsbygoogle || []).push({});\n\/\/ ]]><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les Meyrinois ont assur\u00e9 leur semaine post-B\u00e2le\u00a0avec quatre points en deux journ\u00e9es. Ils se partagent d\u00e9sormais la t\u00eate avec trois autres \u00e9quipes.<\/p>\n","protected":false},"author":30,"featured_media":23233,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[26],"tags":[223,64],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.proxifoot.ch\/geneve\/2015\/08\/la-coupe-suisse-digeree-meyrin-se-place-co-leader\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Coupe suisse dig\u00e9r\u00e9e, Meyrin se place co-leader - Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"og:description\" content=\"Les Meyrinois ont assur\u00e9 leur semaine post-B\u00e2le\u00a0avec quatre points en deux journ\u00e9es. Ils se partagent d\u00e9sormais la t\u00eate avec trois autres \u00e9quipes.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.proxifoot.ch\/geneve\/2015\/08\/la-coupe-suisse-digeree-meyrin-se-place-co-leader\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2015-08-24T19:39:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-08-24T12:30:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2015\/08\/Lebeau-Meyrin-Monthey-1516.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1130\" \/>\n\t<meta property=\"og:image:height\" content=\"695\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@www.twitter.com\/maikel_f\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2015\/08\/la-coupe-suisse-digeree-meyrin-se-place-co-leader\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2015\/08\/Lebeau-Meyrin-Monthey-1516.png\",\"width\":1130,\"height\":695},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2015\/08\/la-coupe-suisse-digeree-meyrin-se-place-co-leader\/#webpage\",\"url\":\"http:\/\/www.proxifoot.ch\/geneve\/2015\/08\/la-coupe-suisse-digeree-meyrin-se-place-co-leader\/\",\"name\":\"La Coupe suisse dig\\u00e9r\\u00e9e, Meyrin se place co-leader - Proxifoot, le m\\u00e9dia du football genevois\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2015\/08\/la-coupe-suisse-digeree-meyrin-se-place-co-leader\/#primaryimage\"},\"datePublished\":\"2015-08-24T19:39:40+00:00\",\"dateModified\":\"2016-08-24T12:30:53+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/f8763ae73551193f68b47b57e2bdfb15\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.proxifoot.ch\/geneve\/2015\/08\/la-coupe-suisse-digeree-meyrin-se-place-co-leader\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/f8763ae73551193f68b47b57e2bdfb15\",\"name\":\"Maikel\",\"sameAs\":[\"https:\/\/twitter.com\/www.twitter.com\/maikel_f\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/23220"}],"collection":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=23220"}],"version-history":[{"count":0,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/23220\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/23233"}],"wp:attachment":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=23220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=23220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=23220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}