﻿{"id":2498,"date":"2012-04-01T11:00:53","date_gmt":"2012-04-01T10:00:53","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=2498"},"modified":"2016-07-20T17:28:33","modified_gmt":"2016-07-20T15:28:33","slug":"3eme-ligue-groupe-1-15eme-journee","status":"publish","type":"post","link":"https:\/\/www.proxifoot.ch\/geneve\/2012\/04\/3eme-ligue-groupe-1-15eme-journee\/","title":{"rendered":"3\u00e8me ligue groupe 1 : 15\u00e8me journ\u00e9e"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Dans le choc au sommet, Grand-Lancy II a pris le dessus sur Champel et devient ainsi le nouveau leader du groupe 1. Du c\u00f4t\u00e9 de la zone de rel\u00e9gation, Gen\u00e8ve-Ville et Satigny ont obtenu des succ\u00e8s importants face \u00e0 des adversaires directs. La situation est donc plus que serr\u00e9e, tant en haut qu&#8217;en bas du classement.<\/strong><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>FC Meyrin II\u00a0 &#8211; \u00a0US Meinier \u00a0 5 &#8211; 0<br \/>\nButs :<\/strong><em> Pas d&#8217;information\u00a0<\/em><\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s leur bonne performance contre A\u00efre-le-Lignon le week-end pass\u00e9, les Meyrinois ont obtenu un net succ\u00e8s face \u00e0 Meinier. Les Meynites ont pourtant bien commenc\u00e9 la partie, en se cr\u00e9ant trois occasions franches, qu&#8217;ils n&#8217;ont pas r\u00e9ussi \u00e0 concr\u00e9tiser. Les visiteurs n&#8217;ont pas tard\u00e9 \u00e0 regretter leur manque de concr\u00e9tisation, puisqu&#8217;\u00e0 la 20\u00e8me minute, Meyrin II a ouvert le score. Les joueurs de Tiago Terrinha ont ensuite doubl\u00e9 la mise, suite \u00e0 un autogoal meynite. &#8220;Le 2-0 sur autogoal nous a an\u00e9anti et le match \u00e9tait pli\u00e9&#8221;, nous avouait Jos\u00e9 Burgos.<\/p>\n<p style=\"text-align: justify;\">En seconde p\u00e9riode, Meyrin II n&#8217;a pas laiss\u00e9 le temps \u00e0 Meinier de r\u00e9agir. En effet, \u00e0 la 50\u00e8me minute, ils ont inscrit un troisi\u00e8me but, suite \u00e0 un nouvel autogoal meynite. &#8220;Meyrin a su provoqu\u00e9 la chance, nous n&#8217;avons pas r\u00e9ussi \u00e0 aller la chercher&#8221;, reconnaissait Jos\u00e9 Burgos. Les Meyrinois, plus r\u00e9alistes que leur adversaire, ont encore aggrav\u00e9 le score, infligeant un sec 5-0 \u00e0 Meinier<em>.<br \/>\n<\/em><em><br \/>\n<\/em>A la fin de la rencontre, Jos\u00e9 Burgos nous livrait son analyse: &#8220;Il fallait faire douter cette jeune \u00e9quipe de Meyrin II pour esp\u00e9rer prendre des points. A part les vingt premi\u00e8res minutes, nous n&#8217;y sommes pas parvenus. A partir de l\u00e0,\u00a0 nous n&#8217;avons pas pu emp\u00eacher cette \u00e9quipe de tr\u00e8s bien jouer au ballon et nous avons \u00e9t\u00e9 totalement d\u00e9bord\u00e9s. Un match \u00e0 oublier donc et nous devons retrouver le chemin des filets!&#8221;<em><br \/>\n<span style=\"font-family: Arial; font-size: x-small;\"><br \/>\n<\/span><br \/>\n<\/em><\/p>\n<p><strong>US Gen\u00e8ve-Ville \u00a0 &#8211; \u00a0FC Kosova II \u00a0 2 &#8211; 0<br \/>\nButs : <\/strong>Burnier 1-0, Vasquez 2-0<\/p>\n<p style=\"text-align: justify;\">Il n&#8217;est jamais facile de jouer contre Kosova II, une \u00e9quipe physique et combative. Abdou Lijouom, le coach de Gen\u00e8ve-Ville, estimait d&#8217;ailleurs \u00e0 juste titre que &#8220;l&#8217;engagement et physique et le mental \u00e9taient plus qu&#8217;une n\u00e9cessit\u00e9 pour s&#8217;imposer dans cette rencontre&#8221;. Les joueurs de Gen\u00e8ve-Ville ont justement d\u00e9montr\u00e9 toutes ces qualit\u00e9s dans cette partie et ont ainsi obtenu un succ\u00e8s important dans la course au maintien.<\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s un bon premier quart d&#8217;heure de jeu, les locaux ont pris l&#8217;avantage gr\u00e2ce \u00e0 une astucieuse d\u00e9viation de Burnier et ont conserv\u00e9 ce score jusqu&#8217;\u00e0 la pause. En seconde mi-temps, le jeu s&#8217;est durci et Kosova II aurait pu se retrouver \u00e0 10. En effet, sur une faute de dernier recours, l&#8217;arbitre n&#8217;a sanctionn\u00e9 que d&#8217;un jaune le capitaine kosovar. Qu&#8217;importe, puisque sur le coup-franc cons\u00e9cutif \u00e0 cette faute, Vasquez doublait la mise pour son \u00e9quipe. La seconde garniture kosovare a eu par la suite quelques occasions de r\u00e9duire le score, mais Gen\u00e8ve-Ville a tenu bon, comme l&#8217;expliquait Abdou Lijouom: &#8220;Pour une fois, la chance et la d\u00e9termination de mes joueurs, ainsi qu&#8217;un grand gardien, nous ont permis de garder notre cage inviol\u00e9e&#8221;. A noter que les Kosovars ont fini la partie \u00e0 10.<\/p>\n<p style=\"text-align: justify;\">Abdou Lijouom se montrait ainsi fier de ses joueurs suite \u00e0 cette victoire: &#8220;Le travail et le jeu finissent toujours par payer. Un grand bravo \u00e0 mes joueurs, qui match apr\u00e8s match, progressent mentalement et collectivement. Cette victoire nous permet de continuer \u00e0 esp\u00e9rer pour la suite de ce championnat&#8221;. L&#8217;entra\u00eeneur de Gen\u00e8ve-Ville attribuait \u00e9galement &#8220;une mention bien pour l&#8217;arbitre, Monsieur Frik, qui a siffl\u00e9 de fa\u00e7on intelligente et pris ses responsabilit\u00e9s au moment opportun&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>FC Satigny \u00a0 &#8211; \u00a0FC Famalic\u00e3o \u00a0 7 &#8211; 1<\/strong><br \/>\n<strong>Buts : <\/strong>Gomes 1-0, Gomes 2-0, Goutter 3-0, 3-1, Estupina 4-1, Carvalho 5-1, Gomes 6-1, Ammar 7-1<\/p>\n<p style=\"text-align: justify;\">La rencontre opposant Satigny et Famalic\u00e3o rev\u00eatait une importance consid\u00e9rable, les deux \u00e9quipes luttant pour leur maintien. C\u00e9dric Tallant, l\u2019entra\u00eeneur satignote avouait d\u2019ailleurs\u00a0: \u00ab\u00a0C&#8217;\u00e9tait un match de la peur pour nous. L&#8217;\u00e9quipe \u00e9tait consciente qu&#8217;une d\u00e9faite serait difficile \u00e0 dig\u00e9rer. Nous avons donc pris ce match tr\u00e8s au s\u00e9rieux.\u00a0\u00bb<\/p>\n<p style=\"text-align: justify;\">Les Satignotes ont rapidement pris l\u2019avantage, profitant de deux erreurs du gardien lusitanien transform\u00e9es par Gomes. Juste avant la mi-temps, Goutter a pu inscrire le 3-0 sur \u00ab\u00a0une pichenette audacieuse\u00a0\u00bb, selon les termes de C\u00e9dric Tallant. Apr\u00e8s 45 minutes difficiles, les Lusitaniens ont relev\u00e9 la t\u00eate en seconde p\u00e9riode et ont r\u00e9duit le score \u00e0 la 50<span style=\"font-size: 11px;\">\u00e8me<\/span>\u00a0minute. Les locaux n\u2019ont pas tard\u00e9 \u00e0 r\u00e9agir et ont marqu\u00e9 un quatri\u00e8me but peu apr\u00e8s. Les Satignotes ne se sont pas content\u00e9s de g\u00e9rer leur avantage, puisqu\u2019ils ont encore inscrit trois autres r\u00e9ussites. C\u00e9dric Tallant expliquait\u00a0: \u00ab\u00a0Les buts se sont encha\u00een\u00e9s, les joueurs se sont lib\u00e9r\u00e9s et ont produit un jeu all\u00e9chant\u00a0\u00bb.<\/p>\n<p style=\"text-align: justify;\">Cette victoire r\u00e9jouissait bien entendu le coach satignote\u00a0: \u00ab\u00a0Bravo \u00e0 l&#8217;\u00e9quipe et merci aux joueurs de la deuxi\u00e8me, ainsi que le gardien des v\u00e9t\u00e9rans qui ont \u00e9toff\u00e9 une premi\u00e8re \u00e9quipe toujours p\u00e9nalis\u00e9e par les neuf bless\u00e9s.\u00a0\u00bb De son c\u00f4t\u00e9, Famalic\u00e3o laisse \u00e9chapper trois points importants dans la lutte pour le maintien. Les Lusitaniens devront oublier ce match au plus vite et r\u00e9agir face \u00e0 A\u00efre le week-end prochain.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>FC Champel \u00a0 &#8211; \u00a0FC Grand-Lancy II \u00a0 1 &#8211; 2<br \/>\nButs :<\/strong> Gobbi 0-1, Schwarb 1-1, Ferreras 1-2.<\/p>\n<p style=\"text-align: justify;\">Grand-Lancy II est ressorti vainqueur du choc au sommet qui l&#8217;opposait \u00e0 Champel. Il n&#8217;a pas fallu attendre beaucoup de temps pour que les compteurs se d\u00e9bloquent dans ce match. En effet, apr\u00e8s six minutes de jeu, les Lanc\u00e9ens ont fait trembler les filets une premi\u00e8re fois gr\u00e2ce \u00e0 Gobbi, profitant d&#8217;une erreur du gardien champelois Andreoli qui a rel\u00e2ch\u00e9 le ballon sur un corner. Le d\u00e9but de match a \u00e9t\u00e9 intense, puisque les locaux ont \u00e9galis\u00e9 peu apr\u00e8s par Schwarb, lanc\u00e9 en profondeur sur son c\u00f4t\u00e9 droit. Les hommes de Farminio Isabella ont ensuite repris l&#8217;avantage, vingt minutes apr\u00e8s cette r\u00e9alisation, sur un centre-tir repris de la t\u00eate par Ferreras.<\/p>\n<p style=\"text-align: justify;\">Les Lanc\u00e9ens ont ensuite g\u00e9r\u00e9 leur r\u00e9sultat, tandis que leurs adversaires ont tout fait pour revenir au score et ont multipli\u00e9 les attaques, comme l&#8217;explique Farminio Isabella: &#8220;Nous avons d\u00e9fendu avec caract\u00e8re et courage. Notre jeune gardien a fait des arr\u00eats d\u00e9terminants cette fois. Il nous a fait gagner le match&#8221;. Cet avis \u00e9tait partag\u00e9 par Pascal P\u00eacheur, le coach champelois: &#8220;Leur gardien a fait plusieurs arr\u00eats \u00e9poustouflants! Face \u00e0 cette baraka, nous avons fait tout ce que nous avons pu, en faisant tr\u00e8s bien circuler le ballon et cela m&#8217;apporte bien des satisfactions&#8221;. Malgr\u00e9 leurs efforts, les Champelois ne sont pas parvenus \u00e0 \u00e9galiser et c\u00e8dent donc leur fauteuil de leader aux Lanc\u00e9ens.<\/p>\n<p style=\"text-align: justify;\">Farminio Isabella \u00e9tait ainsi tr\u00e8s satisfait de ses joueurs et rendait hommage \u00e0 la formation adverse: &#8220;Je tiens \u00e0 f\u00e9liciter toute mon \u00e9quipe, ainsi que notre adversaire du jour, qui a beaucoup donn\u00e9 et qui est, malheureusement pour eux, tomb\u00e9e sur un tr\u00e8s bon gardien. Le championnat est encore tr\u00e8s long. Je pense que si Champel continue sur cette voie, ils monteront. Nous aussi, nous allons tout faire pour jouer le plus longtemps possible la mont\u00e9e&#8221;.<\/p>\n<p style=\"text-align: justify;\">Quant \u00e0 Pascal P\u00eacheur, il f\u00e9licitait ses joueurs pour leur prestation et se projetait vers l&#8217;avenir: &#8220;C&#8217;est une d\u00e9faite rageante pour nous car nous avons fait un tr\u00e8s bon match. Je f\u00e9licite mes joueurs pour leur match et leur engagement total. Ils ont port\u00e9 fi\u00e8rement les couleurs de notre club. Maintenant, ce championnat de fou n&#8217;est de loin pas termin\u00e9. En ce qui nous concerne, nous allons profiter de la pause pascale pour reprendre de la fra\u00eecheur, histoire d&#8217;arriver en\u00a0 pleine forme contre Kosova II! Si nous prenons ces trois points, nous aurons un nouveau match capital, face \u00e0 CS Italien cette fois-ci! Je pense que le suspens va durer jusqu&#8217;au bout, m\u00eame si sur le second tour, CS Italien semble \u00eatre un ton au-dessus&#8221;.<em><br style=\"text-align: justify;\" \/><\/em><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong> FC Puplinge \u00a0 &#8211; \u00a0CS Italien \u00a0 1 &#8211; 3<br \/>\nButs : <\/strong>Tartaglione 1-0 (P), Idrizi 1-1, Chaves 1-2, Yunis 1-3<\/p>\n<p style=\"text-align: justify;\">Au terme d&#8217;un match &#8220;rapide et engag\u00e9&#8221;, selon Yves Vonlanthen, CS Italien est parvenu \u00e0 prendre le dessus sur Puplinge. Cependant, tout n&#8217;a pas \u00e9t\u00e9 simple pour les visiteurs, comme nous l&#8217;explique l&#8217;entra\u00eeneur du CS Italien, Rapha\u00ebl Del Rosso: &#8220;Nous avons jou\u00e9 contre un adversaire bien organis\u00e9 et guerrier avec un potentiel offensif rapide et tranchant. C&#8217;\u00e9tait donc un match difficile pour nous&#8221;.<\/p>\n<p style=\"text-align: justify;\">Les Puplingeois ont d&#8217;abord pris l&#8217;avantage \u00e0 la demi-heure de jeu, gr\u00e2ce \u00e0 un penalty transform\u00e9 par Tartaglione. Men\u00e9 au score, CS Italien a r\u00e9agi juste avant la pause et a \u00e9galis\u00e9 par Idrizi. Les joueurs du CS Italien ont ensuite fait la diff\u00e9rence en seconde p\u00e9riode, profitant notamment des erreurs d\u00e9fensives adverses.<\/p>\n<div id=\"attachment_2877\" style=\"width: 624px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/04\/Puplinge-CS.jpg\"><img aria-describedby=\"caption-attachment-2877\" loading=\"lazy\" class=\"size-large wp-image-2877\" title=\"Puplinge-CS\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/04\/Puplinge-CS-1024x636.jpg\" alt=\"\" width=\"614\" height=\"382\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/04\/Puplinge-CS-1024x636.jpg 1024w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/04\/Puplinge-CS-300x186.jpg 300w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/04\/Puplinge-CS-660x410.jpg 660w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/04\/Puplinge-CS.jpg 1049w\" sizes=\"(max-width: 614px) 100vw, 614px\" \/><\/a><p id=\"caption-attachment-2877\" class=\"wp-caption-text\">Nouvelle victoire pour CS Italien face \u00e0 Puplinge (Photo: IV Sport)<\/p><\/div>\n<p style=\"text-align: justify;\">CS Italien continue ainsi sa belle s\u00e9rie de victoire et ne pointe plus qu&#8217;\u00e0 une unit\u00e9 de la premi\u00e8re place. A l&#8217;issue de la partie, Rapha\u00ebl Del Rosso souhaitait que son \u00e9quipe poursuive sur cette voie: &#8220;Je suis bien \u00e9videmment satisfait de la performance de mes joueurs et du r\u00e9sultat. La route est encore longue, mais nous sommes sur le bon chemin. A nous de continuer \u00e0 travailler avec disponibilit\u00e9 et humilit\u00e9, tout en gardant de l&#8217;ambition et de l&#8217;audace dans tout ce que nous faisons&#8221;.<\/p>\n<p style=\"text-align: justify;\">Du c\u00f4t\u00e9 puplingeois<strong>, <\/strong>Yves Vonlanthen estimait que ses joueurs n&#8217;avaient pas d\u00e9m\u00e9rit\u00e9: &#8220;L&#8217;\u00e9quipe a beaucoup travaill\u00e9, mais n&#8217;est pas r\u00e9compens\u00e9e pour ses efforts. Comme contre Grand-Lancy II, on paye nos erreurs d\u00e9fensives. La meilleure \u00e9quipe a gagn\u00e9, dommage que la mentalit\u00e9 ex\u00e9crable de certains joueurs ait terni cette partie&#8221;. Le coach puplingeois concluait: &#8220;Nous allons continuer \u00e0 nous battre pour sortir de la zone dangereuse&#8221;.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong> FC Rapid Jonction Bosna \u00a0 &#8211; \u00a0FC A\u00efre-le-Lignon \u00a0 1 &#8211; 1<br \/>\nButs : <\/strong>Maric 1-0, Vieira 1-1<\/p>\n<p style=\"text-align: justify;\">Rapid Jonction Bosna recevait ce dimanche A\u00efre-le-Lignon, \u00e9quipe qui, tout comme elle, n&#8217;a perdu que deux fois jusqu&#8217;ici. Malgr\u00e9 l&#8217;absence de six titulaires, les Bosniaques ont pos\u00e9 passablement de probl\u00e8mes \u00e0 leurs adversaires. Ils ont d&#8217;ailleurs ouvert la marque par Maric peu avant le quart d&#8217;heure de jeu et ont tenu ce r\u00e9sultat jusqu&#8217;\u00e0 la mi-temps.<\/p>\n<p style=\"text-align: justify;\">Les A\u00efrois ont \u00e9galis\u00e9 en seconde p\u00e9riode gr\u00e2ce \u00e0 un superbe tir des vingt m\u00e8tres de Vieira. Les visiteurs ont alors pris le dessus sur les Bosniaques, profitant du manque de fra\u00eecheur de leurs adversaires. Il est vrai que l&#8217;entra\u00eeneur bosniaque, Senad Kospo, avait d\u00fb proc\u00e9der \u00e0 trois changements en premi\u00e8re mi-temps, suite \u00e0 des blessures. Malgr\u00e9 quelques occasions a\u00efroises, les locaux ont r\u00e9sist\u00e9 jusqu&#8217;au coup de sifflet final. Les deux \u00e9quipes sont donc reparties avec un point, qui leur permet de rester dans le peloton de t\u00eate.<\/p>\n<p style=\"text-align: justify;\">A l&#8217;issue de la partie, les avis divergeaient. En effet, chaque entra\u00eeneur estimait que sa formation aurait pu l&#8217;emporter. De son c\u00f4t\u00e9, Senad Kospo nous confiait: &#8220;Nous ne sommes pas pass\u00e9s loin d&#8217;obtenir une nouvelle victoire<strong>. <\/strong>On a fait un match solide. On a r\u00e9ussi \u00e0 se procurer beaucoup plus d&#8217;occasions de but que notre adversaire du jour, qui a jou\u00e9 pendant tout le match avec des longs ballons, que nous avons su parfaitement ma\u00eetriser. Pour moi, bien s\u00fbr, c&#8217;est un bon point, mais j&#8217;ai quelques regrets, car on \u00e9tait tout pr\u00e8s des trois points. Je suis vraiment fier de mes gars pour ce qu&#8217;ils ont montr\u00e9 aujourd&#8217;hui. Ils ont fait preuve d&#8217;une volont\u00e9 exceptionnelle&#8221;.<\/p>\n<p style=\"text-align: justify;\">Pour sa part, Helder Silva estimait que son \u00e9quipe aurait m\u00e9rit\u00e9 mieux qu&#8217;un point: &#8220;Nous avons fait un match plein, car nous avons totalement domin\u00e9 notre adversaire du jour. Nous aurions d\u00fb sortir de la B\u00e2tie avec trois points de la victoire, mais il nous a manqu\u00e9 un peu de chance pour marquer le deuxi\u00e8me but, synonyme de victoire&#8221;. Le coach a\u00efrois se montrait ainsi satisfait de son \u00e9quipe: &#8220;Mes joueurs peuvent \u00eatre fiers de\u00a0 leur prestation. Ils ont \u00e9t\u00e9 presque parfaits \u00e0 tous les niveaux. Cette \u00e9quipe prouve une fois de plus qu&#8217;elle a du mental et que \u00e7a va \u00eatre tr\u00e8s difficile de nous battre dans le jeu&#8221;. Helder Silva ajoutait enfin: &#8220;Ce championnat est passionnant et la chance tourne gentiment du bon c\u00f4t\u00e9. On est encore l\u00e0 pour jouer le haut de tableau, alors comptez sur nous!&#8221;<strong><br \/>\n<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/04\/3eligue1-15.jpg\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-2560\" title=\"3eligue1-15\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/04\/3eligue1-15.jpg\" alt=\"\" width=\"500\" height=\"254\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/04\/3eligue1-15.jpg 500w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/04\/3eligue1-15-300x152.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans le choc au sommet, Grand-Lancy II a pris le dessus sur Champel et devient ainsi le nouveau leader du groupe 1. Du c\u00f4t\u00e9 de la zone de rel\u00e9gation, Gen\u00e8ve-Ville et Satigny ont obtenu des succ\u00e8s importants face \u00e0 des adversaires directs. La situation est donc plus que serr\u00e9e, tant en haut qu&#8217;en bas du<\/p>\n<div class=\"read-more\"><a href=\"https:\/\/www.proxifoot.ch\/geneve\/2012\/04\/3eme-ligue-groupe-1-15eme-journee\/\" title=\"Read More\">Read More<\/a><\/div>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[6],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.proxifoot.ch\/geneve\/2012\/04\/3eme-ligue-groupe-1-15eme-journee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3\u00e8me ligue groupe 1 : 15\u00e8me journ\u00e9e - Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"og:description\" content=\"Dans le choc au sommet, Grand-Lancy II a pris le dessus sur Champel et devient ainsi le nouveau leader du groupe 1. Du c\u00f4t\u00e9 de la zone de rel\u00e9gation, Gen\u00e8ve-Ville et Satigny ont obtenu des succ\u00e8s importants face \u00e0 des adversaires directs. La situation est donc plus que serr\u00e9e, tant en haut qu&#8217;en bas duRead More\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.proxifoot.ch\/geneve\/2012\/04\/3eme-ligue-groupe-1-15eme-journee\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2012-04-01T10:00:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-20T15:28:33+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.proxifoot.ch\/new\/wp-content\/uploads\/2012\/04\/Puplinge-CS-1024x636.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2012\/04\/3eme-ligue-groupe-1-15eme-journee\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/04\/Puplinge-CS-1024x636.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2012\/04\/3eme-ligue-groupe-1-15eme-journee\/#webpage\",\"url\":\"http:\/\/www.proxifoot.ch\/geneve\/2012\/04\/3eme-ligue-groupe-1-15eme-journee\/\",\"name\":\"3\\u00e8me ligue groupe 1 : 15\\u00e8me journ\\u00e9e - Proxifoot, le m\\u00e9dia du football genevois\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2012\/04\/3eme-ligue-groupe-1-15eme-journee\/#primaryimage\"},\"datePublished\":\"2012-04-01T10:00:53+00:00\",\"dateModified\":\"2016-07-20T15:28:33+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.proxifoot.ch\/geneve\/2012\/04\/3eme-ligue-groupe-1-15eme-journee\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\",\"name\":\"admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/2498"}],"collection":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=2498"}],"version-history":[{"count":0,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/2498\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=2498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=2498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=2498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}