﻿{"id":26039,"date":"2009-05-25T09:31:28","date_gmt":"2009-05-25T07:31:28","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=26039"},"modified":"2016-10-20T16:46:08","modified_gmt":"2016-10-20T14:46:08","slug":"donzelle-assure-le-maintien","status":"publish","type":"post","link":"https:\/\/www.proxifoot.ch\/geneve\/2009\/05\/donzelle-assure-le-maintien\/","title":{"rendered":"Donzelle assure le maintien"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Sous un soleil de plomb, la troupe de Lamers et Favre d\u00e9roule en seconde p\u00e9riode et s\u2019impose 0-4 au Bout-du-Monde. Avec le maintien assur\u00e9, Donzelle peut d\u00e9sormais se concentrer sur la coupe. Les Portugais de Sporting sont, \u00e0 moins d\u2019un miracle, rel\u00e9gu\u00e9s en 4\u00e8me ligue.<\/strong><!--more--><\/p>\n<p style=\"text-align: justify;\" align=\"justify\">C\u2019est un duel de bas de classement auquel nous assistons ce dimanche matin. Au Stade du Bout-du-Monde s\u2019opposent la lanterne rouge Sporting Futebol Clube,\u00a0et l\u2019\u00e9quipe de Donzelle. Le Sporting, que l\u2019ont croyait condamn\u00e9, est \u00e0 nouveau dans la course au maintien. Les Portugais n\u2019ont perdu qu\u2019un match sur les cinq derniers et sont d\u00e9sormais \u00e0 un petit point de la barre, gr\u00e2ce notamment \u00e0 la victoire acquise la semaine derni\u00e8re sur le terrain de Saint-Jean. Du c\u00f4t\u00e9 de Donzelle, qui peut compter sur son duo d\u2019entra\u00eeneurs sur le terrain, l\u2019euphorie de la finale de coupe qui arrive \u00e0 grands pas doit \u00eatre canalis\u00e9e dans un match important comme celui-ci. Une victoire les \u00e9carterait d\u00e9finitivement de la lutte contre la rel\u00e9gation.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\"><strong>Les gardiens protagonistes en d\u00e9but de match<\/strong><\/p>\n<p style=\"text-align: justify;\" align=\"justify\">Les visiteurs se procurent les premi\u00e8res occasions en d\u00e9but de rencontre sur des tentatives non cadr\u00e9es d\u2019Omeragic et Darqu\u00e9 suite \u00e0 des corners dangereux. Donzelle est install\u00e9 dans le camp lusitanien et domine ce d\u00e9but de partie.<\/p>\n<div style=\"width: 564px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" src=\"http:\/\/www.proxifoot.ch\/home\/images\/Photos\/spo-don_01.jpg\" alt=\" \" width=\"554\" height=\"426\" \/><p class=\"wp-caption-text\">Le v\u00e9t\u00e9ran Omeragic (35 ans) face \u00e0 Dias (Sporting)<\/p><\/div>\n<p style=\"text-align: justify;\" align=\"center\">Mais c\u2019est le Sporting qui va se procurer la premi\u00e8re occasion nette par l\u2019interm\u00e9diaire de Salgado, qui profite d\u2019une mauvaise relance de Darqu\u00e9 pour se trouver en position favorable et armer un tir. Malheureusement pour lui, le jeune gardien Stierlin repousse sa tentative d\u2019un bel arr\u00eat.<\/p>\n<p style=\"text-align: justify;\" align=\"center\">Les hommes de Martins gagnent des m\u00e8tres sur le terrain et obtiennent un coup franc dangereux. Le tir de Salgado est une nouvelle fois \u00e9cart\u00e9 par Stierlin, bien d\u00e9cid\u00e9 \u00e0 sauver les siens en cette matin\u00e9e ensoleill\u00e9e.<\/p>\n<p style=\"text-align: justify;\" align=\"center\">Puis, ce sont les \u00ab jaunes \u00bb qui r\u00e9agissent \u00e0 leur tour en se procurant deux possibilit\u00e9s de but suppl\u00e9mentaires. D\u2019abord un tir de De Pedro est repouss\u00e9 par le gardien Santos, et ensuite, apr\u00e8s une belle combinaison entre Magalhaes, Omeragic et Landrecy, ce dernier est stopp\u00e9 \u00e0 la derni\u00e8re seconde par un d\u00e9fenseur portugais alors que tout le monde croyait d\u00e9j\u00e0 \u00e0 l\u2019ouverture du score.<\/p>\n<p style=\"text-align: justify;\" align=\"center\"><strong>Baisse d\u2019intensit\u00e9<\/strong><\/p>\n<p style=\"text-align: justify;\" align=\"center\">Dans ce match \u00e0 enjeu, personne ne veut perdre. Les occasions en seconde partie de mi-temps se font rares mais les visiteurs peuvent \u00eatre dangereux \u00e0 tout moment sur le c\u00f4t\u00e9 gauche du talentueux Magalhaes.<\/p>\n<div>\n<div style=\"width: 521px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" src=\"http:\/\/www.proxifoot.ch\/home\/images\/Photos\/spo-don_02.jpg\" alt=\" \" width=\"511\" height=\"453\" \/><p class=\"wp-caption-text\">Le jeune Magalhaes (Donzelle) prend le dessus sur Bicho (Sporting)<\/p><\/div>\n<\/div>\n<p style=\"text-align: justify;\" align=\"center\">En cette fin de mi-temps, l\u2019intensit\u00e9 a un peu baiss\u00e9 des deux c\u00f4t\u00e9s. Les d\u00e9fenses prennent peu de risques et n\u2019h\u00e9sitent pas \u00e0 abuser des longs ballons. Dans les arr\u00eats de jeu, c\u2019est encore une fois le portier Stierlin qui va sauver les siens, suite \u00e0 une t\u00eate d\u2019Almeida.<\/p>\n<p style=\"text-align: justify;\" align=\"center\">Nous arrivons \u00e0 la mi-temps sur un score nul et vierge, dans laquelle les protagonistes ont \u00e9t\u00e9 les gardiens, auteurs de plusieurs arr\u00eats salvateurs. Ce score n\u2019arrange pas les affaires des Portugais qui doivent s\u2019imposer \u00e0 tout prix.<\/p>\n<div style=\"width: 510px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" src=\"http:\/\/www.proxifoot.ch\/home\/images\/Photos\/spo-don_03.jpg\" alt=\" \" width=\"500\" height=\"270\" \/><p class=\"wp-caption-text\">Juste avant la pause, Almeida (Sporting) passe pr\u00e8s de l&#8217;ouverture du score<\/p><\/div>\n<p style=\"text-align: justify;\" align=\"center\"><strong>Donzelle profite des espaces<\/strong><\/p>\n<p style=\"text-align: justify;\" align=\"center\">Apr\u00e8s le th\u00e9, les deux \u00e9quipes peinent \u00e0 imposer leur rythme. Les \u00ab verts \u00bb sont oblig\u00e9s de prendre des risques car le match nul ne leur suffit pas pour sortir des places de rel\u00e9gation. Ce qui laisse bien entendu des espaces aux joueurs de Lamers et Favre (dit \u00ab Boulon \u00bb) pour partir en contre-attaque.<\/p>\n<p style=\"text-align: justify;\" align=\"center\">C\u2019est justement sur une contre-attaque \u00e0 l\u2019heure de jeu que les visiteurs vont ouvrir le score : Stefani, parti en vitesse sur le c\u00f4t\u00e9 gauche, change le jeu pour De Pedro qui a le temps de contr\u00f4ler et tirer. Sa frappe molle, a priori sans danger, passe sous le bras du portier Santos et rentre, mourante, non sans avoir touch\u00e9 le poteau !<\/p>\n<div style=\"width: 548px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" src=\"http:\/\/www.proxifoot.ch\/home\/images\/Photos\/spo-don_04.jpg\" alt=\" \" width=\"538\" height=\"409\" \/><p class=\"wp-caption-text\">Le capitaine De Pedro (Donzelle), auteur de l&#8217;ouverture du score pour les siens<\/p><\/div>\n<p style=\"text-align: justify;\" align=\"center\"><strong>Les visiteurs d\u00e9roulent en fin de match<\/strong><\/p>\n<p style=\"text-align: justify;\" align=\"center\">Sporting doit prendre des risques car la d\u00e9faite est interdite. C\u2019est Donzelle qui profite des espaces \u00e0 disposition pour aggraver le score. Sur une touche de Hagmann, Jimmy \u00ab Floyd \u00bb Landrecy, le buteur maison, peut contr\u00f4ler et armer un tir qui finit dans le petit filet : 0-2 pour les \u00ab jaunes \u00bb !<\/p>\n<div>\n<div style=\"width: 510px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" src=\"http:\/\/www.proxifoot.ch\/home\/images\/Photos\/spo-don_05.jpg\" alt=\" \" width=\"500\" height=\"385\" \/><p class=\"wp-caption-text\">Landrecy, auteur du 2-0, est malheureusement suspendu pour la finale de coupe<\/p><\/div>\n<\/div>\n<p style=\"text-align: justify;\" align=\"center\">A 2-0, le match est quasiment boucl\u00e9 et le maintien quasiment assur\u00e9 pour la troupe de La Plaine. Cela leur permet de jouer sans pression et de se faire plaisir sur ce terrain du Bout-du-Monde. Les occasions pleuvent pour les visiteurs, les locaux \u00e9tant d\u00e9sormais moralement abattus et d\u00e9cid\u00e9s \u00e0 s\u2019en prendre \u00e0 l\u2019arbitre M. De Dominicis.<\/p>\n<p style=\"text-align: justify;\" align=\"center\">Les visiteurs inscrivent un troisi\u00e8me but apr\u00e8s un tir de De Pedro qui est doublement d\u00e9vi\u00e9 par la d\u00e9fense lusitanienne. Le malheureux Louren\u00e7o aura \u00e9t\u00e9 le dernier \u00e0 toucher le ballon avant qu\u2019il ne se faufile au fond de ses propres cages. En toute fin de match, Magalhaes, le meilleur homme sur le terrain, sera r\u00e9compens\u00e9 de son tr\u00e8s bon match en inscrivant le 0-4 d\u2019un puissant tir lointain.<\/p>\n<p style=\"text-align: justify;\" align=\"center\">L\u2019arbitre siffle la fin de la rencontre sur un score sans appel : 0-4 pour Donzelle et maintien math\u00e9matiquement assur\u00e9 ! Les prot\u00e9g\u00e9s de Favre et Lamers peuvent d\u00e9sormais se concentrer sur la tant attendue finale de coupe genevoise qui les opposera \u00e0 Vernier le 10 juin prochain. Malgr\u00e9 les six absences de poids pour la finale, il est malgr\u00e9 tout permis de r\u00eaver\u2026<\/p>\n<p style=\"text-align: justify;\" align=\"center\">Quant aux joueurs de Fernando Martins, c\u2019est quasiment la 4\u00e8me ligue assur\u00e9e\u2026 Avec 3 points de retard sur leurs compatriotes de Benfica et une diff\u00e9rence de buts n\u00e9gative de -10, il faudrait un v\u00e9ritable miracle pour que les hommes du Bout-du-Monde sauvent leur place dans la cat\u00e9gorie\u2026<\/p>\n<p>&nbsp;<\/p>\n<blockquote>\n<p align=\"justify\"><strong>SPORTING FUTEBOL CLUBE \u2013 FC DONZELLE \u00a00-4 (0-0)<br \/>\n<\/strong>Stade du Bout-du-Monde, environ 50 spectateurs.<\/p>\n<p align=\"justify\"><strong>Arbitre <\/strong>: Amico de Dominicis<\/p>\n<p style=\"text-align: justify;\" align=\"justify\"><strong>Buts<\/strong>: 60\u2019 De Pedro 0-1, 69\u2019 Landrecy 0-2, 83\u2019 Louren\u00e7o B. (CSC) 0-3, 88\u2019 Magalhaes 0-4<\/p>\n<p style=\"text-align: justify;\" align=\"justify\"><strong>Sporting <\/strong>(4-4-2) : Santos ; Bicho, Caseiro, Dias (76\u2019 Louren\u00e7o B.), De Almeida ; Aleixo, Almeida, Sim\u00f5es (61\u2019 Louren\u00e7o J.), Correia F. (61\u2019 Correia D.) ; Salgado, Neves \u00a9.<br \/>\nEntra\u00eeneur : Fernando Martins<\/p>\n<p style=\"text-align: justify;\" align=\"justify\"><strong>Donzelle\u00a0 <\/strong>(4-4-2) : Stierlin ; Hagmann, Duding, Darqu\u00e9, Stefani ; De Pedro \u00a9, Omeragic (68\u2019 W\u00fctrich), Lamers (75\u2019 Marques), Magalhaes ; Favre ; Landrecy (75\u2019 Pellaux).<br \/>\nEntra\u00eeneurs : Vincent Favre et Christian Lamers.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\"><strong>Avertissement <\/strong>: Neves (Sporting).<\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><script src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\" async=\"\"><\/script><!-- superieur --> <ins class=\"adsbygoogle\" style=\"display: inline-block; width: 728px; height: 90px;\" data-ad-slot=\"1875735477\" data-ad-client=\"ca-pub-1317159203547503\"><\/ins><script>\/\/ <![CDATA[ (adsbygoogle = window.adsbygoogle || []).push({}); \/\/ ]]><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sous un soleil de plomb, la troupe de Lamers et Favre d\u00e9roule en seconde p\u00e9riode et s\u2019impose 0-4 au Bout-du-Monde. Avec le maintien assur\u00e9, Donzelle peut d\u00e9sormais se concentrer sur la coupe. Les Portugais de Sporting sont, \u00e0 moins d\u2019un miracle, rel\u00e9gu\u00e9s en 4\u00e8me ligue.<\/p>\n","protected":false},"author":30,"featured_media":26040,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[6],"tags":[92,315],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.proxifoot.ch\/geneve\/2009\/05\/donzelle-assure-le-maintien\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Donzelle assure le maintien - Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"og:description\" content=\"Sous un soleil de plomb, la troupe de Lamers et Favre d\u00e9roule en seconde p\u00e9riode et s\u2019impose 0-4 au Bout-du-Monde. Avec le maintien assur\u00e9, Donzelle peut d\u00e9sormais se concentrer sur la coupe. Les Portugais de Sporting sont, \u00e0 moins d\u2019un miracle, rel\u00e9gu\u00e9s en 4\u00e8me ligue.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.proxifoot.ch\/geneve\/2009\/05\/donzelle-assure-le-maintien\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2009-05-25T07:31:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-10-20T14:46:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/07\/Sporting-Donzelle-0809.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"576\" \/>\n\t<meta property=\"og:image:height\" content=\"380\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@www.twitter.com\/maikel_f\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2009\/05\/donzelle-assure-le-maintien\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/07\/Sporting-Donzelle-0809.jpg\",\"width\":576,\"height\":380},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2009\/05\/donzelle-assure-le-maintien\/#webpage\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/2009\/05\/donzelle-assure-le-maintien\/\",\"name\":\"Donzelle assure le maintien - Proxifoot, le m\\u00e9dia du football genevois\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2009\/05\/donzelle-assure-le-maintien\/#primaryimage\"},\"datePublished\":\"2009-05-25T07:31:28+00:00\",\"dateModified\":\"2016-10-20T14:46:08+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/f8763ae73551193f68b47b57e2bdfb15\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.proxifoot.ch\/geneve\/2009\/05\/donzelle-assure-le-maintien\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/f8763ae73551193f68b47b57e2bdfb15\",\"name\":\"Maikel\",\"sameAs\":[\"https:\/\/twitter.com\/www.twitter.com\/maikel_f\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/26039"}],"collection":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=26039"}],"version-history":[{"count":0,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/26039\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/26040"}],"wp:attachment":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=26039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=26039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=26039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}