﻿{"id":26417,"date":"2010-05-18T16:54:23","date_gmt":"2010-05-18T14:54:23","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=26417"},"modified":"2016-07-18T17:11:49","modified_gmt":"2016-07-18T15:11:49","slug":"2eme-ligue-les-enjeux-de-ce-soir","status":"publish","type":"post","link":"https:\/\/www.proxifoot.ch\/geneve\/2010\/05\/2eme-ligue-les-enjeux-de-ce-soir\/","title":{"rendered":"2\u00e8me ligue : les enjeux de ce soir"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Team Gen\u00e8ve peut assurer sa promotion en cas de victoire. Dans le bas de classement Kosova et Plan-les-Ouates n&#8217;ont\u00a0pas le\u00a0droit \u00e0 l&#8217;erreur pour esp\u00e9rer s&#8217;en sortir.<\/strong><!--more--><\/p>\n<p align=\"justify\"><strong>FC Collex-Bossy \u2013 FC Kosova : Encore un espoir ?<\/strong><\/p>\n<p align=\"justify\">Confrontation entre deux \u00e9quipes qui ont un mince espoir de r\u00e9ussir leur objectif. D&#8217;un c\u00f4t\u00e9, Collex qui a perdu \u00e0 Onex la plus grande partie de ses chances d&#8217;obtenir la deuxi\u00e8me place synonyme de promotion et de l&#8217;autre Kosova qui voit le maintien s&#8217;\u00e9loigner au fur et \u00e0 mesure des week-ends. Si les deux \u00e9quipes veulent encore avoir le droit de r\u00eaver, il faut faire un sans-faute, et donc gagner mercredi soir.<\/p>\n<p align=\"justify\">Au niveau des stats : Collex-Bossy est 2\u00e8me du classement \u00e0 domicile (22 pts\/11 matches) alors que Kosova est avant-dernier de celui \u00e0 l&#8217;ext\u00e9rieur (9pts \/ 11 matches). Kosova qui n&#8217;a inscrit que six points en 2010 en comparaison aux 15 de leur adversaire du soir\u2026<\/p>\n<p align=\"justify\"><strong>CS Italien GE \u2013 Team Gen\u00e8ve : Attention danger<\/strong><\/p>\n<p align=\"justify\">Ce match pourrait s&#8217;av\u00e9rer dangereux pour le vaincu. En effet, CS Italien n&#8217;est toujours pas \u00e0 l&#8217;abri d&#8217;un retour d&#8217;une des \u00e9quipes en dessous de la barre (situ\u00e9e \u00e0 5 unit\u00e9s des &#8220;bleu&#8221;) alors que Team Gen\u00e8ve pourrait voir Versoix lui passer devant en cas de d\u00e9faite.<\/p>\n<p align=\"justify\">\u00a0<img loading=\"lazy\" src=\"http:\/\/www.proxifoot.ch\/home\/images\/Lancy_TeamGE\/img_4532.jpg\" alt=\" \" width=\"291\" height=\"366\" \/><\/p>\n<p align=\"justify\">Au niveau des stats : CS Italien s&#8217;est repris depuis deux matches, accumulant quatre unit\u00e9s sur les six glan\u00e9es depuis le d\u00e9but de l&#8217;ann\u00e9e. Il a surtout r\u00e9ussi \u00e0 inscrire en deux parties deux fois plus de buts que lors de ses sept premi\u00e8res sorties du deuxi\u00e8me tour ! Team GE, quant \u00e0 elle, a perdu la t\u00eate du second tour au profit d&#8217;Onex. Les jeunes espoirs qui sont \u00e9galement deuxi\u00e8me du classement &#8220;ext\u00e9rieur&#8221; derri\u00e8re Versoix, alors que CS Italien, et ses 14 unit\u00e9s en 10 rencontres &#8220;at home&#8221; figurent dans le milieu de ce classement particulier.<\/p>\n<p align=\"justify\"><strong>FC Plan-les-Ouates \u2013 FC Choulex : Match des extr\u00eames<\/strong><\/p>\n<p align=\"justify\">D&#8217;un c\u00f4t\u00e9, Plan-les-Ouates, dont le nouvel entra\u00eeneur et les nouveaux joueurs peinent \u00e0 trouver une bonne carburation et de la constance entre de bons r\u00e9sultats (nuls contre Onex et Team Gen\u00e8ve) et d&#8217;autres plus dommageables (d\u00e9faite contre Kosova). De l&#8217;autre, Choulex, qui n&#8217;a tout simplement pas perdu de l&#8217;ann\u00e9e ! Les hommes de Jos\u00e9 Brea peuvent par ailleurs mettre une pression certaine sur Versoix et une deuxi\u00e8me place inattendue au d\u00e9but de l&#8217;ann\u00e9e.<\/p>\n<p align=\"justify\">Au niveau des stats : Choulex est donc la seule \u00e9quipe invaincue du second tour, quant \u00e0 Plan-les-Ouates, ses 8 unit\u00e9s font d&#8217;elle une des cancres de ce classement particulier. Les pensionnaires des Cherpines sont aussi la plus mauvaise \u00e9quipe \u00e0 domicile avec deux petites victoires pour huit d\u00e9faites alors que Choulex en est \u00e0 17 pts en 11 matches hors de ses terres.<\/p>\n<p align=\"justify\"><strong>FC Meyrin II \u2013 FC Versoix : Duel au sommet ?<\/strong><\/p>\n<p align=\"justify\">C&#8217;est une affiche int\u00e9ressante qui se d\u00e9roulera \u00e0 Meyrin. Si les hommes d&#8217;Henrique Freitas ont quelques peu d\u00e9croch\u00e9 au classement, on s&#8217;aper\u00e7oit \u00e0 la lecture du tableau qu&#8217;ils peuvent se retrouver en position d&#8217;aff\u00fbt s\u2019ils gagnent ce match contre Versoix. Mais la question est la suivante : qualifi\u00e9 pour la finale de la coupe genevoise et ne pouvant monter \u00e0 cause de la r\u00e9glementation les r\u00e9gissant, les Meyrinois vont-ils jouer la fin de championnat \u00e0 fond ? Une chose est s\u00fbre, Versoix, lui, sera sur-motiv\u00e9 ! A deux petits points d&#8217;un Team Gen\u00e8ve jouant au Bois de la B\u00e2tie et qui termine le championnat contre Collex et Onex, les joueurs de Sergio Carmo sentent le titre \u00e0 leur port\u00e9e. Il faut pour cela gagner les matches qu&#8217;il leur reste (Meyrin, Plan-les-Ouates, CS Italien).<\/p>\n<p align=\"justify\"><img loading=\"lazy\" src=\"http:\/\/www.proxifoot.ch\/home\/images\/TeamGE_Versoix\/0-1.jpg\" alt=\" \" width=\"566\" height=\"354\" \/><\/p>\n<p align=\"justify\">Au niveau des stats : Pour l&#8217;ann\u00e9e 2010, Versoix est troisi\u00e8me alors que Meyrin est\u2026 dernier avec cinq petites unit\u00e9s inscrites. Versoix est aussi la meilleure \u00e9quipe en d\u00e9placement alors que Meyrin figure en milieu de tableau \u00e0 domicile.<\/p>\n<p align=\"justify\"><strong>FC Lancy-Sports \u2013 FC Veyrier Sports : Veyrier dos au mur<\/strong><\/p>\n<p align=\"justify\">Lancy ne joue plus rien dans ce championnat, alors que leur d\u00e9but de deuxi\u00e8me tour pouvait leur faire r\u00eaver \u00e0 un podium, objectif initial de Dominique Coehlo, les deux d\u00e9faites cons\u00e9cutives contre Choulex et Versoix y ont mis un terme abrupt et math\u00e9matiquement, Lancy ne peut plus viser une des deux premi\u00e8res places\u2026<\/p>\n<p align=\"justify\">Pour Veyrier par contre, ce match rev\u00eat une importance capitale, avec la confrontation directe entre Ch\u00eanois et Grand-Lancy et la r\u00e9ception de Team GE par CS Italien peut donner un aspect de tr\u00e8s bonne affaire \u00e0 une victoire de Veyrier.<\/p>\n<p align=\"justify\">\u00a0<img loading=\"lazy\" src=\"http:\/\/www.proxifoot.ch\/home\/images\/Veyrier_Chenois_2009_2010\/les%20deux%20buteurs%20de%20veyrier%20l%E0%20manu%20apr%E8s%20son%20but%20%281%29.jpg\" alt=\" \" width=\"273\" height=\"437\" \/><\/p>\n<p align=\"justify\">Au niveau des stats : Pour l&#8217;ann\u00e9e 2010, les deux \u00e9quipes se tiennent (respectivement 14 et 11 pts). Pour le classement &#8220;domicile-ext\u00e9rieur&#8221;, Lancy est \u00e0 l&#8217;aise chez lui (18pts, 4\u00e8me du classement) alors que Veyrier est la moins bonne \u00e9quipe \u00e0 l&#8217;ext\u00e9rieur (8 pts en 10 matches).<\/p>\n<p align=\"justify\"><strong>CS Ch\u00eanois \u2013 FC Grand-Lancy II : &#8220;Match \u00e0 six points&#8221;<\/strong><\/p>\n<p align=\"justify\">Un match capital pour ses deux formations. Pour Ch\u00eanois d&#8217;abord, \u00e0 qui il ne reste que deux matches de ce championnat pour se sauver, pour Grand-Lancy II ensuite qui doit inscrire des points pour tenter de se sortir de ces quatre derni\u00e8res places dangereuses, surtout que les deux derni\u00e8res rencontres des joueurs de Marignac se feront contre Lancy et Meyrin, deux \u00e9quipes qui ne jouent plus rien dans ce championnat.<\/p>\n<p align=\"justify\">Au niveau des stats : Ch\u00eanois fait une meilleure seconde partie de saison, avec 16 pts inscrits en 10 sorties alors que Grand-Lancy en a inscrit 11 en 9 matches. Il est \u00e9galement \u00e0 noter que les deux \u00e9quipes sont 11\u00e8me de leur classement &#8220;domicile-ext\u00e9rieur&#8221; respectif. Ch\u00eanois a inscrit 11 pts sur ses terres alors que Gd-Lancy en a inscrit 9 sur terrain adverse.<\/p>\n<p><script src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\" async=\"\"><\/script><!-- superieur --> <ins class=\"adsbygoogle\" style=\"display: inline-block; width: 728px; height: 90px;\" data-ad-client=\"ca-pub-1317159203547503\" data-ad-slot=\"1875735477\"><\/ins><script>\/\/ <![CDATA[\n(adsbygoogle = window.adsbygoogle || []).push({});\n\/\/ ]]><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Team Gen\u00e8ve peut assurer sa promotion en cas de victoire. Dans le bas de classement Kosova et Plan-les-Ouates n&#8217;ont\u00a0pas le\u00a0droit \u00e0 l&#8217;erreur pour esp\u00e9rer s&#8217;en sortir.<\/p>\n","protected":false},"author":34,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[5],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.proxifoot.ch\/geneve\/2010\/05\/2eme-ligue-les-enjeux-de-ce-soir\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2\u00e8me ligue : les enjeux de ce soir - Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"og:description\" content=\"Team Gen\u00e8ve peut assurer sa promotion en cas de victoire. Dans le bas de classement Kosova et Plan-les-Ouates n&#8217;ont\u00a0pas le\u00a0droit \u00e0 l&#8217;erreur pour esp\u00e9rer s&#8217;en sortir.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.proxifoot.ch\/geneve\/2010\/05\/2eme-ligue-les-enjeux-de-ce-soir\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2010-05-18T14:54:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-18T15:11:49+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.proxifoot.ch\/home\/images\/Lancy_TeamGE\/img_4532.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2010\/05\/2eme-ligue-les-enjeux-de-ce-soir\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"http:\/\/www.proxifoot.ch\/home\/images\/Lancy_TeamGE\/img_4532.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2010\/05\/2eme-ligue-les-enjeux-de-ce-soir\/#webpage\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/2010\/05\/2eme-ligue-les-enjeux-de-ce-soir\/\",\"name\":\"2\\u00e8me ligue : les enjeux de ce soir - Proxifoot, le m\\u00e9dia du football genevois\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2010\/05\/2eme-ligue-les-enjeux-de-ce-soir\/#primaryimage\"},\"datePublished\":\"2010-05-18T14:54:23+00:00\",\"dateModified\":\"2016-07-18T15:11:49+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/85c9e873354a0bdc93a855141f775b3d\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.proxifoot.ch\/geneve\/2010\/05\/2eme-ligue-les-enjeux-de-ce-soir\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/85c9e873354a0bdc93a855141f775b3d\",\"name\":\"Greg\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/26417"}],"collection":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=26417"}],"version-history":[{"count":0,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/26417\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=26417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=26417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=26417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}