﻿{"id":27911,"date":"2010-10-03T09:51:50","date_gmt":"2010-10-03T07:51:50","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=27911"},"modified":"2016-10-25T10:48:21","modified_gmt":"2016-10-25T08:48:21","slug":"grand-saconnex-dompte-champel","status":"publish","type":"post","link":"https:\/\/www.proxifoot.ch\/geneve\/2010\/10\/grand-saconnex-dompte-champel\/","title":{"rendered":"Grand-Saconnex dompte Champel"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Les locaux profitent des largesses d&#8217;un Champel peu inspir\u00e9 ce dimanche pour s&#8217;imposer\u00a0et encha\u00eener un troisi\u00e8me succ\u00e8s consecutive.<\/strong><!--more--><\/p>\n<p style=\"text-align: justify;\" align=\"center\">&#8220;Nous n&#8217;avons pas produit de jeu et on a fait preuve de trop d&#8217;approximations d\u00e9fensives pour esp\u00e9rer prendre des points. La d\u00e9faite est donc logique&#8221;. Par ces mots, l&#8217;entra\u00eeneur champelois Pascal P\u00eacheur r\u00e9sume parfaitement la rencontre disput\u00e9e au Stade du Blanch\u00e9.<\/p>\n<p align=\"justify\"><strong>Grand-Saconnex r\u00e9aliste<\/strong><\/p>\n<p align=\"justify\">La partie a d\u00e9marr\u00e9 depuis 120 secondes lorsque Zeneli trouve Ayete dans le dos de la d\u00e9fense. Le jeune attaquant profite de la sortie du portier Da Costa pour le tromper d&#8217;un joli lob et ouvrir la marque pour son \u00e9quipe.<\/p>\n<p align=\"justify\">Champel, sous l&#8217;impulsion de son capitaine Golay, ne s&#8217;\u00e9nerve pas et cherche avant tout \u00e0 produire du jeu sans se pr\u00e9cipiter vers l&#8217;avant. Malheureusement, d\u00fb \u00e0 certaines impr\u00e9cisions techniques et \u00e0 une \u00e9quipe du Grand-Saconnex tr\u00e8s dense \u00e0 mi-terrain, les visiteurs ne parviennent pas \u00e0 approcher des buts de Azevedo.<\/p>\n<div>\n<div style=\"width: 571px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" src=\"http:\/\/www.proxifoot.ch\/home\/images\/Champelgdac\/champ.jpg\" alt=\" \" width=\"561\" height=\"351\" \/><p class=\"wp-caption-text\">Un match \u00e0 oublier pour le capitaine Golay et ses co\u00e9quipiers<\/p><\/div>\n<\/div>\n<p style=\"text-align: justify;\">Toutefois, au quart d&#8217;heure, le pr\u00e9cieux Manso re\u00e7oit le ballon, le conserve bien puis encha\u00eene d&#8217;une superbe frappe qui vient se loger sous la latte du portier Azevedo qui n&#8217;y peut strictement rien.<\/p>\n<p align=\"justify\">Cette \u00e9galisation ayant remis les champelois dans le match, le jeu va \u00eatre consid\u00e9rablement neutralis\u00e9 au milieu de terrain. Les occasions se font tr\u00e8s rares, hormis une nouvelle tentative de Manso qui devance la sortie du portier et une frappe lointaine de Zeneli non cadr\u00e9e.<\/p>\n<p align=\"justify\">Alors qu&#8217;on croit se diriger vers un score de parit\u00e9 \u00e0 l&#8217;heure du th\u00e9, Grand-Saconnex va doubler la mise sur une action similaire \u00e0 l&#8217;ouverture du score. Ayete, lanc\u00e9 une nouvelle fois sur le c\u00f4t\u00e9 droit, bat Da Costa en deux temps.<\/p>\n<p align=\"justify\"><strong>Champel n&#8217;y arrive pas<\/strong><\/p>\n<p style=\"text-align: justify;\" align=\"justify\">Pour la seconde p\u00e9riode, le d\u00e9cor ne change pas, idem pour la physionomie de la rencontre. Champel tente de poser le jeu mais le trio Jodar-Rodrigues-Caamano ne se trouve pas et le club cher au pr\u00e9sident Mifano peine \u00e0 se montrer dangereux. Du c\u00f4t\u00e9 des prot\u00e9g\u00e9s d&#8217;Olivier Marrone, on continue \u00e0 bloquer le jeu et gagner des duels \u00e0 l&#8217;image du jeune Alonso et des exp\u00e9riment\u00e9s Lavanchy et Bader impeccables ce dimanche.<\/p>\n<div>\n<div style=\"width: 616px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" src=\"http:\/\/www.proxifoot.ch\/home\/images\/Champelgdac\/champ3.jpg\" alt=\" \" width=\"606\" height=\"347\" \/><p class=\"wp-caption-text\">Zeneli prend le dessus sur Jodar<\/p><\/div>\n<\/div>\n<p style=\"text-align: justify;\" align=\"center\">Les chances de but ne sont toujours pas l\u00e9gion. Comte tente alors une frappe puissante que le portier local capte en deux temps. Grand-Saconnex r\u00e9plique en cherchant le remuant Afran, entr\u00e9 \u00e0 la mi-temps. Ce dernier va alors mettre d\u00e9finitivement son \u00e9quipe \u00e0 l&#8217;abri \u00e0 quinze minutes du terme. Sur un ballon qui semblait pourtant anodin, Golay se fait surprendre et laisse passer Afran qui trompe Da Costa.<\/p>\n<p align=\"justify\">Les visiteurs, abattus par cette troisi\u00e8me r\u00e9ussite, n&#8217;y croient plus vraiment. Zeneli n&#8217;en demandait pas tant et profite d&#8217;une b\u00e9vue de Deguise pour inscrire un quatri\u00e8me but pour son \u00e9quipe.<\/p>\n<p align=\"justify\">L&#8217;opposition de style entre ces deux formations aura tourn\u00e9 \u00e0 l&#8217;avantage de Grand-Saconnex, gr\u00e2ce \u00e0 une plus grande d\u00e9termination et une plus grande concentration dans les moments-cl\u00e9s de la rencontre. Champel, quant \u00e0 lui, aura peut-\u00eatre trop cherch\u00e9 \u00e0 produire du jeu, payant cash une qualit\u00e9 technique d\u00e9faillante ce dimanche.<\/p>\n<div>\n<div style=\"width: 550px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" src=\"http:\/\/www.proxifoot.ch\/home\/images\/Champelgdac\/champ4.jpg\" alt=\" \" width=\"540\" height=\"338\" \/><p class=\"wp-caption-text\">Arnal au duel avec Shabani<\/p><\/div>\n<\/div>\n<p style=\"text-align: justify;\" align=\"center\"><strong>R\u00e9actions\u00a0<\/strong><\/p>\n<p align=\"justify\">Olivier Marrone: &#8220;Je tiens \u00e0 f\u00e9liciter tous les joueurs aujourd&#8217;hui. On avait envie de gagner pour rester au contact du peloton de t\u00eate. On a su marquer au bon moment. En deuxi\u00e8me p\u00e9riode, il fallait contenir cette forte \u00e9quipe de Champel et nous avons su le faire. Enfin, offensivement, la r\u00e9ussite \u00e9tait avec nous, c&#8217;est une belle victoire.&#8221;<\/p>\n<p align=\"justify\">Pascal P\u00eacheur: &#8220;L&#8217;\u00e9quipe est passablement remani\u00e9e ces derni\u00e8res semaines et certains joueurs manquent de rythme, cela peut donc expliquer que notre jeu se met moins bien en place, mais quand en plus on fait des cadeaux en d\u00e9fense, on ne peut tout simplement pas esp\u00e9rer mieux&#8221;<\/p>\n<p>&nbsp;<\/p>\n<blockquote>\n<p style=\"text-align: justify;\" align=\"justify\"><strong>FC GRAND-SACONNEX &#8211; FC CHAMPEL \u00a04-1 (2-1)<br \/>\n<\/strong>Stade du Blanch\u00e9. 80 spectateurs<\/p>\n<p style=\"text-align: justify;\"><strong>Arbitre:<\/strong> M. Donadeo<\/p>\n<p style=\"text-align: justify;\"><strong>Buts:<\/strong> 2&#8242; Ayete 1-0, 14&#8242; Manso 1-1, 45&#8242; Ayete 2-1, 76&#8242; Afran 3-1, 87&#8242; Zeneli 4-1<\/p>\n<p style=\"text-align: justify;\"><strong>Grand-Saconnex:<\/strong> Azevedo; Lavanchy, Roussot, Alonso, Milici; Valerio, Bader, Benmilloud (70&#8242; Shabani); Ayete (85&#8242; S. Rodrigues), Zeneli, Uzeda (46&#8242; Afran).<br \/>\nEntra\u00eeneur: Marrone Olivier<\/p>\n<p style=\"text-align: justify;\"><strong>Champel:<\/strong> Da Costa; Arnal, Deguise, Golay, Comte; Jodar, I. Rodrigues; Roche (80&#8242; Bicaco), Caamano, Possamai (58&#8242; Jeronimo); Manso.<br \/>\nEntra\u00eeneur: Pascal P\u00eacheur<\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<p><em>Photos: Despondos Sporting Shoots<\/em><br \/>\n<script src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\" async=\"\"><\/script><!-- superieur --> <ins class=\"adsbygoogle\" style=\"display: inline-block; width: 728px; height: 90px;\" data-ad-slot=\"1875735477\" data-ad-client=\"ca-pub-1317159203547503\"><\/ins><script>\/\/ <![CDATA[ (adsbygoogle = window.adsbygoogle || []).push({}); \/\/ ]]><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les locaux profitent des largesses d&#8217;un Champel peu inspir\u00e9 ce dimanche pour s&#8217;imposer\u00a0et encha\u00eener un troisi\u00e8me succ\u00e8s consecutive.<\/p>\n","protected":false},"author":33,"featured_media":27912,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[6],"tags":[36,99],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.proxifoot.ch\/geneve\/2010\/10\/grand-saconnex-dompte-champel\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grand-Saconnex dompte Champel - Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"og:description\" content=\"Les locaux profitent des largesses d&#8217;un Champel peu inspir\u00e9 ce dimanche pour s&#8217;imposer\u00a0et encha\u00eener un troisi\u00e8me succ\u00e8s consecutive.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.proxifoot.ch\/geneve\/2010\/10\/grand-saconnex-dompte-champel\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2010-10-03T07:51:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-10-25T08:48:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/07\/Grand-Saconnex-Champel-1011.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2010\/10\/grand-saconnex-dompte-champel\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/07\/Grand-Saconnex-Champel-1011.jpg\",\"width\":720,\"height\":450},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2010\/10\/grand-saconnex-dompte-champel\/#webpage\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/2010\/10\/grand-saconnex-dompte-champel\/\",\"name\":\"Grand-Saconnex dompte Champel - Proxifoot, le m\\u00e9dia du football genevois\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2010\/10\/grand-saconnex-dompte-champel\/#primaryimage\"},\"datePublished\":\"2010-10-03T07:51:50+00:00\",\"dateModified\":\"2016-10-25T08:48:21+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/4ba4dbf1475db283a54e214afa9706bf\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.proxifoot.ch\/geneve\/2010\/10\/grand-saconnex-dompte-champel\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/4ba4dbf1475db283a54e214afa9706bf\",\"name\":\"Julien\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/27911"}],"collection":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=27911"}],"version-history":[{"count":0,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/27911\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/27912"}],"wp:attachment":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=27911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=27911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=27911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}