﻿{"id":30051,"date":"2011-08-15T11:54:16","date_gmt":"2011-08-15T09:54:16","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=30051"},"modified":"2016-09-29T11:56:58","modified_gmt":"2016-09-29T09:56:58","slug":"luefa-futsal-cup-a-geneve","status":"publish","type":"post","link":"https:\/\/www.proxifoot.ch\/geneve\/2011\/08\/luefa-futsal-cup-a-geneve\/","title":{"rendered":"L&#8217;UEFA Futsal Cup \u00e0 Gen\u00e8ve"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Futsal \/ Le Geneva Futsal accueille d\u00e8s mardi le tour pr\u00e9liminaire de l&#8217;UEFA Futsal Cup. La poule, qui comporte 4 \u00e9quipes, se d\u00e9roule \u00e0 Gen\u00e8ve, \u00e0 la Salle Henry Dunant.<\/strong><!--more--><\/p>\n<p style=\"text-align: justify;\" align=\"justify\">Apr\u00e8s avoir \u00e9t\u00e9 sacr\u00e9 <a href=\"http:\/\/www.proxifoot.ch\/home\/index.php?option=com_content&amp;task=view&amp;id=1106&amp;Itemid=74\" target=\"_blank\"><u><span style=\"color: #0066cc;\">champion suisse de futsal<\/span><\/u><\/a> l&#8217;hiver dernier, le Geneva Futsal entame l&#8217;aventure europ\u00e9enne d\u00e8s mardi \u00e0 la salle Henry Dunant pour le compte du tour pr\u00e9liminaire de la Coupe UEFA.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\">Au programme, un poule de 4 \u00e9quipes qui tenteront sur 3 jours (les 16, 17 et 19 ao\u00fbt) de d\u00e9crocher un ticket (seul le premier passe) pour le tour principal.<\/p>\n<p align=\"justify\">Nous ne connaissons pas grand chose des adversaires des Genevois, si ce n&#8217;est le pays de provenance: il s&#8217;agit du <strong>FK Nautara Kaunas<\/strong> (Lituanie), <strong>The New Saints FC<\/strong> (Pays de Galles) et <strong>EID Futsal<\/strong> (Irlande).<\/p>\n<p align=\"justify\">Une qualification des Genevois leur permettrait ensuite de d\u00e9fier les grosses cylindr\u00e9es du football en salle europ\u00e9en, dont le FC Barcelone.<\/p>\n<p align=\"justify\">Allez-y nombreux pour encourager les Genevois et accessoirement appr\u00e9cier (ou d\u00e9couvrir) un sport spectaculaire !<\/p>\n<p align=\"justify\"><a href=\"http:\/\/www.genevafutsal.ch\/\" target=\"_blank\"><img loading=\"lazy\" src=\"http:\/\/www.proxifoot.ch\/home\/images\/2011_2012\/UEFA_Futsal\/uefa_futsal2.jpg\" alt=\" \" width=\"318\" height=\"450\" \/><\/a><\/p>\n<p>&nbsp;<br \/>\n<script src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\" async=\"\"><\/script><!-- superieur --> <ins class=\"adsbygoogle\" style=\"display: inline-block; width: 728px; height: 90px;\" data-ad-client=\"ca-pub-1317159203547503\" data-ad-slot=\"1875735477\"><\/ins><script>\/\/ <![CDATA[ (adsbygoogle = window.adsbygoogle || []).push({}); \/\/ ]]><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Futsal \/ Le Geneva Futsal accueille d\u00e8s mardi le tour pr\u00e9liminaire de l&#8217;UEFA Futsal Cup. La poule, qui comporte 4 \u00e9quipes, se d\u00e9roule \u00e0 Gen\u00e8ve, \u00e0 la Salle Henry Dunant.<\/p>\n","protected":false},"author":1,"featured_media":30050,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[1],"tags":[112,369],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.proxifoot.ch\/geneve\/2011\/08\/luefa-futsal-cup-a-geneve\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;UEFA Futsal Cup \u00e0 Gen\u00e8ve - Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"og:description\" content=\"Futsal \/ Le Geneva Futsal accueille d\u00e8s mardi le tour pr\u00e9liminaire de l&#8217;UEFA Futsal Cup. La poule, qui comporte 4 \u00e9quipes, se d\u00e9roule \u00e0 Gen\u00e8ve, \u00e0 la Salle Henry Dunant.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.proxifoot.ch\/geneve\/2011\/08\/luefa-futsal-cup-a-geneve\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2011-08-15T09:54:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-09-29T09:56:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/09\/uefa-futsal-cup-2011.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"709\" \/>\n\t<meta property=\"og:image:height\" content=\"399\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2011\/08\/luefa-futsal-cup-a-geneve\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/09\/uefa-futsal-cup-2011.jpg\",\"width\":709,\"height\":399},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2011\/08\/luefa-futsal-cup-a-geneve\/#webpage\",\"url\":\"http:\/\/www.proxifoot.ch\/geneve\/2011\/08\/luefa-futsal-cup-a-geneve\/\",\"name\":\"L'UEFA Futsal Cup \\u00e0 Gen\\u00e8ve - Proxifoot, le m\\u00e9dia du football genevois\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2011\/08\/luefa-futsal-cup-a-geneve\/#primaryimage\"},\"datePublished\":\"2011-08-15T09:54:16+00:00\",\"dateModified\":\"2016-09-29T09:56:58+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.proxifoot.ch\/geneve\/2011\/08\/luefa-futsal-cup-a-geneve\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\",\"name\":\"admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/30051"}],"collection":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=30051"}],"version-history":[{"count":0,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/30051\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/30050"}],"wp:attachment":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=30051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=30051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=30051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}