﻿{"id":30111,"date":"2016-10-03T23:51:33","date_gmt":"2016-10-03T21:51:33","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=30111"},"modified":"2016-10-07T11:32:25","modified_gmt":"2016-10-07T09:32:25","slug":"lolympique-de-geneve-senvole-en-tete","status":"publish","type":"post","link":"https:\/\/www.proxifoot.ch\/geneve\/2016\/10\/lolympique-de-geneve-senvole-en-tete\/","title":{"rendered":"L&#8217;Olympique de Gen\u00e8ve s&#8217;envole en t\u00eate"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Lors du match au sommet de 2\u00e8me ligue, les\u00a0Olympiens s\u2019imposent\u00a0sur leur pelouse face \u00e0 Plan-les-Ouates au terme d\u2019une seconde mi-temps compl\u00e8tement folle (3-2).<\/strong><span id=\"more-29358\"><\/span><!--more--><\/p>\n<p style=\"text-align: justify;\">Alors que le match semblait pli\u00e9 apr\u00e8s les 45 premi\u00e8res minutes de jeu pour l\u2019Olympique de Gen\u00e8ve, Plan-les-Ouates a su trouver les ressources n\u00e9cessaires pour \u00e9galiser la partie et mettre sous pression le leader du championnat de 2\u00e8me ligue qui s\u2019impose 3-2 au final. L\u2019\u00e9quipe de Patrick Stifani\u00a0empoche ainsi trois pr\u00e9cieux points qui lui permettent de creuser l\u2019\u00e9cart face \u00e0 ses poursuivants.<\/p>\n<p style=\"text-align: justify;\"><strong>Une premi\u00e8re mi-temps contr\u00f4l\u00e9e<\/strong><\/p>\n<p style=\"text-align: justify;\">Les locaux\u00a0d\u00e9marrent tr\u00e8s bien la rencontre en se montrant tr\u00e8s solides d\u2019entr\u00e9e et n\u2019offrant pratiquement aucun espace \u00e0 leurs\u00a0adversaires. Bien que Plan-les-Ouates se montre le premier dangereux suite \u00e0 une belle incursion depuis la gauche de Rebelo qui voit sa frappe repouss\u00e9e par le portier local,\u00a0l\u2019OG\u00a0va tr\u00e8s rapidement mettre le pied sur le ballon et prendre le jeu \u00e0 son compte. Bien en place sur le terrain, ce sont eux qui s\u2019offrent les meilleures occasions, faisant la diff\u00e9rence \u00e0 plusieurs reprises par les c\u00f4t\u00e9s. Une domination qui ne va pas tarder \u00e0 se concr\u00e9tiser puisque l\u2019ouverture du score survient\u00a0au quart d\u2019heure de jeu\u00a0des pieds de Bilal Benguetib qui culmine une contre-attaque parfaitement men\u00e9e \u00e0 la suite d\u2019un corner mal n\u00e9goci\u00e9 par les visiteurs (1-0).<\/p>\n<p style=\"text-align: justify;\">On attend alors la r\u00e9action de Plan-les-Ouates mais la formation de Jose Brea a du mal \u00e0 trouver ses joueurs d\u2019attaque et ne parvient pas \u00e0 inqui\u00e9ter le dernier rempart de la formation bleu c\u00e9leste, Monteiro, si ce n\u2019est par l\u2019interm\u00e9diaire de quelques coups de pied arr\u00eat\u00e9s. Au contraire, ce sont les joueurs locaux qui doublent la mise \u00e0 la 38\u00e8me\u00a0minute par Dany Barbosa bien d\u00e9cal\u00e9 sur la droite par Maxime Sanou avant de propulser le cuire dans le petit filet oppos\u00e9 d\u2019une frappe \u00e0 ras-terre sublime (2-0).<\/p>\n<p style=\"text-align: justify;\">L\u2019addition aurait pu \u00eatre encore plus sal\u00e9e \u00e0 la pause si la frappe de Maxime Sanou, encore lui, ne terminait pas sa course sur le poteau gauche de Giorgi juste avant la mi-temps. Plan-les-Ouates s\u2019en tire bien apr\u00e8s une premi\u00e8re p\u00e9riode tout en ma\u00eetrise de la part du leader du championnat qui semble avoir la main sur le match.<\/p>\n<div id=\"attachment_29354\" class=\"wp-caption alignnone\">\n<div id=\"attachment_30119\" style=\"width: 610px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-30119\" loading=\"lazy\" class=\"wp-image-30119\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/10\/OG-PLO-1617-3-1.png\" alt=\"og-plo-1617-3\" width=\"600\" height=\"455\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/10\/OG-PLO-1617-3-1.png 950w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/10\/OG-PLO-1617-3-1-300x227.png 300w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/10\/OG-PLO-1617-3-1-768x582.png 768w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><p id=\"caption-attachment-30119\" class=\"wp-caption-text\">Barbosa, le second buteur olympien<\/p><\/div>\n<\/div>\n<p style=\"text-align: justify;\"><strong>Deuxi\u00e8me p\u00e9riode totalement folle<\/strong><\/p>\n<p style=\"text-align: justify;\">u retour des vestiaires, les Jaunes, plus d\u00e9termin\u00e9s, montrent de bonnes intentions en essayant d\u2019aller davantage vers l\u2019avant et de jouer plus rapidement avec les attaquants, trop esseul\u00e9s jusque-l\u00e0, \u00e0 l\u2019image de Matias qui tente sa chance de loin mais soul\u00e8ve trop sa frappe (47\u2032). Bien en place, l\u2019arri\u00e8re garde locale ne laisse rien filtrer et se contente de repousser les tentatives adverses.<\/p>\n<p style=\"text-align: justify;\">Et pourtant, alors que l\u2019on atteint l\u2019heure de jeu, Mbacke, \u00e9trangement seul, re\u00e7oit le ballon en position favorable dans la zone de v\u00e9rit\u00e9 avant d\u2019\u00eatre d\u00e9riv\u00e9 par le gardien Monteiro. L\u2019arbitre signale la peine maximale et le capitaine\u00a0Cabale ne manque pas la cible (60\u2032, 2-1). Les hommes de Jose Brea commencent \u00e0 y croire et redoublent d\u2019intensit\u00e9 pour aller chercher l\u2019\u00e9galisation en multipliant les actions offensives. En face, l\u2019\u00e9quipe de Patrick Stifani\u00a0tente de r\u00e9agir rapidement mais n\u2019y parvient pas gr\u00e2ce notamment au bon pressing adverse au milieu de terrain. Un pressing qui aura finalement raison de la d\u00e9fense des Bleus qui craque une nouvelle fois \u00e0 la 64\u00e8me minute sur un bel exploit de Bruno\u00a0Rebelo\u00a0bien servi par Mbacke. En \u00e0 peine cinq minutes, le match chavire totalement (2-2).<\/p>\n<p style=\"text-align: justify;\">Malheureusement pour Plan-les-Ouates, l\u2019euphorie ne dure pas longtemps puisque qu\u2019\u00e0 peine six minutes plus tard, les Olympiens reprennent leur\u00a0avance suite \u00e0 une magnifique perc\u00e9e du tr\u00e8s remuant Jocelyn Mboso qui se pr\u00e9sente seul face au gardien vis-\u00e0-vis avant de conclure d\u2019un plat du pied pour remettre son \u00e9quipe dans les bons rails (70\u2032, 3-2). Pourtant, \u00e0 peine replac\u00e9s que\u00a0Matias d\u00e9croche une frappe magistrale des 25 m\u00e8tres qui finit sa course sur le poteau gauche de Monteiro, battu, avant de rebondir sur le dos de celui-ci et sortir en corner.<\/p>\n<div id=\"attachment_29353\" class=\"wp-caption alignnone\">\n<div id=\"attachment_30115\" style=\"width: 610px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-30115\" loading=\"lazy\" class=\"wp-image-30115\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/10\/OG-PLO-1617-2-1.png\" alt=\"og-plo-1617-2\" width=\"600\" height=\"430\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/10\/OG-PLO-1617-2-1.png 941w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/10\/OG-PLO-1617-2-1-300x215.png 300w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/10\/OG-PLO-1617-2-1-768x551.png 768w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><p id=\"caption-attachment-30115\" class=\"wp-caption-text\">Le suspense a regn\u00e9 jusqu&#8217;au bout<\/p><\/div>\n<p><strong>Une fin de match sous tension<\/strong><\/p>\n<\/div>\n<p style=\"text-align: justify;\">Le match est d\u00e9chain\u00e9 et la tension monte d\u2019un cran avec la multiplication de duels des deux c\u00f4t\u00e9s obligeant l\u2019arbitre \u00e0 interrompre le jeu \u00e0 multiples reprises et \u00e0 sortir les cartons. L\u2019\u00e9quipe locale va d\u2019ailleurs terminer le match \u00e0 dix apr\u00e8s l\u2019expulsion de\u00a0Barbosa suite \u00e0\u00a0une faute rigoureuse sur son adversaire.<\/p>\n<p style=\"text-align: justify;\">Avec un joueur de plus, Plan-les-Ouates met tous ses efforts sur l\u2019attaque pour tenter d\u2019arracher le point, mais n\u2019y parviendra plus. Une semaine apr\u00e8s\u00a0avoir inflig\u00e9 un sec 5-1 \u00e0 Veyrier, l\u2019Olympique de Gen\u00e8ve savoure ainsi une excellente victoire face \u00e0 un concurrent direct qui lui permet de caracoler seul en t\u00eate avec quatre points d\u2019avance. Et si on tenait l\u00e0 un nouveau favori pour le titre ?<\/p>\n<p>&nbsp;<\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><strong>OLYMPIQUE DE GEN\u00c8VE FC \u2013 FC PLAN-LES-OUATES \u00a03-2 (2-0)<\/strong><br \/>\nStade de Varemb\u00e9<\/p>\n<p style=\"text-align: justify;\"><strong>Buts<\/strong>\u00a0: 15\u2032 Benguetib 1-0, 38\u2032 Barbosa 2-0, 60\u2032 Cabale (P) 2-1, 64\u2032 Rebelo 2-2, 70\u2032 Mboso 3-2<\/p>\n<p style=\"text-align: justify;\"><strong>Olympique Gen\u00e8ve<\/strong>\u00a0: Monteiro \u2013 Barona, Guachino, Ntsoli \u00a9, Pereira \u2013 Mboso, Arifi, Sanou, Barbosa \u2013 Rittiner (63\u2032 El Assouli), Benguetib (55\u2032 Marques).<br \/>\nEntra\u00eeneur : Patrick Stifani<\/p>\n<p style=\"text-align: justify;\"><strong>Plan-les-Ouates<\/strong>\u00a0: Giorgi \u2013 Gomes, Matias, Sakho, Leal \u2013 Rossier, Dupraz (58\u2032 Sylejmani), Mbacke (80\u2032 G\u00fcnl\u00fc), Rebelo (76\u2032 Vallejo) \u2013 Cabale \u00a9, Rodrigues Merlo.<br \/>\nEntra\u00eeneur : Jos\u00e9 Brea<\/p>\n<p style=\"text-align: justify;\"><strong>Avertissements<\/strong>\u00a0: Marques (OG) ; Matias, Dupraz et Vallejo (PLO)<br \/>\n<strong>Expulsion<\/strong> : 88\u2032 Barbosa (OG)<\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-30111 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/10\/OG-PLO-1617-3-1.png'><img width=\"150\" height=\"150\" src=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/10\/OG-PLO-1617-3-1-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/10\/OG-PLO-1617-5-1.png'><img width=\"150\" height=\"150\" src=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/10\/OG-PLO-1617-5-1-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/10\/OG-PLO-1617-7.png'><img width=\"150\" height=\"150\" src=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/10\/OG-PLO-1617-7-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/10\/OG-PLO-1617-4-1.png'><img width=\"150\" height=\"150\" src=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/10\/OG-PLO-1617-4-1-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/10\/OG-PLO-1617-2-1.png'><img width=\"150\" height=\"150\" src=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/10\/OG-PLO-1617-2-1-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/10\/OG-PLO-1617-1-1.png'><img width=\"150\" height=\"150\" src=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/10\/OG-PLO-1617-1-1-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/10\/OG-PLO-1617-6-1.png'><img width=\"150\" height=\"150\" src=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/10\/OG-PLO-1617-6-1-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n<script src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\" async=\"\"><\/script><!-- superieur --> <ins class=\"adsbygoogle\" style=\"display: inline-block; width: 728px; height: 90px;\" data-ad-slot=\"1875735477\" data-ad-client=\"ca-pub-1317159203547503\"><\/ins><script>\/\/ <![CDATA[ (adsbygoogle = window.adsbygoogle || []).push({}); \/\/ ]]><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lors du match au sommet de 2\u00e8me ligue, les\u00a0Olympiens s\u2019imposent\u00a0sur leur pelouse face \u00e0 Plan-les-Ouates au terme d\u2019une seconde mi-temps compl\u00e8tement folle (3-2).<\/p>\n","protected":false},"author":31,"featured_media":30114,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[5],"tags":[163,80],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.proxifoot.ch\/geneve\/2016\/10\/lolympique-de-geneve-senvole-en-tete\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;Olympique de Gen\u00e8ve s&#039;envole en t\u00eate - Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"og:description\" content=\"Lors du match au sommet de 2\u00e8me ligue, les\u00a0Olympiens s\u2019imposent\u00a0sur leur pelouse face \u00e0 Plan-les-Ouates au terme d\u2019une seconde mi-temps compl\u00e8tement folle (3-2).\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.proxifoot.ch\/geneve\/2016\/10\/lolympique-de-geneve-senvole-en-tete\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-03T21:51:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-10-07T09:32:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/10\/OG-PLO-1617-1-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1079\" \/>\n\t<meta property=\"og:image:height\" content=\"541\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2016\/10\/lolympique-de-geneve-senvole-en-tete\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/10\/OG-PLO-1617-1-1.png\",\"width\":1079,\"height\":541},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2016\/10\/lolympique-de-geneve-senvole-en-tete\/#webpage\",\"url\":\"http:\/\/www.proxifoot.ch\/geneve\/2016\/10\/lolympique-de-geneve-senvole-en-tete\/\",\"name\":\"L'Olympique de Gen\\u00e8ve s'envole en t\\u00eate - Proxifoot, le m\\u00e9dia du football genevois\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2016\/10\/lolympique-de-geneve-senvole-en-tete\/#primaryimage\"},\"datePublished\":\"2016-10-03T21:51:33+00:00\",\"dateModified\":\"2016-10-07T09:32:25+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/b8492933a08023023e25a975cba9dd70\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.proxifoot.ch\/geneve\/2016\/10\/lolympique-de-geneve-senvole-en-tete\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/b8492933a08023023e25a975cba9dd70\",\"name\":\"Damian Fernandez\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/30111"}],"collection":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=30111"}],"version-history":[{"count":0,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/30111\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/30114"}],"wp:attachment":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=30111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=30111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=30111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}