﻿{"id":30199,"date":"2016-10-10T21:30:44","date_gmt":"2016-10-10T19:30:44","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=30199"},"modified":"2016-10-12T15:07:43","modified_gmt":"2016-10-12T13:07:43","slug":"servette-m21-manque-le-coche","status":"publish","type":"post","link":"https:\/\/www.proxifoot.ch\/geneve\/2016\/10\/servette-m21-manque-le-coche\/","title":{"rendered":"Servette M21 manque le coche !"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Dans un duel tr\u00e8s serr\u00e9, Servette M21 et Perly se sont neutralis\u00e9s sur un score nul et vierge samedi soir sur la pelouse de Balexert. Les joueurs de Niederhauser manquent ainsi l\u2019opportunit\u00e9 de se hisser en t\u00eate du championnat suite \u00e0 la d\u00e9faite d\u2019UGS face \u00e0 Interstar la veille.<\/strong><!--more--><\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s la surprenante d\u00e9faite d&#8217;UGS, alors leader du championnat, \u00e0 domicile face au CS Interstar (1-2), la r\u00e9serve de Servette\u00a0tenait l\u00e0 une excellente opportunit\u00e9 de chiper la premi\u00e8re place du classement en cas de victoire face \u00e0 Perly. Une opportunit\u00e9 qu\u2019ils n\u2019auront malheureusement pas su saisir face une coriace \u00e9quipe perlysienne qui n\u2019aura rien l\u00e2ch\u00e9 jusqu\u2019\u00e0 la fin. C\u2019est finalement le FC Aigle qui en profite pour prendre la\u00a0t\u00eate du groupe 1 de 2\u00e8me ligue inter.<\/p>\n<p><strong>Premi\u00e8re p\u00e9riode tr\u00e8s intense<\/strong><\/p>\n<p style=\"text-align: justify;\">Victorieux lors des trois derniers matchs de championnat, les hommes de William Niederhauser partaient avec l\u2019\u00e9toffe de favori face \u00e0 une \u00e9quipe de Perly qui occupe la dixi\u00e8me place au classement. C\u2019est donc logiquement que la formation grenat tente de prendre l\u2019initiative d\u2019entr\u00e9e de jeu et montre une forte volont\u00e9 d\u2019aller rapidement vers l\u2019avant en cherchant la profondeur. Malheureusement, en face, la formation dirig\u00e9e par Michel Poinsignon, arriv\u00e9 cet \u00e9t\u00e9\u00a0sur le banc perlysien pour remplacer Mario Chedly, bien repli\u00e9e et parfaitement organis\u00e9e d\u00e9fensivement, ne laisse aucun espace aux jeunes joueurs servettiens qui ont du mal \u00e0 trouver la faille dans l\u2019arri\u00e8re garde adverse.<\/p>\n<p style=\"text-align: justify;\">Le match est tr\u00e8s ferm\u00e9 et les occasions, en majorit\u00e9 locales, se font rares. Ce sont d\u2019ailleurs les Servettiens qui sont tout proches\u00a0d\u2019ouvrir la marque d\u00e8s la 13\u00e8m<sup>e<\/sup> minute de jeu lorsque le portier visiteur, Kevin Volpilhac, d\u00e9vie de justesse le ballon sur la latte suite \u00e0 une belle reprise de la t\u00eate du d\u00e9fenseur central, Mvodo, sur corner. Il faudra attendre la demi-heure\u00a0minute pour revoir Volpilhac mis \u00e0 contribution sur une tr\u00e8s belle frappe lointaine d\u2019Adler Da Silva qui passe tout pr\u00e8s du cadre. Le score restera nul et vierge jusqu\u2019\u00e0 la pause malgr\u00e9 une derni\u00e8re opportunit\u00e9 franche pour Bell (42&#8242;) qui culmine de la t\u00eate une tr\u00e8s belle action collective mais sa frappe, trop centr\u00e9e, manque de puissance pour tromper le dernier rempart perlysien, tr\u00e8s s\u00fbr dans sa cage.<\/p>\n<div id=\"attachment_28403\" style=\"width: 610px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-28403\" loading=\"lazy\" class=\"wp-image-28403\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/07\/Niederhauser-Servette-2015-1024x673.png\" alt=\"Niederhauser-Servette-2015\" width=\"600\" height=\"395\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/07\/Niederhauser-Servette-2015-1024x673.png 1024w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/07\/Niederhauser-Servette-2015-300x197.png 300w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/07\/Niederhauser-Servette-2015-768x505.png 768w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/07\/Niederhauser-Servette-2015-214x140.png 214w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/07\/Niederhauser-Servette-2015.png 1241w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><p id=\"caption-attachment-28403\" class=\"wp-caption-text\">L&#8217;entra\u00eeneur grenat William Niederhauser (Photo : OneClick)<\/p><\/div>\n<p><strong>\u00ab\u00a0On aurait d\u00fb faire la diff\u00e9rence en premi\u00e8re mi-temps\u00a0\u00bb<\/strong><\/p>\n<p style=\"text-align: justify;\">Au retour des vestiaires, les quelque 150 valeureux spectateurs pr\u00e9sents au Stade de Balexert malgr\u00e9 le froid assistent au m\u00eame sc\u00e9nario offert lors des 45 premi\u00e8res minutes. D\u00e9termin\u00e9, Servette repart avec les m\u00eames intentions affich\u00e9es en premi\u00e8re p\u00e9riode, mais se heurte constamment au tr\u00e8s bon repli d\u00e9fensif effectu\u00e9 par Perly qui ne laisse rien filtrer. L\u00e0 encore, les occasions se font rares des deux c\u00f4t\u00e9s et se r\u00e9sument principalement \u00e0 quelques tentatives sur coup de pied arr\u00eat\u00e9 tant les blocs d\u00e9fensifs sont bien en place. Pourtant, Perly est tout pr\u00e8s du KO suite \u00e0 un bel encha\u00eenement de Primiceri\u00a0qui d\u00e9clenche une lourde frappe qui passe tout pr\u00eat du montant droit du portier Dumont (78&#8242;). Le score en restera l\u00e0 jusqu\u2019au coup de sifflet final.<\/p>\n<p style=\"text-align: justify;\">Malgr\u00e9 le nul, William Niederhauser s\u2019est montr\u00e9 satisfait de l\u2019ensemble de la prestation de ses joueurs dans un match difficile o\u00f9 ils auraient d\u00fb, selon lui, passer l\u2019\u00e9paule dans le premier acte : \u00ab\u00a0<em>Nous aurions d\u00fb ouvrir le score en premi\u00e8re mi-temps. Nous nous sommes cr\u00e9\u00e9s plusieurs situations dangereuses que nous aurions d\u00fb concr\u00e9tiser. Cela nous aurait permis de changer la dynamique du match et de peut-\u00eatre prendre une option sur la victoire. En deuxi\u00e8me mi-temps, notre adversaire a tr\u00e8s bien d\u00e9fendu ne nous laissant pratiquement aucun espace pour concr\u00e9tiser nos actions <\/em>\u00bb.<\/p>\n<p style=\"text-align: justify;\">Un manque regrettable d\u2019efficacit\u00e9 dans les moments importants compte tenu du fait que la r\u00e9compense n\u2019\u00e9tait ni plus ni moins que la t\u00eate du classement : \u00ab\u00a0 <em>C\u2019est dommage car en cas de victoire nous aurions pu prendre la premi\u00e8re place du championnat, mais nous allons continuer de travailler pour tenter d\u2019\u00eatre plus efficace lors des prochaines matchs<\/em>\u00a0\u00bb. Enfin questionn\u00e9 sur les objectifs pour la saison, le coach servettien reste pr\u00e9venant et ne souhaite pas br\u00fbler les \u00e9tapes\u00a0: \u00ab\u00a0<em>Nous sommes avant tout un club formateur avec de jeunes joueurs. Actuellement, l\u2019\u00e9quipe fonctionne bien et les performances suivent selon notre objectif qui est de nous maintenir dans le haut du classement \u00e0 No\u00ebl. Nous ne voulons pas nous projeter plus loin pour l\u2019instant\u00a0\u00bb. <\/em><\/p>\n<p style=\"text-align: justify;\">Avec la meilleure d\u00e9fense du championnat (6 buts re\u00e7us en 9 matchs) la r\u00e9serve grenat\u00a0est plut\u00f4t bien partie pour r\u00e9pondre aux objectifs de son entra\u00eeneur. De son c\u00f4t\u00e9, apr\u00e8s deux matchs difficiles contre UGS et Servette, Perly devra redoubler de vigilance et r\u00e9agir rapidement pour \u00e9viter d&#8217;\u00eatre pris au pi\u00e8ge lors de la tr\u00eave hivernale.<\/p>\n<p>&nbsp;<\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><strong>SERVETTE FC M-21 &#8211; FC PERLY-CERTOUX\u00a0 0-0<\/strong><br \/>\nStade de Balexert<\/p>\n<p style=\"text-align: justify;\"><strong>Servette<\/strong>\u00a0(4-4-2) : Dumont\u00a0\u2013 Gazzetta, Mvodo, Ackun, D. Tavares\u00a0\u2013 Ndongo, Tsimba \u00a9, Cespedes, Da Silva (60&#8242; Boteli)\u00a0\u2013 Machado, Bell.<br \/>\nEntra\u00eeneur : William Niederhauser<\/p>\n<p style=\"text-align: justify;\"><strong>Perly<\/strong> (4-3-3) : Volpilhac \u2013 Cimelli, Christmant, Soumahin, Nsiakanda \u2013 Olivera \u00a9,\u00a0Wafir, Casorella\u00a0\u2013 Primiceri (60&#8242; Pr\u00e9bandier), Jung (67&#8242; Mboli), Canton.<br \/>\nEntra\u00eeneur : Michel Poinsignon<\/p>\n<p style=\"text-align: justify;\"><strong>Avertissements<\/strong> : Machado (Servette) ; Wafir (Perly)<\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><script src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\" async=\"\"><\/script><!-- superieur --> <ins class=\"adsbygoogle\" style=\"display: inline-block; width: 728px; height: 90px;\" data-ad-slot=\"1875735477\" data-ad-client=\"ca-pub-1317159203547503\"><\/ins><script>\/\/ <![CDATA[ (adsbygoogle = window.adsbygoogle || []).push({}); \/\/ ]]><\/script><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans un duel tr\u00e8s serr\u00e9, Servette M21 et Perly se sont neutralis\u00e9s sur un score nul et vierge samedi soir sur la pelouse de Balexert. Les joueurs de Niederhauser manquent ainsi l\u2019opportunit\u00e9 de se hisser en t\u00eate du championnat suite \u00e0 la d\u00e9faite d\u2019UGS face \u00e0 Interstar la veille.<\/p>\n","protected":false},"author":31,"featured_media":30189,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[26],"tags":[48,146],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.proxifoot.ch\/geneve\/2016\/10\/servette-m21-manque-le-coche\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Servette M21 manque le coche ! - Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"og:description\" content=\"Dans un duel tr\u00e8s serr\u00e9, Servette M21 et Perly se sont neutralis\u00e9s sur un score nul et vierge samedi soir sur la pelouse de Balexert. Les joueurs de Niederhauser manquent ainsi l\u2019opportunit\u00e9 de se hisser en t\u00eate du championnat suite \u00e0 la d\u00e9faite d\u2019UGS face \u00e0 Interstar la veille.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.proxifoot.ch\/geneve\/2016\/10\/servette-m21-manque-le-coche\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-10T19:30:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-10-12T13:07:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/10\/SFC-M21-Perly-1617.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1152\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2016\/10\/servette-m21-manque-le-coche\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/10\/SFC-M21-Perly-1617.jpg\",\"width\":2048,\"height\":1152},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2016\/10\/servette-m21-manque-le-coche\/#webpage\",\"url\":\"http:\/\/www.proxifoot.ch\/geneve\/2016\/10\/servette-m21-manque-le-coche\/\",\"name\":\"Servette M21 manque le coche ! - Proxifoot, le m\\u00e9dia du football genevois\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2016\/10\/servette-m21-manque-le-coche\/#primaryimage\"},\"datePublished\":\"2016-10-10T19:30:44+00:00\",\"dateModified\":\"2016-10-12T13:07:43+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/b8492933a08023023e25a975cba9dd70\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.proxifoot.ch\/geneve\/2016\/10\/servette-m21-manque-le-coche\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/b8492933a08023023e25a975cba9dd70\",\"name\":\"Damian Fernandez\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/30199"}],"collection":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=30199"}],"version-history":[{"count":0,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/30199\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/30189"}],"wp:attachment":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=30199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=30199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=30199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}