﻿{"id":30422,"date":"2016-10-21T22:47:55","date_gmt":"2016-10-21T20:47:55","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=30422"},"modified":"2016-10-21T23:34:00","modified_gmt":"2016-10-21T21:34:00","slug":"nicolas-vitkieviez-sest-bien-inspire-de-leo-messi","status":"publish","type":"post","link":"https:\/\/www.proxifoot.ch\/geneve\/2016\/10\/nicolas-vitkieviez-sest-bien-inspire-de-leo-messi\/","title":{"rendered":"Nicolas Vitkieviez s&#8217;est bien inspir\u00e9 de Leo Messi"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Avec trois buts en dix minutes, l\u2019attaquant uruguayen a offert la victoire \u00e0 l\u2019US Carouge sur le terrain de Meyrin II (1-3).<\/strong><!--more--><\/p>\n<p style=\"text-align: justify;\">Mercredi soir, Nicolas Vitkieviez \u00e9tait au Nou Camp pour voir son Bar\u00e7a \u00e9craser Manchester City en Ligue des Champions (4-0). Pendant que Pep Guardiola subissait la loi du monstre qu\u2019il a cr\u00e9\u00e9 \u2013Leo Messi, triple buteur\u2013, l\u2019attaquant de l\u2019US Carouge en prenait de la graine. Le fr\u00e8re du Servettien Matias a d\u00e9cid\u00e9 d\u2019imiter le petit argentin le lendemain au Stade des Arb\u00e8res. Il a d\u2019abord patiemment attendu sur le banc pendant que ses co\u00e9quipiers r\u00e9sistaient aux assauts de la r\u00e9serve meyrinoise, avant de rentrer en jeu en seconde p\u00e9riode&nbsp;et de s\u2019offrir un tripl\u00e9.<\/p>\n<p style=\"text-align: justify;\"><strong>Un buteur retrouv\u00e9<\/strong><\/p>\n<p style=\"text-align: justify;\">10 minutes ont suffi \u00e0 l\u2019Uruguayen pour faire pencher le match du c\u00f4t\u00e9 de l\u2019US Carouge. Entre la 72\u00e8me et la 82\u00e8me, l\u2019attaquant s&#8217;est d\u00e9barrass\u00e9 de son vis-\u00e0-vis avant de croiser sa frappe dans le petit filet (0-1), a profit\u00e9 d\u2019un ballon sauv\u00e9 sur la ligne&nbsp;suite \u00e0 un travail de Gressent (0-2), puis s\u2019est fait justice lui-m\u00eame apr\u00e8s avoir \u00e9t\u00e9 victime d\u2019un penalty (0-3). Trois buts en 10 minutes, huit au total cette saison pour lui, et le match \u00e9tait r\u00e9gl\u00e9 aux Arb\u00e8res. La r\u00e9duction du score meyrinoise par Thalmas a \u00e9t\u00e9 trop tardive.&nbsp;<em>&#8220;C&#8217;\u00e9tait un match serr\u00e9,<\/em> nous confie le triple buteur. <em>Meyrin est une belle \u00e9quipe, c&#8217;est des jeunes, \u00e7a va dans tous les sens. On a \u00e9t\u00e9 solides derri\u00e8re et on a bien g\u00e9r\u00e9 le match. Apr\u00e8s, j&#8217;ai pu rentrer et j&#8217;ai eu de la r\u00e9ussite&#8221;.&nbsp;<\/em><\/p>\n<p style=\"text-align: justify;\">De la r\u00e9ussite, certes, mais marquer des buts n&#8217;est pas quelque chose de nouveau pour l&#8217;attaquant <em>charr\u00faa<\/em>, lui qui a d\u00e9j\u00e0 \u00e9t\u00e9 meilleur buteur de 2\u00e8me ligue lors de la <a href=\"http:\/\/www.proxifoot.ch\/geneve\/2012\/06\/2eme-ligue-classement-des-buteurs-2\/\">saison 2011-2012<\/a>, devan\u00e7ant un certain Kevin Bua.<em> &#8220;\u00c7a fait plaisir de marquer des buts \u00e0 nouveau, \u00e7a me manquait ! J&#8217;avais arr\u00eat\u00e9 \u00e0 cause de la naissance de mon fils, mais le foot me manquait trop. L&#8217;ann\u00e9e derni\u00e8re, je me suis bless\u00e9 \u00e0 l&#8217;adducteur et j&#8217;ai manqu\u00e9 une partie de la saison&#8221;.<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Des r\u00e9sultats pour convaincre Del Rosso de rester<\/strong><\/p>\n<p style=\"text-align: justify;\">Qu\u2019est-ce que cette victoire carougeoise&nbsp;donne au classement&nbsp;? Inutile de pr\u00e9ciser l\u2019importance de ce&nbsp;succ\u00e8s pour les joueurs de Raffaele Del Rosso, l&#8217;entra\u00eeneur de cette troupe de joyeux lurons, qui reviennent d\u00e9sormais \u00e0 hauteur de leur adversaire du soir avec 18 points. Ce qui donne une occasion en or pour le leader Meinier, qui en compte 19, de se distancer en cas de victoire dimanche contre Puplinge.<\/p>\n<p style=\"text-align: justify;\">Del Rosso, qui est \u00e0 la fois directeur technique du Meyrin FC et entra\u00eeneur de l&#8217;US Carouge, quittera a priori cette seconde fonction d\u00e8s cet hiver, m\u00eame si les joueurs vont tenter de le faire rester. Vitkieviez :&nbsp;<em>&#8220;C&#8217;\u00e9tait un match sp\u00e9cial jeudi soir. On voulait gagner pour montrer \u00e0 Raf qu&#8217;il ne fallait pas qu&#8217;il parte. On esp\u00e8re qu&#8217;on va r\u00e9ussir \u00e0 le convaincre \u00e0 travers les r\u00e9sultats. On aimerait bien viser la mont\u00e9e mais cela ne sera pas facile, il y a des bonnes \u00e9quipes comme Meinier, Perly II ou Veyrier II. Pour beaucoup d&#8217;entre nous, c&#8217;est&nbsp;la derni\u00e8re ann\u00e9e pour jouer la mont\u00e9e. Apr\u00e8s, on commencera \u00e0 se faire vieux !&#8221;<\/em><\/p>\n<p style=\"text-align: justify;\">En tout cas, \u00e0 travers ses performances dans le foot amateur, Nicolas nous rappelle de nouveau qu&#8217;il n&#8217;y a pas qu&#8217;un seul Vitkieviez \u00e0 Gen\u00e8ve. &#8220;<em>A chaque fois que je marque, il marque aussi. On va voir lundi soir \u00e0 la Praille !&#8221;, <\/em>plaisante-t-il.<\/p>\n<p>&nbsp;<\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><strong>MEYRIN FC II&nbsp;\u2013 US CAROUGE FC &nbsp;1-3 (0-0)<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Buts<\/strong> : 72\u2019 Vitkieviez 0-1, 79\u2019 Vitkieviez 0-2, 82\u2019 Vitkieviez (P) 0-3, 85\u2019 Thalmas 1-3<\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<p><em>Photo : IV Sport (archives)<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><script src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\" async=\"\"><\/script><!-- superieur --> <ins class=\"adsbygoogle\" style=\"display: inline-block; width: 728px; height: 90px;\" data-ad-client=\"ca-pub-1317159203547503\" data-ad-slot=\"1875735477\"><\/ins><script>\/\/ <![CDATA[ (adsbygoogle = window.adsbygoogle || []).push({}); \/\/ ]]><\/script><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avec trois buts en dix minutes, l\u2019attaquant uruguayen a offert la victoire \u00e0 l\u2019US Carouge sur le terrain de Meyrin II (1-3).<\/p>\n","protected":false},"author":30,"featured_media":30432,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[6],"tags":[373,154],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.proxifoot.ch\/geneve\/2016\/10\/nicolas-vitkieviez-sest-bien-inspire-de-leo-messi\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nicolas Vitkieviez s&#039;est bien inspir\u00e9 de Leo Messi - Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"og:description\" content=\"Avec trois buts en dix minutes, l\u2019attaquant uruguayen a offert la victoire \u00e0 l\u2019US Carouge sur le terrain de Meyrin II (1-3).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.proxifoot.ch\/geneve\/2016\/10\/nicolas-vitkieviez-sest-bien-inspire-de-leo-messi\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-21T20:47:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-10-21T21:34:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/10\/Nicolas-Vitkieviez-Etoile-Carouge.png\" \/>\n\t<meta property=\"og:image:width\" content=\"856\" \/>\n\t<meta property=\"og:image:height\" content=\"488\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@www.twitter.com\/maikel_f\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2016\/10\/nicolas-vitkieviez-sest-bien-inspire-de-leo-messi\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/10\/Nicolas-Vitkieviez-Etoile-Carouge.png\",\"width\":856,\"height\":488},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2016\/10\/nicolas-vitkieviez-sest-bien-inspire-de-leo-messi\/#webpage\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/2016\/10\/nicolas-vitkieviez-sest-bien-inspire-de-leo-messi\/\",\"name\":\"Nicolas Vitkieviez s'est bien inspir\\u00e9 de Leo Messi - Proxifoot, le m\\u00e9dia du football genevois\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2016\/10\/nicolas-vitkieviez-sest-bien-inspire-de-leo-messi\/#primaryimage\"},\"datePublished\":\"2016-10-21T20:47:55+00:00\",\"dateModified\":\"2016-10-21T21:34:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/f8763ae73551193f68b47b57e2bdfb15\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.proxifoot.ch\/geneve\/2016\/10\/nicolas-vitkieviez-sest-bien-inspire-de-leo-messi\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/f8763ae73551193f68b47b57e2bdfb15\",\"name\":\"Maikel\",\"sameAs\":[\"https:\/\/twitter.com\/www.twitter.com\/maikel_f\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/30422"}],"collection":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=30422"}],"version-history":[{"count":0,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/30422\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/30432"}],"wp:attachment":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=30422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=30422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=30422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}