﻿{"id":31249,"date":"2016-12-12T14:57:34","date_gmt":"2016-12-12T12:57:34","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=31249"},"modified":"2021-09-03T15:23:11","modified_gmt":"2021-09-03T13:23:11","slug":"bojan-dimic-tous-les-matins-je-me-leve-avec-le-sourire","status":"publish","type":"post","link":"https:\/\/www.proxifoot.ch\/geneve\/2016\/12\/bojan-dimic-tous-les-matins-je-me-leve-avec-le-sourire\/","title":{"rendered":"Bojan Dimic : \u00ab Tous les matins, je me l\u00e8ve avec le sourire \u00bb"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>L&#8217;ex-entra\u00eeneur de Lancy prend son pied depuis bient\u00f4t un an en tant que responsable des talents&nbsp;au Servette FC. <\/strong><!--more--><\/p>\n<p style=\"text-align: justify;\">La vie change en un an. En octobre 2015, Bojan Dimic \u00e9tait <a href=\"http:\/\/www.proxifoot.ch\/geneve\/2015\/10\/lancy-nomme-aeby-a-la-place-de-dimic\/\">licenci\u00e9 <\/a>de Lancy apr\u00e8s plus de cinq ans \u00e0 Marignac, o\u00f9 il aura v\u00e9cu la fusion lanc\u00e9enne aux premi\u00e8res loges, passant ainsi d\u2019entra\u00eeneur du FC Grand-Lancy en bleu et blanc, \u00e0 celui du Lancy FC, en rose voire gris. La cat\u00e9gorie, elle, n\u2019a pas chang\u00e9, et l\u2019ex-joueur de Ch\u00eanois et Grand-Lancy a toujours r\u00e9ussi \u00e0 maintenir le club en 1\u00e8re ligue, luttant m\u00eame parfois pour les finales de promotion. En f\u00e9vrier dernier, le Suisse d\u2019origine serbe rebondit au Servette FC dans un tout autre r\u00f4le, celui de responsable des talents du club grenat, succ\u00e9dant \u00e0 Mario Cantaluppi. Loin, la pression des r\u00e9sultats de la 1\u00e8re ligue&nbsp;: d\u00e9sormais, il est davantage dans l\u2019ombre mais son cahier des charges n\u2019est pas moins rempli pour autant. Pour le moment, il vit pleinement son r\u00f4le, avant d\u2019obtenir la Licence UEFA Pro l\u2019ann\u00e9e prochaine. Et le retrouver sur un banc d\u2019entra\u00eeneur&nbsp;? Interview.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>Bojan, comment se passe ta nouvelle vie du c\u00f4t\u00e9 du Servette FC&nbsp;?<br \/>\n<\/strong>Bien, c\u2019est tr\u00e8s passionnant. Tous les matins, je me l\u00e8ve pour aller au foot, c\u2019est quelque chose que j\u2019ai toujours voulu faire. J\u2019ai sacrifi\u00e9 beaucoup de choses dans ma vie pour pouvoir faire \u00e7a, \u00eatre dans le foot et surtout au Servette. En tant que Genevois qui suivait d\u00e9j\u00e0 le Servette \u00e0 l\u2019\u00e9poque sur les \u00e9paules de mon papa aux Charmilles, c\u2019est quelque chose qui me rend fier. Tous les matins, je me l\u00e8ve avec le sourire.<\/p>\n<p style=\"text-align: justify;\"><strong>En quoi consiste pr\u00e9cis\u00e9ment ce r\u00f4le de responsable des talents&nbsp;?<br \/>\n<\/strong>Tout le monde me pose la m\u00eame question (<em>rires<\/em>)&nbsp;! Ce r\u00f4le de responsable des talents ou <em>talent manager<\/em>&nbsp;est obligatoire dans toutes les acad\u00e9mies. D\u2019abord, <em>talent manager<\/em> ce n\u2019est pas le fait d\u2019aller chercher des joueurs \u00e0 l\u2019ext\u00e9rieur et de les manager. Je re\u00e7ois beaucoup de messages de managers qui me proposent des joueurs alors que ce n\u2019est pas du tout \u00e7a. Concr\u00e8tement, je m\u2019occupe de tous les talents qui sont sous contrat \u00e0 Servette.&nbsp;Par <em>talent<\/em>, on entend les joueurs \u00e0 partir de 15 ans r\u00e9volus&nbsp;et jusqu\u2019\u00e0 20-21 ans. On en a en M16, M18, M21 et m\u00eame en premi\u00e8re \u00e9quipe. Je peux m\u2019occuper de beaucoup de choses, de leur planification, de leur charge\u2026 Je suis un petit peu leur grand fr\u00e8re. Je les accompagne, je suis leurs matchs. Pour ceux qui sont en \u00e9quipe suisse, j\u2019assiste aux matchs internationaux qui ont lieu en Suisse. Je dois les mettre dans le meilleur confort et je dois \u00eatre l\u00e0 s\u2019ils ont besoin de quelque chose. Mais sans entraver le travail de leur entra\u00eeneur, je ne m\u2019occupe jamais de la partie tactique. Mais je peux faire des sp\u00e9cifiques, m\u2019occuper de la partie technique et mentale. Je dois aussi faire attention s\u2019ils sont trop sollicit\u00e9s, car il y a beaucoup d\u2019agents autour des terrains. Il faut savoir que le jeune suisse entre 16-18 ans est tr\u00e8s bien cot\u00e9. R\u00e9cemment, un club anglais s\u2019est int\u00e9ress\u00e9 \u00e0 un de nos jeunes. Notre r\u00f4le, c\u2019est de les conseiller aussi.<\/p>\n<p style=\"text-align: justify;\"><strong>Au niveau de tes dipl\u00f4mes d\u2019entra\u00eeneur, o\u00f9 en es-tu&nbsp;?<br \/>\n<\/strong>J\u2019ai pass\u00e9 tous les examens pour la Licence UEFA Pro, niveau foot. J\u2019ai \u00e9galement fait tous les modules Swiss Olympic, il faut juste que je fasse mon examen Swiss Olympic que je passerai l\u2019ann\u00e9e prochaine, pour obtenir la Licence UEFA Pro.&nbsp;C\u2019est des grosses charges de travail pour arriver au bout&nbsp;: il faut presque \u00eatre pro avant d\u2019\u00eatre pro. Pour moi qui&nbsp;venais&nbsp;du monde amateur,&nbsp;c\u2019\u00e9tait&nbsp;beaucoup de sacrifices. Il faut prendre sur ses vacances&nbsp;pour assister aux&nbsp;modules, etc. Alors que ceux qui ont fait la licence avec moi, c\u2019est d\u00e9j\u00e0 des entra\u00eeneurs de GC, Zurich,&nbsp;B\u00e2le\u2026 Pour eux c\u2019\u00e9tait normal de partir six jours pour un module, mais pour un amateur,&nbsp;c\u2019\u00e9tait&nbsp;compliqu\u00e9. J\u2019ai pass\u00e9 plus de temps \u00e0 dormir avec Massimo Lombardo \u00e0 l\u2019h\u00f4tel qu\u2019\u00e0 la maison&nbsp;(<em>rires<\/em>)&nbsp;! Mais j\u2019ai eu la chance d\u2019avoir \u00e9t\u00e9 soutenu par ma famille,&nbsp;ma femme surtout.<\/p>\n<p style=\"text-align: justify;\"><strong>Tu as visit\u00e9 La Masia r\u00e9cemment, c\u2019\u00e9tait dans le cadre du partenariat avec le Bar\u00e7a ?<br \/>\n<\/strong>Oui, l\u2019Acad\u00e9mie a \u00e9t\u00e9 invit\u00e9e par Barcelone, on est partis toute une d\u00e9l\u00e9gation et on a visit\u00e9 leurs installations, les bureaux. On a m\u00eame pu voir le terrain d\u2019entra\u00eenement de la premi\u00e8re \u00e9quipe, ce qui est tr\u00e8s rare.<\/p>\n<p style=\"text-align: justify;\"><strong>Est-ce que coacher te manque&nbsp;?<br \/>\n<\/strong>On me pose aussi beaucoup cette question (<em>rires<\/em>)&nbsp;! Actuellement, pas plus que \u00e7a. J\u2019ai eu peur au d\u00e9but. Maintenant, avec le recul, \u00e7a va. \u00c7a me fait du bien de voir un autre domaine du foot, \u00e7a m\u2019a ouvert les yeux sur beaucoup de choses. Mais je suis tous les jours sur le terrain, que ce soit avec les jeunes ou la premi\u00e8re, il y a toujours quelque chose \u00e0 faire. Je n\u2019ai pas le management d\u2019une \u00e9quipe, seulement celui des talents. Mais entra\u00eener, ce n\u2019est pas quelque chose qui me manque \u00e9norm\u00e9ment. Apr\u00e8s, si tu reviens dans une ann\u00e9e et que je te dis la m\u00eame chose, c\u2019est qu\u2019il y a quelque chose qui ne jouerait pas (<em>rires<\/em>).<\/p>\n<p style=\"text-align: justify;\"><strong>Tu sortais quand m\u00eame de 5-6 ans de 1\u00e8re ligue avec une pression des r\u00e9sultats. Cette pression du match ne te manque pas&nbsp;?<br \/>\n<\/strong>Non, parce qu\u2019avec le recul je pense que j\u2019ai fait des choses&nbsp;que peu de coll\u00e8gues entra\u00eeneurs ont fait&nbsp;\u00e0 ce niveau-l\u00e0,&nbsp;que ce soit dans le domaine sportif qu&#8217;extra-sportif.&nbsp;Mes coll\u00e8gues&nbsp;du Servette&nbsp;me disent&nbsp;: \u00ab&nbsp;Mais tu filmais vraiment tous les matchs&nbsp;\u00e0 ce niveau&nbsp;? \u00bb. Pour eux, la 1\u00e8re ligue, c\u2019est du foot amateur. Apr\u00e8s, quand j\u2019entra\u00eenais, j\u2019\u00e9tais aussi stress\u00e9 par mes dipl\u00f4mes, donc je n\u2019avais pas beaucoup de temps. Cela ne veut pas dire que je me repose maintenant. Mes semaines sont&nbsp;tr\u00e8s souvent du lundi au dimanche. Je n\u2019ai eu que quelques dimanches de libres depuis juillet. Ma femme m\u2019a m\u00eame dit&nbsp;: \u00ab&nbsp;Tu ne m\u2019avais pas dit que tu serais plus souvent \u00e0 la maison ?&nbsp;\u00bb (<em>rires<\/em>). Alors l\u2019adr\u00e9naline du match, de la tactique et tout \u00e7a\u2026 est-ce que \u00e7a me manque&nbsp;? Ce qui me manque vraiment, c\u2019est de voir une progression. L\u00e0 je la vois \u00e0 titre individuel avec les talents, mais je ne la vois pas au niveau d\u2019un collectif.&nbsp;Par exemple, on parle beaucoup de la d\u00e9fense \u00e0 trois maintenant, j\u2019ai jou\u00e9 \u00e0 trois longtemps \u00e0 Lancy d\u00e9j\u00e0. Maintenant je me dis&nbsp;: quelle est l\u2019\u00e9tape d\u2019apr\u00e8s&nbsp;? \u00c7a, peut-\u00eatre que \u00e7a me manque. Alors j\u2019en discute beaucoup avec mes coll\u00e8gues, mais je ne peux pas le mettre en pratique. Donc ce n\u2019est pas un manque de la pression du match,&nbsp;d\u2019ailleurs&nbsp;je n\u2019ai jamais eu peur de la pression. Moi ce que je disais toujours \u00e0 mes joueurs c\u2019est&nbsp;: \u00ab&nbsp;La seule chose dont vous devez avoir peur, c\u2019est qu\u2019il arrive quelque chose \u00e0 votre famille, le foot ce n\u2019est que du plaisir&nbsp;\u00bb. Dans mon ambition, j\u2019avais tr\u00e8s envie d\u2019aller l\u00e0 o\u00f9 je suis maintenant. Si j\u2019ai peur de la pression, je n\u2019ai rien \u00e0 faire ici au&nbsp;Servette FC.<\/p>\n<p style=\"text-align: justify;\"><strong>Quel regard portes-tu&nbsp;ton ancien, club,&nbsp;le&nbsp;Lancy FC, qui vient de vivre une ann\u00e9e 2016 exceptionnelle&nbsp;?<br \/>\n<\/strong>Tr\u00e8s honn\u00eatement, je suis tr\u00e8s content, surtout pour les joueurs qui restent. Eux savent les sacrifices qu\u2019on faisait et dans quelle situation on \u00e9tait. Ce club m\u00e9rite d\u2019\u00eatre en Promotion League. J\u2019ai ador\u00e9 mon passage \u00e0 Lancy, humainement on a v\u00e9cu plein de trucs. Et sportivement, n\u2019oubliez pas que l\u2019on a battu le record de points de l\u2019histoire du FC Grand-Lancy et que l\u2019on a loup\u00e9 de tr\u00e8s peu la mont\u00e9e lorsque la Promotion League a \u00e9t\u00e9 cr\u00e9\u00e9e et avec tr\u00e8s peu de moyens.<\/p>\n<p style=\"text-align: justify;\"><strong>Comment vois-tu ton avenir&nbsp;?<br \/>\n<\/strong>Actuellement, j\u2019aime ce que je fais. Mais on ne fait pas une Licence UEFA Pro sans vouloir avoir une \u00e9quipe dans le futur. J\u2019emmagasine beaucoup d\u2019exp\u00e9rience en rencontrant et en \u00e9changeant avec mes homologues des autres clubs de la SFL. De plus, on a la chance d\u2019avoir beaucoup de comp\u00e9tences dans notre acad\u00e9mie du Servette, autour de notre chef, Thierry Cotting. Quand tu veux parler de syst\u00e8me de jeu, de pr\u00e9paration physique, d\u2019animation d\u00e9fensive ou offensive, etc\u2026 il y a de quoi faire car il y a des sp\u00e9cialistes dans tous ces domaines&nbsp;! En plus, je suis dans le bureau de la premi\u00e8re avec Anthony Braizat. J\u2019ai \u00e9galement&nbsp;Adam Owen \u00e0 c\u00f4t\u00e9 de moi et parfois il est au t\u00e9l\u00e9phone avec Gareth Bale\u2026 c\u2019est juste dingue. Donc pour la suite, on verra. Mais en tout cas mon avenir, je le vois \u00e0 Servette.<\/p>\n<p>&nbsp;<\/p>\n<p><em>Photo : <a href=\"http:\/\/www.oneclick-photo.ch\" target=\"_blank\" rel=\"noopener noreferrer\">OneClick-Photo<\/a><\/em><\/p>\n<p>&nbsp;<\/p>\n<p><script src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\" async=\"\"><\/script><!-- superieur --> <ins class=\"adsbygoogle\" style=\"display: inline-block; width: 728px; height: 90px;\" data-ad-slot=\"1875735477\" data-ad-client=\"ca-pub-1317159203547503\"><\/ins><script>\/\/ <![CDATA[ (adsbygoogle = window.adsbygoogle || []).push({}); \/\/ ]]><\/script><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;ex-entra\u00eeneur de Lancy prend son pied depuis bient\u00f4t un an en tant que responsable des talents&nbsp;au Servette FC.<\/p>\n","protected":false},"author":30,"featured_media":31271,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[544],"tags":[253,46,146],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.proxifoot.ch\/geneve\/2016\/12\/bojan-dimic-tous-les-matins-je-me-leve-avec-le-sourire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bojan Dimic : \u00ab Tous les matins, je me l\u00e8ve avec le sourire \u00bb - Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"og:description\" content=\"L&#8217;ex-entra\u00eeneur de Lancy prend son pied depuis bient\u00f4t un an en tant que responsable des talents&nbsp;au Servette FC.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.proxifoot.ch\/geneve\/2016\/12\/bojan-dimic-tous-les-matins-je-me-leve-avec-le-sourire\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-12T12:57:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-03T13:23:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/12\/Bojan-Dimic-2015.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1045\" \/>\n\t<meta property=\"og:image:height\" content=\"529\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@www.twitter.com\/maikel_f\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2016\/12\/bojan-dimic-tous-les-matins-je-me-leve-avec-le-sourire\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2016\/12\/Bojan-Dimic-2015.jpg\",\"width\":1045,\"height\":529},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2016\/12\/bojan-dimic-tous-les-matins-je-me-leve-avec-le-sourire\/#webpage\",\"url\":\"http:\/\/www.proxifoot.ch\/geneve\/2016\/12\/bojan-dimic-tous-les-matins-je-me-leve-avec-le-sourire\/\",\"name\":\"Bojan Dimic : \\u00ab Tous les matins, je me l\\u00e8ve avec le sourire \\u00bb - Proxifoot, le m\\u00e9dia du football genevois\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2016\/12\/bojan-dimic-tous-les-matins-je-me-leve-avec-le-sourire\/#primaryimage\"},\"datePublished\":\"2016-12-12T12:57:34+00:00\",\"dateModified\":\"2021-09-03T13:23:11+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/f8763ae73551193f68b47b57e2bdfb15\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.proxifoot.ch\/geneve\/2016\/12\/bojan-dimic-tous-les-matins-je-me-leve-avec-le-sourire\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/f8763ae73551193f68b47b57e2bdfb15\",\"name\":\"Maikel\",\"sameAs\":[\"https:\/\/twitter.com\/www.twitter.com\/maikel_f\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/31249"}],"collection":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=31249"}],"version-history":[{"count":3,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/31249\/revisions"}],"predecessor-version":[{"id":45971,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/31249\/revisions\/45971"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/31271"}],"wp:attachment":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=31249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=31249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=31249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}