﻿{"id":4403,"date":"2012-06-01T10:43:15","date_gmt":"2012-06-01T09:43:15","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=4403"},"modified":"2016-07-20T16:18:50","modified_gmt":"2016-07-20T14:18:50","slug":"3eme-ligue-quels-enjeux-pour-la-derniere-journee","status":"publish","type":"post","link":"https:\/\/www.proxifoot.ch\/geneve\/2012\/06\/3eme-ligue-quels-enjeux-pour-la-derniere-journee\/","title":{"rendered":"3\u00e8me ligue : quels enjeux pour la derni\u00e8re journ\u00e9e ?"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>A quelques jours de la derni\u00e8re journ\u00e9e de 3<span style=\"font-size: 11px;\">\u00e8me<\/span>\u00a0ligue, retrouvez quelles sont les possibilit\u00e9s des \u00e9quipes concern\u00e9es. A vos calculettes\u00a0!<!--more--><\/strong><\/p>\n<p style=\"text-align: justify;\">Contrairement \u00e0 la 2\u00e8me\u00a0ligue, o\u00f9 tout est d\u00e9j\u00e0 d\u00e9cid\u00e9, la 3<span style=\"font-size: 11px;\">\u00e8me<\/span>\u00a0ligue nous r\u00e9serve encore du suspense pour la derni\u00e8re journ\u00e9e. Les deux rel\u00e9gu\u00e9s du groupe 1 \u00e9tant d\u00e9j\u00e0 connus, Gen\u00e8ve-Ville et Famalic\u00e3o, les deux places de t\u00eate sont encore \u00e0 d\u00e9cider. Mais c\u2019est dans le groupe 2 que les choses sont totalement ind\u00e9cises puisque ni les deux premi\u00e8res places, ni les deux derni\u00e8res, n\u2019ont encore trouv\u00e9 preneur\u00a0!<\/p>\n<p><strong>GROUPE 1<\/strong><\/p>\n<p style=\"text-align: justify;\">Encore quatre \u00e9quipes sont en lice pour les deux premi\u00e8res places. Si le titre de champion \u2013 et la promotion directe en 2<span style=\"font-size: 11px;\">\u00e8me<\/span>\u00a0ligue \u2013 se jouera entre CS Italien et Champel, la 2<span style=\"font-size: 11px;\">\u00e8me<\/span>\u00a0place, synonyme de barragiste, peut encore revenir \u00e0 A\u00efre, dont les chances sont par contre minimes. Rappelons que Grand-Lancy II peut aussi finir second mais ne peut pas \u00eatre barragiste. Si tel \u00e9tait le sc\u00e9nario, le 2<span style=\"font-size: 11px;\">\u00e8me<\/span>\u00a0class\u00e9 du groupe 2 monterait directement en 2\u00e8me\u00a0ligue.<\/p>\n<p style=\"text-align: center;\">\u00a0<strong>Matchs pour le titre et la 2\u00e8me place :<\/strong><br \/>\nCS Italien \u2013 US Meinier<br \/>\nFC Champel \u2013 FC Rapid Jonction Bosna<br \/>\nFC Puplinge \u2013 FC A\u00efre-le-Lignon<br \/>\nFC Kosova II \u2013 FC Grand-Lancy II<\/p>\n<p style=\"text-align: justify;\">1<span style=\"font-size: 11px;\">er<\/span>\u00a0: <strong>CS Italien<\/strong> (45 points, goal-average de +37) serait champion en cas de\u00a0:<\/p>\n<p style=\"padding-left: 30px;\">&#8211; Victoire<br \/>\n&#8211; Match nul\u00a0: si Champel ne gagne pas<br \/>\n&#8211; D\u00e9faite\u00a0: si Champel perd aussi<\/p>\n<p>2<span style=\"font-size: 11px;\">\u00e8me<\/span>\u00a0: <strong>Champel<\/strong> (44 points, goal-average de +50) serait champion en cas de\u00a0:<\/p>\n<p style=\"padding-left: 30px;\">&#8211; Victoire\u00a0: si CS Italien ne gagne pas<br \/>\n&#8211; Match nul\u00a0: si CS Italien perd<\/p>\n<div id=\"attachment_4422\" style=\"width: 503px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/CSI-Champel.jpg\"><img aria-describedby=\"caption-attachment-4422\" loading=\"lazy\" class=\"size-full wp-image-4422\" title=\"CSI-Champel\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/CSI-Champel.jpg\" alt=\"\" width=\"493\" height=\"307\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/CSI-Champel.jpg 705w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/CSI-Champel-300x186.jpg 300w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/CSI-Champel-660x410.jpg 660w\" sizes=\"(max-width: 493px) 100vw, 493px\" \/><\/a><p id=\"caption-attachment-4422\" class=\"wp-caption-text\">Le CS conservera-t-il son tr\u00f4ne au terme de la derni\u00e8re journ\u00e9e?<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>3<span style=\"font-size: 11px;\">\u00e8me<\/span>\u00a0: <strong>Grand-Lancy II<\/strong> (42 points, goal-average de +17) ne peut pas \u00eatre barragiste mais finirait 2<span style=\"font-size: 11px;\">\u00e8me<\/span>\u00a0en cas de\u00a0:<\/p>\n<p style=\"padding-left: 30px;\">&#8211; Victoire\u00a0: si Champel perd et A\u00efre n&#8217;obtient pas une victoire plus large de 5 buts<\/p>\n<p>4<span style=\"font-size: 11px;\">\u00e8me<\/span>\u00a0: <strong>A\u00efre-le-Lignon<\/strong> (42 points, goal-average de +13) serait barragiste en cas de\u00a0:<\/p>\n<p style=\"padding-left: 30px;\">&#8211; Victoire\u00a0: si Champel perd et Grand-Lancy II ne gagne pas ou obtient une victoire avec un \u00e9cart de moins de 4 buts (exemple: si Grand-Lancy II gagne 1-0 et A\u00efre gagne 6-0, A\u00efre passerait devant Grand-Lancy II)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>GROUPE 2<\/strong><\/p>\n<p style=\"text-align: justify;\">Le titre se jouera entre deux \u00e9quipes qui, comme dans le groupe 1, sont s\u00e9par\u00e9es d&#8217;un point : UGS II et Veyrier. L\u00e9ger avantage \u00e0 UGS II qui d\u00e9pend de lui-m\u00eame pour \u00eatre champion du groupe. Mais attention tout de m\u00eame puisque l\u2019adversaire n\u2019est autre que le 3<span style=\"font-size: 11px;\">\u00e8me<\/span>\u00a0du classement, \u00e0 savoir Donzelle. De son c\u00f4t\u00e9, Veyrier ne devra pas passer \u00e0 c\u00f4t\u00e9 de son match face \u00e0 une \u00e9quipe qui l&#8217;avait battu au premier tour.<\/p>\n<p align=\"center\"><strong>Matchs pour le titre\u00a0:<\/strong><br \/>\nFC UGS II \u2013 FC Donzelle<br \/>\nFC Grand-Saconnex \u2013 FC Veyrier Sports<\/p>\n<p>1<span style=\"font-size: 11px;\">er<\/span>\u00a0: <strong>UGS II<\/strong> (47 points, goal-average de +38) serait champion en cas de\u00a0:<\/p>\n<p style=\"padding-left: 30px;\">&#8211; Victoire<br \/>\n&#8211; Match nul\u00a0: si Veyrier ne gagne pas<br \/>\n&#8211; D\u00e9faite\u00a0: si Veyrier perd aussi<\/p>\n<p>2<span style=\"font-size: 11px;\">\u00e8me<\/span>\u00a0: <strong>Veyrier<\/strong> (46 points, goal-average de +39) serait champion en cas de\u00a0:<\/p>\n<p style=\"padding-left: 30px;\">&#8211; Victoire\u00a0: si UGS II ne gagne pas<br \/>\n&#8211; Match nul\u00a0: si UGS II perd<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Contrairement au groupe 1, le bas de tableau doit encore se d\u00e9cider. Entre City, Laconnex et Tordoya, seule une \u00e9quipe sauvera sa peau. Les choses semblent compliqu\u00e9es pour Tordoya, qui a besoin d\u2019une victoire contre Bernex II ainsi qu&#8217;une d\u00e9faite des deux autres concurrents pour se sauver. Rappelons que m\u00eame si Laconnex et City sont \u00e0 \u00e9galit\u00e9 de points, les &#8220;Citizen&#8217;s&#8221; ont un meilleur goal-average de 5 buts.<\/p>\n<p align=\"center\"><strong>Matchs pour le maintien\u00a0:<br \/>\n<\/strong>FC City \u2013 FC Choulex<br \/>\nFC Perly-Certoux II \u2013 FC Etoile Laconnex<br \/>\nSignal FC Bernex-Confignon II \u2013 FC Tordoya<\/p>\n<p>10\u00e8me<sup>\u00a0<\/sup>: <strong>City<\/strong> (17 points, goal-average de -17) se sauverait en cas de\u00a0:<\/p>\n<p style=\"padding-left: 30px;\">&#8211; Victoire\u00a0: si Laconnex ne l\u2019emporte pas d\u2019une diff\u00e9rence meilleure de 6 buts (exemple : si City gagne 2-0 et Laconnex gagne 7-0, City est sauv\u00e9 d&#8217;un but)<br \/>\n&#8211; Match nul\u00a0: si Laconnex ne gagne pas<br \/>\n&#8211; D\u00e9faite\u00a0: si Laconnex perd aussi et Tordoya ne gagne pas<\/p>\n<div id=\"attachment_4418\" style=\"width: 605px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.oneclick-photo.ch\/category\/city-vs-etoile-laconnex.html\" target=\"_blank\"><img aria-describedby=\"caption-attachment-4418\" loading=\"lazy\" class=\"size-full wp-image-4418\" title=\"City vs Etoile Laconnex\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/City-Laco.jpg\" alt=\"\" width=\"595\" height=\"357\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/City-Laco.jpg 850w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/City-Laco-300x180.jpg 300w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/City-Laco-660x396.jpg 660w\" sizes=\"(max-width: 595px) 100vw, 595px\" \/><\/a><p id=\"caption-attachment-4418\" class=\"wp-caption-text\">Qui de City ou Laconnex sauvera sa peau? (Photo: OneClick-Photo)<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>11<span style=\"font-size: 11px;\">\u00e8me\u00a0<\/span>: <strong>Laconnex<\/strong> (17 points, goal-average de -22) se sauverait en cas de\u00a0:<\/p>\n<p style=\"padding-left: 30px;\">&#8211; Victoire\u00a0: si City ne gagne pas ou si la diff\u00e9rence est de 6 buts meilleure qu\u2019une \u00e9ventuelle victoire de City (exemple\u00a0: si City gagne 1-0, Laconnex devra gagner son match 7-0)<br \/>\n&#8211; Match nul\u00a0: si City perd<br \/>\n<span style=\"text-align: justify;\">&#8211; D\u00e9faite\u00a0: si Tordoya ne gagne pas et City perd d\u2019une diff\u00e9rence sup\u00e9rieure \u00e0 6 buts (exemple\u00a0: si Laconnex perd 1-0 et City perd 7-0, Laconnex se sauve)<\/span><\/p>\n<p>12<span style=\"font-size: 11px;\">\u00e8me<\/span>\u00a0: <strong>Tordoya<\/strong> (15 points, goal-average de -40) se sauverait en cas de\u00a0:<\/p>\n<p style=\"padding-left: 30px;\">&#8211; Victoire\u00a0: si City ET Laconnex perdent<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Vous aussi vous \u00eates perdus\u00a0? Alors rendez-vous dimanche \u00e0 10h du matin pour suivre tous les r\u00e9sultats des matchs \u00e0 enjeu en direct sur notre application mobile\u00a0!<\/p>\n<p style=\"text-align: justify;\"><a title=\"Proxifoot d\u00e9barque sur votre mobile !\" href=\"http:\/\/www.proxifoot.ch\/geneve\/?p=3929\" target=\"_blank\"><img loading=\"lazy\" class=\"alignnone size-large wp-image-4440\" title=\"bache+appli\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/bache+appli-1024x383.jpg\" alt=\"\" width=\"645\" height=\"241\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/bache+appli-1024x383.jpg 1024w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/bache+appli-300x112.jpg 300w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/bache+appli-660x247.jpg 660w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/bache+appli.jpg 1181w\" sizes=\"(max-width: 645px) 100vw, 645px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>A quelques jours de la derni\u00e8re journ\u00e9e de 3\u00e8me\u00a0ligue, retrouvez quelles sont les possibilit\u00e9s des \u00e9quipes concern\u00e9es. A vos calculettes\u00a0!<\/p>\n","protected":false},"author":1,"featured_media":4413,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[6],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.proxifoot.ch\/geneve\/2012\/06\/3eme-ligue-quels-enjeux-pour-la-derniere-journee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3\u00e8me ligue : quels enjeux pour la derni\u00e8re journ\u00e9e ? - Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"og:description\" content=\"A quelques jours de la derni\u00e8re journ\u00e9e de 3\u00e8me\u00a0ligue, retrouvez quelles sont les possibilit\u00e9s des \u00e9quipes concern\u00e9es. A vos calculettes\u00a0!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.proxifoot.ch\/geneve\/2012\/06\/3eme-ligue-quels-enjeux-pour-la-derniere-journee\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2012-06-01T09:43:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-20T14:18:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/3eligue-titre.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"328\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2012\/06\/3eme-ligue-quels-enjeux-pour-la-derniere-journee\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/05\/3eligue-titre.jpg\",\"width\":660,\"height\":328},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2012\/06\/3eme-ligue-quels-enjeux-pour-la-derniere-journee\/#webpage\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/2012\/06\/3eme-ligue-quels-enjeux-pour-la-derniere-journee\/\",\"name\":\"3\\u00e8me ligue : quels enjeux pour la derni\\u00e8re journ\\u00e9e ? - Proxifoot, le m\\u00e9dia du football genevois\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2012\/06\/3eme-ligue-quels-enjeux-pour-la-derniere-journee\/#primaryimage\"},\"datePublished\":\"2012-06-01T09:43:15+00:00\",\"dateModified\":\"2016-07-20T14:18:50+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.proxifoot.ch\/geneve\/2012\/06\/3eme-ligue-quels-enjeux-pour-la-derniere-journee\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\",\"name\":\"admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/4403"}],"collection":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=4403"}],"version-history":[{"count":0,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/4403\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/4413"}],"wp:attachment":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=4403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=4403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=4403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}