﻿{"id":44793,"date":"2021-06-01T06:36:32","date_gmt":"2021-06-01T04:36:32","guid":{"rendered":"https:\/\/www.proxifoot.ch\/new\/?p=44793"},"modified":"2021-06-01T11:24:51","modified_gmt":"2021-06-01T09:24:51","slug":"2eme-ligue-inter-des-occasions-en-or-pour-la-reprise","status":"publish","type":"post","link":"https:\/\/www.proxifoot.ch\/geneve\/2021\/06\/2eme-ligue-inter-des-occasions-en-or-pour-la-reprise\/","title":{"rendered":"2\u00e8me ligue inter : des occasions en or pour la reprise"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Parmi les six \u00e9quipes genevoises de 2\u00e8me ligue inter, certaines peuvent esp\u00e9rer gros de cette reprise. Tour d&#8217;horizon avant un mois intense qui d\u00e9marrera samedi.<br \/>\n<\/strong><\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\"><!-- Soit il n'y a pas de banni\u00e8res, ils sont desactiv\u00e9es ou pas qualifi\u00e9es pour cet endroit! -->\n<p style=\"text-align: justify;\">La 2\u00e8me ligue inter fait son tant attendu retour plus de sept mois apr\u00e8s. Un championnat o\u00f9 les Genevois ont tap\u00e9 du poing sur la table, puisque cinq des six \u00e9quipes du canton repr\u00e9sent\u00e9es figurent dans le top 6. Collex-Bossy, Servette M-21 et CS Italien sont parmi celles pouvant encore se permettre de viser la premi\u00e8re place. Et si Veyrier et UGS semblent destin\u00e9s \u00e0 vivre une reprise plut\u00f4t calme, install\u00e9s dans la premi\u00e8re partie du tableau, Bernex, \u00e0 cinq points de la rel\u00e9gation, n&#8217;aura pas le droit de se rel\u00e2cher.<\/p>\n<h3 style=\"text-align: justify;\"><strong>Collex-Bossy, 2\u00e8me, 20 points<br \/>\n<\/strong><\/h3>\n<p style=\"text-align: justify;\">Les Collesiens ont \u00e9t\u00e9 la meilleure \u00e9quipe genevoise <a href=\"https:\/\/www.proxifoot.ch\/new\/2020\/10\/des-chevaliers-a-prendre-au-serieux\/\">cet automne<\/a>. D\u00e9j\u00e0 quatri\u00e8me lors de la saison 2019-20 avant le d\u00e9cret de la saison blanche, Collex-Bossy a confirm\u00e9 en montant davantage en puissance un an apr\u00e8s.\u00a0 Pendant dix rencontres, les Chevaliers ont tourn\u00e9 \u00e0 une moyenne de deux points par match et sont toujours la seule \u00e9quipe du groupe invaincue. \u00c0 l&#8217;heure de la reprise, ils ne sont qu&#8217;\u00e0 une unit\u00e9 du leader Monthey et peuvent se permettre de voir les choses en grand. De plus, l&#8217;\u00e9quipe d&#8217;Yves Mi\u00e9ville a son destin entre les mains, car l&#8217;avant-dernier match sera justement contre les Valaisans. Mais avant cela, un choc d&#8217;entr\u00e9e attend Collex, contre Servette M-21, troisi\u00e8me. Une affiche dont nous avions \u00e9t\u00e9 priv\u00e9s de justesse avant l&#8217;arr\u00eat des comp\u00e9titions et que nous nous r\u00e9jouissons de vivre ce week-end. Le gagnant pourrait prendre une s\u00e9rieuse option dans la course au titre.<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>Samedi 5 juin Collex-Servette<\/strong><\/li>\n<li><strong>Samedi 12 juin Renens-Collex<\/strong><\/li>\n<li><strong>Dimanche 20 juin Collex-Monthey<\/strong><\/li>\n<li><strong>Samedi 26 juin UGS-Collex<\/strong><\/li>\n<\/ul>\n<h3 style=\"text-align: justify;\"><strong><img loading=\"lazy\" class=\"alignnone wp-image-43185 size-large\" src=\"https:\/\/www.proxifoot.ch\/new\/wp-content\/uploads\/2020\/10\/DSC03381-1024x551.jpg\" alt=\"\" width=\"702\" height=\"378\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2020\/10\/DSC03381-1024x551.jpg 1024w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2020\/10\/DSC03381-300x161.jpg 300w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2020\/10\/DSC03381-768x413.jpg 768w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2020\/10\/DSC03381-1536x826.jpg 1536w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2020\/10\/DSC03381-2048x1101.jpg 2048w\" sizes=\"(max-width: 702px) 100vw, 702px\" \/><\/strong><\/h3>\n<h3 style=\"text-align: justify;\"><strong>Servette M-21, 3\u00e8me, 18 points<br \/>\n<\/strong><\/h3>\n<p style=\"text-align: justify;\">\u00c0 seulement trois points de la premi\u00e8re place, les Grenat font malgr\u00e9 tout figure de favori \u00e0 la mont\u00e9e en 1\u00e8re ligue. La raison est simple : les M-21 du Servette FC, comme tous ceux des autres clubs professionnels en Suisse, ne se sont presque jamais arr\u00eat\u00e9s. En plus de pouvoir s&#8217;entra\u00eener, ils ont b\u00e9n\u00e9fici\u00e9 d&#8217;un <a href=\"https:\/\/www.proxifoot.ch\/new\/2021\/01\/les-m-21-auront-droit-a-un-championnat-amical\/\">championnat amical<\/a> cr\u00e9\u00e9 pour permettre \u00e0 ces acad\u00e9mies de garder un bon rythme. L&#8217;\u00e9quipe de <a href=\"https:\/\/www.proxifoot.ch\/new\/2021\/05\/bruno-pascale-certains-jouent-leur-carriere-et-se-retrouvent-dans-une-situation-compliquee\/\">Bruno Pascale<\/a>, m\u00eame partant l\u00e9g\u00e8rement derri\u00e8re les deux autres formant le podium, a donc un avantage non-n\u00e9gligeable. Ceci \u00e9tant dit, la confrontation directe de ce week-end contre un Collex-Bossy certainement affam\u00e9 sera essentielle pour ne pas se retrouver distanc\u00e9 par le duo de t\u00eate.<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>Samedi 5 juin Collex-Servette<\/strong><\/li>\n<li><strong>Samedi 12 juin Servette-Sierre<\/strong><\/li>\n<li><strong>Samedi 19 juin Saint-Prex-Servette<\/strong><\/li>\n<li><strong>Samedi 26 juin Servette-CS Italien<\/strong><\/li>\n<\/ul>\n<div id=\"attachment_44807\" style=\"width: 712px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-44807\" loading=\"lazy\" class=\"wp-image-44807 size-large\" src=\"https:\/\/www.proxifoot.ch\/new\/wp-content\/uploads\/2021\/05\/IMG_6427-1024x602.jpg\" alt=\"\" width=\"702\" height=\"413\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2021\/05\/IMG_6427-1024x602.jpg 1024w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2021\/05\/IMG_6427-300x176.jpg 300w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2021\/05\/IMG_6427-1536x903.jpg 1536w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2021\/05\/IMG_6427-2048x1205.jpg 2048w\" sizes=\"(max-width: 702px) 100vw, 702px\" \/><p id=\"caption-attachment-44807\" class=\"wp-caption-text\"><em>Les Servettiens et leur capitaine Cameron Barban arrivent fin pr\u00eats \u00e0 cette reprise.<\/em><\/p><\/div>\n<h3><\/h3>\n<h3 style=\"text-align: justify;\"><strong>CS Italien, 4\u00e8me, 18 points<\/strong><\/h3>\n<p style=\"text-align: justify;\">\u00c0 \u00e9galit\u00e9 de points avec la r\u00e9serve servettienne et \u00e0 seulement trois points de Monthey, CS Italien peut encore nourrir de belles ambitions. Il est vrai que la <a href=\"https:\/\/www.proxifoot.ch\/new\/2020\/10\/collex-bossy-regale-son-public\/\">d\u00e9faite 4-1 contre Collex<\/a> peu avant la tr\u00eave a frein\u00e9 drastiquement la troupe de Maxime Antonilli, mais rien n&#8217;est perdu. L&#8217;\u00e9quipe de la B\u00e2tie a un calendrier plut\u00f4t g\u00e9n\u00e9reux avec au menu Saint-Prex, Bernex et Morges : trois \u00e9quipes du bas de tableau. La rencontre finale sera elle face \u00e0 Servette M-21. Si CS Italien r\u00e9ussit \u00e0 faire respecter la hi\u00e9rarchie lors de ses trois premi\u00e8res sorties, qui sait que la derni\u00e8re ne puisse pas \u00eatre une finale&#8230;<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>Samedi 5 juin Saint-Prex-CS Italien<\/strong><\/li>\n<li><strong>Samedi 12 juin CS Italien-Bernex<\/strong><\/li>\n<li><strong>Samedi 19 juin CS Italien-Morges<\/strong><\/li>\n<li><strong>Samedi 26 juin Servette-CS Italien<\/strong><\/li>\n<\/ul>\n<h3 style=\"text-align: justify;\"><strong><img loading=\"lazy\" class=\"alignnone size-full wp-image-44810\" src=\"https:\/\/www.proxifoot.ch\/new\/wp-content\/uploads\/2021\/05\/IMG_4509-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1572\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2021\/05\/IMG_4509-scaled.jpg 2560w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2021\/05\/IMG_4509-300x184.jpg 300w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2021\/05\/IMG_4509-1024x629.jpg 1024w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2021\/05\/IMG_4509-1536x943.jpg 1536w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2021\/05\/IMG_4509-2048x1258.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/strong><\/h3>\n<h3 style=\"text-align: justify;\"><strong>Veyrier, 5\u00e8me, 16 points<\/strong><\/h3>\n<p style=\"text-align: justify;\">La d\u00e9faite contre Servette M-21 (3-1) avant l&#8217;arr\u00eat du championnat n&#8217;a pas fait du bien au classement pour les Veyrites. \u00c0 cinq points du leader, avec d&#8217;ailleurs un match de plus que tous ses concurrents, Veyrier semble presque d\u00e9finitivement \u00e9cart\u00e9 de la course au titre. Par contre, les Jaune et Vert pourraient faire une belle faveur aux autres clubs genevois, en d\u00e9placement \u00e0 Monthey le 12 juin. Mais avant ce match de prestige, l&#8217;\u00e9quipe de Daniel Villa repartira avec la r\u00e9ception de Renens samedi soir (18h).<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>Samedi 5 juin Veyrier-Renens<\/strong><\/li>\n<li><strong>Samedi 12 juin Monthey-Veyrier<\/strong><\/li>\n<li><strong>Samedi 19 juin Veyrier-UGS<\/strong><\/li>\n<\/ul>\n<h3><\/h3>\n<h3 style=\"text-align: justify;\"><strong>UGS, 6\u00e8me, 13 points<\/strong><\/h3>\n<p style=\"text-align: justify;\">Bonne nouvelle : UGS ne devrait pas trembler pour son maintien, comme cela avait \u00e9t\u00e9 le cas<a href=\"https:\/\/www.proxifoot.ch\/new\/2019\/06\/herve-musquere-on-na-jamais-cesse-dy-croire\/\"> lors de la saison 2018-2019<\/a>, la derni\u00e8re s&#8217;\u00e9tant r\u00e9guli\u00e8rement conclue. Sixi\u00e8mes et \u00e0 onze points de la zone rouge, les Ug\u00e9istes n&#8217;ont rien \u00e0 craindre. Par contre, leurs huit points de retard sur la premi\u00e8re place rendent un potentiel miracle presque impossible, mais qui sait. UGS sera aussi l&#8217;\u00e9quipe avec le calendrier le plus charg\u00e9 d&#8217;entr\u00e9e,avec un d\u00e9placement \u00e0 Saint-Maurice samedi et la r\u00e9ception de Genolier-Begnins mercredi. L&#8217;\u00e9quipe d&#8217;Herv\u00e9 Musqu\u00e8re terminera ensuite la saison avec deux derbys face \u00e0 Veyrier et Collex-Bossy.<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>Samedi 5 juin Saint-Maurice-UGS<\/strong><\/li>\n<li><strong>Mercredi 9 juin UGS-Genolier-Begnins<\/strong><\/li>\n<li><strong>Samedi 19 juin Veyrier-UGS<\/strong><\/li>\n<li><strong>Samedi 26 juin UGS-Collex<\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: justify;\"><strong>Bernex, 10\u00e8me, 7 points<\/strong><\/h3>\n<p style=\"text-align: justify;\">Signal Bernex doit se m\u00e9fier. Avec seulement sept points en dix matchs, les Bern\u00e9siens peuvent s&#8217;estimer heureux que la concurrence patine aussi. Cependant, le premier rel\u00e9gable Morges n&#8217;est que cinq points derri\u00e8re l&#8217;\u00e9quipe de Wassil Debbiche, et a un match d&#8217;entr\u00e9e contre la lanterne rouge qui pourrait leur permettre de se rapprocher dangereusement. Au repos ce week-end, Bernex aura une semaine suppl\u00e9mentaire pour pr\u00e9parer la reprise contre CS Italien. Apr\u00e8s cette entr\u00e9e en mati\u00e8re, il y aura trois rencontre finales face \u00e0 Sierre, Saint-Maurice et Morges. C&#8217;est l\u00e0 que le maintien des Bern\u00e9siens devrait se jouer.<\/p>\n<ul>\n<li><strong>Samedi 12 juin CS Italien-Bernex<\/strong><\/li>\n<li><strong>Mercredi 16 juin Sierre-Bernex<\/strong><\/li>\n<li><strong>Samedi 19 juin Bernex-Saint-Maurice<\/strong><\/li>\n<li><strong>Samedi 26 juin Morges-Bernex<\/strong><\/li>\n<\/ul>\n<div id=\"attachment_44808\" style=\"width: 712px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-44808\" loading=\"lazy\" class=\"wp-image-44808 size-large\" src=\"https:\/\/www.proxifoot.ch\/new\/wp-content\/uploads\/2021\/05\/DB86FF57-8402-45E7-9B98-6BB51F91EAB7_1_105_c-1024x680.jpeg\" alt=\"\" width=\"702\" height=\"466\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2021\/05\/DB86FF57-8402-45E7-9B98-6BB51F91EAB7_1_105_c-1024x680.jpeg 1024w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2021\/05\/DB86FF57-8402-45E7-9B98-6BB51F91EAB7_1_105_c-300x199.jpeg 300w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2021\/05\/DB86FF57-8402-45E7-9B98-6BB51F91EAB7_1_105_c.jpeg 1087w\" sizes=\"(max-width: 702px) 100vw, 702px\" \/><p id=\"caption-attachment-44808\" class=\"wp-caption-text\"><em>Bernex devra \u00eatre solide, \u00e0 l&#8217;image de sa <a href=\"https:\/\/www.proxifoot.ch\/new\/2020\/09\/bernex-surprend-veyrier-et-se-rassure\/\">victoire \u00e0 Veyrier<\/a> en septembre.<\/em><\/p><\/div>\n<p style=\"text-align: justify;\">Tous les verdicts seront rendus au plus tard le 26 juin, date de la quatorzi\u00e8me et derni\u00e8re journ\u00e9e. Il ne reste plus qu&#8217;\u00e0 esp\u00e9rer la promotion d&#8217;une nouvelle \u00e9quipe genevoise en 1\u00e8re ligue ainsi que le maintien de Bernex en 2\u00e8me ligue inter, qui permettrait \u00e0 trois \u00e9quipes de 3\u00e8me ligue, au lieu des traditionnelles deux, de rejoindre la cat\u00e9gorie de r\u00e9f\u00e9rence du football r\u00e9gional. Place \u00e0 quatre semaines de football intenses.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Parmi les six \u00e9quipes genevoises de 2\u00e8me ligue inter, certaines peuvent esp\u00e9rer gros de cette reprise. Tour d&#8217;horizon avant un mois intense qui d\u00e9marrera samedi.<\/p>\n","protected":false},"author":51,"featured_media":44811,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[26],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.proxifoot.ch\/geneve\/2021\/06\/2eme-ligue-inter-des-occasions-en-or-pour-la-reprise\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2\u00e8me ligue inter : des occasions en or pour la reprise - Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"og:description\" content=\"Parmi les six \u00e9quipes genevoises de 2\u00e8me ligue inter, certaines peuvent esp\u00e9rer gros de cette reprise. Tour d&#8217;horizon avant un mois intense qui d\u00e9marrera samedi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.proxifoot.ch\/geneve\/2021\/06\/2eme-ligue-inter-des-occasions-en-or-pour-la-reprise\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-01T04:36:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-01T09:24:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2021\/05\/IMG_4377-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1711\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2021\/06\/2eme-ligue-inter-des-occasions-en-or-pour-la-reprise\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2021\/05\/IMG_4377-scaled.jpg\",\"width\":2560,\"height\":1711},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2021\/06\/2eme-ligue-inter-des-occasions-en-or-pour-la-reprise\/#webpage\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/2021\/06\/2eme-ligue-inter-des-occasions-en-or-pour-la-reprise\/\",\"name\":\"2\\u00e8me ligue inter : des occasions en or pour la reprise - Proxifoot, le m\\u00e9dia du football genevois\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2021\/06\/2eme-ligue-inter-des-occasions-en-or-pour-la-reprise\/#primaryimage\"},\"datePublished\":\"2021-06-01T04:36:32+00:00\",\"dateModified\":\"2021-06-01T09:24:51+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/cd8992ff5ae4e66d281c50a350f0c65a\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.proxifoot.ch\/geneve\/2021\/06\/2eme-ligue-inter-des-occasions-en-or-pour-la-reprise\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/cd8992ff5ae4e66d281c50a350f0c65a\",\"name\":\"Giacomo Notari\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/44793"}],"collection":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/51"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=44793"}],"version-history":[{"count":16,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/44793\/revisions"}],"predecessor-version":[{"id":44821,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/44793\/revisions\/44821"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/44811"}],"wp:attachment":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=44793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=44793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=44793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}