﻿{"id":51953,"date":"2023-02-03T08:00:00","date_gmt":"2023-02-03T06:00:00","guid":{"rendered":"https:\/\/www.proxifoot.ch\/new\/?p=51953"},"modified":"2023-09-28T09:05:09","modified_gmt":"2023-09-28T07:05:09","slug":"le-football-corporatif-a-la-croisee-des-chemins","status":"publish","type":"post","link":"https:\/\/www.proxifoot.ch\/geneve\/2023\/02\/le-football-corporatif-a-la-croisee-des-chemins\/","title":{"rendered":"Le football corporatif \u00e0 la crois\u00e9e des chemins"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Bient\u00f4t centenaire, l&#8217;Association Genevoise de Football Corporatif continue de cr\u00e9er du lien social au sein des entreprises du canton, malgr\u00e9 la crise sanitaire. Elle pourrait mettre un terme au football \u00e0 11 pour se consacrer uniquement au football \u00e0 7 qui connait un grand succ\u00e8s.<\/strong><!--more--><\/p>\n<span style=\"font-weight: bold; color: #f00;\">Erreur, le groupe n'existe pas! V\u00e9rifiez votre syntaxe! (ID: 4)<\/span><p style=\"text-align: justify;\">Il y tout d&#8217;abord un acronyme qui pr\u00eate \u00e0 confusion : AGFC, pour Association Genevoise de Football Corporatif, qui g\u00e8re les championnats des entreprises. A ne pas confondre donc avec l&#8217;ACGF, l&#8217;Association Cantonale Genevoise de Football. <em>\u00ab Le football corporatif est un peu le parent pauvre du football de mani\u00e8re g\u00e9n\u00e9rale \u00bb<\/em>, regrette Massimo Gili, pr\u00e9sident depuis 30 ans, qui a \u00e9galement jou\u00e9 au CS Italien et exerc\u00e9 des fonctions \u00e0 Etoile Carouge notamment.<\/p>\n<p style=\"text-align: justify;\">Au sein du comit\u00e9, il est accompagn\u00e9 d\u2019Andr\u00e9 Dumartheray, responsable administratif, et Roberto Zezza, responsable des comp\u00e9titions, deux anciens arbitres aupr\u00e8s de l\u2019ACGF. Les trois comp\u00e8res, qui comptent une trentaine d\u2019ann\u00e9es chacun au sein de l\u2019association, ont \u00e9galement fait partie du comit\u00e9 du CS Ch\u00eanois F\u00e9minin au d\u00e9but des ann\u00e9es 2000. La preuve que les liens entre l\u2019ACGF et l\u2019AGFC sont ind\u00e9niables. <em>\u00ab Nous avons des relations avec l\u2019ACGF, par exemple si un arbitre est d\u00e9fectueux chez eux, ils nous en informent s\u2019ils le jugent utile et vice-versa. \u00c9galement pour des joueurs qui ont des longues suspensions \u00bb<\/em>, d\u00e9taille Roberto Zezza.<\/p>\n<p style=\"text-align: justify;\"><em>\u00ab Cela n\u2019a pas toujours \u00e9t\u00e9 le cas, mais depuis quelques ann\u00e9es, on a mis en place une collaboration et un dialogue avec l\u2019ACGF,<\/em> ajoute Massimo Gili. <em>Et cela se passe tr\u00e8s bien avec eux&nbsp;\u00bb<\/em>. Malgr\u00e9 son manque de m\u00e9diatisation, le football du monde du travail repr\u00e9sente une part non n\u00e9gligeable avec plus de 70 de clubs actifs et plus de 2&#8217;300 licenci\u00e9s dans le canton. <em>\u00ab A chaque fois que nous \u00e9voquons ces chiffres, nous surprenons beaucoup de monde.&nbsp;Cela repr\u00e9sente une jolie manne, mais pas assez reconnue&nbsp;\u00bb,<\/em> d\u00e9plore le pr\u00e9sident.<\/p>\n<p style=\"text-align: justify;\"><strong>Le succ\u00e8s du football \u00e0 7<\/strong><\/p>\n<p style=\"text-align: justify;\">Ce succ\u00e8s, l\u2019AGFC le doit au football \u00e0 7, qui se joue sur un demi-terrain pendant l\u2019automne, de septembre \u00e0 novembre. 42 \u00e9quipes ont pris part au dernier championnat d\u2019automne, divis\u00e9 en 4 ligues (A-B-C-D), dont la Ligue A a \u00e9t\u00e9 remport\u00e9e par l\u2019\u00e9quipe du CERN. Un chiffre en hausse ces derni\u00e8res ann\u00e9es.<\/p>\n<p style=\"text-align: justify;\"><em>\u00ab Nous avons commenc\u00e9 \u00e0 r\u00e9fl\u00e9chir au football \u00e0 7 il y a 10 ans environ, pour r\u00e9pondre \u00e0 une demande de certaines soci\u00e9t\u00e9s,<\/em> se rappelle Massimo Gili. <em>Inscrire une \u00e9quipe demande moins de joueurs. Au niveau des terrains, c\u2019est \u00e9galement plus facile puisque deux matchs peuvent avoir lieu sur un grand terrain. On s\u2019est finalement dit que c\u2019\u00e9tait une bonne alternative pour la deuxi\u00e8me partie de saison \u00bb.<\/em><\/p>\n<p style=\"text-align: justify;\">Le football sur un demi-terrain demande moins de licences et permet aux joueurs plus \u00e2g\u00e9s de tenir davantage le coup que sur un grand terrain. Trois ans apr\u00e8s son lancement \u00e0 Gen\u00e8ve, le succ\u00e8s du foot \u00e0 7 ne cesse de cro\u00eetre. Pour Massimo Gili, il repr\u00e9sente m\u00eame l&#8217;avenir. <em>\u00ab Au niveau europ\u00e9en, le football corporatif est plus sur des championnats \u00e0 7. Nous sommes membres de la World Corporate Football, qui organise des tournois \u00e0 travers le monde, et ces derniers sont toujours \u00e0 7 joueurs. C\u2019est l\u2019avenir du foot corpo \u00bb.<\/em><\/p>\n<div id=\"attachment_53118\" style=\"width: 1546px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-53118\" loading=\"lazy\" class=\"wp-image-53118 size-full\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2023\/02\/CERN-FC-2022.jpg\" alt=\"\" width=\"1536\" height=\"948\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2023\/02\/CERN-FC-2022.jpg 1536w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2023\/02\/CERN-FC-2022-300x185.jpg 300w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2023\/02\/CERN-FC-2022-1024x632.jpg 1024w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2023\/02\/CERN-FC-2022-768x474.jpg 768w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><p id=\"caption-attachment-53118\" class=\"wp-caption-text\">CERN FC, vainqueur du dernier championnat \u00e0 7<\/p><\/div>\n<p style=\"text-align: justify;\"><strong>Le foot \u00e0 11 en p\u00e9ril&nbsp;?<\/strong><\/p>\n<p style=\"text-align: justify;\">Le revers de la m\u00e9daille, c\u2019est la baisse de participation dans le football sur grand terrain. <em>\u00ab&nbsp;Le foot \u00e0 11 a perdu avec le Covid,<\/em> poursuit le pr\u00e9sident. <em>Nous avions un championnat \u00e0 64 \u00e9quipes avant le Covid et l\u2019ann\u00e9e derni\u00e8re il n\u2019y avait plus qu\u2019une trentaine d\u2019\u00e9quipes, donc environ la moiti\u00e9. Ceci est d\u00fb aux soci\u00e9t\u00e9s qui sont un peu plus frileuses, peut-\u00eatre \u00bb.<\/em><\/p>\n<p style=\"text-align: justify;\">Le football corporatif se retrouve aujourd\u2019hui \u00e0 la crois\u00e9e des chemins. La demande dictera l\u2019avenir, mais si cette tendance continue \u00e0 la baisse, l\u2019association pourrait mettre fin au football \u00e0 11, au d\u00e9triment du football \u00e0 7 : <em>\u00ab Je ne vous cache pas qu\u2019aujourd\u2019hui, nous sommes en train de r\u00e9fl\u00e9chir \u00e0 ne faire plus qu\u2019un championnat de foot \u00e0 7, sur toute l\u2019ann\u00e9e, <\/em>d\u00e9taille Gili.<em> Il y a encore des clubs qui nous demandent de faire championnat \u00e0 11. Pour l\u2019instant, si on arrive \u00e0 le faire, on le fera. Mais si les participants continuent \u00e0 baisser, on se basculera sur un championnat total \u00e0 7 \u00bb.<\/em><\/p>\n<p style=\"text-align: justify;\">Mais que les entreprises historiques du football corporatif comme le FC Rolex, le FC Police ou le FC A\u00e9roport se rassurent : sur le court terme, le football \u00e0 11 n\u2019est pas encore en p\u00e9ril. Le championnat reprendra au printemps avec pour l\u2019instant 36 \u00e9quipes inscrites.<\/p>\n<div class=\"g g-3\"><div class=\"g-dyn a-27 c-1\"><a class=\"gofollow\" data-track=\"MjcsMywxLDYw\" href=\"https:\/\/tsm-versoix.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/10\/TSM-CRP-logos-2024.png\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><div class=\"g-dyn a-30 c-2\"><a class=\"gofollow\" data-track=\"MzAsMywxLDYw\" href=\"https:\/\/www.instagram.com\/mysols_sarl\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/08\/MySols-banner.jpg\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><div class=\"g-dyn a-12 c-3\"><a class=\"gofollow\" data-track=\"MTIsMywxLDYw\" href=\"http:\/\/arcus-fin.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2023\/01\/Arcus_Bannie\u0300re2.png\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><div class=\"g-dyn a-15 c-4\"><a class=\"gofollow\" data-track=\"MTUsMywxLDYw\" href=\"https:\/\/gabb-immo.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2022\/06\/Capture-de\u0301cran-202-06-21-a\u0300-15.32.jpg\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><div class=\"g-dyn a-28 c-5\"><a class=\"gofollow\" data-track=\"MjgsMywxLDYw\" href=\"https:\/\/www.rafaelstores.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/10\/Rafael-Stores-logo-2024.png\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><div class=\"g-dyn a-29 c-6\"><a class=\"gofollow\" data-track=\"MjksMywxLDYw\" href=\"https:\/\/www.infomaniak.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/10\/infomaniak-logo-banner.jpg\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><div class=\"g-dyn a-7 c-7\"><a class=\"gofollow\" data-track=\"NywzLDEsNjA=\" href=\"https:\/\/www.instagram.com\/pedrocar_sa\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2022\/06\/perdosss.jpg\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><div class=\"g-dyn a-33 c-8\"><a class=\"gofollow\" data-track=\"MzMsMywxLDYw\" href=\"https:\/\/www.genevoisefiduciaire.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/08\/Genevoise-Fiduciaire-banner.jpg\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><div class=\"g-dyn a-16 c-9\"><a class=\"gofollow\" data-track=\"MTYsMywxLDYw\" href=\"https:\/\/pok-games.com\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2022\/06\/Capture-de\u0301cran-2022-06-21-a\u0300-15.32.19.png\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><div class=\"g-dyn a-26 c-10\"><a class=\"gofollow\" data-track=\"MjYsMywxLDYw\" href=\"https:\/\/hepta-sa.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/10\/HEPTA-Logo-2024.png\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><\/div><p style=\"text-align: justify;\"><strong>La probl\u00e9matique des terrains<\/strong><\/p>\n<p style=\"text-align: justify;\">Un des probl\u00e8mes r\u00e9currents du football corporatif est la disponibilit\u00e9 des terrains, qui est le v\u00e9ritable nerf de la guerre. Les clubs de l\u2019ACGF ayant de plus en plus d\u2019\u00e9quipes juniors et f\u00e9minines, cela r\u00e9duit l&#8217;offre de terrains pour les matchs corporatifs. Voil\u00e0 encore un argument en faveur du football \u00e0 7, o\u00f9 peuvent avoir lieu simultan\u00e9ment deux matchs sur le m\u00eame terrain.<\/p>\n<p style=\"text-align: justify;\"><em>\u00ab Pour certaines communes, cela ne vaut pas la peine de faire venir le gardien du stade pour un match corpo, cela ne les int\u00e9resse pas \u00bb<\/em>, se lamente Massimo Gili, qui peut tout de m\u00eame compter sur des partenaires de longue date comme les communes de Vernier, Lancy, Ch\u00eane-Bourg, Plan-les-Ouates ou encore la Ville de Gen\u00e8ve.<\/p>\n<p style=\"text-align: justify;\">Et d&#8217;insister :<em> \u00ab Nous le r\u00e9p\u00e9tons depuis plusieurs ann\u00e9es : si chaque commune mettait juste une plage horaire \u00e0 disposition par semaine, on ferait le championnat sans difficult\u00e9s. Nous avons rencontr\u00e9 les communes genevoises \u00e0 deux reprises pour faire passer notre message, expliquer ce qu\u2019est le football corporatif mais ce n\u2019est pas toujours facile. Certaines ne comprennent pas pourquoi il y a un championnat d&#8217;entreprises alors que des clubs existent d\u00e9j\u00e0. Alors que ce sont deux choses diff\u00e9rentes, on peut jouer le lundi avec son travail et le week-end avec son club \u00bb.&nbsp;<\/em><\/p>\n<div id=\"attachment_53115\" style=\"width: 2026px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-53115\" loading=\"lazy\" class=\"wp-image-53115 size-full\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2023\/02\/Comite-AGFC-2023.jpg\" alt=\"\" width=\"2016\" height=\"1512\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2023\/02\/Comite-AGFC-2023.jpg 2016w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2023\/02\/Comite-AGFC-2023-300x225.jpg 300w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2023\/02\/Comite-AGFC-2023-1024x768.jpg 1024w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2023\/02\/Comite-AGFC-2023-768x576.jpg 768w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2023\/02\/Comite-AGFC-2023-1536x1152.jpg 1536w\" sizes=\"(max-width: 2016px) 100vw, 2016px\" \/><p id=\"caption-attachment-53115\" class=\"wp-caption-text\">Andr\u00e9 Dumartheray, Massimo Gili et Roberto Zezza, un trentaine d&#8217;ann\u00e9es au service du football corporatif<\/p><\/div>\n<p style=\"text-align: justify;\"><strong>Bient\u00f4t centenaire<\/strong><\/p>\n<p style=\"text-align: justify;\">Au-del\u00e0 des probl\u00e8mes logistiques, il y a tout un raisonnement \u00e0 faire sur l\u2019essence m\u00eame du football corporatif. Incompris pour certains, indispensable pour d\u2019autres, le football des entreprises cr\u00e9e ind\u00e9niablement du lien social.<em> \u00ab Pour nous, le foot corpo doit \u00eatre un \u00e9l\u00e9ment rassembleur au sein d\u2019une entreprise \u00bb,<\/em> tranche Massimo Gili. Le fameux <em>team building.<\/em><\/p>\n<p style=\"text-align: justify;\">Cr\u00e9\u00e9e en 1925, l\u2019AGFC sera centenaire d\u2019ici deux ans. Pour l\u2019occasion, elle pr\u00e9voit de marquer le coup : <em>\u00ab Nous ne voulons pas \u00eatre le comit\u00e9 du 100e anniversaire, nous pr\u00e9f\u00e9rons que ce soit une tierce personne et nous avons demand\u00e9 \u00e0 M. Longchamp, pr\u00e9sident du FC A\u00e9roport, qui conna\u00eet bien la partie \u00e9v\u00e9nementielle. Nous ne savons pas encore si l\u2019\u00e9v\u00e9nement sera sur un jour ou un format plus long, mais ce que je veux, c\u2019est montrer \u00e0 la population genevoise et \u00e0 ses repr\u00e9sentants de tous bords ce qu&#8217;est le football corporatif \u00e0 Gen\u00e8ve et quel impact il a sur son r\u00e9seau d\u2019entreprises \u00bb.<\/em><\/p>\n<p style=\"text-align: justify;\">En attendant de savoir ce que l\u2019association nous r\u00e9serve pour son centenaire en 2025, rendez-vous d\u00e8s le mois de mars pour la reprise du championnat, avec une comme cerise sur le g\u00e2teau les traditionnelles finales au mois de juin.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><img loading=\"lazy\" class=\"size-full wp-image-53127 alignleft\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2022\/02\/logo-agfc.png\" alt=\"\" width=\"141\" height=\"119\">Association Genevoise de Football Corporatif<\/strong><br \/>\n<a href=\"http:\/\/www.agfc.ch\" target=\"_blank\" rel=\"noopener noreferrer\">www.agfc.ch<\/a><br \/>\nR\u00e9seaux sociaux: <a href=\"http:\/\/www.facebook.com\/association.genevoise.de.football.corporatif\" target=\"_blank\" rel=\"noopener noreferrer\">Facebook<\/a>, <a href=\"http:\/\/www.instagram.com\/agfc_ge\" target=\"_blank\" rel=\"noopener noreferrer\">Instagram<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bient\u00f4t centenaire, l&#8217;Association Genevoise de Football Corporatif continue de cr\u00e9er du lien social au sein des entreprises du canton, malgr\u00e9 la crise sanitaire. Elle pourrait mettre un terme au football \u00e0 11 pour se consacrer uniquement au football \u00e0 7 qui connait un grand succ\u00e8s.<\/p>\n","protected":false},"author":30,"featured_media":53044,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.proxifoot.ch\/geneve\/2023\/02\/le-football-corporatif-a-la-croisee-des-chemins\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le football corporatif \u00e0 la crois\u00e9e des chemins\" \/>\n<meta property=\"og:description\" content=\"Bient\u00f4t centenaire, l&#8217;Association Genevoise de Football Corporatif continue de cr\u00e9er du lien social au sein des entreprises du canton, malgr\u00e9 la crise sanitaire. Elle pourrait mettre un terme au football \u00e0 11 pour se consacrer uniquement au football \u00e0 7 qui connait un grand succ\u00e8s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.proxifoot.ch\/geneve\/2023\/02\/le-football-corporatif-a-la-croisee-des-chemins\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-03T06:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-28T07:05:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2022\/11\/Comite-AGFC.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1926\" \/>\n\t<meta property=\"og:image:height\" content=\"1092\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@www.twitter.com\/maikel_f\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\">\n\t<meta name=\"twitter:data1\" content=\"6 minutes\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2023\/02\/le-football-corporatif-a-la-croisee-des-chemins\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2022\/11\/Comite-AGFC.jpg\",\"width\":1926,\"height\":1092},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2023\/02\/le-football-corporatif-a-la-croisee-des-chemins\/#webpage\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/2023\/02\/le-football-corporatif-a-la-croisee-des-chemins\/\",\"name\":\"Le football corporatif \\u00e0 la crois\\u00e9e des chemins\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2023\/02\/le-football-corporatif-a-la-croisee-des-chemins\/#primaryimage\"},\"datePublished\":\"2023-02-03T06:00:00+00:00\",\"dateModified\":\"2023-09-28T07:05:09+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/f8763ae73551193f68b47b57e2bdfb15\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.proxifoot.ch\/geneve\/2023\/02\/le-football-corporatif-a-la-croisee-des-chemins\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/f8763ae73551193f68b47b57e2bdfb15\",\"name\":\"Maikel\",\"sameAs\":[\"https:\/\/twitter.com\/www.twitter.com\/maikel_f\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/51953"}],"collection":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=51953"}],"version-history":[{"count":19,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/51953\/revisions"}],"predecessor-version":[{"id":57750,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/51953\/revisions\/57750"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/53044"}],"wp:attachment":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=51953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=51953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=51953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}