﻿{"id":56359,"date":"2023-08-08T18:20:45","date_gmt":"2023-08-08T16:20:45","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=56359"},"modified":"2023-08-09T12:09:24","modified_gmt":"2023-08-09T10:09:24","slug":"log-est-toujours-en-vie","status":"publish","type":"post","link":"https:\/\/www.proxifoot.ch\/geneve\/2023\/08\/log-est-toujours-en-vie\/","title":{"rendered":"L\u2019OG est toujours en vie"},"content":{"rendered":"<p class=\"p1\" style=\"text-align: justify;\"><b>Sous la houlette de Giuseppe Urro, nouveau pr\u00e9sident, et Khalid Chagna, nouveau directeur sportif et entra\u00eeneur, l\u2019Olympique de Gen\u00e8ve se lance dans un projet ambitieux, avec la formation au centre. <\/b><!--more--><\/p>\n<p class=\"p1\"><span style=\"font-weight: bold; color: #f00;\">Erreur, le groupe n'existe pas! V\u00e9rifiez votre syntaxe! (ID: 4)<\/span>\n<p class=\"p1\" style=\"text-align: justify;\">Difficile de r\u00e9ellement savoir ce qu\u2019il se passait ces derniers mois du c\u00f4t\u00e9 de l\u2019Olympique de Gen\u00e8ve. Alors que de nombreuses \u00e9quipes juniors disparaissaient saison apr\u00e8s saison, c&#8217;est la premi\u00e8re qui a perdu l\u2019ensemble de son staff et de ses joueurs cet \u00e9t\u00e9. Ceci ne laissait pr\u00e9sager rien de positif quant \u00e0 l\u2019avenir du club. Des rumeurs de disparition, voire de fusion avec le CS Interstar se sont m\u00eame mises \u00e0 circuler. Et pourtant, l\u2019OG est bel et bien en vie avec de nouveaux hommes forts \u00e0 sa t\u00eate, \u00e0 commencer par le nouveau pr\u00e9sident Giuseppe Urro qui remplace Luca Mautone. L\u2019ancien pr\u00e9sident du Racing Club Gen\u00e8ve, Khalid Chagna, est lui de retour dans le panorama du football genevois en prenant la direction sportive du club, ainsi que les r\u00eanes de la 1\u00e8re \u00e9quipe. Autre retour important, celui de Carlos De Carvalho, qui avait quitt\u00e9 l\u2019OG pour s\u2019occuper de la pr\u00e9formation \u00e0 Interstar o\u00f9 <a href=\"https:\/\/www.proxifoot.ch\/new\/2023\/02\/interstar-une-croissance-remarquable\/\" target=\"_blank\" rel=\"noopener noreferrer\">il a notamment effectu\u00e9 un excellent travail<\/a>. Il sera le nouveau responsable juniors.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\"><b>Donner un nouvel \u00e9lan depuis la base<\/b><\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Tant pour Giuseppe Urro que pour Khalid Chagna, le nouveau projet de l\u2019Olympique de Gen\u00e8ve doit s\u2019appuyer sur un mouvement junior de qualit\u00e9. D\u00e9laiss\u00e9 ces derni\u00e8res saisons au profit de la premi\u00e8re \u00e9quipe, celui-ci repr\u00e9sentera une vraie priorit\u00e9 pour le nouveau comit\u00e9. &#8220;<i>Nous souhaitons reconstruire depuis la base<\/i>, explique Giuseppe Urro. <i>C\u2019est notamment pour cette raison que nous sommes all\u00e9s chercher Carlos De Carvalho, qui conna\u00eet parfaitement la maison. Il est l\u2019homme de la situation&#8221;<\/i>.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Un total de 12 \u00e9quipes juniors seront engag\u00e9es la saison prochaine. Pour ce faire, le club a \u00e9t\u00e9 dans l\u2019obligation de recruter des personnes comp\u00e9tentes. &#8220;<i>Nous sommes all\u00e9s chercher des entra\u00eeneurs dipl\u00f4m\u00e9s pour chacune des \u00e9quipes<\/i>, confirme Khalid Chagna. <i>Il a fallu tout repenser, tout restructurer pour repartir de z\u00e9ro avec ce nouveau projet&#8221;. <\/i>Un travail de fond qui avait \u00e9t\u00e9 initi\u00e9 par le comit\u00e9 pr\u00e9c\u00e9dent. L\u2019Olympique de Gen\u00e8ve sera donc repr\u00e9sent\u00e9 de l\u2019\u00e9cole de foot jusqu\u2019aux juniors A, avec une \u00e9quipe minimum par cat\u00e9gorie.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Tout ceci pose n\u00e9anmoins un souci, et pas des moindres, celui de la suroccupation des terrains du c\u00f4t\u00e9 de Varemb\u00e9. Entre le CS Interstar et l\u2019Olympique de Gen\u00e8ve, ce seront plus de 60 \u00e9quipes qui devront se partager les installations de la Ville de Gen\u00e8ve. &#8220;<i>Nous sommes clairement en surcapacit\u00e9 d\u2019\u00e9quipes par rapport aux terrains disponibles<\/i>, confirme le nouveau pr\u00e9sident. <i>Le probl\u00e8me est que l\u2019OG a besoin d\u2019un maximum d\u2019\u00e9quipes juniors pour faire vivre le club avec les rentr\u00e9es de cotisations et autres subventions Jeunesse et Sport. Aujourd\u2019hui, nous ne pouvons pas inscrire le nombre d\u2019\u00e9quipes que nous souhaiterions, car il n\u2019y a pas la place. Nous n\u2019arrivons m\u00eame pas \u00e0 caser nos 12 \u00e9quipes&#8221;<\/i>.<\/p>\n<div id=\"attachment_37134\" style=\"width: 712px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.proxifoot.ch\/geneve\/2018\/10\/le-derby-de-varembe-revient-a-log\/jlap-csivsog-075\/\" rel=\"attachment wp-att-37134\"><img aria-describedby=\"caption-attachment-37134\" loading=\"lazy\" class=\"wp-image-37134 size-large\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2018\/10\/jlap-CSIvsOG-075-1024x682.jpg\" alt=\"\" width=\"702\" height=\"468\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2018\/10\/jlap-CSIvsOG-075-1024x682.jpg 1024w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2018\/10\/jlap-CSIvsOG-075-300x200.jpg 300w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2018\/10\/jlap-CSIvsOG-075-768x511.jpg 768w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2018\/10\/jlap-CSIvsOG-075.jpg 1080w\" sizes=\"(max-width: 702px) 100vw, 702px\" \/><\/a><p id=\"caption-attachment-37134\" class=\"wp-caption-text\">Les premi\u00e8res \u00e9quipes de l&#8217;OG et d&#8217;Interstar lors d&#8217;un derby de Varemb\u00e9, \u00e0 l&#8217;\u00e9poque en 2\u00e8me ligue inter. (Photo: Jean-Luc Auboeuf, 2019)<\/p><\/div>\n<p class=\"p1\" style=\"text-align: justify;\">Il sera d\u00e9sormais int\u00e9ressant de voir comment Interstar -qui compte une quarantaine d\u2019\u00e9quipes juniors \u00e0 son actif- et son voisin collaboreront sur ce sujet \u00e9pineux. <em>&#8220;Il<\/em> <i>existe aujourd\u2019hui un d\u00e9s\u00e9quilibre entre les deux clubs<\/i>, affirme Giuseppe Urro. <i>Si deux clubs doivent vivre \u00e0 Varemb\u00e9, ils doivent avoir droit aux m\u00eames ressources. Des discussions sont en cours avec le nouveau pr\u00e9sident de l&#8217;Association des Clubs de Varemb\u00e9, Omer Ibrahimof, et avec le CS Interstar pour trouver une solution. Il est essentiel que nous ayons une bonne entente, le dialogue est une priorit\u00e9&#8221;<\/i>. L\u2019OG paie actuellement la mauvaise gestion du mouvement junior faite par les comit\u00e9s pr\u00e9c\u00e9dents.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\"><b>Des actifs ambitieux<\/b><\/p>\n<p class=\"p1\" style=\"text-align: justify;\">La premi\u00e8re \u00e9quipe de l\u2019Olympique de Gen\u00e8ve \u00e9voluera toujours en 2\u00e8me ligue inter lors de la saison \u00e0 venir, gr\u00e2ce notamment \u00e0 l\u2019excellent travail effectu\u00e9 par <a href=\"https:\/\/www.proxifoot.ch\/new\/2023\/08\/reparti-de-zero-meyrin-a-un-plan-pour-son-futur\/\" target=\"_blank\" rel=\"noopener noreferrer\">Domingos Ribeiro, qui a rejoint le Meyrin FC<\/a> \u00e0 l\u2019inter-saison. L\u2019entra\u00eeneur n\u2019a de loin pas \u00e9t\u00e9 le seul \u00e0 quitter le club de Varemb\u00e9, puisque l\u2019ensemble du staff et de l\u2019effectif sont \u00e9galement partis. Pour Khalid Chagna, il a donc fallu l\u00e0 aussi tout reconstruire : &#8220;<i>Nous avons perdu tous nos joueurs, je n\u2019ai rien pu faire&#8221;<\/i>.<\/p>\n<div id=\"attachment_56403\" style=\"width: 712px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.proxifoot.ch\/geneve\/2021\/08\/log-est-toujours-en-vie\/ribeiro-domingos-og\/\" rel=\"attachment wp-att-56403\"><img aria-describedby=\"caption-attachment-56403\" loading=\"lazy\" class=\"size-large wp-image-56403\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2021\/08\/ribeiro-domingos-og-1024x574.jpg\" alt=\"\" width=\"702\" height=\"394\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2021\/08\/ribeiro-domingos-og-1024x574.jpg 1024w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2021\/08\/ribeiro-domingos-og-300x168.jpg 300w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2021\/08\/ribeiro-domingos-og-768x430.jpg 768w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2021\/08\/ribeiro-domingos-og-1536x860.jpg 1536w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2021\/08\/ribeiro-domingos-og-2048x1147.jpg 2048w\" sizes=\"(max-width: 702px) 100vw, 702px\" \/><\/a><p id=\"caption-attachment-56403\" class=\"wp-caption-text\">Domingos RIbeiro aura su tirer le meilleur de son \u00e9quipe pendant deux saisons \u00e0 l&#8217;OG.<\/p><\/div>\n<p class=\"p1\" style=\"text-align: justify;\">Le directeur sportif a tent\u00e9 de recruter un nouvel entra\u00eeneur en la personne d\u2019Admir Bilibani, mais l\u2019ex de Saint-Prex n&#8217;a finalement pas pu venir. C&#8217;est donc Khalid Chagna en personne qui dirigera l&#8217;\u00e9quipe.<em> &#8220;J&#8217;ai une solide exp\u00e9rience d&#8217;entra\u00eeneur et \u00e9galement de formation des entra\u00eeneurs au sein de l&#8217;Acad\u00e9mie au Maroc<\/em>&#8220;. Il est parvenu \u00e0 recruter pas moins de 26 joueurs : <em>&#8220;J&#8217;<\/em><i>ai r\u00e9ussi \u00e0 constituer un effectif sympathique, avec notamment quelques excellents joueurs&#8221;<\/i>, se r\u00e9jouit-il. Parmi les nombreuses recrues, on note les arriv\u00e9es de Karim Chentouf, Karim Robin et Boubacar Dembele (tous ex-Meyrin), Fabrice Guzel (ex-Nyon, Ch\u00eanois, PLO) ou encore de Reda Medouani et Wilhem Renquin (ex-Thierrens). Osni Mutombo int\u00e8gre quant \u00e0 lui le staff en tant qu&#8217;entra\u00eeneur des gardiens.<\/p>\n<div id=\"attachment_56521\" style=\"width: 532px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-56521\" loading=\"lazy\" class=\"wp-image-56521\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2021\/08\/87638c64-2b24-42c2-9cbc-b8577e8d3c9a.jpg\" alt=\"\" width=\"522\" height=\"522\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2021\/08\/87638c64-2b24-42c2-9cbc-b8577e8d3c9a.jpg 1080w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2021\/08\/87638c64-2b24-42c2-9cbc-b8577e8d3c9a-300x300.jpg 300w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2021\/08\/87638c64-2b24-42c2-9cbc-b8577e8d3c9a-1024x1024.jpg 1024w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2021\/08\/87638c64-2b24-42c2-9cbc-b8577e8d3c9a-150x150.jpg 150w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2021\/08\/87638c64-2b24-42c2-9cbc-b8577e8d3c9a-768x768.jpg 768w\" sizes=\"(max-width: 522px) 100vw, 522px\" \/><p id=\"caption-attachment-56521\" class=\"wp-caption-text\">Karim Chentouf et Karim Robin \u00e9volueront du c\u00f4t\u00e9 de l&#8217;OG la saison prochaine. (Photo : Julian Aguilar)<\/p><\/div>\n<p class=\"p1\" style=\"text-align: justify;\">La premi\u00e8re \u00e9quipe ne sera pas la seule priorit\u00e9 de Khalid Chagna en ce qui concerne les actifs : &#8220;<i>Il va \u00eatre tr\u00e8s important pour nous de faire monter la deuxi\u00e8me \u00e9quipe de 4\u00e8me en 3\u00e8me ligue. Les joueurs qui signent chez nous ainsi que l\u2019ensemble du club sont conscients qu\u2019il faudra tout faire pour remplir cet objectif&#8221;<\/i>. Le groupe 2 de 4\u00e8me ligue, qui compte notamment les ambitieux Bernex II et UGS II, sera donc fort int\u00e9ressant \u00e0 suivre cette saison.<\/p>\n<p style=\"text-align: justify;\"><div class=\"g g-3\"><div class=\"g-dyn a-7 c-1\"><a class=\"gofollow\" data-track=\"NywzLDEsNjA=\" href=\"https:\/\/www.instagram.com\/pedrocar_sa\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2022\/06\/perdosss.jpg\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><div class=\"g-dyn a-28 c-2\"><a class=\"gofollow\" data-track=\"MjgsMywxLDYw\" href=\"https:\/\/www.rafaelstores.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/10\/Rafael-Stores-logo-2024.png\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><div class=\"g-dyn a-27 c-3\"><a class=\"gofollow\" data-track=\"MjcsMywxLDYw\" href=\"https:\/\/tsm-versoix.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/10\/TSM-CRP-logos-2024.png\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><div class=\"g-dyn a-15 c-4\"><a class=\"gofollow\" data-track=\"MTUsMywxLDYw\" href=\"https:\/\/gabb-immo.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2022\/06\/Capture-de\u0301cran-202-06-21-a\u0300-15.32.jpg\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><div class=\"g-dyn a-16 c-5\"><a class=\"gofollow\" data-track=\"MTYsMywxLDYw\" href=\"https:\/\/pok-games.com\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2022\/06\/Capture-de\u0301cran-2022-06-21-a\u0300-15.32.19.png\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><div class=\"g-dyn a-33 c-6\"><a class=\"gofollow\" data-track=\"MzMsMywxLDYw\" href=\"https:\/\/www.genevoisefiduciaire.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/08\/Genevoise-Fiduciaire-banner.jpg\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><div class=\"g-dyn a-26 c-7\"><a class=\"gofollow\" data-track=\"MjYsMywxLDYw\" href=\"https:\/\/hepta-sa.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/10\/HEPTA-Logo-2024.png\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><div class=\"g-dyn a-29 c-8\"><a class=\"gofollow\" data-track=\"MjksMywxLDYw\" href=\"https:\/\/www.infomaniak.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/10\/infomaniak-logo-banner.jpg\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><div class=\"g-dyn a-32 c-9\"><a class=\"gofollow\" data-track=\"MzIsMywxLDYw\" href=\"https:\/\/rentesgenevoises.ch\/l-annexe\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/08\/Annexe-Rentes-banner.jpg\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><div class=\"g-dyn a-30 c-10\"><a class=\"gofollow\" data-track=\"MzAsMywxLDYw\" href=\"https:\/\/www.instagram.com\/mysols_sarl\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/08\/MySols-banner.jpg\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><\/div>\n<p class=\"p1\" style=\"text-align: justify;\">C\u2019est sur le long terme que le nouveau comit\u00e9 de l\u2019Olympique de Gen\u00e8ve, qui compte aujourd\u2019hui 5 membres, souhaite reconstruire. &#8220;<em>Nous allons renforcer notre comit\u00e9 dans un futur proche avec de nouvelles arriv\u00e9es, car nous aurons besoin de nouvelles ressources dans ce que nous souhaitons mettre en place<\/em>, explique Giuseppe Urro. <em>Nous allons notamment organiser plusieurs manifestations sportives tout au long de l&#8217;ann\u00e9e<\/em>&#8220;. Cr\u00e9\u00e9 il y a 10 ans, l&#8217;OG est \u00e0 un tournant de sa jeune histoire avec ce nouveau projet qui verra le jour pour la saison 23\/24.<\/p>\n<p>&nbsp;<\/p>\n<p><em>Photo de couverture : Joana Nogueira<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sous la houlette de Giuseppe Urro, nouveau pr\u00e9sident, et Khalid Chagna, nouveau directeur sportif et entra\u00eeneur, l\u2019Olympique de Gen\u00e8ve se lance dans un projet ambitieux, avec la formation au centre.<\/p>\n","protected":false},"author":32,"featured_media":56360,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[26,1],"tags":[765,766,585,163],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"description\" content=\"Sous la houlette de Giuseppe Urro, nouveau pr\u00e9sident, et Khalid Chagna, nouveau directeur sportif et entra\u00eeneur, l\u2019Olympique de Gen\u00e8ve se lance dans un projet ambitieux avec la formation au centre.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.proxifoot.ch\/geneve\/2023\/08\/log-est-toujours-en-vie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019OG est toujours en vie\" \/>\n<meta property=\"og:description\" content=\"Sous la houlette de Giuseppe Urro, nouveau pr\u00e9sident, et Khalid Chagna, nouveau directeur sportif et entra\u00eeneur, l\u2019Olympique de Gen\u00e8ve se lance dans un projet ambitieux avec la formation au centre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.proxifoot.ch\/geneve\/2023\/08\/log-est-toujours-en-vie\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-08T16:20:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-09T10:09:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2023\/08\/OG.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1404\" \/>\n\t<meta property=\"og:image:height\" content=\"672\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"L\u2019OG est toujours en vie\" \/>\n<meta name=\"twitter:description\" content=\"Sous la houlette de Giuseppe Urro, nouveau pr\u00e9sident, et Khalid Chagna, nouveau directeur sportif et entra\u00eeneur, l\u2019Olympique de Gen\u00e8ve se lance dans un projet ambitieux avec la formation au centre.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2023\/08\/OG.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\">\n\t<meta name=\"twitter:data1\" content=\"6 minutes\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2023\/08\/log-est-toujours-en-vie\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2023\/08\/OG.jpg\",\"width\":1404,\"height\":672},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2023\/08\/log-est-toujours-en-vie\/#webpage\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/2023\/08\/log-est-toujours-en-vie\/\",\"name\":\"L\\u2019OG est toujours en vie\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/2023\/08\/log-est-toujours-en-vie\/#primaryimage\"},\"datePublished\":\"2023-08-08T16:20:45+00:00\",\"dateModified\":\"2023-08-09T10:09:24+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e709cc61b3ec45e30de1699237497595\"},\"description\":\"Sous la houlette de Giuseppe Urro, nouveau pr\\u00e9sident, et Khalid Chagna, nouveau directeur sportif et entra\\u00eeneur, l\\u2019Olympique de Gen\\u00e8ve se lance dans un projet ambitieux avec la formation au centre.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.proxifoot.ch\/geneve\/2023\/08\/log-est-toujours-en-vie\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e709cc61b3ec45e30de1699237497595\",\"name\":\"Thomas Arbes\\u00fa\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/56359"}],"collection":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=56359"}],"version-history":[{"count":18,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/56359\/revisions"}],"predecessor-version":[{"id":56534,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/56359\/revisions\/56534"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/56360"}],"wp:attachment":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=56359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=56359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=56359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}