﻿{"id":68195,"date":"2025-04-25T10:04:18","date_gmt":"2025-04-25T08:04:18","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=68195"},"modified":"2025-04-25T10:13:49","modified_gmt":"2025-04-25T08:13:49","slug":"les-5-matchs-a-suivre-ce-week-end-2","status":"publish","type":"post","link":"https:\/\/www.proxifoot.ch\/geneve\/2025\/04\/les-5-matchs-a-suivre-ce-week-end-2\/","title":{"rendered":"Les 5 matchs \u00e0 suivre ce week-end"},"content":{"rendered":"\r\n<h4><strong>S\u00e9lection et pr\u00e9sentation de cinq rencontres immanquables, ce week-end \u00e0 Gen\u00e8ve.<\/strong><\/h4>\r\n<p><!--more--><\/p>\r\n<div class=\"g g-3\"><div class=\"g-dyn a-28 c-1\"><a class=\"gofollow\" data-track=\"MjgsMywxLDYw\" href=\"https:\/\/www.rafaelstores.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/10\/Rafael-Stores-logo-2024.png\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><div class=\"g-dyn a-16 c-2\"><a class=\"gofollow\" data-track=\"MTYsMywxLDYw\" href=\"https:\/\/pok-games.com\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2022\/06\/Capture-de\u0301cran-2022-06-21-a\u0300-15.32.19.png\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><div class=\"g-dyn a-30 c-3\"><a class=\"gofollow\" data-track=\"MzAsMywxLDYw\" href=\"https:\/\/www.instagram.com\/mysols_sarl\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/08\/MySols-banner.jpg\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><div class=\"g-dyn a-12 c-4\"><a class=\"gofollow\" data-track=\"MTIsMywxLDYw\" href=\"http:\/\/arcus-fin.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2023\/01\/Arcus_Bannie\u0300re2.png\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><div class=\"g-dyn a-33 c-5\"><a class=\"gofollow\" data-track=\"MzMsMywxLDYw\" href=\"https:\/\/www.genevoisefiduciaire.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/08\/Genevoise-Fiduciaire-banner.jpg\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><div class=\"g-dyn a-32 c-6\"><a class=\"gofollow\" data-track=\"MzIsMywxLDYw\" href=\"https:\/\/rentesgenevoises.ch\/l-annexe\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/08\/Annexe-Rentes-banner.jpg\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><div class=\"g-dyn a-27 c-7\"><a class=\"gofollow\" data-track=\"MjcsMywxLDYw\" href=\"https:\/\/tsm-versoix.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/10\/TSM-CRP-logos-2024.png\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><div class=\"g-dyn a-29 c-8\"><a class=\"gofollow\" data-track=\"MjksMywxLDYw\" href=\"https:\/\/www.infomaniak.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2024\/10\/infomaniak-logo-banner.jpg\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><div class=\"g-dyn a-7 c-9\"><a class=\"gofollow\" data-track=\"NywzLDEsNjA=\" href=\"https:\/\/www.instagram.com\/pedrocar_sa\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2022\/06\/perdosss.jpg\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><div class=\"g-dyn a-15 c-10\"><a class=\"gofollow\" data-track=\"MTUsMywxLDYw\" href=\"https:\/\/gabb-immo.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img class=\"aligncenter wp-image-40990 size-full\" src=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2022\/06\/Capture-de\u0301cran-202-06-21-a\u0300-15.32.jpg\" alt=\"\" width=\"100%\" height=\"150\"><\/a><\/div><\/div><p>Pour ce dernier week-end d&#8217;avril lors duquel les enjeux ne manqueront pas, nous avons retenu 5 matchs de 5 ligues diff\u00e9rentes \u00e0 suivre \u00e0 Gen\u00e8ve. \u00c0 vos agendas !<\/p>\r\n<blockquote>\r\n<p><b>FC Vernier &#8211; FC Onex<br \/><\/b>Samedi, 15h, stade municipal de Vernier<br \/>Juniors A Inter, groupe 8<\/p>\r\n<p>Dans le groupe 8 de Youth League A, seuls deux repr\u00e9sentants genevois sont pr\u00e9sents : le FC Vernier et le FC Onex. Ce samedi 26 avril, les deux s&#8217;affrontent dans un duel qui vaudra son pesant d&#8217;or au classement. Actuellement sous la barre, les On\u00e9siens ne sont qu&#8217;\u00e0 trois unit\u00e9s du premier rel\u00e9gable, et \u00e0 4 petits points de Vernier, qui n&#8217;est pas encore sauv\u00e9. Les Verniolans peuvent s&#8217;\u00e9loigner de la zone rouge en cas de victoire \u00e0 la maison, tandis qu&#8217;une d\u00e9faite mettrait les Vert dans uns situation encore plus inconfortable&#8230; <a href=\"http:\/\/www.proxifoot.ch\/geneve\/2024\/10\/onex-arrache-un-point-au-terme-dun-derby-fou\/\" target=\"_blank\" rel=\"noopener noreferrer\">\u00c0 l&#8217;aller, les deux formations s&#8217;\u00e9taient quitt\u00e9es dos \u00e0 dos (4-4).<\/a><\/p>\r\n<div id=\"attachment_68197\" style=\"width: 1662px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.proxifoot.ch\/geneve\/2025\/04\/les-5-matchs-a-suivre-ce-week-end-2\/capture-decran-2025-04-25-a-09-38-43\/\" rel=\"attachment wp-att-68197\"><img aria-describedby=\"caption-attachment-68197\" loading=\"lazy\" class=\"wp-image-68197 size-full\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/04\/Capture-de\u0301cran-2025-04-25-a\u0300-09.38.43.png\" alt=\"\" width=\"1652\" height=\"648\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/04\/Capture-de\u0301cran-2025-04-25-a\u0300-09.38.43.png 1652w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/04\/Capture-de\u0301cran-2025-04-25-a\u0300-09.38.43-300x118.png 300w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/04\/Capture-de\u0301cran-2025-04-25-a\u0300-09.38.43-1024x402.png 1024w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/04\/Capture-de\u0301cran-2025-04-25-a\u0300-09.38.43-768x301.png 768w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/04\/Capture-de\u0301cran-2025-04-25-a\u0300-09.38.43-1536x602.png 1536w\" sizes=\"(max-width: 1652px) 100vw, 1652px\" \/><\/a><p id=\"caption-attachment-68197\" class=\"wp-caption-text\">Les On\u00e9siens n&#8217;ont plus que 5 matchs pour se sauver.<\/p><\/div>\r\n<\/blockquote>\r\n<blockquote>\r\n<p><strong>CS Ch\u00eanois &#8211; FC<\/strong> <strong>Echallens R\u00e9gion<\/strong><br \/>Samedi, 17h30, Trois-Ch\u00eane<br \/>1\u00e8re ligue Classic, groupe 1<\/p>\r\n<p>Il ne reste que 5 matchs, dans le groupe 1 de 1\u00e8re ligue Classic ! Comme cela a \u00e9t\u00e9 le cas depuis le d\u00e9but de la saison, la course aux finales de promotion est plus ouverte que jamais. La troupe de David Joye, <a href=\"http:\/\/www.proxifoot.ch\/geneve\/2025\/04\/chenois-capitule-dans-les-arrets-de-jeu\/\" target=\"_blank\" rel=\"noopener noreferrer\">r\u00e9cemment battue \u00e0 Lausanne (1-0, premier revers de 2025)<\/a>, a l&#8217;occasion de rebondir contre Echallens, un autre pr\u00e9tendant \u00e0 la mont\u00e9e. En cas de succ\u00e8s, les pensionnaires des Trois-Ch\u00eane s&#8217;assureraient quasi math\u00e9matiquement une place parmi les futurs finalistes du groupe 1.<\/p>\r\n<div id=\"attachment_68198\" style=\"width: 1390px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.proxifoot.ch\/geneve\/2025\/04\/les-5-matchs-a-suivre-ce-week-end-2\/classement-1l-classic\/\" rel=\"attachment wp-att-68198\"><img aria-describedby=\"caption-attachment-68198\" loading=\"lazy\" class=\"size-full wp-image-68198\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/04\/classement-1L-classic.png\" alt=\"\" width=\"1380\" height=\"634\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/04\/classement-1L-classic.png 1380w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/04\/classement-1L-classic-300x138.png 300w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/04\/classement-1L-classic-1024x470.png 1024w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/04\/classement-1L-classic-768x353.png 768w\" sizes=\"(max-width: 1380px) 100vw, 1380px\" \/><\/a><p id=\"caption-attachment-68198\" class=\"wp-caption-text\">Ch\u00eanois est d\u00e9j\u00e0 \u00e0 +7 sur Echallens, la premi\u00e8re \u00e9quipe du groupe 1 en dehors des places donnant droit aux finales de promotion.<\/p><\/div>\r\n<\/blockquote>\r\n<blockquote>\r\n<p><strong>CS Interstar &#8211; US Terre Sainte<br \/><\/strong>Dimanche, 11h, Varemb\u00e9<br \/>2\u00e8me ligue inter, groupe 1<\/p>\r\n<p>Interstar s&#8217;attaque \u00e0 une montagne ! <a href=\"http:\/\/www.proxifoot.ch\/geneve\/2025\/04\/interstar-laisse-aire-dans-le-rouge\/\" target=\"_blank\" rel=\"noopener noreferrer\">Deux semaines apr\u00e8s leur victoire contre le rival genevois A\u00efre<\/a>, et trois jours avant le\u00a0<em>remake\u00a0<\/em>de ce match en quarts de finale de la Coupe genevoise, les pensionnaires de Varemb\u00e9 accueillent le leader du groupe 1 de 2\u00e8me ligue inter f\u00e9minine. Actuellement 4\u00e8me, le CSI &#8211; meilleure d\u00e9fense du groupe avec 18 buts encaiss\u00e9s &#8211; a l&#8217;occasion de se rapprocher ult\u00e9rieurement du podium, et de s&#8217;offrir une victoire de prestige face au futures championnes du groupe.\u00a0<\/p>\r\n<div id=\"attachment_68199\" style=\"width: 1388px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.proxifoot.ch\/geneve\/2025\/04\/les-5-matchs-a-suivre-ce-week-end-2\/capture-decran-2025-04-25-a-09-46-29\/\" rel=\"attachment wp-att-68199\"><img aria-describedby=\"caption-attachment-68199\" loading=\"lazy\" class=\"size-full wp-image-68199\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/04\/Capture-de\u0301cran-2025-04-25-a\u0300-09.46.29.png\" alt=\"\" width=\"1378\" height=\"634\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/04\/Capture-de\u0301cran-2025-04-25-a\u0300-09.46.29.png 1378w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/04\/Capture-de\u0301cran-2025-04-25-a\u0300-09.46.29-300x138.png 300w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/04\/Capture-de\u0301cran-2025-04-25-a\u0300-09.46.29-1024x471.png 1024w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/04\/Capture-de\u0301cran-2025-04-25-a\u0300-09.46.29-768x353.png 768w\" sizes=\"(max-width: 1378px) 100vw, 1378px\" \/><\/a><p id=\"caption-attachment-68199\" class=\"wp-caption-text\">Un sacr\u00e9 d\u00e9fi attend le CS Interstar.<\/p><\/div>\r\n<\/blockquote>\r\n<blockquote>\r\n<p><strong>FC Vernier &#8211; FC Stade-Lausanne-Ouchy<br \/><\/strong>Dimanche, 14h, stade municipal de Vernier<br \/>2\u00e8me ligue inter, groupe 1<\/p>\r\n<p>Avec <a href=\"http:\/\/www.proxifoot.ch\/geneve\/2025\/04\/2eme-ligue-inter-coup-de-theatre-dans-la-course-au-maintien\/\" target=\"_blank\" rel=\"noopener noreferrer\">la bonne nouvelle tomb\u00e9e il y a de cela quelques jours<\/a>, le FC Vernier, tout comme les autres \u00e9quipes genevoises du groupe, est bien moins en danger de rel\u00e9gation qu&#8217;il l&#8217;\u00e9tait avant cette r\u00e9forme. N\u00e9anmoins, l&#8217;\u00e9quipe entra\u00een\u00e9e par Kelmend Bejta a tout int\u00e9r\u00eat \u00e0 ne pas se manquer, dimanche, contre le SLO. Les Lausannois sont sous la barre, \u00e0 -7 des Verniolans, et pourraient dangereusement se rapprocher des clubs genevois en cas de succ\u00e8s. \u00c0 Vernier d&#8217;\u00e9viter ce type de sc\u00e9nario et de faire un pas de plus vers son maintien dans la cat\u00e9gorie, <a href=\"http:\/\/www.proxifoot.ch\/geneve\/2024\/06\/vernier-est-champion-de-2eme-ligue\/\" target=\"_blank\" rel=\"noopener noreferrer\">un an apr\u00e8s sa promotion<\/a>.<\/p>\r\n<div id=\"attachment_68200\" style=\"width: 1394px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.proxifoot.ch\/geneve\/2025\/04\/les-5-matchs-a-suivre-ce-week-end-2\/capture-decran-2025-04-25-a-09-49-04\/\" rel=\"attachment wp-att-68200\"><img aria-describedby=\"caption-attachment-68200\" loading=\"lazy\" class=\"size-full wp-image-68200\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/04\/Capture-de\u0301cran-2025-04-25-a\u0300-09.49.04.png\" alt=\"\" width=\"1384\" height=\"644\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/04\/Capture-de\u0301cran-2025-04-25-a\u0300-09.49.04.png 1384w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/04\/Capture-de\u0301cran-2025-04-25-a\u0300-09.49.04-300x140.png 300w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/04\/Capture-de\u0301cran-2025-04-25-a\u0300-09.49.04-1024x476.png 1024w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/04\/Capture-de\u0301cran-2025-04-25-a\u0300-09.49.04-768x357.png 768w\" sizes=\"(max-width: 1384px) 100vw, 1384px\" \/><\/a><p id=\"caption-attachment-68200\" class=\"wp-caption-text\">En l&#8217;\u00e9tat actuel des choses, Echichens, bien qu&#8217;au-dessus de la barre, serait aussi rel\u00e9gu\u00e9 (<a href=\"http:\/\/www.proxifoot.ch\/geneve\/2025\/04\/2eme-ligue-inter-coup-de-theatre-dans-la-course-au-maintien\/\" target=\"_blank\" rel=\"noopener noreferrer\">explications<\/a>).<\/p><\/div>\r\n<\/blockquote>\r\n<blockquote>\r\n<p><strong>AS Charmilles &#8211; Lancy FC II<\/strong><br \/>Dimanche, 14h, Libellules<br \/>3\u00e8me ligue, groupe II<\/p>\r\n<p>Il faudra attendre dimanche, 14h, pour assister \u00e0 l&#8217;affiche la plus attendue du week-end ! Les deux \u00e9quipes se tirant la bourre depuis le d\u00e9but de saison, en t\u00eate du groupe II de 3\u00e8me ligue, s&#8217;affronteront dans un duel qui s&#8217;apparente \u00e0 une finale pour la premi\u00e8re place. \u00c0 l&#8217;aller, Lancy s&#8217;\u00e9tait impos\u00e9 3-1. En ce d\u00e9but de deuxi\u00e8me tour, les Lanc\u00e9ens ont n\u00e9anmoins c\u00e9d\u00e9 leur premi\u00e8re place \u00e0 la formation de Jorge Pais, <a href=\"http:\/\/www.proxifoot.ch\/geneve\/2022\/06\/lancy-ii-se-console-avec-la-coupe-genevoise\/\" target=\"_blank\" rel=\"noopener noreferrer\">ex-entra\u00eeneur de Lancy II, avec qui il avait remport\u00e9 la Coupe genevoise en 2022.<\/a> Le choc pour la place de leader entre l&#8217;AS Charmilles et le Lancy FC II n&#8217;est \u00e0 manquer sous aucun pr\u00e9texte !<\/p>\r\n<div id=\"attachment_68202\" style=\"width: 1378px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.proxifoot.ch\/geneve\/2025\/04\/les-5-matchs-a-suivre-ce-week-end-2\/capture-decran-2025-04-25-a-09-56-02\/\" rel=\"attachment wp-att-68202\"><img aria-describedby=\"caption-attachment-68202\" loading=\"lazy\" class=\"size-full wp-image-68202\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/04\/Capture-de\u0301cran-2025-04-25-a\u0300-09.56.02.png\" alt=\"\" width=\"1368\" height=\"476\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/04\/Capture-de\u0301cran-2025-04-25-a\u0300-09.56.02.png 1368w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/04\/Capture-de\u0301cran-2025-04-25-a\u0300-09.56.02-300x104.png 300w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/04\/Capture-de\u0301cran-2025-04-25-a\u0300-09.56.02-1024x356.png 1024w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/04\/Capture-de\u0301cran-2025-04-25-a\u0300-09.56.02-768x267.png 768w\" sizes=\"(max-width: 1368px) 100vw, 1368px\" \/><\/a><p id=\"caption-attachment-68202\" class=\"wp-caption-text\">Lancy II a un meilleur coefficient fair-play que l&#8217;AS Charmilles, ce qui pourrait faire la diff\u00e9rence en cas d&#8217;\u00e9galit\u00e9 de points.<\/p><\/div>\r\n<\/blockquote>\r\n<p><em>Photo de couverture : <a href=\"https:\/\/www.instagram.com\/zuodarfoto\/\" target=\"_blank\" rel=\"noopener noreferrer\">@zuodarfoto<\/a> \/ Valentin Zuodar<\/em><\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>S\u00e9lection et pr\u00e9sentation de cinq rencontres immanquables, ce week-end \u00e0 Gen\u00e8ve.<\/p>\n","protected":false},"author":51,"featured_media":68204,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[1],"tags":[540],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"description\" content=\"S\u00e9lection et pr\u00e9sentation de cinq rencontres immanquables, ce week-end \u00e0 Gen\u00e8ve.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.proxifoot.ch\/geneve\/2025\/04\/les-5-matchs-a-suivre-ce-week-end-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les 5 matchs \u00e0 suivre ce week-end\" \/>\n<meta property=\"og:description\" content=\"S\u00e9lection et pr\u00e9sentation de cinq rencontres immanquables, ce week-end \u00e0 Gen\u00e8ve.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.proxifoot.ch\/geneve\/2025\/04\/les-5-matchs-a-suivre-ce-week-end-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-25T08:04:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-25T08:13:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/04\/cs-interstar-zuodar.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1404\" \/>\n\t<meta property=\"og:image:height\" content=\"672\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"S\u00e9lection et pr\u00e9sentation de cinq rencontres immanquables, ce week-end \u00e0 Gen\u00e8ve.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/04\/cs-interstar-zuodar.png\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\">\n\t<meta name=\"twitter:data1\" content=\"5 minutes\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2025\/04\/les-5-matchs-a-suivre-ce-week-end-2\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2025\/04\/cs-interstar-zuodar.png\",\"width\":1404,\"height\":672},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2025\/04\/les-5-matchs-a-suivre-ce-week-end-2\/#webpage\",\"url\":\"http:\/\/www.proxifoot.ch\/geneve\/2025\/04\/les-5-matchs-a-suivre-ce-week-end-2\/\",\"name\":\"Les 5 matchs \\u00e0 suivre ce week-end\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2025\/04\/les-5-matchs-a-suivre-ce-week-end-2\/#primaryimage\"},\"datePublished\":\"2025-04-25T08:04:18+00:00\",\"dateModified\":\"2025-04-25T08:13:49+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/cd8992ff5ae4e66d281c50a350f0c65a\"},\"description\":\"S\\u00e9lection et pr\\u00e9sentation de cinq rencontres immanquables, ce week-end \\u00e0 Gen\\u00e8ve.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.proxifoot.ch\/geneve\/2025\/04\/les-5-matchs-a-suivre-ce-week-end-2\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/cd8992ff5ae4e66d281c50a350f0c65a\",\"name\":\"Giacomo Notari\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/68195"}],"collection":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/51"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=68195"}],"version-history":[{"count":5,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/68195\/revisions"}],"predecessor-version":[{"id":68206,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/68195\/revisions\/68206"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/68204"}],"wp:attachment":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=68195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=68195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=68195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}