﻿{"id":9872,"date":"2013-03-17T21:29:02","date_gmt":"2013-03-17T20:29:02","guid":{"rendered":"http:\/\/www.proxifoot.ch\/geneve\/?p=9872"},"modified":"2016-07-20T17:20:02","modified_gmt":"2016-07-20T15:20:02","slug":"3eme-ligue-groupe-2-premiere-pour-grand-saconnex","status":"publish","type":"post","link":"https:\/\/www.proxifoot.ch\/geneve\/2013\/03\/3eme-ligue-groupe-2-premiere-pour-grand-saconnex\/","title":{"rendered":"3\u00e8me ligue, groupe 2 : premi\u00e8re pour Grand-Saconnex"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>13\u00e8me journ\u00e9e \/ La lutte pour le titre ne semble concerner que deux \u00e9quipes, Champel et Bernex II. La lutte pour le maintien, elle, s&#8217;annonce passionnante, apr\u00e8s la victoire de Grand-Saconnex sur le terrain de Bosna.<!--more--><\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong>Athl\u00e9tique-R\u00e9gina FC\u00a0 \u00a0\u2013 \u00a0 \u00a0FC Puplinge \u00a0 3 &#8211; 3<br \/>\nButs :\u00a0<\/strong>Hbabaz 1-0, Maiorano 2-0, Maiorano 3-0, Ghazraoui 3-1, Luisoni 3-2, Luisoni 3-3<\/p>\n<p style=\"text-align: justify;\">Leur match contre Plan-les-Ouates ayant \u00e9t\u00e9 annul\u00e9 dimanche pass\u00e9, les Puplingeois d\u00e9butent leur premier tour sur le terrain de Varemb\u00e9 face \u00e0 Athl\u00e9tique-R\u00e9gina.<\/p>\n<p style=\"text-align: justify;\">L\u2019entame de match est compl\u00e8tement \u00e0 l\u2019avantage des locaux, qui profitent des errements et du manque d\u2019agressivit\u00e9 de leurs adversaires pour prendre l\u2019avantage par trois fois. Sonn\u00e9s par ces trois buts, les Puplingeois se r\u00e9veillent enfin et parviennent \u00e0 r\u00e9duire le score juste avant la mi-temps gr\u00e2ce \u00e0 leur buteur Ghazraoui.<\/p>\n<p style=\"text-align: justify;\">Au retour des vestiaires, alors qu\u2019on pourrait penser qu\u2019Athl\u00e9tique-R\u00e9gina va g\u00e9rer ses deux longueurs d\u2019avance, l\u2019\u00e9quipe perd pied, comme l\u2019explique leur entra\u00eeneur Michel Cautillo\u00a0: \u00ab\u00a0On sombre de nouveau dans nos travers du premier tour. On s&#8217;arr\u00eate de jouer et on laisse notre adversaire libre de tout marquage.\u00a0\u00bb<\/p>\n<p style=\"text-align: justify;\">Au contraire, les visiteurs affichent davantage de d\u00e9termination et de solidarit\u00e9 qu\u2019en premi\u00e8re p\u00e9riode. Ils sont alors r\u00e9compens\u00e9s pour leurs efforts en arrachant l\u2019\u00e9galisation gr\u00e2ce \u00e0 deux coups-francs transform\u00e9s par leur milieu Sandro Luisoni. La victoire aurait m\u00eame pu revenir aux Puplingeois, si le capitaine Jonathan Tartaglione n\u2019avait pas manqu\u00e9 un penalty.<\/p>\n<p style=\"text-align: justify;\">Au final, Puplinge ram\u00e8ne un bon point de Varemb\u00e9. M\u00eame men\u00e9e au score, l\u2019\u00e9quipe n\u2019a pas baiss\u00e9 les bras, comme le relevait Claudio Cerato\u00a0: \u00ab\u00a0Il faudra \u00eatre plus concentr\u00e9s en d\u00e9but de match. Mais je suis tr\u00e8s satisfait de l&#8217;\u00e9tat d&#8217;esprit de ce groupe. Il faudra continuer comme \u00e7a pour la suite.\u00a0\u00bb\u00a0 Les Puplingeois tenteront cette fois de ne pas manquer leur d\u00e9part dimanche prochain contre Vernier II.<\/p>\n<p style=\"text-align: justify;\">Quant \u00e0 Athl\u00e9tique-R\u00e9gina, l\u2019\u00e9quipe conserve sa troisi\u00e8me place. Cependant, elle aurait pu obtenir les trois points, si elle ne s\u2019\u00e9tait pas rel\u00e2ch\u00e9e en deuxi\u00e8me p\u00e9riode. \u00ab\u00a0Il faut que mes joueurs prennent conscience qu&#8217;un match dure 90 minutes et ne s&#8217;arr\u00eate pas quand on est entrain de gagner\u00a0\u00bb, d\u00e9clarait Michel Cautillo.<\/p>\n<p style=\"text-align: justify;\">\u00ab\u00a0Il faut se battre et continuer \u00e0 jouer au ballon du d\u00e9but jusqu&#8217;\u00e0 la fin de la m\u00eame fa\u00e7on. Pour cela, il faut \u00eatre pr\u00eat physiquement. Maintenant, on ne peut que faire mieux. J&#8217;attends une r\u00e9action de toute l\u2019\u00e9quipe, une pr\u00e9sence aux entra\u00eenements et aussi ce samedi contre City\u00a0\u00bb, concluait le mentor d\u2019Athl\u00e9tique-R\u00e9gina.<\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>FC Saint-Paul\u00a0 \u00a0\u2013 \u00a0 \u00a0Signal FC Bernex-Confignon II \u00a0 1 &#8211; 2<br \/>\nButs : <\/strong>15&#8242; 1-0, 65&#8242; Trifiletti 1-1, 83&#8242; Olela 1-2<strong><em><\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Tous deux d\u00e9faits lors de la journ\u00e9e pr\u00e9c\u00e9dente, Saint-Paul et Signal-Bernex II esp\u00e9raient renouer avec le succ\u00e8s dimanche. Les trois points \u00e9taient aussi n\u00e9cessaire pour les Bern\u00e9siens, afin de rester au contact du leader champelois.<\/p>\n<p style=\"text-align: justify;\">Le d\u00e9but de rencontre penche davantage en faveur de Saint-Paul. En effet, les hommes de Pino Mugnaio ouvrent le score sur une t\u00eate concluant un coup-franc. Apr\u00e8s cette r\u00e9ussite, Saint-Paul continue sur sa lanc\u00e9e et continue \u00e0 se montrer dangereux sur plusieurs occasions. A la demi-heure de jeu, les locaux sont tout proches de doubler la mise, mais le poteau vient sauver les Bern\u00e9siens. De son c\u00f4t\u00e9, Signal-Bernex II tente de d\u00e9velopper son jeu, mais la d\u00e9fense collongeoise est bien place et ne lui laisse que peu de chance.<\/p>\n<p style=\"text-align: justify;\">En seconde p\u00e9riode, la partie s&#8217;\u00e9quilibre et chaque \u00e9quipe semble en mesure de pouvoir inscrire un but. Sur une action anodine, Trifiletti s&#8217;empare du ballon dans l&#8217;axe aux 20 m\u00e8tres et \u00e9galise d&#8217;un tir puissant \u00e0 ras le poteau. Suite \u00e0 cette \u00e9galisation, les deux formations redoublent leurs efforts pour prendre l&#8217;avantage. Les visiteurs parviennent finalement \u00e0 faire la diff\u00e9rence \u00e0 dix minutes du terme gr\u00e2ce \u00e0 une r\u00e9ussite du capitaine Olela. Saint-Paul se rue alors \u00e0 l&#8217;attaque, tandis que leur adversaire a l&#8217;opportunit\u00e9 d&#8217;aggraver le score. Mais le score ne bougera plus et Signal-Bernex II remporte les trois points.<\/p>\n<p style=\"text-align: justify;\">La satisfaction \u00e9tait donc de mise du c\u00f4t\u00e9 de Jos\u00e9 Monnerat: &#8220;On est tr\u00e8s heureux et je f\u00e9licite tout mon groupe qui s&#8217;est montr\u00e9 solidaire et volontaire jusqu&#8217;au bout. On va rester tr\u00e8s humble, parce que l&#8217;on est conscient que l&#8217;adversaire a eu des opportunit\u00e9s en premi\u00e8re mi-temps qui n&#8217;ont, heureusement pour nous, pas abouties. Ce genre de match gagn\u00e9 sur un terrain difficile pour les deux \u00e9quipes, fait un bien fou au moral et on est vraiment content.&#8221;<\/p>\n<p style=\"text-align: justify;\">Saint-Paul, qui n&#8217;a pas d\u00e9m\u00e9rit\u00e9, reste au sixi\u00e8me rang. Apr\u00e8s avoir affront\u00e9 les deux premiers du classement, Saint-Paul recevra Meyrin II. Quant aux Bern\u00e9siens, ils accueilleront Satigny.<\/p>\n<p style=\"text-align: justify;\"><strong><strong><\/strong><br \/>\n<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>FC Meyrin II\u00a0 \u00a0\u2013 \u00a0 \u00a0FC Vernier II \u00a0 0 &#8211; 0<br \/>\n<\/strong><em><\/em><\/p>\n<p style=\"text-align: justify;\">Avant cette rencontre, Meyrin II et Vernier II comptabilisaient le m\u00eame nombre de points. A l\u2019image de leur classement, le match qui les a oppos\u00e9s s\u2019est av\u00e9r\u00e9 \u00e9quilibr\u00e9.<\/p>\n<p style=\"text-align: justify;\">La partie aurait pu basculer d\u2019un c\u00f4t\u00e9 comme de l\u2019autre. En effet, les deux formations se sont cr\u00e9\u00e9 plusieurs occasions franches, mais toutes ces tentatives ont \u00e9t\u00e9 repouss\u00e9es par les gardiens. La seule diff\u00e9rence entre les deux \u00e9quipes a r\u00e9sid\u00e9 au niveau de leur jeu, comme l\u2019explique Tiago Terrinha, coach meyrinois : \u00ab Nous avons essay\u00e9 de poser le ballon et de d\u00e9velopper du jeu, contrairement \u00e0 notre adversaire qui a opt\u00e9 pour un jeu direct tout au long des 90 minutes. \u00bb Meyrin II et Vernier II n\u2019ont donc pas r\u00e9ussi \u00e0 se d\u00e9partager et restent \u00e0 \u00e9galit\u00e9 au classement.<\/p>\n<p style=\"text-align: justify;\">Ce r\u00e9sultat ne comblait pas les attentes de Tiago Terrinha : \u00ab Je suis d\u00e9\u00e7u du r\u00e9sultat ainsi que de la prestation de l\u2019\u00e9quipe. Nous sommes capables de faire nettement mieux ! A nous de travailler cette semaine et de pr\u00e9parer le prochain match avec beaucoup plus d\u2019envie ! \u00bb Les \u00ab jaunes et noirs \u00bb iront du c\u00f4t\u00e9 de la Californie dimanche pour affronter Saint-Paul.<\/p>\n<p style=\"text-align: justify;\">De son c\u00f4t\u00e9, Jos\u00e9-Manuel Dinis se contentait de ce point : \u00ab Nous ramenons un tr\u00e8s bon point de Meyrin, qui est une \u00e9quipe jeune et de qualit\u00e9 aid\u00e9e par des joueurs d&#8217;exp\u00e9rience. Comme je l&#8217;avais dit \u00e0 mes joueurs, le match se jouerait sur des d\u00e9tails. Malheureusement, nous avons rat\u00e9 des occasions \u00e0 deux reprises face au gardien et nous n&#8217;avons pas su n\u00e9gocier les balles arr\u00eat\u00e9es. \u00bb L\u2019entra\u00eeneur verniolan poursuivait : \u00ab Malgr\u00e9 tout, je suis content de l&#8217;\u00e9tat d&#8217;esprit et suis convaincu que nous sommes sur le droit chemin pour atteindre nos objectifs. \u00bb<\/p>\n<p style=\"text-align: justify;\">Jos\u00e9-Manuel Dinis tenait \u00e9galement \u00e0 soulever un \u00e9l\u00e9ment : \u00ab A souligner tout de m\u00eame que le match nous a \u00e9t\u00e9 confirm\u00e9 sur le terrain synth\u00e9tique ce vendredi, avant que nous apprenions une heure avant le coup d&#8217;envoi qu&#8217;il aurait finalement lieu sur le terrain en herbe. Certains joueurs n&#8217;\u00e9taient du coup pas \u00e9quip\u00e9s, les appuis \u00e9taient rendus difficiles. Cela nous a port\u00e9 quelque peu pr\u00e9judice, mais heureusement cela n&#8217;a pas eu de cons\u00e9quences. \u00bb<\/p>\n<p style=\"text-align: justify;\">Vernier II effectuera un nouveau d\u00e9placement le week-end prochain, puisque les joueurs se rendront \u00e0 Puplinge.<\/p>\n<p style=\"text-align: justify;\"><strong><strong><\/strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>FC Plan-les-Ouates II\u00a0 \u00a0\u2013 \u00a0 \u00a0FC City \u00a0 3 &#8211; 3<br \/>\nButs : <\/strong>Duarte 0-1, Aguilar 1-1, S. Petulla 2-1, Dos Santos 2-2, S. Petulla 3-2, Duarte 3-3<strong><\/strong><\/p>\n<p style=\"text-align: justify;\">Avant le d\u00e9but de cette partie, l&#8217;objectif \u00e9tait clair pour Plan-les-Ouates II et City, deux \u00e9quipes en mal de points: la victoire! Les joueurs de Roberto Petulla esp\u00e9raient retrouver le chemin de la victoire, qui leur \u00e9chappe depuis la cinqui\u00e8me journ\u00e9e, tandis que les &#8220;Citizens&#8221; voulaient se racheter apr\u00e8s leur d\u00e9faite conc\u00e9d\u00e9e contre Rapid Jonction Bosna dimanche pass\u00e9.<\/p>\n<p style=\"text-align: justify;\">Au final, aucune des deux \u00e9quipes n&#8217;a r\u00e9ussi \u00e0 faire la diff\u00e9rence et elles se sont donc quitt\u00e9es sur un match nul logique. Chaque formation peut nourrir quelques regrets. En effet, Plan-les-Ouates II a men\u00e9 au score par deux fois, avant de se faire rejoindre par son adversaire. Quant aux &#8220;Citizens&#8221;, la victoire leur tendait les bras \u00e0 la 89e minute et un penalty siffl\u00e9 en leur faveur. Mais l&#8217;essai n&#8217;a pas \u00e9t\u00e9 transform\u00e9 et les prot\u00e9g\u00e9s de Patrick Stifani ont manqu\u00e9 l&#8217;occasion de remporter trois points pr\u00e9cieux dans la course au maintien.<\/p>\n<p style=\"text-align: justify;\">A l&#8217;issue de la partie, Patrick Stifani soulignait les points que son \u00e9quipe doit am\u00e9liorer en vue du maintien: &#8220;Si nous voulons rester dans cette cat\u00e9gorie de jeu il faudra faire preuve rapidement de beaucoup plus de d\u00e9termination et d&#8217;intransigeance dans nos duels d\u00e9fensifs, car nous prenons beaucoup trop de buts sur des erreurs individuelles.&#8221;<\/p>\n<p style=\"text-align: justify;\">City reste donc \u00e0 la neuvi\u00e8me place du classement et compte toujours trois points d&#8217;avance sur le premier rel\u00e9gable. La r\u00e9ception d&#8217;Athl\u00e9tique-R\u00e9gina les attend samedi prochain.<\/p>\n<p style=\"text-align: justify;\">Pour sa part, Plan-les-Ouates profite du match nul de Rapid Jonction Bosna pour remonter au-dessus de la barre. Un match capital attend les Plan-les-Ouatiens lors de la prochaine journ\u00e9e, puisqu&#8217;ils se d\u00e9placeront au Stade du Blanch\u00e9 pour affronter Grand-Saconnex.<br \/>\n<strong><br \/>\n<strong>\u00a0<\/strong><br \/>\n<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>FC Rapid Jonction Bosna\u00a0 \u00a0\u2013 \u00a0 \u00a0FC Grand-Saconnex \u00a0 0 &#8211; 1<br \/>\n<\/strong><strong>But :<\/strong>\u00a0Vazquez 0-1<\/p>\n<p style=\"text-align: justify;\">Il aura fallu attendre la 13\u00e8me journ\u00e9e pour que Grand-Saconnex obtienne enfin une premi\u00e8re victoire. Une victoire \u00f4 combien importante, puisqu\u2019elle est tomb\u00e9e contre un adversaire direct pour le maintien, Rapid Jonction Bosna. Un seul but d&#8217;Angel Vazquez a suffi aux Saconn\u00e9siens pour prendre le meilleur sur les Bosniaques.<\/p>\n<p style=\"text-align: justify;\">Gr\u00e2ce \u00e0 ce succ\u00e8s, la formation d\u2019Orazio Leonti revient \u00e0 deux points de son adversaire du jour. A noter que Grand-Saconnex compte \u00e9galement un match en moins. Leur mission \u00ab maintien \u00bb continuera dimanche contre Plan-les-Ouates II, le premier non-rel\u00e9gable.<\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s \u00eatre sortis de la zone de rel\u00e9gation le week-end pass\u00e9, les Bosniaques retombent eux sous la barre \u00e0 cause de cette d\u00e9faite. Senad Kospo nous livrait ses impressions sur cette mauvaise op\u00e9ration r\u00e9alis\u00e9e par son \u00e9quipe : \u00ab Malheureusement, ce sont trois points de perdus. Nous aurions m\u00e9rit\u00e9 de prendre trois points, ou au moins le match nul par rapport au jeu pr\u00e9sent\u00e9 et au nombre d&#8217;occasions de but cr\u00e9\u00e9es par notre \u00e9quipe. Je suis extr\u00eamement satisfait du jeu et de l&#8217;attitude du groupe. Mais \u00e7a n&#8217;enl\u00e8ve pas le m\u00e9rite de l&#8217;\u00e9quipe de Grand-Saconnex. Ils sont venus chercher le r\u00e9sultat et ils l&#8217;ont obtenu avec la rigueur. Je soulignerai aussi un tr\u00e8s bon arbitrage dans ce match bien engag\u00e9, mais correct quand m\u00eame. \u00bb<\/p>\n<p style=\"text-align: justify;\">Rapid Jonction Bosna n\u2019aura pas la t\u00e2che facile lors de la prochaine journ\u00e9e, puisque l\u2019\u00e9quipe affrontera Champel, avant de les visiter \u00e0 nouveau pour le compte de la coupe.<\/p>\n<p style=\"text-align: justify;\"><strong><strong><\/strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>FC Satigny\u00a0 \u00a0\u2013 \u00a0 \u00a0FC Champel \u00a0 0 &#8211; 1<br \/>\nBut :<\/strong> 65&#8242; Caamano 0-1<\/p>\n<p style=\"text-align: justify;\">Occupant toujours la place de leader, Champel se rendait \u00e0 Satigny pour continuer son beau parcours.<\/p>\n<p style=\"text-align: justify;\">Face \u00e0 une \u00e9quipe satignote volontaire et bien organis\u00e9e, les Champelois peinent \u00e0 d\u00e9velopper leur jeu en premi\u00e8re p\u00e9riode. \u00ab Nous \u00e9tions quelques peu timor\u00e9s en premi\u00e8re mi-temps. Le ballon nous br\u00fblait un peu les pieds, peut-\u00eatre par peur de mal faire \u00bb, explique Pascal P\u00eacheur.<\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s la pause, les visiteurs haussent leur niveau de jeu et leur domination est enfin concr\u00e9tis\u00e9e peu apr\u00e8s l\u2019heure de jeu \u00ab par un but de grande classe de K-Man \u00bb dixit l\u2019entra\u00eeneur champelois. Le leader a alors plusieurs occasions de tuer le match, mais le portier satignote Lotterio met son veto \u00e0 toutes ces tentatives.<\/p>\n<p style=\"text-align: justify;\">Champel parvient n\u00e9anmoins \u00e0 conserver son avantage et repart avec une victoire importante, qui lui permet de conforter sa place de leader. Pascal P\u00eacheur se montrait donc satisfait de sa formation : \u00ab Je f\u00e9licite mes joueurs, car ils ont \u00e9t\u00e9 extraordinaires de solidarit\u00e9. Nous allons maintenant pr\u00e9parer la double confrontation contre Bosna. Et il va falloir hausser notre niveau de jeu si nous voulons remporter les deux matches. \u00bb En effet, Champel recevra dimanche Rapid Jonction Bosna, avant de les affronter pour la Coupe trois jours plus tard.<\/p>\n<p style=\"text-align: justify;\">Satigny, qui compte un match de retard, recule \u00e0 la huiti\u00e8me place. Apr\u00e8s avoir affront\u00e9 le leader, un nouveau match difficile attend les prot\u00e9g\u00e9s de C\u00e9dric Tallant, qui se rendront \u00e0 Bernex.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-9952\" title=\"3ligue2-13\" alt=\"\" src=\"http:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2013\/03\/3ligue2-13.jpg\" width=\"633\" height=\"350\" srcset=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2013\/03\/3ligue2-13.jpg 633w, https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2013\/03\/3ligue2-13-300x165.jpg 300w\" sizes=\"(max-width: 633px) 100vw, 633px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>13\u00e8me journ\u00e9e \/ La lutte pour le titre ne semble concerner que deux \u00e9quipes, Champel et Bernex II. La lutte pour le maintien, elle, s&#8217;annonce passionnante, apr\u00e8s la victoire de Grand-Saconnex sur le terrain de Bosna.<\/p>\n","protected":false},"author":1,"featured_media":6245,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[6],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.proxifoot.ch\/geneve\/2013\/03\/3eme-ligue-groupe-2-premiere-pour-grand-saconnex\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3\u00e8me ligue, groupe 2 : premi\u00e8re pour Grand-Saconnex - Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"og:description\" content=\"13\u00e8me journ\u00e9e \/ La lutte pour le titre ne semble concerner que deux \u00e9quipes, Champel et Bernex II. La lutte pour le maintien, elle, s&#8217;annonce passionnante, apr\u00e8s la victoire de Grand-Saconnex sur le terrain de Bosna.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.proxifoot.ch\/geneve\/2013\/03\/3eme-ligue-groupe-2-premiere-pour-grand-saconnex\/\" \/>\n<meta property=\"og:site_name\" content=\"Proxifoot, le m\u00e9dia du football genevois\" \/>\n<meta property=\"article:published_time\" content=\"2013-03-17T20:29:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-20T15:20:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/09\/banniere-3\u00e8me-ligue2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"164\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/\",\"name\":\"Proxifoot, le m\\u00e9dia du football genevois\",\"description\":\"Le m\\u00e9dia du football genevois\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.proxifoot.ch\/geneve\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2013\/03\/3eme-ligue-groupe-2-premiere-pour-grand-saconnex\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.proxifoot.ch\/geneve\/wp-content\/uploads\/2012\/09\/banniere-3\\u00e8me-ligue2.jpg\",\"width\":660,\"height\":164},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2013\/03\/3eme-ligue-groupe-2-premiere-pour-grand-saconnex\/#webpage\",\"url\":\"http:\/\/www.proxifoot.ch\/geneve\/2013\/03\/3eme-ligue-groupe-2-premiere-pour-grand-saconnex\/\",\"name\":\"3\\u00e8me ligue, groupe 2 : premi\\u00e8re pour Grand-Saconnex - Proxifoot, le m\\u00e9dia du football genevois\",\"isPartOf\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.proxifoot.ch\/geneve\/2013\/03\/3eme-ligue-groupe-2-premiere-pour-grand-saconnex\/#primaryimage\"},\"datePublished\":\"2013-03-17T20:29:02+00:00\",\"dateModified\":\"2016-07-20T15:20:02+00:00\",\"author\":{\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.proxifoot.ch\/geneve\/2013\/03\/3eme-ligue-groupe-2-premiere-pour-grand-saconnex\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.proxifoot.ch\/geneve\/#\/schema\/person\/e79532f1e0a9be41ee2fa7c8e50815e7\",\"name\":\"admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/9872"}],"collection":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/comments?post=9872"}],"version-history":[{"count":0,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/posts\/9872\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media\/6245"}],"wp:attachment":[{"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/media?parent=9872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/categories?post=9872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proxifoot.ch\/geneve\/wp-json\/wp\/v2\/tags?post=9872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}